{"id":12409,"date":"2019-10-02T13:42:50","date_gmt":"2019-10-02T16:42:50","guid":{"rendered":"https:\/\/beduka.com\/blog\/?p=12409"},"modified":"2022-04-13T12:16:33","modified_gmt":"2022-04-13T15:16:33","slug":"nota-de-corte-gestao-publica","status":"publish","type":"post","link":"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-gestao-publica\/","title":{"rendered":"Nota de Corte para Gest\u00e3o P\u00fablica &#8211; Sisu 2022 e Prouni 2022"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote\"><p><strong><em>Descubra quais s\u00e3o as notas de corte para o curso de Gest\u00e3o P\u00fablica no Sisu e no Prouni  2022 e tenha uma ideia melhor de qual nota voc\u00ea precisa tirar no <a rel=\"noreferrer noopener\" aria-label=\"ENEM (abre numa nova aba)\" href=\"https:\/\/enem.inep.gov.br\/\" target=\"_blank\">ENEM<\/a> se quiser fazer este curso em uma institui\u00e7\u00e3o p\u00fablica ou privada.<\/em><\/strong><br><\/p><\/blockquote>\n\n\n\n<p><strong>ATEN\u00c7\u00c3O:<\/strong>&nbsp;As notas descritas neste artigo s\u00e3o do ano de&nbsp;<strong>2020<\/strong>, mas voc\u00ea pode, e deve, utiliz\u00e1-las como refer\u00eancia para&nbsp;<strong>2022<\/strong>!   <\/p>\n\n\n\n<p>Neste artigo voc\u00ea ir\u00e1 conferir quais as maiores e as menores notas de corte para Gest\u00e3o P\u00fablica. Dessa forma, queremos que voc\u00ea saiba de forma mais clara qual precisa ser a sua nota no ENEM se quiser fazer este curso pelo Sisu ou Prouni.<\/p>\n\n\n\n<p><strong>Quer seguir diretamente para alguma parte espec\u00edfica?<\/strong> Clique em algum dos t\u00f3picos abaixo:<\/p>\n\n\n\n<ul><li><a href=\"#Menor-nota-de-corte-Sisu-2021\">Menor nota de Corte do Sisu 2022<\/a><\/li><li><a href=\"#Maior-nota-de-corte-Sisu-2021\">Maior nota de Corte do Sisu 2022<\/a><\/li><li><a href=\"#Menor-nota-de-corte-para-o-Prouni-2020\">Menor nota de Corte do Prouni 2022<\/a><\/li><li><a href=\"#Maior-nota-de-corte-para-o-Prouni-2020\">Maior nota de Corte do Prouni 2022<\/a><\/li><li><a href=\"#Nota-de-Corte-do-Fies\">Nota de Corte do Fies 2022<\/a><\/li><\/ul>\n\n\n\n<p>No site <a href=\"https:\/\/beduka.com\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">beduka.com<\/a> voc\u00ea v\u00ea <strong>TODAS as notas<\/strong> de corte de <strong>TODOS os cursos<\/strong> e em todas as cidades do Brasil. N\u00e3o perca mais tempo!<br><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Menor-nota-de-corte-Sisu-2021\">Menor nota de corte para Gest\u00e3o P\u00fablica &#8211; Sisu 2022<\/h2>\n\n\n\n<p>A menor nota foi registrada em <strong>Campina Grande<\/strong>. Na UFCG (Universidade Federal de Campina Grande), a nota registrada foi <strong>440,24<\/strong> na modalidade Ampla Concorr\u00eancia. <a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/detalhes\/gestao-publica\/instituto-federal-de-educacao-ciencia-e-tecnologia-do-maranhao\/buriticupu--maranhao\" target=\"_blank\">Confira mais detalhes sobre a institui\u00e7\u00e3o<\/a>.<br><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Maior-nota-de-corte-Sisu-2021\">Maior nota de corte para Gest\u00e3o P\u00fablica &#8211; Sisu 2022<\/h2>\n\n\n\n<p>Em <strong>Minas Gerais<\/strong>, tivemos a maior nota de corte para Gest\u00e3o P\u00fablica. Na UFMG (Universidade Federal de Minas Gerais), a nota registrada foi<strong> 659,56<\/strong>, na modalidade Ampla Concorr\u00eancia. <a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/detalhes\/gestao-publica\/universidade-de-sao-paulo\/sao-paulo--sao-paulo\" target=\"_blank\">Confira mais detalhes sobre a institui\u00e7\u00e3o<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Menor-nota-de-corte-para-o-Prouni-2020\">Menor nota de corte para o Prouni 2022<\/h2>\n\n\n\n<p>A menor nota de corte para Gest\u00e3o P\u00fablica foi <strong>450.82<\/strong>, no Prouni 100%. Essa nota foi registrada em <strong>Curitiba &#8211; Paran\u00e1<\/strong>, no UNINTER (Centro Universit\u00e1rio Internacional). <a href=\"https:\/\/beduka.com\/detalhes\/gestao-publica\/centro-universitario-internacional\/curitiba--parana\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">Confira mais detalhes sobre a institui\u00e7\u00e3o<\/a>.<br><\/p>\n\n\n\n<p>No Prouni 50%, a menor nota de corte foi registrada em <strong>Lucas do Rio Verde<\/strong>, no Mato Grosso. No UNINTER (Centro Universit\u00e1rio Internacional), a nota de corte foi <strong>452.06<\/strong>. <a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/detalhes\/gestao-publica\/centro-universitario-internacional\/lucas-do-rio-verde--mato-grosso\" target=\"_blank\">Confira mais detalhes sobre a institui\u00e7\u00e3o<\/a>.<\/p>\n\n\n\n<p>No momento, ainda n\u00e3o temos as notas de corte referentes a 2022. As fornecidas aqui s\u00e3o dos anos anteriores, <strong>mas elas s\u00e3o muito \u00fateis e servem como base.<\/strong><br><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Maior-nota-de-corte-para-o-Prouni-2020\">Maior nota de corte para o Prouni 2022<\/h2>\n\n\n\n<p>Em <strong>Contagem &#8211; Minas Gerais<\/strong>, tivemos a maior nota de corte para Gest\u00e3o P\u00fablica. No Centro Universit\u00e1rio UNA, a nota de corte foi <strong>698.04<\/strong>, no Prouni 100%. <a href=\"https:\/\/beduka.com\/detalhes\/gestao-publica\/centro-universitario-una\/contagem--minas-gerais\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">Confira mais detalhes sobre a institui\u00e7\u00e3o<\/a>.<br><\/p>\n\n\n\n<p>No Prouni 50%, a maior nota de corte foi registrada em <strong>Palmas<\/strong>, no Tocantins. Na UNICEUMA (Universidade do Ceuma), a nota de corte foi <strong>672.46<\/strong>. <a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/detalhes\/gestao-publica\/universidade-do-ceuma-uniceuma\/palmas--tocantins\" target=\"_blank\">Confira mais detalhes sobre a institui\u00e7\u00e3o<\/a>.<\/p>\n\n\n\n<p>No momento, ainda n\u00e3o temos as notas de corte referentes a 2022. As fornecidas aqui s\u00e3o dos anos anteriores, <strong>mas elas s\u00e3o muito \u00fateis e servem como base.<\/strong><br><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Nota-de-Corte-do-Fies\">Nota de Corte do Fies para Gest\u00e3o P\u00fablica<\/h2>\n\n\n\n<p>As exig\u00eancias do Fies s\u00e3o que o candidato obtenha, no m\u00ednimo, 450 pontos no Enem e que n\u00e3o tire zero a reda\u00e7\u00e3o. Tendo cumprido essas exig\u00eancias, haver\u00e1 uma disputa normal e as maiores notas preencher\u00e3o as vagas disponibilizadas para financiamento.<br><\/p>\n\n\n\n<ul><li><a href=\"https:\/\/beduka.com\/blog\/como-funciona-o-fies\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">Aprenda tamb\u00e9m como funciona o Fies<\/a>.<\/li><\/ul>\n\n\n\n<p>Gostou de conferir as notas de Gest\u00e3o P\u00fablica? Se prepare para a prova do ENEM ou de outros vestibulares com o <a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/simulado\/#\/\" target=\"_blank\">Simulado do Beduka<\/a>. \u00c9 gratuito e voc\u00ea pode fazer a hora que quiser!<br><\/p>\n\n\n\n<p>Queremos te ajudar a encontrar a <strong>FACULDADE IDEAL<\/strong>! Logo abaixo, fa\u00e7a uma pesquisa por curso e cidade que te mostraremos todas as faculdades que podem te atender. <strong>Informamos a nota de corte, valor de mensalidade, nota do MEC, avalia\u00e7\u00e3o dos alunos, modalidades de ensino e muito mais.<\/strong><br><\/p>\n\n\n\n<p>Experimente agora!<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Descubra quais s\u00e3o as notas de corte para o curso de Gest\u00e3o P\u00fablica no Sisu e no Prouni 2022 e tenha uma ideia melhor de qual nota voc\u00ea precisa tirar no ENEM se quiser fazer este curso em uma institui\u00e7\u00e3o p\u00fablica ou privada. ATEN\u00c7\u00c3O:&nbsp;As notas descritas neste artigo s\u00e3o do ano de&nbsp;2020, mas voc\u00ea pode, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12410,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[535],"tags":[779,1479,1347,1205],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>NOTA de Corte para Gest\u00e3o P\u00fablica \u25b7 Sisu\/Prouni 2022<\/title>\n<meta name=\"description\" content=\"Descubra quais s\u00e3o as notas de corte para Gest\u00e3o P\u00fablica no Sisu e Prouni 2022 e saiba qual precisa ser a sua nota no ENEM se quiser fazer este curso!!!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-gestao-publica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NOTA de Corte para Gest\u00e3o P\u00fablica \u25b7 Sisu\/Prouni 2022\" \/>\n<meta property=\"og:description\" content=\"Descubra quais s\u00e3o as notas de corte para Gest\u00e3o P\u00fablica no Sisu e Prouni 2022 e saiba qual precisa ser a sua nota no ENEM se quiser fazer este curso!!!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-gestao-publica\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-02T16:42:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-13T15:16:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/10\/capa_gestao_publica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-gestao-publica\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-gestao-publica\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a\"},\"headline\":\"Nota de Corte para Gest\u00e3o P\u00fablica &#8211; Sisu 2022 e Prouni 2022\",\"datePublished\":\"2019-10-02T16:42:50+00:00\",\"dateModified\":\"2022-04-13T15:16:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-gestao-publica\/\"},\"wordCount\":649,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/beduka.com\/blog\/#organization\"},\"keywords\":[\"nota de corte\",\"nota de corte gestao publica\",\"nota de corte prouni\",\"nota de corte sisu\"],\"articleSection\":[\"Cursos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-gestao-publica\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-gestao-publica\/\",\"url\":\"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-gestao-publica\/\",\"name\":\"NOTA de Corte para Gest\u00e3o P\u00fablica \u25b7 Sisu\/Prouni 2022\",\"isPartOf\":{\"@id\":\"https:\/\/beduka.com\/blog\/#website\"},\"datePublished\":\"2019-10-02T16:42:50+00:00\",\"dateModified\":\"2022-04-13T15:16:33+00:00\",\"description\":\"Descubra quais s\u00e3o as notas de corte para Gest\u00e3o P\u00fablica no Sisu e Prouni 2022 e saiba qual precisa ser a sua nota no ENEM se quiser fazer este curso!!!\",\"breadcrumb\":{\"@id\":\"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-gestao-publica\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-gestao-publica\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-gestao-publica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/beduka.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nota de Corte para Gest\u00e3o P\u00fablica &#8211; Sisu 2022 e Prouni 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/beduka.com\/blog\/#website\",\"url\":\"https:\/\/beduka.com\/blog\/\",\"name\":\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\",\"description\":\"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!\",\"publisher\":{\"@id\":\"https:\/\/beduka.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/beduka.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/beduka.com\/blog\/#organization\",\"name\":\"Beduka\",\"url\":\"https:\/\/beduka.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png\",\"contentUrl\":\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png\",\"width\":1077,\"height\":368,\"caption\":\"Beduka\"},\"image\":{\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/\",\"https:\/\/www.instagram.com\/beduka_oficial\/\",\"https:\/\/www.linkedin.com\/company\/beduka\",\"https:\/\/br.pinterest.com\/bedukaoficial\/\",\"https:\/\/www.youtube.com\/beduka\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a\",\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o Beduka (a)\"},\"description\":\"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.\",\"sameAs\":[\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\",\"https:\/\/www.instagram.com\/beduka_oficial\/\",\"https:\/\/br.pinterest.com\/bedukaoficial\/\"],\"url\":\"https:\/\/beduka.com\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NOTA de Corte para Gest\u00e3o P\u00fablica \u25b7 Sisu\/Prouni 2022","description":"Descubra quais s\u00e3o as notas de corte para Gest\u00e3o P\u00fablica no Sisu e Prouni 2022 e saiba qual precisa ser a sua nota no ENEM se quiser fazer este curso!!!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-gestao-publica\/","og_locale":"pt_BR","og_type":"article","og_title":"NOTA de Corte para Gest\u00e3o P\u00fablica \u25b7 Sisu\/Prouni 2022","og_description":"Descubra quais s\u00e3o as notas de corte para Gest\u00e3o P\u00fablica no Sisu e Prouni 2022 e saiba qual precisa ser a sua nota no ENEM se quiser fazer este curso!!!","og_url":"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-gestao-publica\/","og_site_name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","article_publisher":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","article_author":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades","article_published_time":"2019-10-02T16:42:50+00:00","article_modified_time":"2022-04-13T15:16:33+00:00","og_image":[{"width":600,"height":300,"url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/10\/capa_gestao_publica.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Beduka (a)","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Beduka (a)","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-gestao-publica\/#article","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-gestao-publica\/"},"author":{"name":"Reda\u00e7\u00e3o Beduka (a)","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a"},"headline":"Nota de Corte para Gest\u00e3o P\u00fablica &#8211; Sisu 2022 e Prouni 2022","datePublished":"2019-10-02T16:42:50+00:00","dateModified":"2022-04-13T15:16:33+00:00","mainEntityOfPage":{"@id":"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-gestao-publica\/"},"wordCount":649,"commentCount":0,"publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"keywords":["nota de corte","nota de corte gestao publica","nota de corte prouni","nota de corte sisu"],"articleSection":["Cursos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-gestao-publica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-gestao-publica\/","url":"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-gestao-publica\/","name":"NOTA de Corte para Gest\u00e3o P\u00fablica \u25b7 Sisu\/Prouni 2022","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/#website"},"datePublished":"2019-10-02T16:42:50+00:00","dateModified":"2022-04-13T15:16:33+00:00","description":"Descubra quais s\u00e3o as notas de corte para Gest\u00e3o P\u00fablica no Sisu e Prouni 2022 e saiba qual precisa ser a sua nota no ENEM se quiser fazer este curso!!!","breadcrumb":{"@id":"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-gestao-publica\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-gestao-publica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-gestao-publica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/beduka.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Nota de Corte para Gest\u00e3o P\u00fablica &#8211; Sisu 2022 e Prouni 2022"}]},{"@type":"WebSite","@id":"https:\/\/beduka.com\/blog\/#website","url":"https:\/\/beduka.com\/blog\/","name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","description":"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!","publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beduka.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beduka.com\/blog\/#organization","name":"Beduka","url":"https:\/\/beduka.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","contentUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","width":1077,"height":368,"caption":"Beduka"},"image":{"@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/www.linkedin.com\/company\/beduka","https:\/\/br.pinterest.com\/bedukaoficial\/","https:\/\/www.youtube.com\/beduka"]},{"@type":"Person","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a","name":"Reda\u00e7\u00e3o Beduka (a)","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o Beduka (a)"},"description":"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.","sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/br.pinterest.com\/bedukaoficial\/"],"url":"https:\/\/beduka.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/12409"}],"collection":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/comments?post=12409"}],"version-history":[{"count":8,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/12409\/revisions"}],"predecessor-version":[{"id":25395,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/12409\/revisions\/25395"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media\/12410"}],"wp:attachment":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media?parent=12409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/categories?post=12409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/tags?post=12409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}