{"id":1348,"date":"2018-09-05T20:31:46","date_gmt":"2018-09-05T23:31:46","guid":{"rendered":"https:\/\/beduka.com\/blog\/?p=1348"},"modified":"2019-11-05T15:42:06","modified_gmt":"2019-11-05T18:42:06","slug":"questoes-sobre-origem-vida","status":"publish","type":"post","link":"https:\/\/beduka.com\/blog\/materias\/biologia\/questoes-sobre-origem-vida\/","title":{"rendered":"Quest\u00f5es sobre a origem da vida"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote\"><p><strong><em>A origem da vida \u00e9 um tema bastante recorrente no ENEM e em outros diversos vestibulares. Por esse motivo, preparamos uma lista de quest\u00f5es sobre o tema para que voc\u00ea se prepare da melhor forma!<\/em><\/strong><\/p><\/blockquote>\n\n\n\n<p>Teste hoje os seus conhecimentos com as nossas <span style=\"color: #1c609a;\"><b>quest\u00f5es sobre a origem da vida<\/b><\/span>. Tanto o Exame Nacional do Ensino M\u00e9dio (ENEM) quanto muitos outros vestibulares adoram colocar este tema em suas provas. Afinal de contas, \u00e9 um assunto complexo, curioso e at\u00e9 filos\u00f3fico em alguns momentos.<\/p>\n\n\n\n<p>Estude para o Enem com o <a href=\"https:\/\/beduka.com\/blog\/exercicios\/simulados-para-enem-online-e-gratuito\/\" target=\"_blank\" rel=\"noopener noreferrer\">Simulado Beduka<\/a>. \u00c9 gratuito! Clique no banner abaixo para acess\u00e1-lo.<\/p>\n\n\n\n<p><strong>Estima-se que o planeta Terra tenha surgido por volta de 4,6 bilh\u00f5es de anos atr\u00e1s. <\/strong>Mesmo assim, ainda existem muitos mist\u00e9rios e d\u00favidas sobre o que realmente come\u00e7ou tudo. Alguns pendem para o lado religioso e outros para o lado cient\u00edfico, alguns ainda <strong>unem a ci\u00eancia e a religi\u00e3o<\/strong> para fornecer uma explica\u00e7\u00e3o.<\/p>\n\n\n\n<p>Detalhamos abaixo o resumo de algumas das <a href=\"https:\/\/beduka.com\/blog\/dicas\/teorias-sobre-origem-vida\/\">principais teorias sobre a origem da vida<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color: #1c609a;\"><b>Teoria do Big Bang <\/b><\/span><\/h2>\n\n\n\n<p>Voc\u00ea j\u00e1 deve ter ouvido falar da s\u00e9rie com o mesmo nome, certo? Isso faz todo o sentido porque os personagens dessa s\u00e9rie s\u00e3o cientistas, e <strong>\u00e9 nessa teoria que a ci\u00eancia mais coloca credibilidade. <\/strong>Segundo os estudiosos, todo o cosmos, planetas e estrelas teriam surgido da explos\u00e3o de um ponto denso misterioso, que seria o Big Bang.<\/p>\n\n\n\n<p>Esta teoria foi composta por um padre chamado Lema\u00eetre, que era jesu\u00edta. A verdade \u00e9 que a exegese cat\u00f3lica moderna n\u00e3o v\u00ea problemas de incompatibilidade entre o Big Bang e o relato b\u00edblico.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color: #1c609a;\"><b>Teoria da Evolu\u00e7\u00e3o Qu\u00edmica <\/b><\/span><\/h2>\n\n\n\n<p>Outra teoria cient\u00edfica. Ela diz que <strong>tudo come\u00e7ou atrav\u00e9s da evolu\u00e7\u00e3o de transtornos qu\u00edmicos inorg\u00e2nicos que foram se combinando<\/strong> at\u00e9 formarem mol\u00e9culas org\u00e2nicas simples, que eventualmente deram origem \u00e0 vida.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><b><span style=\"color: #1c609a;\">Teoria do Criacionismo<\/span><\/b><\/h2>\n\n\n\n<p>Essa \u00e9 uma teoria totalmente religiosa. De acordo com ela, <strong>todo o universo e a vida teriam sido criados por Deus. <\/strong>Ainda assim, o criacionismo n\u00e3o limita a pesquisa cient\u00edfica, pois dizer que Deus \u00e9 o criador n\u00e3o impede o trabalho intelectual de se investigar como a cria\u00e7\u00e3o se deu e se desenvolveu ao longo das eras.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color: #1c609a;\"><b>Teoria da Gera\u00e7\u00e3o Espont\u00e2nea (ou Abiog\u00eanese)<\/b><\/span><\/h2>\n\n\n\n<p>Teoria um tanto quanto pol\u00eamica, que basicamente diz que a vida pode surgir a partir de qualquer material org\u00e2nico que estiver nas condi\u00e7\u00f5es apropriadas.<\/p>\n\n\n\n<p>Existem ainda outras teorias, como o <strong>Fixismo <\/strong>(acredita que esp\u00e9cies independentes surgiram no planeta) e a <strong>Panspermia<\/strong> (cr\u00ea que a vida foi trazida para a Terra de outras partes do universo por meio de meteoros).<\/p>\n\n\n\n<p>De qualquer forma, independente de suas cren\u00e7as religiosas, \u00e9 necess\u00e1rio estudar as diversas <span style=\"color: #1c609a;\"><strong><a href=\"https:\/\/beduka.com\/blog\/materias\/biologia\/teorias-sobre-origem-vida\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"teorias sobre a origem da vida (abre numa nova aba)\">teorias sobre a origem da vida<\/a><\/strong><\/span>, j\u00e1 que elas podem aparecer em quest\u00f5es dos diversos vestibulares.<\/p>\n\n\n\n<p>Voc\u00ea pode tamb\u00e9m aprofundar os conhecimentos em:<\/p>\n\n\n\n<ul><li><a href=\"https:\/\/beduka.com\/blog\/enem\/filosofos-mais-caem-enem\/\">Quais s\u00e3o os fil\u00f3sofos que mais caem no ENEM?<\/a><\/li><li><a href=\"https:\/\/beduka.com\/blog\/dicas\/questoes-sobre-idade-media\/\">Quest\u00f5es de vestibular sobre a Idade M\u00e9dia<\/a><\/li><li><a href=\"https:\/\/beduka.com\/blog\/dicas\/principais-caracteristicas-feudalismo\/\">Quais as principais caracter\u00edsticas do feudalismo?<\/a><\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" loading=\"lazy\" width=\"400\" height=\"400\" src=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/03\/principais-teorias-sobre-a-origem-da-vida.jpg\" alt=\"principais teorias sobre a origem da vida\" class=\"wp-image-5304\" srcset=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/03\/principais-teorias-sobre-a-origem-da-vida.jpg 400w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/03\/principais-teorias-sobre-a-origem-da-vida-300x300.jpg 300w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/03\/principais-teorias-sobre-a-origem-da-vida-320x320.jpg 320w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/03\/principais-teorias-sobre-a-origem-da-vida-180x180.jpg 180w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/03\/principais-teorias-sobre-a-origem-da-vida-70x70.jpg 70w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><span style=\"color: #1c609a;\">Veja seis exerc\u00edcios sobre a origem da vida<\/span><\/strong><\/h2>\n\n\n\n<p>Depois de fazer um resumo sobre as principais teorias sobre a origem da vida, \u00e9 hora de validar o seu conhecimento sobre este assunto. Pegue um papel e uma caneta para responder \u00e0s quest\u00f5es sobre a origem da vida. N\u00e3o se esque\u00e7a de comparar as suas respostas com o gabarito no final!<\/p>\n\n\n\n<p><span style=\"color: #1c609a;\"><b>1\u00aa quest\u00e3o sobre a origem da vida &#8211; UNIFAL (2008)<\/b><\/span> &#8211; Do in\u00edcio da vida na Terra, at\u00e9 o aparecimento dos seres vivos atuais, aconteceram v\u00e1rios eventos, como, por exemplo:<\/p>\n\n\n\n<ul><li>I &#8211; forma\u00e7\u00e3o das primeiras c\u00e9lulas;<\/li><li>II &#8211; forma\u00e7\u00e3o de mol\u00e9culas org\u00e2nicas complexas;<\/li><li>III &#8211; aparecimento de organismos capazes de produzir alimentos pela fotoss\u00edntese;<\/li><li>IV &#8211; surgimento dos primeiros organismos aer\u00f3bicos.<\/li><\/ul>\n\n\n\n<p>Marque a alternativa que indica a ordem mais aceita, atualmente, para o acontecimento desses eventos.<\/p>\n\n\n\n<p>a) I &#8211; II &#8211; IV &#8211; III<\/p>\n\n\n\n<p>b) II &#8211; III &#8211; IV &#8211; I<\/p>\n\n\n\n<p>c)  &#8211; IV &#8211; III &#8211; II<\/p>\n\n\n\n<p>d) II &#8211; I &#8211; III &#8211; IV<\/p>\n\n\n\n<p><span style=\"color: #1c609a;\"><b>2\u00aa quest\u00e3o sobre a origem da vida &#8211; UFC (2009)<\/b><\/span> &#8211; A defini\u00e7\u00e3o de vida \u00e9 motivo de muitos debates. Segundo a biologia, o in\u00edcio da vida na Terra deu-se com:<\/p>\n\n\n\n<p>a) O &#8220;Big Bang&#8221;, que deu origem ao universo e, consequentemente, \u00e0 vida<\/p>\n\n\n\n<p>b) O aumento dos n\u00edveis de O\u201a atmosf\u00e9rico, que permitiu a prolifera\u00e7\u00e3o dos seres aer\u00f3bios<\/p>\n\n\n\n<p>c) O surgimento dos coacervados, os quais, em solu\u00e7\u00f5es aquosas, s\u00e3o capazes de criar uma membrana, isolando a mat\u00e9ria org\u00e2nica do meio externo<\/p>\n\n\n\n<p>d) O surgimento de uma bicamada fosfolip\u00eddica, que envolveu mol\u00e9culas com capacidade de autoduplica\u00e7\u00e3o e metabolismo<\/p>\n\n\n\n<p>e) O resfriamento da atmosfera, que propiciou uma condi\u00e7\u00e3o favor\u00e1vel para a origem de mol\u00e9culas precursoras de vida<\/p>\n\n\n\n<p><span style=\"color: #1c609a;\"><b>3\u00aa quest\u00e3o sobre a origem da vida<\/b><strong> &#8211; UFCSPA (2009)<\/strong><\/span> &#8211; Assinale a alternativa INCORRETA:<\/p>\n\n\n\n<p>a) \u00d3rg\u00e3os de diferentes evolutivas e que apresentam mesma fun\u00e7\u00e3o s\u00e3o chamados de an\u00e1logos<\/p>\n\n\n\n<p>b) S\u00e3o evid\u00eancias da evolu\u00e7\u00e3o das esp\u00e9cies a anatomia, a embriologia e a bioqu\u00edmica comparadas, bem como o estudo dos f\u00f3sseis<\/p>\n\n\n\n<p>c) \u00d3rg\u00e3os de mesma origem evolutiva, embora possam apresentar fun\u00e7\u00f5es diferentes, s\u00e3o chamados de hom\u00f3logos<\/p>\n\n\n\n<p>d) Algumas das ideias de Alexander Oparin acerca da origem da vida foram comprovadas experimentalmente por Stanley Miller e Sidney Fox<\/p>\n\n\n\n<p>e) Um dos experimentos de Louis Pasteur corroborou a teoria da gera\u00e7\u00e3o espont\u00e2nea<\/p>\n\n\n\n<p><span style=\"color: #1c609a;\"><b>4\u00aa quest\u00e3o sobre a origem da vida <\/b><strong>&#8211; UEL (2007) <\/strong><\/span>&#8211; Charles Darwin, al\u00e9m de postular que os organismos vivos evolu\u00edam pela a\u00e7\u00e3o da sele\u00e7\u00e3o natural, tamb\u00e9m considerou a possibilidade de as primeiras formas de vida terem surgido em algum lago t\u00e9pido do nosso planeta. Entretanto, existem outras teorias que tentam explicar como e onde a vida surgiu. Uma delas, a panspermia, sustenta que:<\/p>\n\n\n\n<p>a) As primeiras formas de vida podem ter surgido nas regi\u00f5es mais in\u00f3spitas da Terra, como as fontes hidrotermais do fundo dos oceanos<\/p>\n\n\n\n<p>b) Compostos org\u00e2nicos simples, como os amino\u00e1cidos, podem ter sido produzidos de maneira abi\u00f3tica em v\u00e1rios pontos do planeta Terra<\/p>\n\n\n\n<p>c) Bact\u00e9rias ancestrais podem ter surgido por toda a Terra, em fun\u00e7\u00e3o dos requisitos m\u00ednimos necess\u00e1rios para a sua forma\u00e7\u00e3o e subsist\u00eancia<\/p>\n\n\n\n<p>d) A capacidade de replica\u00e7\u00e3o das primeiras mol\u00e9culas org\u00e2nicas foi o que permitiu que elas se difundissem pelos oceanos primitivos da Terra<\/p>\n\n\n\n<p>e) A vida se originou fora do planeta Terra, tendo sido trazida por meteoritos, cometas ou ent\u00e3o pela poeira espacial<\/p>\n\n\n\n<p><strong>5\u00aa quest\u00e3o sobre a origem da vida &#8211; Unicentro &#8211;<\/strong> S\u00e3o muitas as discuss\u00f5es sobre a origem da  vida no planeta Terra. Os estudos sobre o assunto evidenciam a  import\u00e2ncia dos avan\u00e7os tecnol\u00f3gicos e das pesquisas para o  aprimoramento das hip\u00f3teses sobre a origem da vida. Por\u00e9m, ap\u00f3s alguns  s\u00e9culos de estudos, apesar de consider\u00e1veis avan\u00e7os, ainda existem  muitas perguntas sem respostas. Sobre as principais teorias da origem da  vida, pode-se afirmar:<\/p>\n\n\n\n<p>a) Haldane e Oparin admitiam que mol\u00e9culas\n inorg\u00e2nicas, encontradas na atmosfera primitiva, se combinariam \noriginando mol\u00e9culas org\u00e2nicas simples, que, posteriormente, adquiriram a\n capacidade de autoduplica\u00e7\u00e3o e metabolismo.<\/p>\n\n\n\n<p>b) A teoria da abiog\u00eanese foi confirmada \ncom as pesquisas realizadas por Pasteur, em que micro-organismos foram \nencontrados em frascos com \u201cpesco\u00e7o de cisne\u201d, ap\u00f3s o processo de \nfervura.<\/p>\n\n\n\n<p>c) Os avan\u00e7os tecnol\u00f3gicos e as pesquisas \natuais permitiram definir a descoberta da vida como sendo atrav\u00e9s da \nevolu\u00e7\u00e3o de componentes inorg\u00e2nicos originados no pr\u00f3prio planeta Terra.<\/p>\n\n\n\n<p>d) Segundo a panspermia, os primeiros seres vivos teriam vindo do cosmos e seriam pluricelulares e aut\u00f3trofos.<\/p>\n\n\n\n<p>e) As pesquisas realizadas puderam  comprovar a hip\u00f3tese autotr\u00f3fica, pois n\u00e3o existiam nutrientes  suficientes na Terra primitiva para suprir os seres vivos.<\/p>\n\n\n\n<p> <strong>6\u00aa quest\u00e3o sobre a origem da vida &#8211; (UCPel) &#8211;<\/strong> O aglomerado de mol\u00e9culas org\u00e2nicas, \nrevestido por uma pel\u00edcula de mol\u00e9culas de \u00e1gua e que, na opini\u00e3o de \nalguns cientistas, pode ser um dos primeiros passos rumo \u00e0 origem da \nvida, chama-se:<\/p>\n\n\n\n<p>a) Amino\u00e1cido.<\/p>\n\n\n\n<p>b) Coacervado.<\/p>\n\n\n\n<p>c) Micro-organismo.<\/p>\n\n\n\n<p>d) Enzima.<\/p>\n\n\n\n<p>d) Prote\u00edna.<\/p>\n\n\n\n<p>Agora que voc\u00ea j\u00e1 testou os seus conhecimentos com as quest\u00f5es sobre a origem da vida, que tal avaliar os resultados? <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Gabarito dos exerc\u00edcios sobre origem da vida:<\/h2>\n\n\n\n<p><strong>Exerc\u00edcio resolvido da quest\u00e3o 1:<\/strong> d) II &#8211; I &#8211; III &#8211; IV<\/p>\n\n\n\n<p><strong>Exerc\u00edcio resolvido da quest\u00e3o 2:<\/strong> d) O surgimento de uma bicamada fosfolip\u00eddica, que envolveu mol\u00e9culas com capacidade de autoduplica\u00e7\u00e3o e metabolismo<\/p>\n\n\n\n<p><strong>Exerc\u00edcio resolvido da quest\u00e3o 3:<\/strong> e) Um dos experimentos de Louis Pasteur corroborou a teoria da gera\u00e7\u00e3o espont\u00e2nea<\/p>\n\n\n\n<p><strong>Exerc\u00edcio resolvido da quest\u00e3o 4:<\/strong> e) A vida se originou fora do planeta Terra, tendo sido trazida por meteoritos, cometas ou ent\u00e3o pela poeira espacial<\/p>\n\n\n\n<p><strong>Exerc\u00edcio resolvido da quest\u00e3o 5:<\/strong> a) Haldane e Oparin admitiam que mol\u00e9culas  inorg\u00e2nicas, encontradas na  atmosfera primitiva, se combinariam  originando mol\u00e9culas org\u00e2nicas  simples, que, posteriormente, adquiriram a  capacidade de autoduplica\u00e7\u00e3o  e metabolismo. <\/p>\n\n\n\n<p><strong>Exerc\u00edcio resolvido da quest\u00e3o 6: <\/strong>b) Coacervado<\/p>\n\n\n\n<p>Durante os seus <a href=\"https:\/\/beduka.com\/blog\/dicas\/como-estudar-para-vestibular\/\">estudos para tirar uma boa nota no vestibular<\/a>, todas as mat\u00e9rias merecem dedica\u00e7\u00e3o especial. J\u00e1 destacamos aqui no Beduka <a href=\"https:\/\/beduka.com\/blog\/dicas\/como-fazer-redacao-nota-1000\/\">como fazer uma reda\u00e7\u00e3o nota 1000<\/a> e tamb\u00e9m <a href=\"https:\/\/beduka.com\/blog\/dicas\/como-estudar-ingles-com-musica\/\">como aprender ingl\u00eas com m\u00fasica<\/a>.<\/p>\n\n\n\n<p><span style=\"color: #1c609a;\"><strong>Estas quest\u00f5es sobre a origem da vida foram simples ou dif\u00edceis<\/strong><\/span>? Deixe seu coment\u00e1rio no final deste texto. Se preferir, fa\u00e7a os outros testes que preparamos:<\/p>\n\n\n\n<ul><li><a href=\"https:\/\/beduka.com\/blog\/dicas\/questoes-vestibular-sobre-platao\/\">Quest\u00f5es de vestibular sobre Plat\u00e3o<\/a><\/li><li><a href=\"https:\/\/beduka.com\/blog\/dicas\/questoes-sobre-semana-arte-moderna\/\">Quest\u00f5es sobre a Semana de 22<\/a><\/li><li><a href=\"https:\/\/beduka.com\/blog\/dicas\/questoes-vestibular-vanguardas-europeias\/\">Quest\u00f5es sobre vanguardas europeias<\/a><\/li><\/ul>\n\n\n\n<p>N\u00f3s aqui no <a href=\"https:\/\/beduka.com\">Beduka, <\/a>o buscador de faculdades e cursos, estamos preocupados com a sua capacita\u00e7\u00e3o para <a href=\"https:\/\/beduka.com\/blog\/profissoes\/como-descobrir-minha-vocacao\/\">descobrir a sua voca\u00e7\u00e3o<\/a> e para decidir a <a href=\"https:\/\/beduka.com\/blog\/profissoes\/como-escolher-profissao-certa\/\">profiss\u00e3o certa a seguir<\/a>.<\/p>\n\n\n\n<p>Temos uma s\u00e9rie de conte\u00fados que v\u00e3o te ajudar a saber <a href=\"https:\/\/beduka.com\/blog\/dicas\/palavras-enriquecem-redacao-dissertativa-argumentativa\/\">quais palavras usar para enriquecer sua reda\u00e7\u00e3o<\/a>, saber quais as <a href=\"https:\/\/beduka.com\/blog\/profissoes\/profissoes-mais-valorizadas-mercado-trabalho\/\">profiss\u00f5es mais valorizadas do mercado de trabalho<\/a> e <a href=\"https:\/\/beduka.com\/blog\/dicas\/como-estudar-interpretacao-texto\/\">como estudar interpreta\u00e7\u00e3o de texto<\/a>.<\/p>\n\n\n\n<p>Al\u00e9m das j\u00e1 citadas quest\u00f5es sobre a origem da vida, veja tamb\u00e9m:<\/p>\n\n\n\n<ul><li><a href=\"https:\/\/beduka.com\/blog\/enem\/temas-redacao-que-cairam-enem\/\">Quais os temas de reda\u00e7\u00e3o que j\u00e1 ca\u00edram no ENEM?<\/a><\/li><li><a href=\"https:\/\/beduka.com\/blog\/dicas\/principais-ideias-emile-durkheim\/\">Quais s\u00e3o as principais ideias de \u00c9mile Durkheim?<\/a><\/li><li><a href=\"https:\/\/beduka.com\/blog\/dicas\/como-prova-fuvest\/\">Como \u00e9 a prova da FUVEST?<\/a><\/li><\/ul>\n\n\n\n<p>Beduka tamb\u00e9m est\u00e1 no<a href=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/\" target=\"_blank\" rel=\"noopener noreferrer\"> Facebook<\/a>. Curta nossa p\u00e1gina e receba as atualiza\u00e7\u00f5es.<\/p>\n\n\n\n<p>Baixe o melhor <a rel=\"noopener noreferrer\" href=\"https:\/\/beduka.com\/blog\/enem\/plano-de-estudos-gratuito\/\" target=\"_blank\">plano de estudos gratuito<\/a> que voc\u00ea encontrar\u00e1 na internet.<\/p>\n\n\n\n<p>Queremos te ajudar a encontrar a <strong>FACULDADE IDEAL<\/strong>! Logo abaixo, fa\u00e7a uma pesquisa por curso e cidade que te mostraremos todas as faculdades que podem te atender. <strong>Informamos a nota de corte, valor de mensalidade, nota do MEC, avalia\u00e7\u00e3o dos alunos, modalidades de ensino e muito mais.<\/strong><\/p>\n\n\n\n<p>Experimente agora!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A origem da vida \u00e9 um tema bastante recorrente no ENEM e em outros diversos vestibulares. Por esse motivo, preparamos uma lista de quest\u00f5es sobre o tema para que voc\u00ea se prepare da melhor forma! Teste hoje os seus conhecimentos com as nossas quest\u00f5es sobre a origem da vida. Tanto o Exame Nacional do Ensino [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1350,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[495],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u25b7EXERC\u00cdCIOS sobre a Origem da Vida com GABARITO! Principais teorias<\/title>\n<meta name=\"description\" content=\"Voc\u00ea conhece a Teoria da Evolu\u00e7\u00e3o Qu\u00edmica? E o Big Bang? Criacionismo? Abiog\u00eanese? Selecionamos quest\u00f5es de vestibulares sobre a origem da vida. Confira!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beduka.com\/blog\/materias\/biologia\/questoes-sobre-origem-vida\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u25b7EXERC\u00cdCIOS sobre a Origem da Vida com GABARITO! Principais teorias\" \/>\n<meta property=\"og:description\" content=\"Voc\u00ea conhece a Teoria da Evolu\u00e7\u00e3o Qu\u00edmica? E o Big Bang? Criacionismo? Abiog\u00eanese? Selecionamos quest\u00f5es de vestibulares sobre a origem da vida. Confira!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beduka.com\/blog\/materias\/biologia\/questoes-sobre-origem-vida\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-05T23:31:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-05T18:42:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2018\/09\/questoes-sobre-origem-vida1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/beduka.com\/blog\/materias\/biologia\/questoes-sobre-origem-vida\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/beduka.com\/blog\/materias\/biologia\/questoes-sobre-origem-vida\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a\"},\"headline\":\"Quest\u00f5es sobre a origem da vida\",\"datePublished\":\"2018-09-05T23:31:46+00:00\",\"dateModified\":\"2019-11-05T18:42:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/beduka.com\/blog\/materias\/biologia\/questoes-sobre-origem-vida\/\"},\"wordCount\":1865,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\/\/beduka.com\/blog\/#organization\"},\"articleSection\":[\"Biologia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/beduka.com\/blog\/materias\/biologia\/questoes-sobre-origem-vida\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/beduka.com\/blog\/materias\/biologia\/questoes-sobre-origem-vida\/\",\"url\":\"https:\/\/beduka.com\/blog\/materias\/biologia\/questoes-sobre-origem-vida\/\",\"name\":\"\u25b7EXERC\u00cdCIOS sobre a Origem da Vida com GABARITO! Principais teorias\",\"isPartOf\":{\"@id\":\"https:\/\/beduka.com\/blog\/#website\"},\"datePublished\":\"2018-09-05T23:31:46+00:00\",\"dateModified\":\"2019-11-05T18:42:06+00:00\",\"description\":\"Voc\u00ea conhece a Teoria da Evolu\u00e7\u00e3o Qu\u00edmica? E o Big Bang? Criacionismo? Abiog\u00eanese? Selecionamos quest\u00f5es de vestibulares sobre a origem da vida. Confira!\",\"breadcrumb\":{\"@id\":\"https:\/\/beduka.com\/blog\/materias\/biologia\/questoes-sobre-origem-vida\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/beduka.com\/blog\/materias\/biologia\/questoes-sobre-origem-vida\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/beduka.com\/blog\/materias\/biologia\/questoes-sobre-origem-vida\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/beduka.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quest\u00f5es sobre a origem da vida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/beduka.com\/blog\/#website\",\"url\":\"https:\/\/beduka.com\/blog\/\",\"name\":\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\",\"description\":\"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!\",\"publisher\":{\"@id\":\"https:\/\/beduka.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/beduka.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/beduka.com\/blog\/#organization\",\"name\":\"Beduka\",\"url\":\"https:\/\/beduka.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png\",\"contentUrl\":\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png\",\"width\":1077,\"height\":368,\"caption\":\"Beduka\"},\"image\":{\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/\",\"https:\/\/www.instagram.com\/beduka_oficial\/\",\"https:\/\/www.linkedin.com\/company\/beduka\",\"https:\/\/br.pinterest.com\/bedukaoficial\/\",\"https:\/\/www.youtube.com\/beduka\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a\",\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o Beduka (a)\"},\"description\":\"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.\",\"sameAs\":[\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\",\"https:\/\/www.instagram.com\/beduka_oficial\/\",\"https:\/\/br.pinterest.com\/bedukaoficial\/\"],\"url\":\"https:\/\/beduka.com\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u25b7EXERC\u00cdCIOS sobre a Origem da Vida com GABARITO! Principais teorias","description":"Voc\u00ea conhece a Teoria da Evolu\u00e7\u00e3o Qu\u00edmica? E o Big Bang? Criacionismo? Abiog\u00eanese? Selecionamos quest\u00f5es de vestibulares sobre a origem da vida. Confira!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beduka.com\/blog\/materias\/biologia\/questoes-sobre-origem-vida\/","og_locale":"pt_BR","og_type":"article","og_title":"\u25b7EXERC\u00cdCIOS sobre a Origem da Vida com GABARITO! Principais teorias","og_description":"Voc\u00ea conhece a Teoria da Evolu\u00e7\u00e3o Qu\u00edmica? E o Big Bang? Criacionismo? Abiog\u00eanese? Selecionamos quest\u00f5es de vestibulares sobre a origem da vida. Confira!","og_url":"https:\/\/beduka.com\/blog\/materias\/biologia\/questoes-sobre-origem-vida\/","og_site_name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","article_publisher":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","article_author":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades","article_published_time":"2018-09-05T23:31:46+00:00","article_modified_time":"2019-11-05T18:42:06+00:00","og_image":[{"width":600,"height":300,"url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2018\/09\/questoes-sobre-origem-vida1.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Beduka (a)","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Beduka (a)","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beduka.com\/blog\/materias\/biologia\/questoes-sobre-origem-vida\/#article","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/materias\/biologia\/questoes-sobre-origem-vida\/"},"author":{"name":"Reda\u00e7\u00e3o Beduka (a)","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a"},"headline":"Quest\u00f5es sobre a origem da vida","datePublished":"2018-09-05T23:31:46+00:00","dateModified":"2019-11-05T18:42:06+00:00","mainEntityOfPage":{"@id":"https:\/\/beduka.com\/blog\/materias\/biologia\/questoes-sobre-origem-vida\/"},"wordCount":1865,"commentCount":4,"publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"articleSection":["Biologia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/beduka.com\/blog\/materias\/biologia\/questoes-sobre-origem-vida\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/beduka.com\/blog\/materias\/biologia\/questoes-sobre-origem-vida\/","url":"https:\/\/beduka.com\/blog\/materias\/biologia\/questoes-sobre-origem-vida\/","name":"\u25b7EXERC\u00cdCIOS sobre a Origem da Vida com GABARITO! Principais teorias","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/#website"},"datePublished":"2018-09-05T23:31:46+00:00","dateModified":"2019-11-05T18:42:06+00:00","description":"Voc\u00ea conhece a Teoria da Evolu\u00e7\u00e3o Qu\u00edmica? E o Big Bang? Criacionismo? Abiog\u00eanese? Selecionamos quest\u00f5es de vestibulares sobre a origem da vida. Confira!","breadcrumb":{"@id":"https:\/\/beduka.com\/blog\/materias\/biologia\/questoes-sobre-origem-vida\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beduka.com\/blog\/materias\/biologia\/questoes-sobre-origem-vida\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/beduka.com\/blog\/materias\/biologia\/questoes-sobre-origem-vida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/beduka.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Quest\u00f5es sobre a origem da vida"}]},{"@type":"WebSite","@id":"https:\/\/beduka.com\/blog\/#website","url":"https:\/\/beduka.com\/blog\/","name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","description":"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!","publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beduka.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beduka.com\/blog\/#organization","name":"Beduka","url":"https:\/\/beduka.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","contentUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","width":1077,"height":368,"caption":"Beduka"},"image":{"@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/www.linkedin.com\/company\/beduka","https:\/\/br.pinterest.com\/bedukaoficial\/","https:\/\/www.youtube.com\/beduka"]},{"@type":"Person","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a","name":"Reda\u00e7\u00e3o Beduka (a)","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o Beduka (a)"},"description":"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.","sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/br.pinterest.com\/bedukaoficial\/"],"url":"https:\/\/beduka.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/1348"}],"collection":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/comments?post=1348"}],"version-history":[{"count":10,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/1348\/revisions"}],"predecessor-version":[{"id":9148,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/1348\/revisions\/9148"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media\/1350"}],"wp:attachment":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media?parent=1348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/categories?post=1348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/tags?post=1348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}