{"id":15072,"date":"2020-03-06T14:34:32","date_gmt":"2020-03-06T17:34:32","guid":{"rendered":"https:\/\/beduka.com\/blog\/?p=15072"},"modified":"2024-08-22T12:52:45","modified_gmt":"2024-08-22T15:52:45","slug":"prova-do-ita","status":"publish","type":"post","link":"https:\/\/beduka.com\/blog\/dicas\/vestibulares\/prova-do-ita\/","title":{"rendered":"Tudo sobre a prova do ITA 2025: Veja como ela funciona, quais s\u00e3o os conte\u00fados e dicas imperd\u00edveis!"},"content":{"rendered":"\n<p><strong>A prova do ITA &#8211; Instituto Tecnol\u00f3gico da Aeron\u00e1utica &#8211; \u00e9 um dos vestibulares mais concorridos do pa\u00eds! <\/strong>Al\u00e9m de ser a gradua\u00e7\u00e3o dos sonhos de todo amante de exatas, por ser uma institui\u00e7\u00e3o militar, possui uma s\u00e9rie de especificidades.<\/p>\n\n\n\n<p>Entre elas est\u00e3o a <strong>idade limite para ingresso no Instituto e as fases espec\u00edficas<\/strong> para conquistar a vaga, que envolvem muitas etapas e v\u00e1rios tipos de exames.<\/p>\n\n\n\n<p>Por isso, \u00e9 preciso ter todas as informa\u00e7\u00f5es principais, que v\u00e3o te ajudar a evitar ficar de fora. Fique atento nessa mat\u00e9ria que preparamos com todas as informa\u00e7\u00f5es pra voc\u00ea!<\/p>\n\n\n\n<p>Neste artigo voc\u00ea encontrar\u00e1:<\/p>\n\n\n\n<ul>\n<li><a href=\"#gerais\">Aspectos gerais da prova do ITA: cursos oferecidos, taxa de inscri\u00e7\u00e3o e cidades de aplica\u00e7\u00e3o<\/a><\/li>\n\n\n\n<li><a href=\"#fases\">Fases da prova e suas mat\u00e9rias: quantidade e tipo de quest\u00f5es + provas anteriores<\/a><\/li>\n\n\n\n<li><a href=\"#nota\">Composi\u00e7\u00e3o da nota<\/a><\/li>\n\n\n\n<li><a href=\"#peculiaridades\">Peculiaridades e site oficial<\/a><\/li>\n\n\n\n<li><a href=\"#calend\u00e1rio\">Calend\u00e1rio da Prova do ITA<\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"gerais\">Aspectos gerais da prova do ITA<\/h2>\n\n\n\n<p>Por se tratar de uma institui\u00e7\u00e3o governamental militar de grande prest\u00edgio, o ITA se tornou destaque nos <strong>cursos de exatas, especificamente <a aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/?s=engenharia\" target=\"_blank\" rel=\"noreferrer noopener\">engenharia<\/a>.<\/strong> Muito concorrido, <strong>a \u00fanica forma de ingressar \u00e9 o vestibular pr\u00f3prio <\/strong>&#8211; n\u00e3o h\u00e1 possibilidade de transfer\u00eancia ou ingresso por <a aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/sisu\/\" target=\"_blank\" rel=\"noreferrer noopener\">Sisu<\/a>.<\/p>\n\n\n\n<p>Nele,<strong> h\u00e1 vagas tanto para os que aspiram seguir a carreira militar quanto para civis <\/strong>que queiram ter um ensino superior de ponta. Al\u00e9m disso, \u00e9 preciso pagar uma <strong>taxa de R$ 195,00.<\/strong> Os candidatos que n\u00e3o possu\u00edrem condi\u00e7\u00f5es de arcar com o valor podem solicitar isen\u00e7\u00e3o do pagamento, na hora de se inscrever no site oficial.<\/p>\n\n\n\n<p>Este vestibular <strong>\u00e9 realizado em cidades espec\u00edficas e n\u00e3o h\u00e1 formas de faz\u00ea-lo \u00e0 dist\u00e2ncia. <\/strong>Observe quais s\u00e3o as cidades sede.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Cidades para realiza\u00e7\u00e3o da prova do ITA<\/h3>\n\n\n\n<p>Bel\u00e9m, Natal, Belo Horizonte, Porto Alegre, Bras\u00edlia, Recife, Campinas, Ribeir\u00e3o Preto, Campo Grande, Rio de Janeiro, Cuiab\u00e1, S\u00e3o Jos\u00e9 dos Campos, Curitiba, S\u00e3o Jos\u00e9 do Rio Preto, Fortaleza, Salvador, Goi\u00e2nia, S\u00e3o Lu\u00eds, Juiz de Fora, S\u00e3o Paulo, Londrina, Teresina, Manaus e Vit\u00f3ria.\u00a0<\/p>\n\n\n\n<p>Dessa forma, a institui\u00e7\u00e3o oferece <strong>cursos de gradua\u00e7\u00e3o e vagas separadas<\/strong>. H\u00e1 140 vagas para civis e 40 vagas para optantes de carreira militar nos cursos de:<\/p>\n\n\n\n<ul>\n<li>Engenharia Aeron\u00e1utica<\/li>\n\n\n\n<li>Engenharia Eletr\u00f4nica<\/li>\n\n\n\n<li>Engenharia Mec\u00e2nica-Aeron\u00e1utica:<\/li>\n\n\n\n<li>Engenharia Civil-Aeron\u00e1utica<\/li>\n\n\n\n<li>Engenharia de Computa\u00e7\u00e3o<\/li>\n\n\n\n<li>Engenharia Aeroespacial<\/li>\n<\/ul>\n\n\n\n<p><strong>Contudo, a separa\u00e7\u00e3o entre optantes e n\u00e3o-optantes da carreira militar s\u00f3 ocorre a partir do segundo ano.<\/strong> E os que quiserem ser engenheiros militares, mas n\u00e3o obtiveram resultados suficientes, ser\u00e3o qualificados para a carreira civil.<\/p>\n\n\n\n<p><strong>Todos os cursos t\u00eam dura\u00e7\u00e3o de cinco anos:<\/strong> nos dois primeiros os estudantes cursam mat\u00e9rias fundamentais comuns e depois se agregam as especialidades.&nbsp;<\/p>\n\n\n\n<ul>\n<li>Confira tamb\u00e9m nosso artigo sobre a prova da <strong>Fuvest:<\/strong> <a aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/dicas\/vestibulares\/vestibular-fuvest\/\" target=\"_blank\" rel=\"noreferrer noopener\">como \u00e9<\/a> e principais<a aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/dicas\/vestibulares\/assuntos-que-mais-caem-na-fuvest\/\" target=\"_blank\" rel=\"noreferrer noopener\"> mat\u00e9rias<\/a>.<\/li>\n\n\n\n<li>Saiba tudo sobre a prova da <a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/dicas\/vestibulares\/prova-da-unicamp\/\" target=\"_blank\">Unicamp<\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"fases\">Fases da prova do ITA e suas mat\u00e9rias<\/h2>\n\n\n\n<p><strong>O conte\u00fado program\u00e1tico da prova do ITA \u00e9 bem enxuto<\/strong>. Contudo, <strong>as quest\u00f5es s\u00e3o extremamente elaboradas e densas. <\/strong>\u00c9 preciso dominar a mat\u00e9ria em todos os aspectos para poder resolv\u00ea-las com perfei\u00e7\u00e3o.<\/p>\n\n\n\n<p>Al\u00e9m disso, antes havia uma lista de livros obrigat\u00f3rios, mas a partir da edi\u00e7\u00e3o que d\u00e1 vagas para 2025 <strong>exige-se apenas que os participantes tenham contato com obras liter\u00e1rias de momentos diferentes da hist\u00f3ri<\/strong>a<strong>.<\/strong> Portanto, leia diversos livros da literatura nacional.<\/p>\n\n\n\n<p>Nossas recomenda\u00e7\u00f5es s\u00e3o de livros que j\u00e1 foram cobrados pelo exame anteriormente, como:<\/p>\n\n\n\n<ul>\n<li><a href=\"https:\/\/beduka.com\/blog\/materias\/literatura\/resumo-do-livro-senhora-de-jose-de-alencar\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">Senhora<\/a>, de Jos\u00e9 de Alencar<\/li>\n\n\n\n<li>Quincas Borba, de<a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-machado-de-assis\/\" target=\"_blank\"> Machado de Assis<\/a><\/li>\n\n\n\n<li>S\u00e3o Bernardo, de<a href=\"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-graciliano-ramos\/\" target=\"_blank\" rel=\"noreferrer noopener\"> Graciliano Ramos<\/a><\/li>\n<\/ul>\n\n\n\n<p><strong>Tamb\u00e9m j\u00e1 separamos os conte\u00fados que tiveram mais frequ\u00eancia nas edi\u00e7\u00f5es passadas. <a href=\"https:\/\/beduka.com\/blog\/dicas\/faculdades\/o-que-estudar-para-o-ita\/\" target=\"_blank\" rel=\"noreferrer noopener\">Acesse e saiba o que estudar para o vestibular do ITA 2025<\/a>.<\/strong><\/p>\n\n\n\n<p>Visto que \u00e9 uma prova bem espec\u00edfica e com n\u00edveis diferenciados, \u00e9 necess\u00e1rio refazer o m\u00e1ximo das provas anteriores para entender bem o estilo cobrado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Primeira fase<\/h3>\n\n\n\n<p><strong>Quantidade de quest\u00f5es:<\/strong> 48 quest\u00f5es, sendo 12 por mat\u00e9ria<\/p>\n\n\n\n<p><strong>Tipo de quest\u00e3o:<\/strong> Objetivas (fechada)<\/p>\n\n\n\n<p><strong>Dura\u00e7\u00e3o:<\/strong> 4 horas<\/p>\n\n\n\n<p><strong>Hor\u00e1rio<\/strong>: de 8h \u00e0s 12h<\/p>\n\n\n\n<p><strong>Mat\u00e9rias cobradas:<\/strong> Ingl\u00eas, Matem\u00e1tica, Qu\u00edmica e F\u00edsica<\/p>\n\n\n\n<p><strong>Observa\u00e7\u00e3o:<\/strong> \u00e9 realizada em apenas 1 dia<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Segunda fase<\/h3>\n\n\n\n<p><strong>Quantidade de quest\u00f5es:<\/strong> 10 quest\u00f5es por mat\u00e9ria (exceto Portugu\u00eas, que s\u00e3o 15) e reda\u00e7\u00e3o de g\u00eanero dissertativo-argumentativo, com m\u00ednimo de 15 linhas<\/p>\n\n\n\n<p><strong>Tipo de quest\u00e3o:<\/strong> Dissertativa (aberta)<\/p>\n\n\n\n<p><strong>Dura\u00e7\u00e3o:<\/strong> 4 horas por dia<\/p>\n\n\n\n<p><strong>Hor\u00e1rio<\/strong>: de 8h \u00e0s 12h<\/p>\n\n\n\n<p><strong>Mat\u00e9rias cobradas:<\/strong> Portugu\u00eas, Matem\u00e1tica, Qu\u00edmica e F\u00edsica<\/p>\n\n\n\n<p><strong>Observa\u00e7\u00e3o:<\/strong> \u00e9 realizada em 4 dias<\/p>\n\n\n\n<ul>\n<li>Fa\u00e7a nosso<strong> <a href=\"https:\/\/beduka.com\/simulado-enem\/#\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">simulado<\/a> totalmente gratuito e online<\/strong>, que pode ser<strong> personalizado<\/strong> de acordo com as mat\u00e9rias que voc\u00ea mais precisa!<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"nota\">Composi\u00e7\u00e3o da nota da prova do ITA<\/h2>\n\n\n\n<p>Para que as quest\u00f5es dissertativas e reda\u00e7\u00e3o sejam corrigidas, \u00e9 preciso pontuar, numa escala de 0 a 10:<\/p>\n\n\n\n<ul>\n<li>Nota igual ou superior a 5 em todas as mat\u00e9rias;<\/li>\n\n\n\n<li>M\u00e9dia geral superior a 5;<\/li>\n\n\n\n<li>N\u00e3o zerar a reda\u00e7\u00e3o.<\/li>\n\n\n\n<li>Estar entre os 560 candidatos com maior nota na ampla concorr\u00eancia, ou<\/li>\n\n\n\n<li>Entre os 140 cotistas.<\/li>\n<\/ul>\n\n\n\n<p>J\u00e1 a m\u00e9dia geral do vestibular do ITA \u00e9 composta por:<\/p>\n\n\n\n<ul>\n<li>20% pela nota da primeira fase;<\/li>\n\n\n\n<li>20% pela nota da segunda fase de qu\u00edmica;<\/li>\n\n\n\n<li>20% pela nota da segunda fase de matem\u00e1tica;<\/li>\n\n\n\n<li>20% pela nota da segunda fase de f\u00edsica;<\/li>\n\n\n\n<li>20% pela nota da reda\u00e7\u00e3o&nbsp;<\/li>\n<\/ul>\n\n\n\n<p><strong>A nota de corte varia a cada vestibular. <\/strong>Contudo, na sele\u00e7\u00e3o de 2024, era preciso tirar <strong>acima de 6<\/strong> (entre os optantes da carreira militar) e <strong>acima de 6,8<\/strong> (entre os n\u00e3o optantes) na primeira fase para poder prosseguir.<\/p>\n\n\n\n<ul>\n<li>D\u00favidas sobre a prova da Unesp? <a aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/dicas\/vestibulares\/prova-da-unesp\/\" target=\"_blank\" rel=\"noreferrer noopener\">Confira aqui <\/a>o guia completo sobre a prova!<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"peculiaridades\">Regras para a prova do ITA &#8211; Peculiaridades e site oficial<\/h2>\n\n\n\n<p>Por se tratar de uma institui\u00e7\u00e3o militar, h\u00e1 <strong>uma s\u00e9rie de exig\u00eancias pouco comuns<\/strong> em rela\u00e7\u00e3o aos demais vestibulares. N\u00f3s do Beduka, fizemos esta lista para voc\u00ea ficar por dentro de todos os detalhes:<\/p>\n\n\n\n<ul>\n<li>Uma das condi\u00e7\u00f5es para acessar o local de provas \u00e9 estar com<strong> \u201ctrajes adequados\u201d<\/strong><\/li>\n<\/ul>\n\n\n\n<ul>\n<li>Passando pelas duas etapas, os aprovados v\u00e3o para a terceira fase, que se constitui de uma <strong>Inspe\u00e7\u00e3o de Sa\u00fade<\/strong>, realizada pelo <strong>Esquadr\u00e3o de Sa\u00fade de S\u00e3o Jos\u00e9 dos Campos- SP<\/strong><\/li>\n<\/ul>\n\n\n\n<ul>\n<li><strong>O cabelo n\u00e3o pode cobrir as orelhas<\/strong>, logo, o candidato deve cort\u00e1-lo ou prend\u00ea-lo antes da prova<\/li>\n<\/ul>\n\n\n\n<ul>\n<li>\u00c9 necess\u00e1rio que <strong>o candidato tenha at\u00e9 23 anos de idade <\/strong>para realizar a inscri\u00e7\u00e3o<\/li>\n<\/ul>\n\n\n\n<ul>\n<li>O candidato deve levar l\u00e1pis ou lapiseira, <strong>caneta esferogr\u00e1fica de corpo transparente preta<\/strong>, borracha macia e r\u00e9gua simples<\/li>\n<\/ul>\n\n\n\n<ul>\n<li>\u00c9 obrigat\u00f3rio chegar no local de prova 1 (uma) hora antes do in\u00edcio da prova do ITA<\/li>\n<\/ul>\n\n\n\n<ul>\n<li>As respostas de m\u00faltipla escolha dever\u00e3o ser preenchidas na folha \u00f3ptica com <strong>caneta preta<\/strong><\/li>\n<\/ul>\n\n\n\n<ul>\n<li>O Cart\u00e3o de Inscri\u00e7\u00e3o deve estar com o candidato durante as provas<\/li>\n<\/ul>\n\n\n\n<ul>\n<li>\u00c9 obrigat\u00f3ria a apresenta\u00e7\u00e3o de Documento de Identidade atualizado para realiza\u00e7\u00e3o da prova<\/li>\n<\/ul>\n\n\n\n<ul>\n<li><strong><a aria-label=\" (abre numa nova aba)\" href=\"http:\/\/www.vestibular.ita.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">O site oficial do vestibular ITA <\/a>apresenta todos os demais crit\u00e9rios de avalia\u00e7\u00e3o<\/strong><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"calend\u00e1rio\">Calend\u00e1rio da Prova do ITA<\/h2>\n\n\n\n<p>As provas do ITA s\u00e3o realizadas no segundo semestre de cada ano, com apenas uma edi\u00e7\u00e3o anual. Veja a seguir o cronograma:<\/p>\n\n\n\n<ul>\n<li><strong>Inscri\u00e7\u00f5es<\/strong>: 03 de junho a 17 de julho de 2024<\/li>\n\n\n\n<li><strong>Provas<\/strong>: 13 de outubro de 2024 (1\u00aa fase)\/ 05 e 08 de novembro de 2024 (2\u00aa fase)<\/li>\n\n\n\n<li><strong>Resultado<\/strong>: 19 de dezembro de 2024<\/li>\n<\/ul>\n\n\n\n<p>Gostou do nosso artigo sobre a prova do ITA? Confira <strong>outros artigos<\/strong> do nosso blog e <strong>se prepare para o Enem<\/strong> da melhor maneira! Voc\u00ea tamb\u00e9m pode se organizar com o nosso <a aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/dicas\/enem-dicas\/plano-de-estudos-gratuito\/\" target=\"_blank\" rel=\"noreferrer noopener\">plano de estudos<\/a>, o mais completo da internet!<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A prova do ITA &#8211; Instituto Tecnol\u00f3gico da Aeron\u00e1utica &#8211; \u00e9 um dos vestibulares mais concorridos do pa\u00eds! Al\u00e9m de ser a gradua\u00e7\u00e3o dos sonhos de todo amante de exatas, por ser uma institui\u00e7\u00e3o militar, possui uma s\u00e9rie de especificidades. Entre elas est\u00e3o a idade limite para ingresso no Instituto e as fases espec\u00edficas para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15070,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[537],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>TUDO sobre a prova do ITA: Entenda as regras e as fases!<\/title>\n<meta name=\"description\" content=\"Veja como \u00e9 a prova do ITA, seu m\u00e9todo de corre\u00e7\u00e3o, suas mat\u00e9rias, suas regras militares espec\u00edficas e tenha acesso \u00e0s provas anteriores!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beduka.com\/blog\/dicas\/vestibulares\/prova-do-ita\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TUDO sobre a prova do ITA: Entenda as regras e as fases!\" \/>\n<meta property=\"og:description\" content=\"Veja como \u00e9 a prova do ITA, seu m\u00e9todo de corre\u00e7\u00e3o, suas mat\u00e9rias, suas regras militares espec\u00edficas e tenha acesso \u00e0s provas anteriores!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beduka.com\/blog\/dicas\/vestibulares\/prova-do-ita\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-06T17:34:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-22T15:52:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/03\/Prova-do-ITA-e-bras\u00e3o-do-instituto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/beduka.com\/blog\/dicas\/vestibulares\/prova-do-ita\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/beduka.com\/blog\/dicas\/vestibulares\/prova-do-ita\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a\"},\"headline\":\"Tudo sobre a prova do ITA 2025: Veja como ela funciona, quais s\u00e3o os conte\u00fados e dicas imperd\u00edveis!\",\"datePublished\":\"2020-03-06T17:34:32+00:00\",\"dateModified\":\"2024-08-22T15:52:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/beduka.com\/blog\/dicas\/vestibulares\/prova-do-ita\/\"},\"wordCount\":1303,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/beduka.com\/blog\/#organization\"},\"articleSection\":[\"Vestibulares\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/beduka.com\/blog\/dicas\/vestibulares\/prova-do-ita\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/beduka.com\/blog\/dicas\/vestibulares\/prova-do-ita\/\",\"url\":\"https:\/\/beduka.com\/blog\/dicas\/vestibulares\/prova-do-ita\/\",\"name\":\"TUDO sobre a prova do ITA: Entenda as regras e as fases!\",\"isPartOf\":{\"@id\":\"https:\/\/beduka.com\/blog\/#website\"},\"datePublished\":\"2020-03-06T17:34:32+00:00\",\"dateModified\":\"2024-08-22T15:52:45+00:00\",\"description\":\"Veja como \u00e9 a prova do ITA, seu m\u00e9todo de corre\u00e7\u00e3o, suas mat\u00e9rias, suas regras militares espec\u00edficas e tenha acesso \u00e0s provas anteriores!\",\"breadcrumb\":{\"@id\":\"https:\/\/beduka.com\/blog\/dicas\/vestibulares\/prova-do-ita\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/beduka.com\/blog\/dicas\/vestibulares\/prova-do-ita\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/beduka.com\/blog\/dicas\/vestibulares\/prova-do-ita\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/beduka.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tudo sobre a prova do ITA 2025: Veja como ela funciona, quais s\u00e3o os conte\u00fados e dicas imperd\u00edveis!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/beduka.com\/blog\/#website\",\"url\":\"https:\/\/beduka.com\/blog\/\",\"name\":\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\",\"description\":\"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!\",\"publisher\":{\"@id\":\"https:\/\/beduka.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/beduka.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/beduka.com\/blog\/#organization\",\"name\":\"Beduka\",\"url\":\"https:\/\/beduka.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png\",\"contentUrl\":\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png\",\"width\":1077,\"height\":368,\"caption\":\"Beduka\"},\"image\":{\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/\",\"https:\/\/www.instagram.com\/beduka_oficial\/\",\"https:\/\/www.linkedin.com\/company\/beduka\",\"https:\/\/br.pinterest.com\/bedukaoficial\/\",\"https:\/\/www.youtube.com\/beduka\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a\",\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o Beduka (a)\"},\"description\":\"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.\",\"sameAs\":[\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\",\"https:\/\/www.instagram.com\/beduka_oficial\/\",\"https:\/\/br.pinterest.com\/bedukaoficial\/\"],\"url\":\"https:\/\/beduka.com\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TUDO sobre a prova do ITA: Entenda as regras e as fases!","description":"Veja como \u00e9 a prova do ITA, seu m\u00e9todo de corre\u00e7\u00e3o, suas mat\u00e9rias, suas regras militares espec\u00edficas e tenha acesso \u00e0s provas anteriores!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beduka.com\/blog\/dicas\/vestibulares\/prova-do-ita\/","og_locale":"pt_BR","og_type":"article","og_title":"TUDO sobre a prova do ITA: Entenda as regras e as fases!","og_description":"Veja como \u00e9 a prova do ITA, seu m\u00e9todo de corre\u00e7\u00e3o, suas mat\u00e9rias, suas regras militares espec\u00edficas e tenha acesso \u00e0s provas anteriores!","og_url":"https:\/\/beduka.com\/blog\/dicas\/vestibulares\/prova-do-ita\/","og_site_name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","article_publisher":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","article_author":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades","article_published_time":"2020-03-06T17:34:32+00:00","article_modified_time":"2024-08-22T15:52:45+00:00","og_image":[{"width":600,"height":300,"url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/03\/Prova-do-ITA-e-bras\u00e3o-do-instituto.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Beduka (a)","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Beduka (a)","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beduka.com\/blog\/dicas\/vestibulares\/prova-do-ita\/#article","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/dicas\/vestibulares\/prova-do-ita\/"},"author":{"name":"Reda\u00e7\u00e3o Beduka (a)","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a"},"headline":"Tudo sobre a prova do ITA 2025: Veja como ela funciona, quais s\u00e3o os conte\u00fados e dicas imperd\u00edveis!","datePublished":"2020-03-06T17:34:32+00:00","dateModified":"2024-08-22T15:52:45+00:00","mainEntityOfPage":{"@id":"https:\/\/beduka.com\/blog\/dicas\/vestibulares\/prova-do-ita\/"},"wordCount":1303,"commentCount":0,"publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"articleSection":["Vestibulares"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/beduka.com\/blog\/dicas\/vestibulares\/prova-do-ita\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/beduka.com\/blog\/dicas\/vestibulares\/prova-do-ita\/","url":"https:\/\/beduka.com\/blog\/dicas\/vestibulares\/prova-do-ita\/","name":"TUDO sobre a prova do ITA: Entenda as regras e as fases!","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/#website"},"datePublished":"2020-03-06T17:34:32+00:00","dateModified":"2024-08-22T15:52:45+00:00","description":"Veja como \u00e9 a prova do ITA, seu m\u00e9todo de corre\u00e7\u00e3o, suas mat\u00e9rias, suas regras militares espec\u00edficas e tenha acesso \u00e0s provas anteriores!","breadcrumb":{"@id":"https:\/\/beduka.com\/blog\/dicas\/vestibulares\/prova-do-ita\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beduka.com\/blog\/dicas\/vestibulares\/prova-do-ita\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/beduka.com\/blog\/dicas\/vestibulares\/prova-do-ita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/beduka.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Tudo sobre a prova do ITA 2025: Veja como ela funciona, quais s\u00e3o os conte\u00fados e dicas imperd\u00edveis!"}]},{"@type":"WebSite","@id":"https:\/\/beduka.com\/blog\/#website","url":"https:\/\/beduka.com\/blog\/","name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","description":"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!","publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beduka.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beduka.com\/blog\/#organization","name":"Beduka","url":"https:\/\/beduka.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","contentUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","width":1077,"height":368,"caption":"Beduka"},"image":{"@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/www.linkedin.com\/company\/beduka","https:\/\/br.pinterest.com\/bedukaoficial\/","https:\/\/www.youtube.com\/beduka"]},{"@type":"Person","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a","name":"Reda\u00e7\u00e3o Beduka (a)","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o Beduka (a)"},"description":"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.","sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/br.pinterest.com\/bedukaoficial\/"],"url":"https:\/\/beduka.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/15072"}],"collection":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/comments?post=15072"}],"version-history":[{"count":2,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/15072\/revisions"}],"predecessor-version":[{"id":32960,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/15072\/revisions\/32960"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media\/15070"}],"wp:attachment":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media?parent=15072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/categories?post=15072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/tags?post=15072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}