{"id":16100,"date":"2020-05-22T13:39:29","date_gmt":"2020-05-22T16:39:29","guid":{"rendered":"https:\/\/beduka.com\/blog\/?p=16100"},"modified":"2023-04-03T16:13:50","modified_gmt":"2023-04-03T19:13:50","slug":"exercicios-sobre-pronome-interrogativo","status":"publish","type":"post","link":"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-pronome-interrogativo\/","title":{"rendered":"Exerc\u00edcios sobre Pronome Interrogativo COM GABARITO"},"content":{"rendered":"\n<p><a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/materias\/portugues\/quais-sao-pronomes-interrogativos\/\" target=\"_blank\">Pronomes Interrogativos<\/a> s\u00e3o os utilizados para realizar perguntas diretas ou indiretas. Fa\u00e7a os exerc\u00edcios sobre Pronome Interrogativo e <a href=\"https:\/\/beduka.com\/simulado-enem\/#\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">Simulado Beduka<\/a> para entender melhor o assunto e se dar bem nos vestibulares.<br><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O que s\u00e3o Pronomes Interrogativos?&nbsp;<\/h2>\n\n\n\n<p>Vamos come\u00e7ar entendendo o que s\u00e3o esses <a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/materias\/portugues\/quais-sao-os-pronomes\/\" target=\"_blank\">pronomes<\/a>. Leia atentamente para entender e fazer os exerc\u00edcios sobre Pronome Interrogativo.&nbsp;<br><\/p>\n\n\n\n<p>Pra come\u00e7ar, os pronomes interrogativos s\u00e3o os seguintes:&nbsp;<br><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" loading=\"lazy\" width=\"600\" height=\"300\" src=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/05\/Pronomes_Interrogativos.jpg\" alt=\"Tabela de Pronome Interrogativo\" class=\"wp-image-16103\" srcset=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/05\/Pronomes_Interrogativos.jpg 600w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/05\/Pronomes_Interrogativos-300x150.jpg 300w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/05\/Pronomes_Interrogativos-320x160.jpg 320w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><figcaption>Tabela de Pronome Interrogativo<\/figcaption><\/figure><\/div>\n\n\n<p>O <strong>\u201cqual\u201d <\/strong>pode variar quanto ao n\u00famero, tornando-se <strong>\u201cquais\u201d. <\/strong>O <strong>\u201cquanto\u201d <\/strong>pode variar quanto ao n\u00famero e g\u00eanero, tornando-se <strong>\u201cquanto, quanta, quantos e quantas\u201d. \u201cQue e Quem\u201d <\/strong>s\u00e3o invari\u00e1veis. Os pronomes interrogativos podem ter valor de:<br><\/p>\n\n\n\n<ul><li><strong>Pronome Interrogativo substantivo: <\/strong>\u00c9 o que pergunta sobre um sujeito.&nbsp;<\/li><\/ul>\n\n\n\n<p><strong>Exemplo:&nbsp;<\/strong><br><\/p>\n\n\n\n<p><strong>Quem <\/strong>foi \u00e0 reuni\u00e3o?&nbsp;<br><\/p>\n\n\n\n<ul><li><strong>Pronome Interrogativo Adjetivo: <\/strong>\u00c9 o que pergunta sobre uma caracter\u00edstica.&nbsp;<\/li><\/ul>\n\n\n\n<p><strong>Exemplo:&nbsp;<\/strong><br><\/p>\n\n\n\n<p><strong>Qual <\/strong>\u00e9 a cor da sua gravata?&nbsp;<br><\/p>\n\n\n\n<p>Os pronomes interrogativos s\u00e3o usados para fazer <strong>frases interrogativas<\/strong>. Elas podem ser:&nbsp;<br><\/p>\n\n\n\n<ul><li><strong>Frases Interrogativas Diretas: <\/strong>Possuem <strong>pronome interrogativo no come\u00e7o <\/strong>da frase e <strong>ponto de interroga\u00e7\u00e3o no final<\/strong>.&nbsp;<\/li><\/ul>\n\n\n\n<p><strong>Exemplo:&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Quem <\/strong>far\u00e1 o caf\u00e9<strong>?&nbsp;<\/strong><\/p>\n\n\n\n<ul><li><strong>Frases Interrogativas Indiretas: N\u00e3o possuem<\/strong> <strong>pronome interrogativo<\/strong> <strong>no come\u00e7o e terminam com ponto final.&nbsp;<\/strong><\/li><\/ul>\n\n\n\n<p><strong>Exemplo:&nbsp;<\/strong><\/p>\n\n\n\n<p>Queria saber <strong>quem<\/strong> far\u00e1 o caf\u00e9.&nbsp;<\/p>\n\n\n\n<p>Eles <strong>sempre<\/strong> se referem \u00e0 <strong>3\u00aa pessoa<\/strong> e <strong>nunca<\/strong> se referem a algo<strong> j\u00e1 mencionado <\/strong>como s\u00e3o os <strong>pronomes relativos<\/strong>, por exemplo. Isso porque, como se est\u00e1 fazendo uma pergunta sup\u00f5e-se que voc\u00ea n\u00e3o sabe a resposta.&nbsp;<\/p>\n\n\n\n<p>Logo, voc\u00ea faz a <strong>pergunta a respeito de algo ou algu\u00e9m (3\u00aa pessoa)<\/strong> e o seu pronome interrogativo<strong> se referir\u00e1 \u00e0 resposta que voc\u00ea receber<\/strong>. Por isso, <strong>originalmente ele n\u00e3o se refere a nada.&nbsp;<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Especifica\u00e7\u00f5es dos pronomes interrogativos<\/h2>\n\n\n\n<p>Alguns pronomes interrogativos t\u00eam caracter\u00edsticas espec\u00edficas. Vamos v\u00ea-las para voc\u00ea n\u00e3o se perder quando fizer os exerc\u00edcios sobre pronome interrogativo.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Pronome Interrogativo \u201cque\u201d<\/h3>\n\n\n\n<p>Normalmente, o pronome <strong>\u201cque\u201d <\/strong>se refere a <strong>coisas. <\/strong>Nesse caso ele \u00e9 um <strong>pronome interrogativo substantivo.&nbsp;<\/strong><br><\/p>\n\n\n\n<p><strong>Exemplos:&nbsp;<\/strong><br><\/p>\n\n\n\n<p><strong>Que <\/strong>viagem \u00e9 essa?&nbsp;<br><\/p>\n\n\n\n<p>O pronome <strong>\u201cque\u201d<\/strong> tamb\u00e9m pode ser <strong>adjetivo <\/strong>quando ele tem sentido de <strong>\u201cque esp\u00e9cie de\u201d.&nbsp;<\/strong><br><\/p>\n\n\n\n<p><strong>Exemplo:&nbsp;<\/strong><br><\/p>\n\n\n\n<p><strong>Que <\/strong>tipo de couro \u00e9 esse?&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Pronome interrogativo \u201cquem\u201d&nbsp;<\/h3>\n\n\n\n<p>Esse pronome est\u00e1 mais ligado a personifica\u00e7\u00e3o. Normalmente ele pergunta sobre pessoas ou coisa personificadas. Nesse caso ele \u00e9 um <strong>pronome substantivo.&nbsp;<\/strong><br><\/p>\n\n\n\n<p><strong>Exemplo:&nbsp;<\/strong><br><\/p>\n\n\n\n<p><strong>Quem <\/strong>vai tocar esse projeto.&nbsp;<br><\/p>\n\n\n\n<p>Ele pode ser um <strong>predicativo do sujeito <\/strong>se esse estiver no <strong>plural <\/strong>e se a ora\u00e7\u00e3o conter o verbo <strong>\u201cser\u201d<\/strong>.&nbsp;<br><\/p>\n\n\n\n<p><strong>Exemplo:&nbsp;<\/strong><br><\/p>\n\n\n\n<p>Voc\u00ea sabe <strong>quem <\/strong>eram?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Pronome interrogativo \u201cqual\u201d<\/h3>\n\n\n\n<p>Esse pronome tem a ver com <strong>sele\u00e7\u00e3o. <\/strong>Deixando a entender a presen\u00e7a de v\u00e1rias pessoas ou coisas. Geralmente usado como <strong>pronome adjetivo.&nbsp;<\/strong><br><\/p>\n\n\n\n<p><strong>Exemplo:&nbsp;<\/strong><br><\/p>\n\n\n\n<p>J\u00e1 escolheu <strong>quais <\/strong>vai levar?&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Pronome interrogativo \u201cquanto\u201d<\/h3>\n\n\n\n<p>Esse pronome tamb\u00e9m passa uma ideia de quantidade de coisas ou pessoas. <strong>Normalmente usado como pronome adjetivo.&nbsp;<\/strong><br><\/p>\n\n\n\n<p><strong>Exemplo:&nbsp;<\/strong><br><\/p>\n\n\n\n<p><strong>Quantos <\/strong>t\u00eam com voc\u00ea?&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Exclama\u00e7\u00e3o com pronomes interrogativos<\/h3>\n\n\n\n<p>Os pronomes interrogativos tamb\u00e9m podem ser usados para demonstrar exclama\u00e7\u00e3o.&nbsp;<br><\/p>\n\n\n\n<p><strong>Exemplos:&nbsp;<\/strong><br><\/p>\n\n\n\n<p><strong>Que <\/strong>coisa chata!<br><\/p>\n\n\n\n<p><strong>Quem <\/strong>diria!&nbsp;<br><\/p>\n\n\n\n<p><strong>Qual <\/strong>\u00e9 cara!&nbsp;<br><\/p>\n\n\n\n<p><strong>Quanta <\/strong>chiquesa.&nbsp;&nbsp;<br><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Exerc\u00edcios sobre Pronomes Interrogativos&nbsp;<\/h2>\n\n\n\n<p>Ok, hora dos exerc\u00edcios sobre pronomes interrogativos. Fa\u00e7a com aten\u00e7\u00e3o. Fa\u00e7a tamb\u00e9m o <a href=\"https:\/\/beduka.com\/simulado-enem\/#\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">Simulado Beduka<\/a> e depois baixe nosso <a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/dicas\/enem-dicas\/plano-de-estudos-gratuito\/\" target=\"_blank\">Plano de Estudos<\/a>.&nbsp;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>1<\/strong>. <strong>(MACK)<\/strong> &#8220;Este inferno de amar &#8211; como eu amo! &#8211; \/ Quem mo p\u00f4s aqui n\u2019alma &#8230; quem foi? \/ Esta chama que alenta e consome, \/ Que \u00e9 a vida &#8211; e que a vida destr\u00f3i &#8211; \/ Como \u00e9 que se veio a atear, \/ Quando &#8211; ai quando se h\u00e1-de apagar?&#8221; (Almeida Garret)<\/p>\n\n\n\n<p>No texto, os pronomes eu &#8211; quem &#8211; este, s\u00e3o, respectivamente:<\/p>\n\n\n\n<p>a) indefinido &#8211; pessoal &#8211; indefinido<\/p>\n\n\n\n<p>b) pessoal &#8211; interrogativo &#8211; demonstrativo<\/p>\n\n\n\n<p>c) pessoal &#8211; indefinido &#8211; demonstrativo<\/p>\n\n\n\n<p>d) interrogativo &#8211; pessoal &#8211; indefinido<\/p>\n\n\n\n<p>e) indefinido &#8211; pessoal &#8211; interrogativo<\/p>\n\n\n\n<p><strong>2<\/strong>. <strong>(TRE-AM)<\/strong> Assinale a alternativa que preenche corretamenteas lacunas da frase apresentada.<\/p>\n\n\n\n<p>O funcion\u00e1rio ___ o chefe se dirigiu era a pessoa ___ todos confiavam.<\/p>\n\n\n\n<p>a) para quem &#8211; em que<\/p>\n\n\n\n<p>b) em que &#8211; com quem<\/p>\n\n\n\n<p>c) por quem &#8211; de que<\/p>\n\n\n\n<p>d) a quem &#8211; em quem<\/p>\n\n\n\n<p>e) de quem &#8211; a quem<\/p>\n\n\n\n<p><strong>3<\/strong>.<strong> (EPCAR)<\/strong> O que \u00e9 pronome interrogativo na frase:<\/p>\n\n\n\n<p>a) Os que chegaram atrasados far\u00e3o a prova?<\/p>\n\n\n\n<p>b) Se n\u00e3o precisas de n\u00f3s, que vieste fazer aqui?<\/p>\n\n\n\n<p>c) Quem pode afian\u00e7ar que seja ele o criminoso?<\/p>\n\n\n\n<p>d) Teria sido o livro que me prometeste?<\/p>\n\n\n\n<p>e) Conseguirias tudo que desejas?<\/p>\n\n\n\n<p><strong>4-(CONSULPLAN)<\/strong>&nbsp;<br><\/p>\n\n\n\n<p><strong>Trapezista<\/strong><\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Querida, eu juro que n\u00e3o era eu. Que coisa rid\u00edcula! Se voc\u00ea estivesse aqui \u2013 Al\u00f4? Al\u00f4? \u2013 olha, se voc\u00ea estivesse aqui ia ver a minha cara, inocente como o Diabo. O qu\u00ea? Mas como, ironia? \u201cComo o Diabo\u201d \u00e9 for\u00e7a de express\u00e3o, que diabo. Voc\u00ea acha que eu ia brincar numa hora desta? Al\u00f4! Eu juro, pelo que h\u00e1 de mais sagrado, pelo t\u00famulo de minha m\u00e3e, pela nossa conta no banco, pela cabe\u00e7a dos nossos filhos que n\u00e3o era eu naquela foto de carnaval no Cascalho que saiu na Folha da Manh\u00e3. O qu\u00ea? Al\u00f4! Al\u00f4! Como \u00e9 que eu sei qual \u00e9 a foto? Mas voc\u00ea n\u00e3o acaba de dizer&#8230; Ah, voc\u00ea n\u00e3o chegou a dizer&#8230; ah, voc\u00ea n\u00e3o chegou a dizer qual era o jornal. Bom, bem. Voc\u00ea n\u00e3o vai acreditar mas acontece que eu tamb\u00e9m vi a foto. N\u00e3o desliga! Eu tamb\u00e9m vi a foto e tive a mesma rea\u00e7\u00e3o. Que sujeito parecido comigo, pensei. Podia ser g\u00eameo. Agora, querida, nunca, em nenhum momento, est\u00e1 ouvindo? Em nenhum momento me passou pela cabe\u00e7a a ideia de que voc\u00ea fosse pensar \u2014 querida, eu estou at\u00e9 come\u00e7ando a achar gra\u00e7a \u2014, que voc\u00ea fosse pensar que aquele era eu. Por amor de Deus. Pra come\u00e7o de conversa voc\u00ea pode me imaginar de pare\u00f4 vermelho e colar havaiano, pulando no Cascalho com uma bandida em cada bra\u00e7o? N\u00e3o, fa\u00e7a-me o favor. E a cara das bandidas! Francamente, j\u00e1 que voc\u00ea n\u00e3o confia na minha fidelidade, que confiasse no meu bom gosto, poxa! O qu\u00ea? Querida, eu n\u00e3o disse \u201cpare\u00f4 vermelho\u201d. Tenho a mais absoluta, a mais tranquila, a mais inabal\u00e1vel certeza que eu disse apenas \u201cpare\u00f4\u201d. Como \u00e9 que eu podia saber que era vermelho se a fotografia n\u00e3o era em cores, certo? Al\u00f4? Al\u00f4? N\u00e3o desliga! N\u00e3o&#8230; Olha, se voc\u00ea desligar est\u00e1 tudo acabado. Tudo acabado. Voc\u00ea n\u00e3o precisa nem voltar da praia. Fica a\u00ed com as crian\u00e7as e funda uma col\u00f4nia de pescadores. N\u00e3o, estou falando s\u00e9rio.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Perdi a paci\u00eancia. Afinal, se voc\u00ea n\u00e3o confia em mim n\u00e3o adianta nada a gente continuar. Um casamento deve se&#8230; se&#8230; como \u00e9 mesmo a palavra?&#8230; se alicer\u00e7ar na confian\u00e7a m\u00fatua. O casamento \u00e9 como um n\u00famero de trap\u00e9zio, um precisa confiar no outro at\u00e9 de olhos fechados. \u00c9 isso mesmo. E sabe de outra coisa? Eu n\u00e3o precisava ficar na cidade durante o carnaval. Foi tudo mentira. Eu n\u00e3o tinha trabalho acumulado no escrit\u00f3rio cois\u00edssima nenhuma. Eu fiquei sabe para qu\u00ea? Para testar voc\u00ea. Ficar na cidade foi como dar um salto mortal, sem rede, s\u00f3 para saber se voc\u00ea me pegaria no ar. Um teste do nosso amor. E voc\u00ea falhou. Voc\u00ea me decepcionou. N\u00e3o vou nem gritar por socorro. N\u00e3o, n\u00e3o me interrompa.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Desculpas n\u00e3o adiantam mais. O pr\u00f3ximo som que voc\u00ea ouvir ser\u00e1 do meu corpo se estatelando, com o baque surdo da desilus\u00e3o, no duro ch\u00e3o da realidade. Al\u00f4? Eu disse que o pr\u00f3ximo som&#8230; que&#8230; O qu\u00ea? Voc\u00ea n\u00e3o estava ouvindo nada? Qual foi a \u00faltima coisa que voc\u00ea ouviu, cora\u00e7\u00e3o?<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Pois sim, eu n\u00e3o falei \u2014 tenho certeza absoluta que n\u00e3o falei \u2014 em \u201cpare\u00f4 vermelho\u201d. Sei l\u00e1 que cor era o pare\u00f4 daquele cretino na foto. Voc\u00ea precisa acreditar em mim, querida. O casamento \u00e9 como um n\u00famero de&#8230;<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Sim. N\u00e3o. Claro. Como? N\u00e3o. Certo. Quando voc\u00ea voltar pode perguntar para o&#8230; Voc\u00ea quer que eu jure? De novo? Pois eu juro. Passei s\u00e1bado, domingo, segunda e ter\u00e7a no escrit\u00f3rio. N\u00e3o vi carnaval nem pela janela. S\u00f3 vim em casa tomar um banho e comer um sandu\u00edche e vou logo voltar para l\u00e1. Como? Voc\u00ea telefonou para o escrit\u00f3rio. Meu bem, \u00e9 claro que a telefonista n\u00e3o estava trabalhando, n\u00e3o \u00e9, bem. Ha, ha, voc\u00ea \u00e9 demais. Olha, querida? Al\u00f4? S\u00e1bado eu estou a\u00ed. beijo nas crian\u00e7as. Socorro. Eu disse, um beijo.<\/p>\n\n\n\n<p><em>(In: Ver\u00edssimo, L. F. As mentiras que os homens contam. S\u00e3o Paulo, Objetiva: ????.)<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Assinale a alternativa que classifica corretamente a fun\u00e7\u00e3o da palavra destacada na frase recortada.<br><\/p>\n\n\n\n<p>a)<strong> <\/strong>\u201c<em>\u00c9 <\/em><em>isso<\/em><em> mesmo<\/em>.\u201d (2\u00ba\u00a7) \u2013 pronome demonstrativo.<\/p>\n\n\n\n<p>b) \u201c<em>[&#8230;] <\/em><em>como<\/em><em> \u00e9 mesmo a palavra?<\/em>\u201d (2\u00ba\u00a7) \u2013 pronome interrogativo.<\/p>\n\n\n\n<p>c) \u201c<em>Voc\u00ea<\/em><em> telefonou para o escrit\u00f3rio<\/em>.\u201d (5\u00ba\u00a7) \u2013 pronome pessoal do caso reto.<\/p>\n\n\n\n<p>d) \u201c<em>Afinal, <\/em><em>se<\/em><em> voc\u00ea n\u00e3o confia em mim n\u00e3o adianta nada a gente continuar<\/em>.\u201d (2\u00ba\u00a7) \u2013 conjun\u00e7\u00e3o coordenativa.<\/p>\n\n\n\n<p><strong>5-(CESGRANRIO) <\/strong>Na senten\u00e7a \u201cSabe por qu\u00ea?&#8221; (L. 5, Texto I), a palavra destacada \u00e9 um pronome interrogativo. Em qual das senten\u00e7as h\u00e1 tamb\u00e9m pronome interrogativo?<\/p>\n\n\n\n<p>a) O port\u00e3o por que voc\u00ea passou quebrou.<\/p>\n\n\n\n<p>b) O porqu\u00ea da escola \u00e9 ensinar.<\/p>\n\n\n\n<p>c) O motivo por que n\u00e3o vou \u00e0 cidade \u00e9 particular.<\/p>\n\n\n\n<p>d) Eu vou \u00e0 cidade porque me pediram.<\/p>\n\n\n\n<p>e) Gostaria de saber por que voc\u00ea n\u00e3o quer ir ao cinema.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Respostas dos Exerc\u00edcios sobre Pronome Interrogativo&nbsp;<\/strong><\/h2>\n\n\n\n<p><strong>Exerc\u00edcio resolvido da quest\u00e3o 1 \u2013<\/strong><\/p>\n\n\n\n<p>b) pessoal &#8211; interrogativo &#8211; demonstrativo<br><\/p>\n\n\n\n<p><strong>Exerc\u00edcio resolvido da quest\u00e3o 2 \u2013<\/strong><\/p>\n\n\n\n<p>d) a quem &#8211; em quem<br><\/p>\n\n\n\n<p><strong>Exerc\u00edcio resolvido da quest\u00e3o 3 \u2013<\/strong><\/p>\n\n\n\n<p>b) Se n\u00e3o precisas de n\u00f3s, que vieste fazer aqui?<br><\/p>\n\n\n\n<p><strong>Exerc\u00edcio resolvido da quest\u00e3o 4 \u2013<\/strong><\/p>\n\n\n\n<p>a) \u201c<em>\u00c9 <\/em><em>isso<\/em><em> mesmo<\/em>.\u201d (2\u00ba\u00a7) \u2013 pronome demonstrativo.<\/p>\n\n\n\n<p><strong>Exerc\u00edcio resolvido da quest\u00e3o 5 \u2013<\/strong><\/p>\n\n\n\n<p>e) Gostaria de saber por que voc\u00ea n\u00e3o quer ir ao cinema.<\/p>\n\n\n\n<p>Estude para o Enem com o<a href=\"https:\/\/beduka.com\/simulado\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\"> Simulado Beduka.<\/a> <strong>\u00c9 gratuito!<\/strong><\/p>\n\n\n\n<p>Gostou dos nossos Exerc\u00edcios sobre Pronome Interrogativo? Compartilhe com os seus amigos e comente abaixo sobre \u00e1reas que voc\u00ea deseja mais explica\u00e7\u00f5es.<\/p>\n\n\n\n<p>Queremos te ajudar a encontrar a <strong>FACULDADE IDEAL! <\/strong>Logo abaixo, fa\u00e7a uma pesquisa por curso e cidade que te mostraremos todas as faculdades que podem te atender. <strong>Informamos a nota de corte, valor de mensalidade, nota do MEC, avalia\u00e7\u00e3o dos alunos, modalidades de ensino e muito mais.<\/strong><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Teste seus conhecimentos com exerc\u00edcios sobre Pronome Interrogativo. Temos GABARITO e resumo da mat\u00e9ria para voc\u00ea tirar suas d\u00favidas. <\/p>\n","protected":false},"author":1,"featured_media":16102,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[605],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Exerc\u00edcios sobre Pronome Interrogativo COM GABARITO E RESUMO<\/title>\n<meta name=\"description\" content=\"Teste seus conhecimentos com exerc\u00edcios sobre Pronome Interrogativo. Temos GABARITO e resumo da mat\u00e9ria para voc\u00ea tirar suas d\u00favidas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-pronome-interrogativo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exerc\u00edcios sobre Pronome Interrogativo COM GABARITO E RESUMO\" \/>\n<meta property=\"og:description\" content=\"Teste seus conhecimentos com exerc\u00edcios sobre Pronome Interrogativo. Temos GABARITO e resumo da mat\u00e9ria para voc\u00ea tirar suas d\u00favidas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-pronome-interrogativo\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-22T16:39:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-03T19:13:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/05\/Exerc\u00edcios_sobre_Pronomes_Interrogativos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-pronome-interrogativo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-pronome-interrogativo\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a\"},\"headline\":\"Exerc\u00edcios sobre Pronome Interrogativo COM GABARITO\",\"datePublished\":\"2020-05-22T16:39:29+00:00\",\"dateModified\":\"2023-04-03T19:13:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-pronome-interrogativo\/\"},\"wordCount\":1821,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/beduka.com\/blog\/#organization\"},\"articleSection\":[\"Portugu\u00eas\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-pronome-interrogativo\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-pronome-interrogativo\/\",\"url\":\"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-pronome-interrogativo\/\",\"name\":\"Exerc\u00edcios sobre Pronome Interrogativo COM GABARITO E RESUMO\",\"isPartOf\":{\"@id\":\"https:\/\/beduka.com\/blog\/#website\"},\"datePublished\":\"2020-05-22T16:39:29+00:00\",\"dateModified\":\"2023-04-03T19:13:50+00:00\",\"description\":\"Teste seus conhecimentos com exerc\u00edcios sobre Pronome Interrogativo. Temos GABARITO e resumo da mat\u00e9ria para voc\u00ea tirar suas d\u00favidas.\",\"breadcrumb\":{\"@id\":\"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-pronome-interrogativo\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-pronome-interrogativo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-pronome-interrogativo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/beduka.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exerc\u00edcios sobre Pronome Interrogativo COM GABARITO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/beduka.com\/blog\/#website\",\"url\":\"https:\/\/beduka.com\/blog\/\",\"name\":\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\",\"description\":\"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!\",\"publisher\":{\"@id\":\"https:\/\/beduka.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/beduka.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/beduka.com\/blog\/#organization\",\"name\":\"Beduka\",\"url\":\"https:\/\/beduka.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png\",\"contentUrl\":\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png\",\"width\":1077,\"height\":368,\"caption\":\"Beduka\"},\"image\":{\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/\",\"https:\/\/www.instagram.com\/beduka_oficial\/\",\"https:\/\/www.linkedin.com\/company\/beduka\",\"https:\/\/br.pinterest.com\/bedukaoficial\/\",\"https:\/\/www.youtube.com\/beduka\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a\",\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o Beduka (a)\"},\"description\":\"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.\",\"sameAs\":[\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\",\"https:\/\/www.instagram.com\/beduka_oficial\/\",\"https:\/\/br.pinterest.com\/bedukaoficial\/\"],\"url\":\"https:\/\/beduka.com\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exerc\u00edcios sobre Pronome Interrogativo COM GABARITO E RESUMO","description":"Teste seus conhecimentos com exerc\u00edcios sobre Pronome Interrogativo. Temos GABARITO e resumo da mat\u00e9ria para voc\u00ea tirar suas d\u00favidas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-pronome-interrogativo\/","og_locale":"pt_BR","og_type":"article","og_title":"Exerc\u00edcios sobre Pronome Interrogativo COM GABARITO E RESUMO","og_description":"Teste seus conhecimentos com exerc\u00edcios sobre Pronome Interrogativo. Temos GABARITO e resumo da mat\u00e9ria para voc\u00ea tirar suas d\u00favidas.","og_url":"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-pronome-interrogativo\/","og_site_name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","article_publisher":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","article_author":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades","article_published_time":"2020-05-22T16:39:29+00:00","article_modified_time":"2023-04-03T19:13:50+00:00","og_image":[{"width":600,"height":300,"url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/05\/Exerc\u00edcios_sobre_Pronomes_Interrogativos.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Beduka (a)","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Beduka (a)","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-pronome-interrogativo\/#article","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-pronome-interrogativo\/"},"author":{"name":"Reda\u00e7\u00e3o Beduka (a)","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a"},"headline":"Exerc\u00edcios sobre Pronome Interrogativo COM GABARITO","datePublished":"2020-05-22T16:39:29+00:00","dateModified":"2023-04-03T19:13:50+00:00","mainEntityOfPage":{"@id":"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-pronome-interrogativo\/"},"wordCount":1821,"commentCount":0,"publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"articleSection":["Portugu\u00eas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-pronome-interrogativo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-pronome-interrogativo\/","url":"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-pronome-interrogativo\/","name":"Exerc\u00edcios sobre Pronome Interrogativo COM GABARITO E RESUMO","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/#website"},"datePublished":"2020-05-22T16:39:29+00:00","dateModified":"2023-04-03T19:13:50+00:00","description":"Teste seus conhecimentos com exerc\u00edcios sobre Pronome Interrogativo. Temos GABARITO e resumo da mat\u00e9ria para voc\u00ea tirar suas d\u00favidas.","breadcrumb":{"@id":"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-pronome-interrogativo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-pronome-interrogativo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-pronome-interrogativo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/beduka.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Exerc\u00edcios sobre Pronome Interrogativo COM GABARITO"}]},{"@type":"WebSite","@id":"https:\/\/beduka.com\/blog\/#website","url":"https:\/\/beduka.com\/blog\/","name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","description":"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!","publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beduka.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beduka.com\/blog\/#organization","name":"Beduka","url":"https:\/\/beduka.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","contentUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","width":1077,"height":368,"caption":"Beduka"},"image":{"@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/www.linkedin.com\/company\/beduka","https:\/\/br.pinterest.com\/bedukaoficial\/","https:\/\/www.youtube.com\/beduka"]},{"@type":"Person","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a","name":"Reda\u00e7\u00e3o Beduka (a)","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o Beduka (a)"},"description":"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.","sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/br.pinterest.com\/bedukaoficial\/"],"url":"https:\/\/beduka.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/16100"}],"collection":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/comments?post=16100"}],"version-history":[{"count":2,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/16100\/revisions"}],"predecessor-version":[{"id":29560,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/16100\/revisions\/29560"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media\/16102"}],"wp:attachment":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media?parent=16100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/categories?post=16100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/tags?post=16100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}