{"id":16120,"date":"2020-05-25T11:13:47","date_gmt":"2020-05-25T14:13:47","guid":{"rendered":"https:\/\/beduka.com\/blog\/?p=16120"},"modified":"2023-04-03T16:13:59","modified_gmt":"2023-04-03T19:13:59","slug":"exercicios-sobre-objeto-direto","status":"publish","type":"post","link":"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-objeto-direto\/","title":{"rendered":"Exerc\u00edcios sobre Objeto Direto RESOLVIDOS"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote\"><p><strong><em>O <\/em><\/strong><a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-objeto-direto\/\" target=\"_blank\"><strong><em>Objeto Direto<\/em><\/strong><\/a><strong><em> \u00e9 o termo com a fun\u00e7\u00e3o de completar o sentido de um <\/em><\/strong><a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-sao-verbos\/\" target=\"_blank\"><strong><em>verbo<\/em><\/strong><\/a><strong><em> que n\u00e3o consegue pass\u00e1-lo completamente sozinho. Esses s\u00e3o os <\/em><\/strong><a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-verbo-transitivo-direto\/\" target=\"_blank\"><strong><em>Verbos Transitivos Diretos<\/em><\/strong><\/a><strong><em>. O Objeto Direto tem esse nome porque n\u00e3o precisa de <\/em><\/strong><a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-uma-preposicao\/\" target=\"_blank\"><strong><em>preposi\u00e7\u00e3o<\/em><\/strong><\/a><strong><em> para se ligar. Fa\u00e7a os exerc\u00edcios sobre Objeto Direto e o<a href=\"https:\/\/beduka.com\/simulado-enem\/#\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\"> Simulado Beduka<\/a> para se preparar para os vestibulares.<\/em><\/strong><\/p><\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\">O que \u00e9 Objeto Direto?&nbsp;<\/h2>\n\n\n\n<p>Vamos come\u00e7ar entendendo o que \u00e9 esse objeto para voc\u00ea fazer os exerc\u00edcios sobre Objeto Direto.&nbsp;<br><\/p>\n\n\n\n<p><strong>Objeto Direto <\/strong>\u00e9 um termo que completa o sentido de um <strong>verbo <\/strong>na frase. Esse verbo precisa de um complemento pois ele <strong>n\u00e3o consegue <\/strong>exprimir o sentido completo por si s\u00f3. A esse tipo de verbo chamamos de <strong>verbo transitivo. <\/strong>Dito isso, s\u00f3 precisamos ver se ele exige preposi\u00e7\u00e3o ou n\u00e3o. Caso n\u00e3o exija, o chamamos de <strong>verbo transitivo direto.&nbsp;<\/strong><br><\/p>\n\n\n\n<p>O objeto direto pode ir desde uma \u00fanica palavra at\u00e9 uma frase completa (nesse caso ele teria um <strong>n\u00facleo<\/strong>). Vamos ver algumas formas em que ele pode aparecer.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Substantivo ou palavra substantivada<\/h3>\n\n\n\n<p><strong>Exemplo:<\/strong><br><\/p>\n\n\n\n<ul><li>O fazendeiro fez <strong>a horta&nbsp;<\/strong><\/li><\/ul>\n\n\n\n<p>Nesse exemplo o objeto est\u00e1 sendo representado pelo substantivo <strong>\u201chorta\u201d <\/strong>e como o verbo <strong>\u201cfazer\u201d n\u00e3o pede preposi\u00e7\u00e3o<\/strong>, esse objeto \u00e9 <strong>direto<\/strong>.&nbsp;<br><\/p>\n\n\n\n<p>Um bom macete para saber se o verbo precisa de preposi\u00e7\u00e3o ou n\u00e3o \u00e9 falar a frase incompleta. Desse jeito:&nbsp;<br><\/p>\n\n\n\n<p>O fazendeiro fez <strong>(fez o que?) <\/strong>a horta.&nbsp;<br><\/p>\n\n\n\n<p>Se essa pergunta ficar naturalmente preenchida por um <a href=\"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-sao-artigos\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">artigo<\/a> <strong>\u201co(s), a(s), etc&#8230;\u201d<\/strong>antes do <strong>\u201cque\u201d <\/strong>ent\u00e3o o verbo <strong>n\u00e3o precisa<\/strong> de preposi\u00e7\u00e3o para se ligar ao objeto. Nesse caso seria <strong>direto. <\/strong>Mas se ele s\u00f3 se completar com uma preposi\u00e7\u00e3o, ele \u00e9 <strong>indireto. <\/strong>&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Pronomes Substantivos<\/h3>\n\n\n\n<p><strong>Exemplo:&nbsp;<\/strong><br><\/p>\n\n\n\n<ul><li>Eu odeio <strong>(odeia o qu\u00ea?) isso!<\/strong><\/li><\/ul>\n\n\n\n<p>Nesse exemplo, o pronome substantivo <strong>\u201cisso\u201d <\/strong>est\u00e1 representando o <a href=\"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-complemento-verbal\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">complemento verbal<\/a>, e como o verbo <strong>n\u00e3o pede preposi\u00e7\u00e3o<\/strong>, a liga\u00e7\u00e3o \u00e9 <strong>direta<\/strong>.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Pronome Obl\u00edquo&nbsp;<\/h3>\n\n\n\n<p><strong>Exemplo:&nbsp;<\/strong><br><\/p>\n\n\n\n<ul><li>Explique<strong>-me <\/strong>se puder&nbsp;<\/li><\/ul>\n\n\n\n<p>Nesse exemplo o Objeto Direto est\u00e1 sendo representado pelo Pronome Obl\u00edquo <strong>\u201cme\u201d.<\/strong><br><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ora\u00e7\u00e3o Subordinada Substantiva&nbsp;<\/h3>\n\n\n\n<p><strong>Exemplo:&nbsp;<\/strong><br><\/p>\n\n\n\n<ul><li>Percebi <strong>que alguma coisa mudou<\/strong>.<\/li><\/ul>\n\n\n\n<p>Nesse caso o objeto direto \u00e9 <strong>toda a ora\u00e7\u00e3o: \u201cque alguma coisa mudou\u201d. <\/strong>Pois quem percebe <strong>percebe alguma coisa<\/strong>, logo toda a ora\u00e7\u00e3o \u00e9 complemento do verbo <strong>\u201cperceber\u201d.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Tipos de Objeto Direto<\/h2>\n\n\n\n<p>Existem dois tipos de objeto direto. <strong>Preposicionado e Pleon\u00e1stico. <\/strong>Veremos os dois para que voc\u00ea fa\u00e7a os exerc\u00edcios sobre objeto direto.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Objeto Direto Preposicionado&nbsp;<\/h3>\n\n\n\n<p>Se voc\u00ea leu com aten\u00e7\u00e3o at\u00e9 aqui deve estar pensando: \u201cu\u00e9, mas objeto direto n\u00e3o precisa de preposi\u00e7\u00e3o\u201d. Est\u00e1 certo. Objeto Direto n\u00e3o <strong>precisa <\/strong>de preposi\u00e7\u00e3o, mas ele n\u00e3o \u00e9 proibido de usar alguma para evitar repetir palavras ou por demais quest\u00f5es estil\u00edsticas.&nbsp;<br><\/p>\n\n\n\n<p>Veja algumas situa\u00e7\u00f5es em que a preposi\u00e7\u00e3o \u00e9 usada:<br><\/p>\n\n\n\n<ul><li>Quando se refere a um <strong>substantivo <\/strong>pr\u00f3prio;<\/li><li>Quando se refere a um<strong> pronome obl\u00edquo<\/strong> t\u00f4nico;<\/li><li>Quando se refere a um <strong>pronome indefinido<\/strong>;<\/li><li>Quando se refere ao pronome relativo <strong>quem<\/strong>;<\/li><li>Quando se refere aos numerais <strong>ambos <\/strong>e <strong>ambas<\/strong>;<\/li><li>Quando se encontra <strong>antecipado <\/strong>na frase.<\/li><\/ul>\n\n\n\n<p><strong>Exemplos:&nbsp;<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" loading=\"lazy\" width=\"600\" height=\"300\" src=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/05\/Exemplos_de_Objeto_Direto.jpg\" alt=\"Exemplos de Objeto Direto\" class=\"wp-image-16123\" srcset=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/05\/Exemplos_de_Objeto_Direto.jpg 600w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/05\/Exemplos_de_Objeto_Direto-300x150.jpg 300w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/05\/Exemplos_de_Objeto_Direto-320x160.jpg 320w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><figcaption>Exemplos de Objeto Direto<\/figcaption><\/figure><\/div>\n\n\n<h3 class=\"wp-block-heading\">Objeto Direto Pleon\u00e1stico<\/h3>\n\n\n\n<p>Se voc\u00ea j\u00e1 leu nosso texto sobre<a href=\"https:\/\/beduka.com\/blog\/materias\/portugues\/principais-figuras-linguagem\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\"> figuras de linguagem que caem no enem <\/a>voc\u00ea sabe que um <strong>pleonasmo <\/strong>\u00e9 quando repetimos um termo da frase para refor\u00e7ar a mensagem. Pode-se fazer isso com o objeto direto, assim o chamamos de <strong>objeto direto pleon\u00e1stico<\/strong>.&nbsp;&nbsp;&nbsp;<br><\/p>\n\n\n\n<p>Para fazer isso o <strong>objeto tem que vir no in\u00edcio da frase<\/strong> e ser <strong>repetido ap\u00f3s o verbo na forma de <a href=\"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-pronome-obliquo\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">pronome obl\u00edquo<\/a> \u00e1tono<\/strong>. Esse pronome <strong>n\u00e3o \u00e9 antecedido de preposi\u00e7\u00e3o <\/strong>e <strong>substitui um substantivo<\/strong>.&nbsp;<br><\/p>\n\n\n\n<p><strong>Exemplo:<\/strong><br><\/p>\n\n\n\n<p><strong>Os textos<\/strong>, estudei<strong>-os<\/strong> completamente. (<strong>\u201c-os\u201d <\/strong>substitui o substantivo <strong>\u201cos textos\u201d, <\/strong>que \u00e9 o objeto direto da frase).&nbsp;<br><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Exerc\u00edcios sobre Objeto Direto&nbsp;<\/h2>\n\n\n\n<p>Pois ent\u00e3o, est\u00e1 na hora de fazer os exerc\u00edcios sobre Objeto Direto. Baixe nosso<a href=\"https:\/\/beduka.com\/blog\/dicas\/enem-dicas\/plano-de-estudos-gratuito\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\"> Plano de Estudos<\/a> e fa\u00e7a o <a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/simulado-enem\/#\/\" target=\"_blank\">Simulado Beduka<\/a>. Boa sorte nas suas provas!<br><\/p>\n\n\n\n<p><strong>1-(PUC) <\/strong>Em: \u201cPorque eu continuarei a chamar <strong>guerra a toda esta \u00e9poca embaralhada<\/strong> de in\u00e9ditos valores\u2026\u201d, as express\u00f5es destacadas s\u00e3o, respectivamente:<\/p>\n\n\n\n<p>a) objeto direto, objeto indireto.<\/p>\n\n\n\n<p>b) predicativo, objeto indireto.<\/p>\n\n\n\n<p>c) objeto direto, objeto direto preposicionado.<\/p>\n\n\n\n<p>d) predicativo, objeto direto pleon\u00e1stico.<\/p>\n\n\n\n<p>e) objeto direto, objeto indireto.<\/p>\n\n\n\n<p><strong>2-(Mackenzie) <\/strong>Entre as alternativas abaixo, aponte a \u00fanica em que um dos termos corresponde \u00e0 an\u00e1lise dada: &#8220;Pareciam infinitas as combina\u00e7\u00f5es de cores no azul do c\u00e9u.&#8221;<\/p>\n\n\n\n<p>a) Pareciam \u00e9 um verbo intransitivo.<\/p>\n\n\n\n<p>b) Infinitas \u00e9 objeto direto.<\/p>\n\n\n\n<p>c) Cores \u00e9 o n\u00facleo do sujeito.<\/p>\n\n\n\n<p>d) Do c\u00e9u \u00e9 o complemento nominal.<\/p>\n\n\n\n<p>e) n.d.a.<\/p>\n\n\n\n<p><strong>3-(Unimar) <\/strong>Classifique corretamente os termos integrantes destacados<\/p>\n\n\n\n<p>Mulher que <strong>a dois<\/strong> ama, a <strong>ambos<\/strong> engana.<\/p>\n\n\n\n<p>a) objeto direto preposicionado e objeto direto preposicionado.<\/p>\n\n\n\n<p>b) objeto indireto e objeto direto.<\/p>\n\n\n\n<p>c) objeto indireto pleon\u00e1stico e complemento nominal.<\/p>\n\n\n\n<p>d) objeto direto e objeto direto preposicionado.<\/p>\n\n\n\n<p>e) objeto direto preposicionado e objeto indireto<\/p>\n\n\n\n<p><strong>4-(UFV)<\/strong> Na frase &#8220;Ela atribui-se uma culpa que n\u00e3o tem&#8221;, o pronome <strong>se<\/strong> \u00e9 classificado como:<\/p>\n\n\n\n<p>a) pronome apassivador.<\/p>\n\n\n\n<p>b) \u00edndice de indetermina\u00e7\u00e3o do sujeito.<\/p>\n\n\n\n<p>c) objeto direto.<\/p>\n\n\n\n<p>d) objeto indireto.<\/p>\n\n\n\n<p>e) part\u00edcula expletiva ou de realce.<\/p>\n\n\n\n<p><strong>5-(Escola de Marinha Mercante)<\/strong> No per\u00edodo &#8220;Cumpriria <strong>com as obriga\u00e7\u00f5es<\/strong>, certamente&#8221;, a fun\u00e7\u00e3o sint\u00e1tica do elemento sublinhado \u00e9:<\/p>\n\n\n\n<p>a) complemento nominal.<\/p>\n\n\n\n<p>b) objeto direto.<\/p>\n\n\n\n<p>c) objeto direto preposicionado.<\/p>\n\n\n\n<p>d) objeto indireto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Respostas dos Exerc\u00edcios sobre Objeto Direto<\/strong><\/h2>\n\n\n\n<p><strong>Exerc\u00edcio resolvido da quest\u00e3o 1 \u2013<\/strong><\/p>\n\n\n\n<p>b) predicativo, objeto indireto.<br><\/p>\n\n\n\n<p><strong>Exerc\u00edcio resolvido da quest\u00e3o 2 \u2013<\/strong><\/p>\n\n\n\n<p>e) n.d.a.<br><\/p>\n\n\n\n<p><strong>Exerc\u00edcio resolvido da quest\u00e3o 3 \u2013<\/strong><\/p>\n\n\n\n<p>a) objeto direto preposicionado e objeto direto preposicionado.<br><\/p>\n\n\n\n<p><strong>Exerc\u00edcio resolvido da quest\u00e3o 4 \u2013<\/strong><\/p>\n\n\n\n<p>d) objeto indireto.<\/p>\n\n\n\n<p><strong>Exerc\u00edcio resolvido da quest\u00e3o 5 \u2013<\/strong><\/p>\n\n\n\n<p>c) objeto direto preposicionado.<\/p>\n\n\n\n<p>Estude para o Enem com o<a href=\"https:\/\/beduka.com\/simulado\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\"> Simulado Beduka.<\/a> <strong>\u00c9 gratuito!<\/strong><\/p>\n\n\n\n<p>Gostou dos nossos Exerc\u00edcios sobre Objeto Direto? Compartilhe com os seus amigos e comente abaixo sobre \u00e1reas que voc\u00ea deseja mais explica\u00e7\u00f5es.<\/p>\n\n\n\n<p>Queremos te ajudar a encontrar a <strong>FACULDADE IDEAL! <\/strong>Logo abaixo, fa\u00e7a uma pesquisa por curso e cidade que te mostraremos todas as faculdades que podem te atender. <strong>Informamos a nota de corte, valor de mensalidade, nota do MEC, avalia\u00e7\u00e3o dos alunos, modalidades de ensino e muito mais.<\/strong><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se tem dificuldade com os complementos voc\u00ea tem que ler esse artigo. Separamos exerc\u00edcios sobre Objeto Direto e todos com GABARITO para voc\u00ea checar suas respostas. Tamb\u00e9m temos resumo completo da mat\u00e9ria. <\/p>\n","protected":false},"author":1,"featured_media":16124,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[605],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Exerc\u00edcios sobre Objeto Direto + GABARITO E RESUMO<\/title>\n<meta name=\"description\" content=\"Se tem dificuldade com os complementos voc\u00ea tem que ler esse artigo. Separamos exerc\u00edcios sobre Objeto Direto e todos com GABARITO. Tamb\u00e9m temos resumo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-objeto-direto\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exerc\u00edcios sobre Objeto Direto + GABARITO E RESUMO\" \/>\n<meta property=\"og:description\" content=\"Se tem dificuldade com os complementos voc\u00ea tem que ler esse artigo. Separamos exerc\u00edcios sobre Objeto Direto e todos com GABARITO. Tamb\u00e9m temos resumo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-objeto-direto\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-25T14:13:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-03T19:13:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/05\/Exerc\u00edcios_sobre_Objeto_Direto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-objeto-direto\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-objeto-direto\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a\"},\"headline\":\"Exerc\u00edcios sobre Objeto Direto RESOLVIDOS\",\"datePublished\":\"2020-05-25T14:13:47+00:00\",\"dateModified\":\"2023-04-03T19:13:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-objeto-direto\/\"},\"wordCount\":1070,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/beduka.com\/blog\/#organization\"},\"articleSection\":[\"Portugu\u00eas\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-objeto-direto\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-objeto-direto\/\",\"url\":\"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-objeto-direto\/\",\"name\":\"Exerc\u00edcios sobre Objeto Direto + GABARITO E RESUMO\",\"isPartOf\":{\"@id\":\"https:\/\/beduka.com\/blog\/#website\"},\"datePublished\":\"2020-05-25T14:13:47+00:00\",\"dateModified\":\"2023-04-03T19:13:59+00:00\",\"description\":\"Se tem dificuldade com os complementos voc\u00ea tem que ler esse artigo. Separamos exerc\u00edcios sobre Objeto Direto e todos com GABARITO. Tamb\u00e9m temos resumo.\",\"breadcrumb\":{\"@id\":\"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-objeto-direto\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-objeto-direto\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-objeto-direto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/beduka.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exerc\u00edcios sobre Objeto Direto RESOLVIDOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/beduka.com\/blog\/#website\",\"url\":\"https:\/\/beduka.com\/blog\/\",\"name\":\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\",\"description\":\"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!\",\"publisher\":{\"@id\":\"https:\/\/beduka.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/beduka.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/beduka.com\/blog\/#organization\",\"name\":\"Beduka\",\"url\":\"https:\/\/beduka.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png\",\"contentUrl\":\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png\",\"width\":1077,\"height\":368,\"caption\":\"Beduka\"},\"image\":{\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/\",\"https:\/\/www.instagram.com\/beduka_oficial\/\",\"https:\/\/www.linkedin.com\/company\/beduka\",\"https:\/\/br.pinterest.com\/bedukaoficial\/\",\"https:\/\/www.youtube.com\/beduka\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a\",\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o Beduka (a)\"},\"description\":\"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.\",\"sameAs\":[\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\",\"https:\/\/www.instagram.com\/beduka_oficial\/\",\"https:\/\/br.pinterest.com\/bedukaoficial\/\"],\"url\":\"https:\/\/beduka.com\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exerc\u00edcios sobre Objeto Direto + GABARITO E RESUMO","description":"Se tem dificuldade com os complementos voc\u00ea tem que ler esse artigo. Separamos exerc\u00edcios sobre Objeto Direto e todos com GABARITO. Tamb\u00e9m temos resumo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-objeto-direto\/","og_locale":"pt_BR","og_type":"article","og_title":"Exerc\u00edcios sobre Objeto Direto + GABARITO E RESUMO","og_description":"Se tem dificuldade com os complementos voc\u00ea tem que ler esse artigo. Separamos exerc\u00edcios sobre Objeto Direto e todos com GABARITO. Tamb\u00e9m temos resumo.","og_url":"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-objeto-direto\/","og_site_name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","article_publisher":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","article_author":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades","article_published_time":"2020-05-25T14:13:47+00:00","article_modified_time":"2023-04-03T19:13:59+00:00","og_image":[{"width":600,"height":300,"url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/05\/Exerc\u00edcios_sobre_Objeto_Direto.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Beduka (a)","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Beduka (a)","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-objeto-direto\/#article","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-objeto-direto\/"},"author":{"name":"Reda\u00e7\u00e3o Beduka (a)","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a"},"headline":"Exerc\u00edcios sobre Objeto Direto RESOLVIDOS","datePublished":"2020-05-25T14:13:47+00:00","dateModified":"2023-04-03T19:13:59+00:00","mainEntityOfPage":{"@id":"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-objeto-direto\/"},"wordCount":1070,"commentCount":0,"publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"articleSection":["Portugu\u00eas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-objeto-direto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-objeto-direto\/","url":"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-objeto-direto\/","name":"Exerc\u00edcios sobre Objeto Direto + GABARITO E RESUMO","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/#website"},"datePublished":"2020-05-25T14:13:47+00:00","dateModified":"2023-04-03T19:13:59+00:00","description":"Se tem dificuldade com os complementos voc\u00ea tem que ler esse artigo. Separamos exerc\u00edcios sobre Objeto Direto e todos com GABARITO. Tamb\u00e9m temos resumo.","breadcrumb":{"@id":"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-objeto-direto\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-objeto-direto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-sobre-objeto-direto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/beduka.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Exerc\u00edcios sobre Objeto Direto RESOLVIDOS"}]},{"@type":"WebSite","@id":"https:\/\/beduka.com\/blog\/#website","url":"https:\/\/beduka.com\/blog\/","name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","description":"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!","publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beduka.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beduka.com\/blog\/#organization","name":"Beduka","url":"https:\/\/beduka.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","contentUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","width":1077,"height":368,"caption":"Beduka"},"image":{"@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/www.linkedin.com\/company\/beduka","https:\/\/br.pinterest.com\/bedukaoficial\/","https:\/\/www.youtube.com\/beduka"]},{"@type":"Person","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a","name":"Reda\u00e7\u00e3o Beduka (a)","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o Beduka (a)"},"description":"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.","sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/br.pinterest.com\/bedukaoficial\/"],"url":"https:\/\/beduka.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/16120"}],"collection":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/comments?post=16120"}],"version-history":[{"count":2,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/16120\/revisions"}],"predecessor-version":[{"id":29561,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/16120\/revisions\/29561"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media\/16124"}],"wp:attachment":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media?parent=16120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/categories?post=16120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/tags?post=16120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}