{"id":16960,"date":"2020-07-17T22:42:01","date_gmt":"2020-07-18T01:42:01","guid":{"rendered":"https:\/\/beduka.com\/blog\/?p=16960"},"modified":"2020-07-29T08:52:09","modified_gmt":"2020-07-29T11:52:09","slug":"reino-protista","status":"publish","type":"post","link":"https:\/\/beduka.com\/blog\/materias\/biologia\/reino-protista\/","title":{"rendered":"Resumo completo com tudo o que precisa para conhecer o Reino Protista!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O Reino Protista \u00e9 formado por seres eucariontes, de maioria unicelular embora haja pluricelulares e que podem ser heter\u00f3trofos ou aut\u00f3trofos fotossintetizantes. Seus principais representantes s\u00e3o os protozo\u00e1rios, as algas inferiores e os mixomicetos. Com toda essa diversidade de seres e fun\u00e7\u00f5es, h\u00e1 pol\u00eamicas que rondam a classifica\u00e7\u00e3o desses seres!<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Neste artigo sobre o Reino Protista, voc\u00ea encontrar\u00e1:<br><\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>O que \u00e9 Reino Protista: defini\u00e7\u00e3o, origem, import\u00e2ncia ecol\u00f3gica, caracter\u00edsticas gerais, curiosidades, pol\u00eamicas e fisiologia: digest\u00e3o respira\u00e7\u00e3o e excre\u00e7\u00e3o<\/li><li>Caracter\u00edsticas dos Protozo\u00e1rios: tipos, estrutura e doen\u00e7as causadas<\/li><li>O que s\u00e3o Mixomicetos<\/li><li>Tudo sobre Algas: tipos, classifica\u00e7\u00f5es, aplicabilidade e exemplos<\/li><\/ol>\n\n\n\n<ul class=\"wp-block-list\"><li>Estudando para as provas? Conhe\u00e7a nosso <a href=\"https:\/\/beduka.com\/blog\/dicas\/enem-dicas\/simulados-para-enem-online-e-gratuito\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">Simulado gratuito<\/a>, que pode ser personalizado com as mat\u00e9rias que voc\u00ea mais precisa!<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">O que \u00e9 Reino Protista e caracter\u00edsticas gerais<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O Reino Protista \u00e9 aquele que agrupa os seres vivos conhecidos como <strong>protozo\u00e1rios <\/strong>(amebas e outros)<strong> , algas e mixomicetos<\/strong>. Esses seres s\u00e3o <strong>muito diversos<\/strong> e costumam ser <strong>os mais primitivos <\/strong>de acordo com a <strong>ordem de estudo dos Reinos:<\/strong><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/beduka.com\/blog\/materias\/biologia\/reino-monera\/\">Reino Monera<\/a>,  <strong>Reino Protista<\/strong>, <a rel=\"noreferrer noopener\" href=\"https:\/\/beduka.com\/blog\/materias\/biologia\/reino-fungi\/\" target=\"_blank\">Reino Fungi<\/a>, <a rel=\"noreferrer noopener\" href=\"https:\/\/beduka.com\/blog\/materias\/biologia\/reino-plantae\/\" target=\"_blank\">Reino Plantae<\/a> e <a rel=\"noreferrer noopener\" href=\"https:\/\/beduka.com\/blog\/materias\/biologia\/resumo-do-reino-animal\/\" target=\"_blank\">Reino Anim\u00e1lia<\/a>. <br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mesmo sendo <strong>muito diferentes entre si<\/strong>, apresentam as seguintes <strong>caracter\u00edsticas gerais:<\/strong><br><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>S\u00e3o <strong>eucariontes<\/strong>, ou seja, apresentam n\u00facleo bem definido e delimitado pela carioteca (tipo de membrana) e possui <a href=\"https:\/\/beduka.com\/blog\/materias\/biologia\/organelas-e-suas-funcoes\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">organelas membranosas<\/a>.<\/li><li><strong>A maioria \u00e9 unicelular <\/strong>e microsc\u00f3pica, no entanto h\u00e1 tamb\u00e9m a presen\u00e7a de organismos <strong>pluricelulares<\/strong> ou que formam <a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/materias\/biologia\/o-que-sao-relacoes-ecologicas\/\" target=\"_blank\">col\u00f4nias<\/a>.<\/li><li>Podem ser de <strong>vida livre<\/strong>, <a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/materias\/biologia\/o-que-e-mutualismo\/\" target=\"_blank\">simbi\u00f3tica<\/a> ou <a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/materias\/biologia\/o-que-sao-relacoes-ecologicas\/\" target=\"_blank\">parasit\u00e1ria<\/a>.<\/li><li><strong>A<\/strong> <strong>maioria \u00e9 aqu\u00e1tica<\/strong>, podendo tamb\u00e9m habitar ambientes <strong>terrestres \u00famidos<\/strong> ou <strong>interior de seres vivos<\/strong>.<\/li><li>Quanto \u00e0 nutri\u00e7\u00e3o, podem ser <strong>heter\u00f3trofos, aut\u00f3trofos<\/strong> (<a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/materias\/biologia\/formula-da-fotossintese\/\" target=\"_blank\">fotoss\u00edntese<\/a>) ou que <strong>realizam<\/strong> <strong>ambas (<\/strong>chamados de <strong>mixotr\u00f3ficos<\/strong>).<\/li><li>As formas de reprodu\u00e7\u00e3o podem ser <strong>sexuadas <\/strong>(biparti\u00e7\u00e3o ou cissiparidade, zoosporia, divis\u00e3o m\u00faltipla ou fragmenta\u00e7\u00e3o) <strong>ou assexuadas <\/strong>(conjun\u00e7\u00e3o, zigosporia ou altern\u00e2ncia de gera\u00e7\u00e3o).<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Ainda que a maioria dos protistas seja unicelular, eles <strong>s\u00e3o capazes de desempenhar todas as fun\u00e7\u00f5es<\/strong> que um ser pluricelular complexo possui, apenas com <strong>uma c\u00e9lula repleta de estruturas especializadas.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Curiosidade e pol\u00eamicas<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Antigamente<\/strong>, os Protistas eram <strong>classificados no reino animal<\/strong> por serem capazes de realizar fun\u00e7\u00f5es complexas e serem de maioria heterotr\u00f3fica. Com o tempo, foi-se descobrindo algas que se encaixavam nesse reino e mais: que eles <strong>possivelmente se originaram de antigas algas unicelulares<\/strong>.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso observou-se que a maioria \u00e9 unicelular, ent\u00e3o os taxonomistas <strong>criaram um reino pr\u00f3prio <\/strong>para agrupar esses seres<strong> t\u00e3o diversos<\/strong>, que s\u00e3o uma <strong>mistura de tudo <\/strong>o que<strong> n\u00e3o \u00e9 100% animal, planta ou fungo!<\/strong><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ainda hoje,<\/strong> depois de v\u00e1rias descobertas e reorganiza\u00e7\u00e3o das classifica\u00e7\u00f5es, as <strong>pol\u00eamicas persistem quanto \u00e0 inclus\u00e3o ou retirada de alguns seres<\/strong> como os mixomicetos, que veremos adiante!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Estrutura da C\u00e9lula Protista<\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"300\" src=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/07\/Estrutura-celular-do-reino-protista.jpg\" alt=\"Estrutura-celular-do-reino-protista vac\u00faolo, mitocondria, n\u00facleo, flagelo e demais organelas\" class=\"wp-image-16962\" srcset=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/07\/Estrutura-celular-do-reino-protista.jpg 600w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/07\/Estrutura-celular-do-reino-protista-300x150.jpg 300w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/07\/Estrutura-celular-do-reino-protista-320x160.jpg 320w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">A c\u00e9lula de um Protista possui <strong>algumas semelhan\u00e7as com as dos animais e plantas<\/strong>, contudo, <strong>tem as suas particularidades<\/strong>:<br><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>As algas do Reino Protista, por exemplo, possuem <strong>plastos que diferem quanto \u00e0 organiza\u00e7\u00e3o interna de membranas<\/strong>, em rela\u00e7\u00e3o aos das plantas.<\/li><li>A c\u00e9lula do protozo\u00e1rio tem uma <strong>membrana que pode ser simples ou refor\u00e7ada,<\/strong> seja com <strong>capas externas prot\u00e9icas ou carapa\u00e7as minerais<\/strong><\/li><li>Por serem majoritariamente unicelulares, suas <strong>formas de locomo\u00e7\u00e3o s\u00e3o sempre as das c\u00e9lulas<\/strong>: c\u00edlios e flagelos.&nbsp;<\/li><li>Alguns protozo\u00e1rios apresentam <strong>esqueleto intracelular<\/strong> composto por s\u00edlica<\/li><li>O <strong>citoplasma<\/strong> <strong>dividido em duas zonas<\/strong>, uma externa (hialina, ectoplasma) e outra interna (granular, endoplasma).&nbsp;<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Digest\u00e3o, Respira\u00e7\u00e3o e Excre\u00e7\u00e3o dos Protistas<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Nas esp\u00e9cies de vida livre, h\u00e1 a forma\u00e7\u00e3o de vac\u00faolos digestivos. As part\u00edculas alimentares s\u00e3o englobadas por pseud\u00f3podos ou penetram por uma abertura na membrana, o cit\u00f3stoma. <strong>No interior da c\u00e9lula ocorre a digest\u00e3o<\/strong> e os res\u00edduos s\u00f3lidos n\u00e3o digeridos, s\u00e3o expelidos por extrus\u00e3o do vac\u00faolo ou num ponto aberto da membrana.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A <strong>troca de gases respirat\u00f3rios<\/strong> se d\u00e1 pelo processo de <a href=\"https:\/\/beduka.com\/blog\/materias\/biologia\/transporte-ativo-e-passivo\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">difus\u00e3o<\/a> e ocorre ao longo de toda a superf\u00edcie celular.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre a <strong>excre\u00e7\u00e3o,<\/strong> quando o metabolismo gera produtos sol\u00faveis, s\u00e3o <strong>eliminados por toda a superf\u00edcie da c\u00e9lula<\/strong>. Por\u00e9m, <strong>nos protozo\u00e1rios de \u00e1gua doce h\u00e1 um vac\u00faolo<\/strong> contr\u00e1til que recolhe o excesso de \u00e1gua absorvido pela c\u00e9lula. Assim, a expulsa de tempos em tempos por uma contra\u00e7\u00e3o brusca, servindo como<strong> osmorregulador.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Import\u00e2ncia dos Protistas no Ecossistema<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O Reino Protista est\u00e1 presente, principalmente, <strong>nos mares<\/strong> e s\u00f3 esse fator j\u00e1 \u00e9 uma pista de sua import\u00e2ncia! Sendo assim, s\u00e3o essenciais para a <a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/materias\/biologia\/cadeia-e-teia-alimentar\/\" target=\"_blank\">cadeia alimentar<\/a> dos seres vivos e muitos<strong> realizam<\/strong><a href=\"https:\/\/beduka.com\/blog\/materias\/biologia\/o-que-e-fotossintese\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\"> fotoss\u00edntese<\/a>, respons\u00e1vel por liberar<strong> oxig\u00eanio na atmosfera e manter a vida na Terra.<\/strong><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Os oceanos s\u00e3o os verdadeiros \u201cpulm\u00f5es do mundo\u201d <\/strong>porque concentram a maior parte dos <strong>pl\u00e2nctons<\/strong>, os seres que vivem quase que exclusivamente para a fotoss\u00edntese. Dessa forma, os pl\u00e2nctons possuem subdivis\u00f5es: fitopl\u00e2nctons e zoopl\u00e2nctons, e algumas das <strong>algas protistas entram na categoria fitopl\u00e2ncton.<\/strong><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 importante ressaltar que<strong> o \u201cpulm\u00e3o do mundo\u201d N\u00c3O \u00e9 a Amaz\u00f4nia, <\/strong>porque esse tipo de floresta<strong> consome a maior parte do que produz. <\/strong>Ela \u00e9 importante e deve ser protegida pela <strong>biodiversidade e termorregula\u00e7\u00e3o<\/strong>, pois \u00e9 respons\u00e1vel pela <strong>temperatura&nbsp; e umidade dos biomas <\/strong>ao redor e pela<strong> cria\u00e7\u00e3o de massa de ar<\/strong> que viajam todo o continente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O que s\u00e3o Protozo\u00e1rios?<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"300\" src=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/07\/Tipos-de-protozo\u00e1rios-e-seus-modos-de-locomo\u00e7\u00e3o-sarcodinos-flagelados-ciliados-amebas-1.jpg\" alt=\"Tipos-de-protozo\u00e1rios-e-seus-modos-de-locomo\u00e7\u00e3o-sarcodinos-flagelados-ciliados-amebas-1\" class=\"wp-image-16976\" srcset=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/07\/Tipos-de-protozo\u00e1rios-e-seus-modos-de-locomo\u00e7\u00e3o-sarcodinos-flagelados-ciliados-amebas-1.jpg 600w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/07\/Tipos-de-protozo\u00e1rios-e-seus-modos-de-locomo\u00e7\u00e3o-sarcodinos-flagelados-ciliados-amebas-1-300x150.jpg 300w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/07\/Tipos-de-protozo\u00e1rios-e-seus-modos-de-locomo\u00e7\u00e3o-sarcodinos-flagelados-ciliados-amebas-1-320x160.jpg 320w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Os protozo\u00e1rios s\u00e3o os <strong>principais representantes do Reino Protista. <\/strong>Todos os representantes <strong>s\u00e3o heter\u00f3trofos<\/strong> e est\u00e3o divididos em 4 <strong>grupos<\/strong> <strong>de acordo com suas formas de locomo\u00e7\u00e3o<\/strong>:<br><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Sarcodinos<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00e3o representados pelas <strong>amebas<\/strong> que se <strong>locomovem por meio de pseud\u00f3podes<\/strong>, podendo ser parasitas ou n\u00e3o, como amebas que habitam o intestino humano sem causar danos e outras que causam.<br><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Ciliados<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Os ciliados <strong>locomovem-se por meio de c\u00edlios<\/strong> localizados ao longo da membrana de toda a c\u00e9lula. O mais conhecido \u00e9 o <strong>param\u00e9cio<\/strong>, organismo de vida livre.<br><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Mastig\u00f3foros<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Os mastig\u00f3foros <strong>locomovem-se por meio de flagelos<\/strong>, podendo ser parasitas ou n\u00e3o. Um exemplo \u00e9 o Trypanosoma cruzi, causador da Doen\u00e7a de Chagas.&nbsp;<br><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Esporozo\u00e1rios<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Os esporozo\u00e1rios <strong>n\u00e3o possuem estrutura locomotora<\/strong>. Um exemplo \u00e9 o agente transmissor da mal\u00e1ria.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Protozooses: doen\u00e7as causadas por protozo\u00e1rios<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Protozoose \u00e9 um termo utilizado para identificar as doen\u00e7as transmitidas por protozo\u00e1rios. Como foi dito, alguns protozo\u00e1rios s\u00e3o <strong>parasitas de animais e dos seres humanos<\/strong>.&nbsp;<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Geralmente s\u00e3o transmitidos por \u00e1gua e alimentos contaminados por fezes<\/strong>, que cont\u00e9m os cistos desses microrganismos, uma forma inativa que permite aos protozo\u00e1rios resistir por longos per\u00edodos no ambiente e que s\u00e3o ativadas no corpo do hospedeiro.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A<\/strong> <a href=\"https:\/\/beduka.com\/blog\/materias\/biologia\/o-que-e-malaria\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">Mal\u00e1ria<\/a><strong> \u00e9 uma exce\u00e7\u00e3o<\/strong>, pois o protozo\u00e1rio \u00e9 transmitido <strong>somente pela picada de inseto. <\/strong>E a<strong> <\/strong><a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/materias\/biologia\/o-que-e-doenca-de-chagas\/\" target=\"_blank\">Doen\u00e7a de chagas<\/a><strong> <\/strong>pode ocorrer pelas duas formas. Leia nossos artigos para saber mais dessas importantes <a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/materias\/biologia\/doencas-que-mais-caem-no-enem\/\" target=\"_blank\">doen\u00e7as que caem no Enem<\/a>!<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A <strong>maior ocorr\u00eancia <\/strong>dessas doen\u00e7as se d\u00e1<strong> nos pa\u00edses pobres<\/strong>, isso porque<strong> falta saneamento b\u00e1sico, tratamento eficiente da \u00e1gua<\/strong> e <strong>falta de h\u00e1bitos de higiene<\/strong> e <strong>conscientiza\u00e7\u00e3o.<\/strong><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conhe\u00e7a o resumo de <strong>outras doen\u00e7as<\/strong> causadas por protozo\u00e1rios:<br><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Ameb\u00edase<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">A ameb\u00edase ou <strong>disenteria amebiana<\/strong> \u00e9 provocada pela <strong>ameba Entamoeba histolytica<\/strong>. A transmiss\u00e3o ocorre principalmente por meio da ingest\u00e3o da \u00e1gua ou dos <strong>alimentos contaminados<\/strong> e <strong>tamb\u00e9m pode ser por via sexual,<\/strong> atrav\u00e9s do contato oral-anal, mas isso \u00e9 mais raro. Gera <strong>dores de barriga e diarr\u00e9ia<\/strong>, podendo agravar em <strong>desidrata\u00e7\u00e3o<\/strong>.<br><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Giard\u00edase<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">O agente causador da giard\u00edase \u00e9 o <strong>protozo\u00e1rio flagelado Giardia lamblia<\/strong>, cujos cistos s\u00e3o eliminados nas <strong>fezes das pessoas contaminadas<\/strong>. A infec\u00e7\u00e3o se d\u00e1 tanto pela ingest\u00e3o de \u00e1gua e alimentos contaminados, como pelo contato direto das m\u00e3os com objetos contaminados. Tamb\u00e9m \u00e9 uma doen\u00e7a que <strong>afeta o Intestino.<\/strong><br><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Tricomon\u00edase<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">A tricomon\u00edase \u00e9 uma <strong>Infec\u00e7\u00e3o sexualmente transmiss\u00edvel <\/strong>(IST) causada pelo <strong>Trichomonas vaginalis<\/strong> que pode atingir tanto homens quanto mulheres. Adquire-se por meio de <strong>qualquer tipo de sexo sem prote\u00e7\u00e3o feito com algu\u00e9m contaminado.&nbsp;<\/strong><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Outras <strong>IST\u2019s famosas<\/strong> que <strong>n\u00e3o s\u00e3o causadas por protozo\u00e1rios<\/strong> s\u00e3o: <a href=\"https:\/\/beduka.com\/blog\/materias\/biologia\/o-que-e-hiv\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">AIDS<\/a> e <a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/materias\/biologia\/o-que-e-sifilis\/\" target=\"_blank\">S\u00edfilis<\/a>.<br><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Toxoplasmose<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">A <a href=\"https:\/\/www.saude.gov.br\/saude-de-a-z\/toxoplasmose\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">toxoplasmose<\/a> \u00e9 uma doen\u00e7a causada pelo <strong>protozo\u00e1rio Toxoplasma gondii <\/strong>encontrado nas <strong>fezes de gatos, <\/strong>al\u00e9m de poder ser<strong> <\/strong>contaminado ao <strong>consumir carne de aves e mam\u00edferos mal passadas<\/strong> <strong>e contaminadas. <\/strong>A doen\u00e7a pode ainda ser <strong>cong\u00eanita <\/strong>quando gestantes s\u00e3o infectadas e os seus <strong>sintomas s\u00e3o vari\u00e1veis.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">As Algas, seus tipos e aplicabilidade!<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"300\" src=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/07\/tipos-de-alga-do-reino-protistas-algas-vermelhasalgas-douradas-algas-pardas-algas-verdes.jpg\" alt=\"tipos-de-alga-do-reino-protistas-algas-vermelhasalgas-douradas-algas-pardas-algas-verdes\" class=\"wp-image-16964\" srcset=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/07\/tipos-de-alga-do-reino-protistas-algas-vermelhasalgas-douradas-algas-pardas-algas-verdes.jpg 600w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/07\/tipos-de-alga-do-reino-protistas-algas-vermelhasalgas-douradas-algas-pardas-algas-verdes-300x150.jpg 300w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/07\/tipos-de-alga-do-reino-protistas-algas-vermelhasalgas-douradas-algas-pardas-algas-verdes-320x160.jpg 320w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">As algas s\u00e3o tamb\u00e9m <strong>representantes do Reino Protista<\/strong> e s\u00e3o <strong>todas aut\u00f3trofas<\/strong>, pois t\u00eam clorofila e outros pigmentos, logo, realizam <a href=\"https:\/\/beduka.com\/blog\/materias\/biologia\/o-que-e-fotossintese\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">fotoss\u00edntese<\/a>. S\u00e3o <strong>divididas em 5 grupos de acordo com o pigmento<\/strong> mais abundante.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Inicialmente foram classificadas no Reino Plantae<\/strong> por causa de algumas semelhan\u00e7as, <strong>mas como s\u00e3o organismos mais simples <\/strong>e <strong>n\u00e3o possuem tecidos<\/strong> organizados, foram <strong>reagrupadas no Reino Protista.<\/strong><br><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Algas verdes ou Clorof\u00edceas<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00e3o caracterizadas pela presen\u00e7a de <strong>clorofilas A e B,<\/strong> caroten\u00f3ides e parede celular de celulose (reservas de amido). Podem ser <strong>uni ou pluricelulares<\/strong> e as <strong>esp\u00e9cies comest\u00edveis<\/strong> s\u00e3o pertencentes a esse grupo.<br><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Algas vermelhas ou Rodof\u00edceas<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">As algas vermelhas apresentam <strong>clorofila A e ficobilina<\/strong>, <strong>uni ou pluricelulares<\/strong>, s\u00e3o <strong>filamentosas e fixadas a substratos<\/strong>. Tamb\u00e9m existem <strong>esp\u00e9cies comest\u00edveis<\/strong>, embora n\u00e3o sejam t\u00e3o famosas quanto as verdes.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algumas t\u00eam nas paredes de suas c\u00e9lulas o<strong> \u00e1gar<\/strong>, subst\u00e2ncia <strong>gelatinosa <\/strong>que \u00e9 acrescentada a <strong>v\u00e1rios alimentos, como balas e doces<\/strong>. Tamb\u00e9m possuem utilidade em <strong>t\u00e9cnicas laboratoriais<\/strong> como componente de meios de cultura.<br><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Algas Pardas ou Feof\u00edceas<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">As algas pardas s\u00e3o caracterizadas pela presen\u00e7a de <strong>clorofilas A e C<\/strong>, <strong>caroten\u00f3ides e fucoxantina<\/strong>. Elas s\u00e3o <strong>pluricelulares <\/strong>e existem <strong>esp\u00e9cies comest\u00edveis<\/strong>.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sua parede celular tem um polissacar\u00eddeo chamado <strong>algina, <\/strong>que \u00e9 utilizado no alginato empregado na <strong>fabrica\u00e7\u00e3o de cosm\u00e9ticos, sorvetes e massa de modelagem<\/strong> utilizada na odontologia.<br><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Algas Douradas ou Crisof\u00edceas<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">As algas douradas possuem formas <strong>unicelulares isoladas ou coloniais<\/strong>, sendo <strong>importantes componentes do pl\u00e2ncton<\/strong>.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A <strong>diatom\u00e1cea <\/strong>\u00e9 uma alga que cont\u00eam o diatomito,formado por s\u00edlica e empregado como <strong>componente de filtros<\/strong>. Quando pulverizado, ele pode ser adicionado como abrasivo a <strong>polidores de metal e a cremes dentais.<\/strong><br><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Pirrof\u00edceas<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">As pirrof\u00edceas s\u00e3o algas<strong> unicelulares isoladas ou coloniais.<\/strong> Elas <strong>fazem parte do fitopl\u00e2ncton<\/strong> e incluem tamb\u00e9m os <strong>dinoflagelados<\/strong>, respons\u00e1veis pelo <strong>fen\u00f4meno da<\/strong> <a href=\"https:\/\/www.google.com.br\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=&amp;cad=rja&amp;uact=8&amp;ved=2ahUKEwii672np8vqAhW3IrkGHZUUC-QQFjALegQIAhAB&amp;url=https%3A%2F%2Fsuper.abril.com.br%2Fmundo-estranho%2Fo-que-e-mare-vermelha%2F&amp;usg=AOvVaw184pvzCwcYZviobFqAqWeu\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">mar\u00e9 vermelha.<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Mixomicetos<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"300\" src=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/07\/Mixomicetos-seres-do-Reino-Protista.jpg\" alt=\"Mixomicetos-seres-do-Reino-Protista\" class=\"wp-image-16965\" srcset=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/07\/Mixomicetos-seres-do-Reino-Protista.jpg 600w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/07\/Mixomicetos-seres-do-Reino-Protista-300x150.jpg 300w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/07\/Mixomicetos-seres-do-Reino-Protista-320x160.jpg 320w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Os Mixomicetos s\u00e3o uma grande pol\u00eamica! Eles s\u00e3o organismos com <strong>aspectos f\u00edsicos e reprodutivos de fungo<\/strong>, crescendo em <strong>solos ricos em nutrientes org\u00e2nicos<\/strong> (bosques e florestas). Eles possuem caracter\u00edsticas misturadas de bact\u00e9rias tamb\u00e9m, mas <strong>n\u00e3o realizam decomposi\u00e7\u00e3o, s\u00e3o predadores.<\/strong><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eles <strong>n\u00e3o s\u00e3o parasitas, n\u00e3o produzem toxinas, nem s\u00e3o prejudiciais \u00e0s plantas ou animais<\/strong>.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Contudo, quando surgem na \u00e1gua, s\u00e3o <strong>indicadores de que h\u00e1 algum desequil\u00edbrio<\/strong> no ambiente, pois s\u00f3 vivem em locais com <strong>excesso de mat\u00e9ria org\u00e2nica<\/strong>, o que \u00e9 prejudicial para \u00e1gua.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Existem <strong>muitas controv\u00e9rsias sobre esse grupo<\/strong>, os dados ainda n\u00e3o s\u00e3o conclusivos e <strong>alguns classificam no Reino Protista, enquanto outros consideram que deveriam compor um reino \u00e0 parte.<\/strong><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gostou do nosso artigo sobre o Reino Protista? Confira <strong>outros artigos <\/strong>do nosso blog e <strong>se prepare para o Enem<\/strong> da melhor maneira! Voc\u00ea tamb\u00e9m pode se organizar com o nosso<a href=\"https:\/\/beduka.com\/blog\/dicas\/enem-dicas\/plano-de-estudos-gratuito\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\"> plano de estudos<\/a>, o mais completo da internet, e o melhor: <strong>totalmente gratuito!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Queremos te ajudar a encontrar a FACULDADE IDEAL! Logo abaixo, fa\u00e7a uma pesquisa por curso e cidade que te mostraremos todas as faculdades que podem te atender. Informamos a nota de corte, valor de mensalidade, nota do MEC, avalia\u00e7\u00e3o dos alunos, modalidades de ensino e muito mais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Experimente agora!<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Reino Protista \u00e9 formado por seres eucariontes, de maioria unicelular embora haja pluricelulares e que podem ser heter\u00f3trofos ou aut\u00f3trofos fotossintetizantes. Seus principais representantes s\u00e3o os protozo\u00e1rios, as algas inferiores e os mixomicetos. Com toda essa diversidade de seres e fun\u00e7\u00f5es, h\u00e1 pol\u00eamicas que rondam a classifica\u00e7\u00e3o desses seres! Neste artigo sobre o Reino [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16961,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[495],"tags":[],"class_list":["post-16960","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-biologia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Resumo do Reino Protista: tudo o que voc\u00ea precisa saber!<\/title>\n<meta name=\"description\" content=\"Reino Protista: mat\u00e9ria COMPLETA: representantes, caracter\u00edsticas, estruturas celulares, fun\u00e7\u00f5es, como reproduzem, doen\u00e7as causadas + pol\u00eamica!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beduka.com\/blog\/materias\/biologia\/reino-protista\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resumo do Reino Protista: tudo o que voc\u00ea precisa saber!\" \/>\n<meta property=\"og:description\" content=\"Reino Protista: mat\u00e9ria COMPLETA: representantes, caracter\u00edsticas, estruturas celulares, fun\u00e7\u00f5es, como reproduzem, doen\u00e7as causadas + pol\u00eamica!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beduka.com\/blog\/materias\/biologia\/reino-protista\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-18T01:42:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-29T11:52:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/07\/Tudo-o-que-voc\u00ea-precisa-saber-sobre-o-que-\u00e9-Reino-Protista.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/biologia\\\/reino-protista\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/biologia\\\/reino-protista\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/person\\\/325d912d2cb8dd9ede8ab291427d2b8a\"},\"headline\":\"Resumo completo com tudo o que precisa para conhecer o Reino Protista!\",\"datePublished\":\"2020-07-18T01:42:01+00:00\",\"dateModified\":\"2020-07-29T11:52:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/biologia\\\/reino-protista\\\/\"},\"wordCount\":2055,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/biologia\\\/reino-protista\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Tudo-o-que-voc\u00ea-precisa-saber-sobre-o-que-\u00e9-Reino-Protista.jpg\",\"articleSection\":[\"Biologia\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/biologia\\\/reino-protista\\\/\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/biologia\\\/reino-protista\\\/\",\"name\":\"Resumo do Reino Protista: tudo o que voc\u00ea precisa saber!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/biologia\\\/reino-protista\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/biologia\\\/reino-protista\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Tudo-o-que-voc\u00ea-precisa-saber-sobre-o-que-\u00e9-Reino-Protista.jpg\",\"datePublished\":\"2020-07-18T01:42:01+00:00\",\"dateModified\":\"2020-07-29T11:52:09+00:00\",\"description\":\"Reino Protista: mat\u00e9ria COMPLETA: representantes, caracter\u00edsticas, estruturas celulares, fun\u00e7\u00f5es, como reproduzem, doen\u00e7as causadas + pol\u00eamica!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/biologia\\\/reino-protista\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/biologia\\\/reino-protista\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/biologia\\\/reino-protista\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Tudo-o-que-voc\u00ea-precisa-saber-sobre-o-que-\u00e9-Reino-Protista.jpg\",\"contentUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Tudo-o-que-voc\u00ea-precisa-saber-sobre-o-que-\u00e9-Reino-Protista.jpg\",\"width\":600,\"height\":300,\"caption\":\"Tudo o que voc\u00ea precisa saber sobre o que \u00e9 Reino Protista!\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/biologia\\\/reino-protista\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/beduka.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resumo completo com tudo o que precisa para conhecer o Reino Protista!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/\",\"name\":\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\",\"description\":\"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!\",\"publisher\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beduka.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#organization\",\"name\":\"Beduka\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/marca-beduka.png\",\"contentUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/marca-beduka.png\",\"width\":1077,\"height\":368,\"caption\":\"Beduka\"},\"image\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/beduka.buscadordefaculdades\\\/\",\"https:\\\/\\\/www.instagram.com\\\/beduka_oficial\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/beduka\",\"https:\\\/\\\/br.pinterest.com\\\/bedukaoficial\\\/\",\"https:\\\/\\\/www.youtube.com\\\/beduka\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/person\\\/325d912d2cb8dd9ede8ab291427d2b8a\",\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o Beduka (a)\"},\"description\":\"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/beduka.buscadordefaculdades\",\"https:\\\/\\\/www.instagram.com\\\/beduka_oficial\\\/\",\"https:\\\/\\\/br.pinterest.com\\\/bedukaoficial\\\/\"],\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Resumo do Reino Protista: tudo o que voc\u00ea precisa saber!","description":"Reino Protista: mat\u00e9ria COMPLETA: representantes, caracter\u00edsticas, estruturas celulares, fun\u00e7\u00f5es, como reproduzem, doen\u00e7as causadas + pol\u00eamica!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beduka.com\/blog\/materias\/biologia\/reino-protista\/","og_locale":"pt_BR","og_type":"article","og_title":"Resumo do Reino Protista: tudo o que voc\u00ea precisa saber!","og_description":"Reino Protista: mat\u00e9ria COMPLETA: representantes, caracter\u00edsticas, estruturas celulares, fun\u00e7\u00f5es, como reproduzem, doen\u00e7as causadas + pol\u00eamica!","og_url":"https:\/\/beduka.com\/blog\/materias\/biologia\/reino-protista\/","og_site_name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","article_publisher":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","article_author":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades","article_published_time":"2020-07-18T01:42:01+00:00","article_modified_time":"2020-07-29T11:52:09+00:00","og_image":[{"width":600,"height":300,"url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/07\/Tudo-o-que-voc\u00ea-precisa-saber-sobre-o-que-\u00e9-Reino-Protista.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Beduka (a)","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Beduka (a)","Est. tempo de leitura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beduka.com\/blog\/materias\/biologia\/reino-protista\/#article","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/materias\/biologia\/reino-protista\/"},"author":{"name":"Reda\u00e7\u00e3o Beduka (a)","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a"},"headline":"Resumo completo com tudo o que precisa para conhecer o Reino Protista!","datePublished":"2020-07-18T01:42:01+00:00","dateModified":"2020-07-29T11:52:09+00:00","mainEntityOfPage":{"@id":"https:\/\/beduka.com\/blog\/materias\/biologia\/reino-protista\/"},"wordCount":2055,"commentCount":0,"publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"image":{"@id":"https:\/\/beduka.com\/blog\/materias\/biologia\/reino-protista\/#primaryimage"},"thumbnailUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/07\/Tudo-o-que-voc\u00ea-precisa-saber-sobre-o-que-\u00e9-Reino-Protista.jpg","articleSection":["Biologia"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/beduka.com\/blog\/materias\/biologia\/reino-protista\/","url":"https:\/\/beduka.com\/blog\/materias\/biologia\/reino-protista\/","name":"Resumo do Reino Protista: tudo o que voc\u00ea precisa saber!","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beduka.com\/blog\/materias\/biologia\/reino-protista\/#primaryimage"},"image":{"@id":"https:\/\/beduka.com\/blog\/materias\/biologia\/reino-protista\/#primaryimage"},"thumbnailUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/07\/Tudo-o-que-voc\u00ea-precisa-saber-sobre-o-que-\u00e9-Reino-Protista.jpg","datePublished":"2020-07-18T01:42:01+00:00","dateModified":"2020-07-29T11:52:09+00:00","description":"Reino Protista: mat\u00e9ria COMPLETA: representantes, caracter\u00edsticas, estruturas celulares, fun\u00e7\u00f5es, como reproduzem, doen\u00e7as causadas + pol\u00eamica!","breadcrumb":{"@id":"https:\/\/beduka.com\/blog\/materias\/biologia\/reino-protista\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beduka.com\/blog\/materias\/biologia\/reino-protista\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/materias\/biologia\/reino-protista\/#primaryimage","url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/07\/Tudo-o-que-voc\u00ea-precisa-saber-sobre-o-que-\u00e9-Reino-Protista.jpg","contentUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/07\/Tudo-o-que-voc\u00ea-precisa-saber-sobre-o-que-\u00e9-Reino-Protista.jpg","width":600,"height":300,"caption":"Tudo o que voc\u00ea precisa saber sobre o que \u00e9 Reino Protista!"},{"@type":"BreadcrumbList","@id":"https:\/\/beduka.com\/blog\/materias\/biologia\/reino-protista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/beduka.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Resumo completo com tudo o que precisa para conhecer o Reino Protista!"}]},{"@type":"WebSite","@id":"https:\/\/beduka.com\/blog\/#website","url":"https:\/\/beduka.com\/blog\/","name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","description":"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!","publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beduka.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beduka.com\/blog\/#organization","name":"Beduka","url":"https:\/\/beduka.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","contentUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","width":1077,"height":368,"caption":"Beduka"},"image":{"@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/www.linkedin.com\/company\/beduka","https:\/\/br.pinterest.com\/bedukaoficial\/","https:\/\/www.youtube.com\/beduka"]},{"@type":"Person","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a","name":"Reda\u00e7\u00e3o Beduka (a)","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o Beduka (a)"},"description":"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.","sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/br.pinterest.com\/bedukaoficial\/"],"url":"https:\/\/beduka.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/16960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/comments?post=16960"}],"version-history":[{"count":4,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/16960\/revisions"}],"predecessor-version":[{"id":17151,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/16960\/revisions\/17151"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media\/16961"}],"wp:attachment":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media?parent=16960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/categories?post=16960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/tags?post=16960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}