{"id":17843,"date":"2020-09-10T21:12:11","date_gmt":"2020-09-11T00:12:11","guid":{"rendered":"https:\/\/beduka.com\/blog\/?p=17843"},"modified":"2020-09-10T21:19:49","modified_gmt":"2020-09-11T00:19:49","slug":"exercicios-escala","status":"publish","type":"post","link":"https:\/\/beduka.com\/blog\/exercicios\/matematica-exercicios\/exercicios-escala\/","title":{"rendered":"Exerc\u00edcios de Escala com Gabarito"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote\"><p><strong><em>A raz\u00e3o constante que permite uma compara\u00e7\u00e3o entre qualquer grandeza, \u00e9 chamada de escala. Ela \u00e9 um mecanismo utilizado para representar algo de maneira proporcional, como, por exemplo, representar um territ\u00f3rio em um mapa. Leia nosso resumo e coloque seu conhecimento em pr\u00e1tica com nossa lista de Exerc\u00edcios de Escala selecionados dos maiores vestibulares do Brasil. <\/em><\/strong><\/p><\/blockquote>\n\n\n\n<p>Quando voc\u00ea terminar os <strong>Exerc\u00edcios de Escala<\/strong>, fa\u00e7a nosso <a href=\"https:\/\/beduka.com\/simulado-enem\/#\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">Simulado Enem<\/a>. Coloque em pr\u00e1tica todo o seu estudo, escolhendo as mat\u00e9rias que deseja praticar.<\/p>\n\n\n\n<p>Quando voc\u00ea abre um mapa f\u00edsico ou o <a href=\"https:\/\/www.google.com\/maps\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">Google Maps<\/a>, <strong>os tamanhos dos territ\u00f3rios n\u00e3o s\u00e3o escolhidos aleatoriamente.<\/strong>&nbsp;<\/p>\n\n\n\n<p>Eles possuem uma escala, ou seja, <strong>cada cm do mapa corresponde a um tamanho maior no espa\u00e7o real.<\/strong><\/p>\n\n\n\n<ul><li>A Terra e seus espa\u00e7os s\u00e3o representados pelas <a href=\"https:\/\/beduka.com\/blog\/exercicios\/geografia-exercicios\/exercicios-sobre-projecoes-cartograficas\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">Proje\u00e7\u00f5es Cartogr\u00e1ficas<\/a>.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">O que \u00e9 Escala?<\/h2>\n\n\n\n<p><strong>\u00c9 chamada de escala a raz\u00e3o constante que permite uma compara\u00e7\u00e3o entre qualquer grandeza.<\/strong> Ela \u00e9 um mecanismo utilizado para representar algo de maneira proporcional, como, por exemplo, representar um territ\u00f3rio em um mapa.<\/p>\n\n\n\n<p>A escala utilizada para representar mapas \u00e9 denominada de <strong>Escala Cartogr\u00e1fica.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como representar uma escala?<\/h2>\n\n\n\n<p>A forma de representar uma escala \u00e9 a seguinte:<\/p>\n\n\n\n<ul><li><strong>Escala = <\/strong>tamanho na imagem<strong> \/<\/strong> tamanho no objeto real<\/li><\/ul>\n\n\n\n<p>Tamb\u00e9m pode ser representado por:<\/p>\n\n\n\n<ul><li><strong>Escala =<\/strong> medida na imagem <strong>:<\/strong> medida no objeto real<\/li><\/ul>\n\n\n\n<p>Vamos pensar em um mapa que tem a escala <strong>1:70<\/strong>, isso nos mostra que a cada <strong>1cm<\/strong> de desenho no mapa, equivale a <strong>70 cm<\/strong> no objeto real.<\/p>\n\n\n\n<p>Logo, a partir dessa escala, se uma casa tivesse <strong>8 cm de comprimento<\/strong> em uma parede, ela teria <strong>560 cm, ou 5,6m, de comprimento na realidade<\/strong>.<\/p>\n\n\n\n<p><strong>Lembrando que eu posso informar a minha escala j\u00e1 convertendo as unidades de medida<\/strong>, por exemplo, informando ao leitor do mapa que 1 cm no mapa equivale a 0,7m na vida real.<\/p>\n\n\n\n<p><strong>Tudo o que importa<\/strong> quando falamos sobre escala, \u00e9 manter a propor\u00e7\u00e3o adequada e constante.&nbsp;<\/p>\n\n\n\n<p>Caso aumente no mapa, aumenta proporcionalmente a \u00e1rea da vida real que est\u00e1 sendo representada.<\/p>\n\n\n\n<p>Depois de entender a teoria por tr\u00e1s da escala matem\u00e1tica, <strong>voc\u00ea perceber\u00e1 que calcul\u00e1-la \u00e9 muito simples.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como calcular uma escala?<\/h2>\n\n\n\n<p>A escala matem\u00e1tica ou cartogr\u00e1fica \u00e9 calculada pela seguinte equa\u00e7\u00e3o:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" loading=\"lazy\" width=\"600\" height=\"300\" src=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/09\/f\u00f3rmula.jpg\" alt=\"Equa\u00e7\u00e3o de Escala\" class=\"wp-image-17846\" srcset=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/09\/f\u00f3rmula.jpg 600w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/09\/f\u00f3rmula-300x150.jpg 300w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/09\/f\u00f3rmula-320x160.jpg 320w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n\n\n\n<p><strong>Exemplo:<\/strong><\/p>\n\n\n\n<p>Um mapa possui uma escala de <strong>1:400000<\/strong>, ou seja, a cada <strong>1 cm<\/strong> de mapa, eu tenho <strong>400.000 cm<\/strong> de territ\u00f3rio real.&nbsp;<\/p>\n\n\n\n<p>Supondo que o peda\u00e7o que n\u00f3s desejamos descobrir o tamanho no mapa, tem <strong>8 cent\u00edmetros<\/strong>.<\/p>\n\n\n\n<p>Devemos aplicar a f\u00f3rmula para <strong>descobrir quanto de tamanho real, 8 cent\u00edmetros de mapa representa:<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" loading=\"lazy\" width=\"600\" height=\"300\" src=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/09\/conta.jpg\" alt=\"Equa\u00e7\u00e3o de Escala\" class=\"wp-image-17847\" srcset=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/09\/conta.jpg 600w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/09\/conta-300x150.jpg 300w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/09\/conta-320x160.jpg 320w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n\n\n\n<p><strong>Dica: <\/strong>\u00e9 poss\u00edvel acelerar o processo, simplificando 8\/400000 por 8, da seguinte forma<strong>:&nbsp;<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" loading=\"lazy\" width=\"600\" height=\"300\" src=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/09\/conta-2.jpg\" alt=\"Equa\u00e7\u00e3o de Escala\" class=\"wp-image-17848\" srcset=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/09\/conta-2.jpg 600w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/09\/conta-2-300x150.jpg 300w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/09\/conta-2-320x160.jpg 320w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n\n\n\n<ul><li>Para aprender escala, \u00e9 necess\u00e1rio saber <a href=\"https:\/\/beduka.com\/blog\/materias\/matematica\/o-que-e-fracao\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">o que \u00e9 fra\u00e7\u00e3o<\/a>!<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Quais os tipos de escalas?<\/h2>\n\n\n\n<ul><li><strong>Escala ampliada:<\/strong> Quando o tamanho da <strong>representa\u00e7\u00e3o \u00e9 maior do que o objeto real.<\/strong> Muito utilizada para representar objetos muito pequenos (c\u00e9lulas, ossos, anatomias vegetais, etc&#8230;) ou detalhes de lugares (quinas de uma casa ou pe\u00e7as eletr\u00f4nicas, por exemplo).<\/li><\/ul>\n\n\n\n<ul><li><strong>Escala reduzida:<\/strong> quando o<strong> tamanho real \u00e9 maior do que a representa\u00e7\u00e3o.<\/strong> Por exemplo, o mapa mundi ou o Google Maps citados anteriormente.<\/li><\/ul>\n\n\n\n<ul><li><strong>Escala natural:<\/strong> quando a <strong>representa\u00e7\u00e3o \u00e9 exatamente igual ao objeto real.<\/strong> Por exemplo, a escala da confec\u00e7\u00e3o de bonecos de cera de&nbsp; famosos que existem em v\u00e1rios lugares do mundo.<\/li><\/ul>\n\n\n\n<p>Depois de fazer os Exerc\u00edcios de Escala, que tal afiar seu conhecimento com<a href=\"https:\/\/beduka.com\/blog\/exercicios\/exercicios-de-fracao\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\"> Exerc\u00edcios de Fra\u00e7\u00e3o?<\/a>&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Exerc\u00edcios de Escala com Gabarito<\/h2>\n\n\n\n<p>Chegou o momento de colocar na pr\u00e1tica todo o seu conhecimento fazendo <strong>exerc\u00edcios de Escala.<\/strong>&nbsp;<\/p>\n\n\n\n<p><strong>Parab\u00e9ns<\/strong> por ter lido at\u00e9 aqui!!!&nbsp;<\/p>\n\n\n\n<p><strong>Baixe gratuitamente <\/strong>o <a href=\"https:\/\/beduka.com\/blog\/dicas\/enem-dicas\/plano-de-estudos-gratuito\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">Plano de Estudos<\/a> do Beduka e <strong>tenha uma prepara\u00e7\u00e3o perfeita para o ENEM.<\/strong><\/p>\n\n\n\n<p><strong>Quest\u00e3o 1 &#8211;<\/strong> <a href=\"https:\/\/enem.inep.gov.br\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">(ENEM)<\/a> Sabe-se que a dist\u00e2ncia real, em linha reta, de uma cidade A, localizada no estado de S\u00e3o Paulo, a uma cidade B, localizada no estado de Alagoas, \u00e9 igual a 2 000 km. Um estudante, ao analisar um mapa, verificou com sua r\u00e9gua que a dist\u00e2ncia entre essas duas cidades, A e B, era 8 cm.<\/p>\n\n\n\n<p>Os dados nos indicam que o mapa observado pelo estudante est\u00e1 na escala de<\/p>\n\n\n\n<p><strong>a) <\/strong>1 : 250.<\/p>\n\n\n\n<p><strong>b)<\/strong> 1 : 2 500.<\/p>\n\n\n\n<p><strong>c)<\/strong> 1 : 25 000.<\/p>\n\n\n\n<p><strong>d) <\/strong>1 : 250 000.<\/p>\n\n\n\n<p><strong>e)<\/strong> 1 : 25 000 000.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 2 &#8211;<\/strong> <a href=\"https:\/\/www.mackenzieinvestments.com\/en\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">(Mackenzie)<\/a> Considerando que a dist\u00e2ncia real entre Yokohama e Fukushima, duas importantes localidades, onde ser\u00e3o realizadas competi\u00e7\u00f5es dos Jogos Ol\u00edmpicos de Ver\u00e3o 2020 \u00e9 de 270 quil\u00f4metros, em um mapa, na escala de 1:1.500.000, essa dist\u00e2ncia seria de<\/p>\n\n\n\n<p><strong>a) <\/strong>1,8 cm<\/p>\n\n\n\n<p><strong>b)<\/strong> 40,5 cm<\/p>\n\n\n\n<p><strong>c) <\/strong>1,8 m<\/p>\n\n\n\n<p><strong>d) <\/strong>18 cm<\/p>\n\n\n\n<p><strong>e)<\/strong> 4,05 m<\/p>\n\n\n\n<p><strong>Quest\u00e3o 3 &#8211; <\/strong><a href=\"https:\/\/www.ufpb.br\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">(UFPB)<\/a><strong> <\/strong>Escala gr\u00e1fica, segundo Vesentini e Vlach (1996, p. 50), &#8220;\u00e9 aquela que expressa diretamente os valores da realidade mapeada num gr\u00e1fico situado na parte inferior de um mapa&#8221;. Nesse sentido, considerando que a escala de um mapa est\u00e1 representada como 1:25000 e que duas cidades, A e B, nesse mapa, est\u00e3o distantes, entre si, 5 cm, a dist\u00e2ncia real entre essas cidades \u00e9 de:<\/p>\n\n\n\n<p><strong>a)<\/strong> 25.000 m<\/p>\n\n\n\n<p><strong>b)<\/strong> 1 .250 m<\/p>\n\n\n\n<p><strong>c)<\/strong> 12.500 m<\/p>\n\n\n\n<p><strong>d)<\/strong> 500 m<\/p>\n\n\n\n<p><strong>e)<\/strong> 250 m<\/p>\n\n\n\n<p><strong>Quest\u00e3o 4 &#8211; <\/strong><a href=\"https:\/\/www.unesp.br\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">(UNESP)<\/a> A escala cartogr\u00e1fica define a proporcionalidade entre a superf\u00edcie do terreno e sua representa\u00e7\u00e3o no mapa, podendo ser apresentada de modo gr\u00e1fico ou num\u00e9rico.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/lh6.googleusercontent.com\/U4fl-xhCLNgKVoEsGbJbn23RheMCNyLdUBi-OznLPQbLHIsa5sB_8N1GQW1NtqitOLjL1z0sEJuPYWuXZZ-914smpLjR6MgSGeEuDyESLXJHPJORjRnZg8ttDAicZCmK_oLBCD8r\" alt=\"Escala gr\u00e1fica - quest\u00e3o UNESP 2017\"\/><\/figure><\/div>\n\n\n\n<p>A escala num\u00e9rica correspondente \u00e0 escala gr\u00e1fica apresentada \u00e9:<\/p>\n\n\n\n<p><strong>a)<\/strong> 1:184 500 000.<\/p>\n\n\n\n<p><strong>b)<\/strong> 1:615 000.<\/p>\n\n\n\n<p><strong>c)<\/strong> 1:1 845 000.<\/p>\n\n\n\n<p><strong>d)<\/strong> 1:123 000 000.<\/p>\n\n\n\n<p><strong>e) <\/strong>1:61 500 000.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 5 &#8211; <\/strong><a href=\"https:\/\/www.pucrs.br\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">(PUC &#8211; RS)<\/a> INSTRU\u00c7\u00c3O: Imagine que voc\u00ea tem diante de si dois mapas que representam a \u00e1rea urbana do Munic\u00edpio de Porto Alegre, de acordo com as escalas seguintes:<\/p>\n\n\n\n<p><strong>\u2022 Mapa 1 \u2013 escala 1:50.000<\/strong><\/p>\n\n\n\n<p><strong>\u2022 Mapa 2 \u2013 escala 1:1.000.000<\/strong><\/p>\n\n\n\n<p>Com base nesses dados, \u00e9 correto afirmar que:<\/p>\n\n\n\n<p><strong>a) <\/strong>Em ambos os mapas ocorre uma representa\u00e7\u00e3o rica em detalhes, o que facilita a leitura dos elementos urbanos que constituem a cidade.<\/p>\n\n\n\n<p><strong>b)<\/strong>A escala do mapa 1 \u00e9 mais recomendada para planisf\u00e9rios que fazem parte de atlas escolares.<\/p>\n\n\n\n<p><strong>c)<\/strong>Um mapa na escala 1:500 possibilita a representa\u00e7\u00e3o da \u00e1rea urbana de Porto Alegre com mais detalhes que os mapas 1 e 2.<\/p>\n\n\n\n<p><strong>d)<\/strong>O mapa 2, por ser maior que o mapa 1, \u00e9 mais favor\u00e1vel \u00e0 representa\u00e7\u00e3o de detalhes que este \u00faltimo.<\/p>\n\n\n\n<p><strong>e)<\/strong>A riqueza de detalhes que um mapa pode representar n\u00e3o depende da escala, e sim da qualidade da legenda.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 6 &#8211;<\/strong> <a href=\"https:\/\/www.unicamp.br\/unicamp\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">(Unicamp)<\/a> Escala, em cartografia, \u00e9 a rela\u00e7\u00e3o matem\u00e1tica entre as dimens\u00f5es reais do objeto e a sua representa\u00e7\u00e3o no mapa. Assim, em um mapa de escala 1:50.000, uma cidade que tem 4,5 Km de extens\u00e3o entre seus extremos ser\u00e1 representada com<\/p>\n\n\n\n<p><strong>a)<\/strong> 9 cm.<\/p>\n\n\n\n<p><strong>b)<\/strong> 90 cm.<\/p>\n\n\n\n<p><strong>c)<\/strong> 225 mm.<\/p>\n\n\n\n<p><strong>d)<\/strong> 11 mm.<\/p>\n\n\n\n<p><strong>Quest\u00e3o 7 &#8211;<\/strong> <a href=\"https:\/\/www.uerj.br\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">(UERJ)<\/a> Naquele Imp\u00e9rio, a arte da cartografia alcan\u00e7ou tal perfei\u00e7\u00e3o que o mapa de uma \u00fanica prov\u00edncia ocupava uma cidade inteira, e o mapa do Imp\u00e9rio uma prov\u00edncia inteira. Com o tempo, estes mapas desmedidos n\u00e3o bastaram e os col\u00e9gios de cart\u00f3grafos levantaram um mapa do Imp\u00e9rio que tinha o tamanho do Imp\u00e9rio e coincidia com ele ponto por ponto. Menos dedicadas ao estudo da cartografia, as gera\u00e7\u00f5es seguintes decidiram que esse dilatado mapa era in\u00fatil e n\u00e3o sem impiedade entregaram-no as inclem\u00eancias do sol e dos invernos. Nos desertos do oeste perduram despeda\u00e7adas ru\u00ednas do mapa habitadas por animais e por mendigos.<\/p>\n\n\n\n<p><strong>BORGES, J. L. Sobre o rigor na ci\u00eancia. Em: Hist\u00f3ria universal da inf\u00e2mia. Lisboa: Ass\u00edrio e Alvim, 1982.<\/strong><\/p>\n\n\n\n<p>No conto de Jorge Lu\u00eds Borges, apresenta-se uma reflex\u00e3o sobre as fun\u00e7\u00f5es da linguagem cartogr\u00e1fica para o conhecimento geogr\u00e1fico.<\/p>\n\n\n\n<p>A compreens\u00e3o do conto leva \u00e0 conclus\u00e3o de que um mapa do tamanho exato do Imp\u00e9rio se tornava desnecess\u00e1rio pelo seguinte motivo:<\/p>\n\n\n\n<p><strong>a)<\/strong> extens\u00e3o da grandeza do territ\u00f3rio pol\u00edtico.<\/p>\n\n\n\n<p><strong>b)<\/strong> imprecis\u00e3o da localiza\u00e7\u00e3o das regi\u00f5es administrativas.<\/p>\n\n\n\n<p><strong>c)<\/strong> precariedade de instrumentos de orienta\u00e7\u00e3o tridimensional.<\/p>\n\n\n\n<p><strong>d) <\/strong>equival\u00eancia da proporcionalidade da representa\u00e7\u00e3o espacial.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Respostas dos exerc\u00edcios de Escala<\/h2>\n\n\n\n<p><strong>Exerc\u00edcio resolvido da quest\u00e3o 1 &#8211;<\/strong><\/p>\n\n\n\n<p>Alternativa correta: <strong>e)<\/strong> 1 : 25 000 000.<\/p>\n\n\n\n<p><strong>Exerc\u00edcio resolvido da quest\u00e3o 2 &#8211;<\/strong><\/p>\n\n\n\n<p>Alternativa correta: <strong>d) <\/strong>18 cm<\/p>\n\n\n\n<p><strong>Exerc\u00edcio resolvido da quest\u00e3o 3 &#8211;<\/strong><\/p>\n\n\n\n<p>Alternativa correta: <strong>b)<\/strong> 1 .250 m<\/p>\n\n\n\n<p><strong>Exerc\u00edcio resolvido da quest\u00e3o 4 &#8211;<\/strong><\/p>\n\n\n\n<p>Alternativa correta: <strong>e) <\/strong>1:61 500 000.<\/p>\n\n\n\n<p><strong>Exerc\u00edcio resolvido da quest\u00e3o 5 &#8211;<\/strong><\/p>\n\n\n\n<p>Alternativa correta: <strong>&nbsp;c)<\/strong>Um mapa na escala 1:500 possibilita a representa\u00e7\u00e3o da \u00e1rea urbana de Porto Alegre com mais detalhes que os mapas 1 e 2.<\/p>\n\n\n\n<p><strong>Exerc\u00edcio resolvido da quest\u00e3o 6 &#8211;<\/strong><\/p>\n\n\n\n<p>Alternativa correta: <strong>&nbsp;a)<\/strong> 9 cm.<\/p>\n\n\n\n<p><strong>Exerc\u00edcio resolvido da quest\u00e3o 7 &#8211;<\/strong><\/p>\n\n\n\n<p>Alternativa correta: <strong>d) <\/strong>equival\u00eancia da proporcionalidade da representa\u00e7\u00e3o espacial.<\/p>\n\n\n\n<p>Estude para o Enem com o <a href=\"https:\/\/beduka.com\/simulado\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">Simulado Beduka.<\/a> <strong>\u00c9 gratuito!<\/strong><\/p>\n\n\n\n<p>Gostou dos nossos <strong>Exerc\u00edcios de Escala?<\/strong> Compartilhe com os seus amigos e comente abaixo sobre as \u00e1reas que voc\u00ea deseja mais explica\u00e7\u00f5es.<\/p>\n\n\n\n<p>Queremos te ajudar a encontrar a <strong>FACULDADE IDEAL! <\/strong>Logo abaixo, fa\u00e7a uma pesquisa por curso e cidade que te mostraremos todas as faculdades que podem te atender. <strong>Informamos a nota de corte, valor de mensalidade, nota do MEC, avalia\u00e7\u00e3o dos alunos, modalidades de ensino e muito mais.<\/strong><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A raz\u00e3o constante que permite uma compara\u00e7\u00e3o entre qualquer grandeza, \u00e9 chamada de escala. Ela \u00e9 um mecanismo utilizado para representar algo de maneira proporcional, como, por exemplo, representar um territ\u00f3rio em um mapa. Leia nosso resumo e coloque seu conhecimento em pr\u00e1tica com nossa lista de Exerc\u00edcios de Escala selecionados dos maiores vestibulares do [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17845,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[610],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Exerc\u00edcios de Escala com Gabarito<\/title>\n<meta name=\"description\" content=\"Leia nosso resumo e coloque seu conhecimento em pr\u00e1tica com nossa lista de Exerc\u00edcios de Escala selecionados dos maiores vestibulares do Brasil.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beduka.com\/blog\/exercicios\/matematica-exercicios\/exercicios-escala\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exerc\u00edcios de Escala com Gabarito\" \/>\n<meta property=\"og:description\" content=\"Leia nosso resumo e coloque seu conhecimento em pr\u00e1tica com nossa lista de Exerc\u00edcios de Escala selecionados dos maiores vestibulares do Brasil.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beduka.com\/blog\/exercicios\/matematica-exercicios\/exercicios-escala\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-11T00:12:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-11T00:19:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/09\/escalas-capa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/beduka.com\/blog\/exercicios\/matematica-exercicios\/exercicios-escala\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/beduka.com\/blog\/exercicios\/matematica-exercicios\/exercicios-escala\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a\"},\"headline\":\"Exerc\u00edcios de Escala com Gabarito\",\"datePublished\":\"2020-09-11T00:12:11+00:00\",\"dateModified\":\"2020-09-11T00:19:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/beduka.com\/blog\/exercicios\/matematica-exercicios\/exercicios-escala\/\"},\"wordCount\":1507,\"commentCount\":10,\"publisher\":{\"@id\":\"https:\/\/beduka.com\/blog\/#organization\"},\"articleSection\":[\"Matem\u00e1tica\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/beduka.com\/blog\/exercicios\/matematica-exercicios\/exercicios-escala\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/beduka.com\/blog\/exercicios\/matematica-exercicios\/exercicios-escala\/\",\"url\":\"https:\/\/beduka.com\/blog\/exercicios\/matematica-exercicios\/exercicios-escala\/\",\"name\":\"Exerc\u00edcios de Escala com Gabarito\",\"isPartOf\":{\"@id\":\"https:\/\/beduka.com\/blog\/#website\"},\"datePublished\":\"2020-09-11T00:12:11+00:00\",\"dateModified\":\"2020-09-11T00:19:49+00:00\",\"description\":\"Leia nosso resumo e coloque seu conhecimento em pr\u00e1tica com nossa lista de Exerc\u00edcios de Escala selecionados dos maiores vestibulares do Brasil.\",\"breadcrumb\":{\"@id\":\"https:\/\/beduka.com\/blog\/exercicios\/matematica-exercicios\/exercicios-escala\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/beduka.com\/blog\/exercicios\/matematica-exercicios\/exercicios-escala\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/beduka.com\/blog\/exercicios\/matematica-exercicios\/exercicios-escala\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/beduka.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exerc\u00edcios de Escala com Gabarito\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/beduka.com\/blog\/#website\",\"url\":\"https:\/\/beduka.com\/blog\/\",\"name\":\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\",\"description\":\"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!\",\"publisher\":{\"@id\":\"https:\/\/beduka.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/beduka.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/beduka.com\/blog\/#organization\",\"name\":\"Beduka\",\"url\":\"https:\/\/beduka.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png\",\"contentUrl\":\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png\",\"width\":1077,\"height\":368,\"caption\":\"Beduka\"},\"image\":{\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/\",\"https:\/\/www.instagram.com\/beduka_oficial\/\",\"https:\/\/www.linkedin.com\/company\/beduka\",\"https:\/\/br.pinterest.com\/bedukaoficial\/\",\"https:\/\/www.youtube.com\/beduka\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a\",\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o Beduka (a)\"},\"description\":\"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.\",\"sameAs\":[\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\",\"https:\/\/www.instagram.com\/beduka_oficial\/\",\"https:\/\/br.pinterest.com\/bedukaoficial\/\"],\"url\":\"https:\/\/beduka.com\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exerc\u00edcios de Escala com Gabarito","description":"Leia nosso resumo e coloque seu conhecimento em pr\u00e1tica com nossa lista de Exerc\u00edcios de Escala selecionados dos maiores vestibulares do Brasil.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beduka.com\/blog\/exercicios\/matematica-exercicios\/exercicios-escala\/","og_locale":"pt_BR","og_type":"article","og_title":"Exerc\u00edcios de Escala com Gabarito","og_description":"Leia nosso resumo e coloque seu conhecimento em pr\u00e1tica com nossa lista de Exerc\u00edcios de Escala selecionados dos maiores vestibulares do Brasil.","og_url":"https:\/\/beduka.com\/blog\/exercicios\/matematica-exercicios\/exercicios-escala\/","og_site_name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","article_publisher":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","article_author":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades","article_published_time":"2020-09-11T00:12:11+00:00","article_modified_time":"2020-09-11T00:19:49+00:00","og_image":[{"width":600,"height":300,"url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/09\/escalas-capa.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Beduka (a)","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Beduka (a)","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beduka.com\/blog\/exercicios\/matematica-exercicios\/exercicios-escala\/#article","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/exercicios\/matematica-exercicios\/exercicios-escala\/"},"author":{"name":"Reda\u00e7\u00e3o Beduka (a)","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a"},"headline":"Exerc\u00edcios de Escala com Gabarito","datePublished":"2020-09-11T00:12:11+00:00","dateModified":"2020-09-11T00:19:49+00:00","mainEntityOfPage":{"@id":"https:\/\/beduka.com\/blog\/exercicios\/matematica-exercicios\/exercicios-escala\/"},"wordCount":1507,"commentCount":10,"publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"articleSection":["Matem\u00e1tica"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/beduka.com\/blog\/exercicios\/matematica-exercicios\/exercicios-escala\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/beduka.com\/blog\/exercicios\/matematica-exercicios\/exercicios-escala\/","url":"https:\/\/beduka.com\/blog\/exercicios\/matematica-exercicios\/exercicios-escala\/","name":"Exerc\u00edcios de Escala com Gabarito","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/#website"},"datePublished":"2020-09-11T00:12:11+00:00","dateModified":"2020-09-11T00:19:49+00:00","description":"Leia nosso resumo e coloque seu conhecimento em pr\u00e1tica com nossa lista de Exerc\u00edcios de Escala selecionados dos maiores vestibulares do Brasil.","breadcrumb":{"@id":"https:\/\/beduka.com\/blog\/exercicios\/matematica-exercicios\/exercicios-escala\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beduka.com\/blog\/exercicios\/matematica-exercicios\/exercicios-escala\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/beduka.com\/blog\/exercicios\/matematica-exercicios\/exercicios-escala\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/beduka.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Exerc\u00edcios de Escala com Gabarito"}]},{"@type":"WebSite","@id":"https:\/\/beduka.com\/blog\/#website","url":"https:\/\/beduka.com\/blog\/","name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","description":"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!","publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beduka.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beduka.com\/blog\/#organization","name":"Beduka","url":"https:\/\/beduka.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","contentUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","width":1077,"height":368,"caption":"Beduka"},"image":{"@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/www.linkedin.com\/company\/beduka","https:\/\/br.pinterest.com\/bedukaoficial\/","https:\/\/www.youtube.com\/beduka"]},{"@type":"Person","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a","name":"Reda\u00e7\u00e3o Beduka (a)","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o Beduka (a)"},"description":"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.","sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/br.pinterest.com\/bedukaoficial\/"],"url":"https:\/\/beduka.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/17843"}],"collection":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/comments?post=17843"}],"version-history":[{"count":3,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/17843\/revisions"}],"predecessor-version":[{"id":17850,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/17843\/revisions\/17850"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media\/17845"}],"wp:attachment":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media?parent=17843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/categories?post=17843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/tags?post=17843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}