{"id":19343,"date":"2020-12-23T23:55:35","date_gmt":"2020-12-24T02:55:35","guid":{"rendered":"https:\/\/beduka.com\/blog\/?p=19343"},"modified":"2020-12-23T23:55:37","modified_gmt":"2020-12-24T02:55:37","slug":"separacao-de-misturas","status":"publish","type":"post","link":"https:\/\/beduka.com\/blog\/materias\/quimica\/separacao-de-misturas\/","title":{"rendered":"Separa\u00e7\u00e3o de misturas: principais m\u00e9todos e import\u00e2ncia!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A separa\u00e7\u00e3o de misturas \u00e9 o processo de afastar subst\u00e2ncias diferentes que antes estavam juntas em uma mistura. As misturas podem ser heterog\u00eaneas ou homog\u00eaneas e isso influencia na escolha de um m\u00e9todo para realizar a separa\u00e7\u00e3o eficaz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Neste artigo sobre separa\u00e7\u00e3o de misturas, voc\u00ea encontrar\u00e1:<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>O que s\u00e3o misturas homog\u00eaneas e heterog\u00eaneas<\/li><li>Import\u00e2ncia da separa\u00e7\u00e3o de misturas<\/li><li>M\u00e9todos de separa\u00e7\u00e3o de misturas homog\u00eaneas e heterog\u00eaneas<\/li><li>Exemplos<\/li><\/ol>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Estudando para as provas?<\/strong> Conhe\u00e7a <a href=\"https:\/\/beduka.com\/blog\/dicas\/enem-dicas\/simulados-para-enem-online-e-gratuito\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">O <\/a><strong><a href=\"https:\/\/beduka.com\/blog\/dicas\/enem-dicas\/simulados-para-enem-online-e-gratuito\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">melhor<\/a><\/strong><a href=\"https:\/\/beduka.com\/blog\/dicas\/enem-dicas\/simulados-para-enem-online-e-gratuito\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\"> Simulado do Brasil!<\/a> Ele pode ser personalizado com as mat\u00e9rias que voc\u00ea mais precisa!<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">O que s\u00e3o misturas?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Na qu\u00edmica, \u201c<strong>mistura\u201d <\/strong>\u00e9 definida como a <strong>combina\u00e7\u00e3o de duas ou mais subst\u00e2ncias<\/strong>. Dependendo do modo como essas subst\u00e2ncia ir\u00e3o se relacionar, as misturas podem ser classificadas em <strong>homog\u00eaneas ou heterog\u00eaneas<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vamos entender a diferen\u00e7a entre elas:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Misturas homog\u00eaneas ou solu\u00e7\u00f5es<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">As misturas <strong>homog\u00eaneas<\/strong>, tamb\u00e9m chamadas de <strong>solu\u00e7\u00f5es<\/strong>, s\u00e3o aquelas que possuem <strong>fase \u00fanica.<\/strong> Isso significa que, quando olhamos <strong>a olho nu<\/strong>, vemos uma <strong>mistura perfeita<\/strong>. Dessa forma, s\u00f3 conseguimos identificar <strong>um aspecto<\/strong> <strong>uniforme<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exemplo:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao misturar <strong>\u00e1gua e \u00e1lcool<\/strong>, eles se misturam de forma que <strong>n\u00e3o conseguimos enxergar separadamente <\/strong>o que \u00e9 \u00e1lcool e o que \u00e9 \u00e1gua. Eles se tornam um, ent\u00e3o dizemos que s\u00e3o <strong>misc\u00edveis<\/strong>!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Misturas heterog\u00eaneas<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">As misturas <strong>heterog\u00eaneas<\/strong> s\u00e3o aquelas que possuem <strong>duas ou mais fases.<\/strong> Isso significa que, quando olhamos <strong>a olho nu<\/strong>, vemos uma <strong>divis\u00f3ria entre os componentes.<\/strong> Dessa forma, <strong>n\u00e3o h\u00e1 um aspecto<\/strong> <strong>uniforme.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exemplo:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao misturar <strong>\u00e1gua e \u00f3leo<\/strong>, eles formam uma mistura com <strong>duas fases:<\/strong> vemos o <strong>\u00f3leo em cima e a \u00e1gua abaixo<\/strong>. Isso significa que eles <strong>n\u00e3o s\u00e3o misc\u00edveis<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Aten\u00e7\u00e3o!<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea j\u00e1 deve ter ouvido falar que \u201c\u00e1gua e \u00f3leo n\u00e3o se misturam\u201d e por isso pode ter achado estranho n\u00f3s termos dito que eles formam uma mistura.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A quest\u00e3o \u00e9 que <strong>o vocabul\u00e1rio popular nem sempre est\u00e1 de acordo com o cient\u00edfico<\/strong>\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na realidade, qualquer recipiente que contenha duas ou mais subst\u00e2ncias s\u00e3o sim uma mistura. Ent\u00e3o, <strong>\u00e1gua e \u00f3leo se misturam embora n\u00e3o sejam misc\u00edveis<\/strong>, ou seja, eles n\u00e3o formam uma mistura homog\u00eanea, mas formam uma heterog\u00eanea.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para facilitar o entendimento, veja <strong>mais alguns<\/strong> <strong>exemplos<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u00e1gua + sal \u27f6 mistura homog\u00eanea ou <strong>monof\u00e1sica<\/strong><\/li><li>soro caseiro (\u00e1gua + a\u00e7\u00facar + sal) \u27f6 mistura homog\u00eanea ou monof\u00e1sica<\/li><li>areia + \u00f3leo \u27f6 mistura heterog\u00eanea <strong>bif\u00e1sica<\/strong><\/li><li>\u00e1gua + acetona + terra \u27f6 mistura heterog\u00eanea bif\u00e1sica (\u00e1gua e acetona s\u00e3o misc\u00edveis, contam como 1 fase apenas)<\/li><li>chocolate + passas + castanhas \u27f6 mistura heterog\u00eanea <strong>trif\u00e1sica<\/strong><\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Qual \u00e9 a import\u00e2ncia dos m\u00e9todos de separa\u00e7\u00e3o de misturas?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Separa\u00e7\u00e3o de misturas \u00e9 o nome que se d\u00e1 a <strong>qualquer processo utilizado para separar duas ou mais subst\u00e2ncias<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A separa\u00e7\u00e3o de misturas <strong>\u00e9 muito importante<\/strong> e est\u00e1 mais <strong>presente no nosso dia a dia<\/strong> do que imaginamos.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A maioria dos materiais encontrados na natureza s\u00e3o misturas, ent\u00e3o precisamos saber os m\u00e9todos de separa\u00e7\u00e3o para termos acesso ao que queremos extrair. S\u00f3 depois disso teremos a mat\u00e9ria-prima adequada para fazer novas combina\u00e7\u00f5es e produzir novas coisas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Veja alguns <strong>exemplos<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Separa\u00e7\u00e3o da \u00e1gua do mar para obter sal;<\/li><li>Tratamento da \u00e1gua;&nbsp;<\/li><li>Coleta e reciclagem de lixo;<\/li><li>Produ\u00e7\u00e3o de metais;<\/li><li>Produ\u00e7\u00e3o de medicamentos, alimentos, bebidas, higiene e limpeza;<\/li><li>An\u00e1lise do sangue em laborat\u00f3rio.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Observa\u00e7\u00e3o:<\/strong> normalmente a separa\u00e7\u00e3o dos componentes de uma mistura quase sempre \u00e9 feita com mais de um m\u00e9todo!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quais s\u00e3o os m\u00e9todos de separa\u00e7\u00e3o de misturas?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Existem <strong>v\u00e1rios m\u00e9todos<\/strong> de separa\u00e7\u00e3o de misturas e<strong> a escolha <\/strong>de algum deles <strong>depende das caracter\u00edsticas das subst\u00e2ncias misturadas<\/strong>.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nos t\u00f3picos a seguir, iremos estudar cada um deles, mas agora veja quais s\u00e3o os <strong>fatores que influenciar\u00e3o na escolha<\/strong> do m\u00e9todo adequado:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Tipo de mistura: homog\u00eanea ou heterog\u00eanea;<\/li><li>Natureza dos elementos qu\u00edmicos que formam as misturas;<\/li><li>Densidade, temperatura e solubilidade dos elementos.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Para facilitar o entendimento, <strong>agrupamos os m\u00e9todos em duas categorias:<\/strong> os que servem <strong>para misturas homog\u00eaneas <\/strong>(destila\u00e7\u00e3o, evapora\u00e7\u00e3o, solidifica\u00e7\u00e3o&#8230;) e os <strong>para misturas heterog\u00eaneas <\/strong>(cata\u00e7\u00e3o, leviga\u00e7\u00e3o, centrifuga\u00e7\u00e3o, filtra\u00e7\u00e3o, decanta\u00e7\u00e3o\u2026).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As t\u00e9cnicas podem se <strong>basear em princ\u00edpios f\u00edsicos ou qu\u00edmicos<\/strong>, pois usamos as <strong>propriedades dos componentes<\/strong> das misturas para separ\u00e1-los. Essas propriedades podem ser o <strong>ponto de fus\u00e3o, o ponto de ebuli\u00e7\u00e3o, a solubilidade, a densidade,<\/strong> entre outros.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Voc\u00ea \u00e9 uma daquelas pessoas que tem fome de conhecimento? <\/strong>Ent\u00e3o siga o <a href=\"https:\/\/www.instagram.com\/beduka_oficial\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">Beduka no Instagram<\/a> para conte\u00fados di\u00e1rios.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Como separar uma mistura homog\u00eanea? Exemplos!<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para misturas homog\u00eaneas, aquelas que possuem uma \u00fanica fase e que \u00e9 formada por subst\u00e2ncias misc\u00edveis, \u00e9 mais comum se utilizar os seguintes processos:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Destila\u00e7\u00e3o simples<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A destila\u00e7\u00e3o simples \u00e9 o processo de separa\u00e7\u00e3o que envolve subst\u00e2ncias <strong>s\u00f3lidas e l\u00edquidas. <\/strong>O princ\u00edpio utilizado \u00e9 o <strong>ponto de ebuli\u00e7\u00e3o. <\/strong>A mistura \u00e9 <strong>aquecida <\/strong>at\u00e9 uma das subst\u00e2ncias evaporar e a outra restar no recipiente.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c9 poss\u00edvel canalizar o vapor para um<\/strong> <a href=\"https:\/\/beduka.com\/blog\/materias\/quimica\/mudancas-de-estado-fisico\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">condensador<\/a> e recuperar o que evaporou em forma de l\u00edquido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exemplo:\u00a0<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se pegarmos uma <strong>amostra de \u00e1gua do mar<\/strong> e aquecermos essa mistura at\u00e9 ela ebulir (criar borbulhas), veremos que restar\u00e1 apenas sal no fundo do recipiente.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Isso acontece porque a temperatura de ebuli\u00e7\u00e3o da \u00e1gua \u00e9 bem mais baixa que a do sal. Assim, as mol\u00e9culas de&nbsp; \u00e1gua s\u00e3o induzidas a evaporar, mas as de sal n\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Destila\u00e7\u00e3o fracionada<\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"300\" src=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/12\/destila\u00e7ao-fracionada-petroleo.jpg\" alt=\"destila\u00e7ao-fracionada-petroleo\" class=\"wp-image-19345\" srcset=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/12\/destila\u00e7ao-fracionada-petroleo.jpg 600w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/12\/destila\u00e7ao-fracionada-petroleo-300x150.jpg 300w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/12\/destila\u00e7ao-fracionada-petroleo-320x160.jpg 320w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">A destila\u00e7\u00e3o fracionada costuma ser aplicada em misturas formadas por <strong>2 ou mais<\/strong> <strong>l\u00edquidos <\/strong>e usa o princ\u00edpio do <strong>ponto de ebuli\u00e7\u00e3o <\/strong>para <strong>aquec\u00ea-la<\/strong> e separ\u00e1-la.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A<strong> novidade <\/strong>nesse processo \u00e9 que ele possui um aparelho cheio de <strong>n\u00edveis<\/strong> que atingem diferentes pontos de ebuli\u00e7\u00e3o por vez. Assim, \u00e9 poss\u00edvel separar <strong>v\u00e1rias subst\u00e2ncias diferentes em um mesmo processo<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Normalmente, <strong>o produto desejado \u00e9 o que possui o ponto de ebuli\u00e7\u00e3o mais alto<\/strong>, mas os produtos secund\u00e1rios (que foram formados no meio do caminho) podem ter outras aplica\u00e7\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exemplo:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A produ\u00e7\u00e3o dos <strong>derivados de petr\u00f3leo<\/strong> sempre passa pela destila\u00e7\u00e3o fracionada. O petr\u00f3leo \u00e9 aquecido e o vapor passa por diversos \u201cpratos\u201d, sendo que cada um coleta um composto derivado dependendo da sua temperatura de ebuli\u00e7\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Vaporiza\u00e7\u00e3o<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A vaporiza\u00e7\u00e3o, tamb\u00e9m conhecida por evapora\u00e7\u00e3o, \u00e9 um processo mais <strong>natural <\/strong>e <strong>demorado<\/strong>. Nele, apenas deixamos a <strong>mistura em repouso at\u00e9 a parte l\u00edquida evaporar<\/strong>. Ent\u00e3o, restar\u00e1 o soluto na forma s\u00f3lida.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Observe que <strong>o componente l\u00edquido \u00e9 perdido<\/strong> para a atmosfera, pois n\u00e3o envolve nenhuma aparelhagem artificial que possa fazer a \u00e1gua evaporada condensar e ser recuperada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exemplo:<\/strong> na realidade, a <strong>produ\u00e7\u00e3o de sal marinho<\/strong> \u00e9 feita pela <strong>evapora\u00e7\u00e3o porque \u00e9 mais barato <\/strong>que a ebuli\u00e7\u00e3o!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Destila\u00e7\u00e3o por arraste&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Esse m\u00e9todo <strong>utiliza o calor do vapor de \u00e1gua<\/strong> e \u00e9 ele quem vai passar por uma mistura e fazer algum de seus componentes evaporar junto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exemplo:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se colocamos <strong>folhas de eucalipto sobre a sa\u00edda de vapor quente da sauna<\/strong>, logo o ar fica \u201crefrescante\u201d. Isso ocorre porque o calor do vapor \u201carrasta\u201d consigo uma determinada subst\u00e2ncia da folha.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Liquefa\u00e7\u00e3o fracionada<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A liquefa\u00e7\u00e3o fracionada costuma ser <strong>aplicada em gases<\/strong> e consiste em <strong>resfriar a mistura<\/strong> <strong>de forma gradual <\/strong>at\u00e9 os gases<strong> tornarem-se l\u00edquidos<\/strong>. Ap\u00f3s isso, passam pela destila\u00e7\u00e3o fracionada e s\u00e3o separados conforme os seus pontos de ebuli\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exemplo: <\/strong>separa\u00e7\u00e3o dos componentes do ar atmosf\u00e9rico.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Fus\u00e3o fracionada<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A fus\u00e3o fracionada costuma ser aplicada em misturas formadas apenas por <strong>s\u00f3lidos de diferentes pontos de fus\u00e3o<\/strong>. A mistura \u00e9 <strong>aquecida <\/strong>at\u00e9 atingir o menor ponto de fus\u00e3o, ent\u00e3o <strong>um dos s\u00f3lidos ir\u00e1 se liquefazer<\/strong>. Depois, basta passar por um filtro ou peneira e teremos as duas subst\u00e2ncias separadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exemplo:<\/strong> separa\u00e7\u00e3o dos componentes do ouro 18 quilates.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Solidifica\u00e7\u00e3o fracionada&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A solidifica\u00e7\u00e3o fracionada se aplica a <strong>l\u00edquidos <\/strong>misc\u00edveis com <strong>diferentes pontos de fus\u00e3o. <\/strong>\u00a0A diferen\u00e7a aqui \u00e9 que iremos fazer o <strong>resfriamento<\/strong> deles. Assim, a temperatura \u00e9 diminu\u00edda at\u00e9 o menor ponto de fus\u00e3o e apenas <strong>um dos componentes \u00e9 transformado em s\u00f3lido<\/strong>.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exemplo<\/strong>: separar a parafina dos res\u00edduos do petr\u00f3leo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como separar uma mistura heterog\u00eanea? (Exemplos)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para misturas heterog\u00eaneas, aquelas que possuem duas ou mais fases, \u00e9 mais comum se utilizar os seguintes processos:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Cata\u00e7\u00e3o<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Na cata\u00e7\u00e3o, separamos os <strong>s\u00f3lidos <\/strong>usando a propriedade de <strong>tamanhos diferentes<\/strong>. Tamb\u00e9m \u00e9 poss\u00edvel fazer isso quando se trata de um <strong>s\u00f3lido em um l\u00edquido<\/strong>, visto que \u00e9 para misturas heterog\u00eaneas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Podemos usar recursos como as <strong>m\u00e3os, uma pin\u00e7a, um pegador, etc<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exemplo<\/strong>: catar pedras dentre os gr\u00e3os de feij\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Leviga\u00e7\u00e3o<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A leviga\u00e7\u00e3o \u00e9 usada para separar <strong>s\u00f3lidos que possuem diferentes <\/strong><a href=\"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-densidade\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">densidades<\/a>. Isso \u00e9 feito quando fazemos a <strong>\u00e1gua correr<\/strong> por entre os s\u00f3lidos e o <strong>menos denso \u00e9 levado pela corrente<\/strong> enquanto o mais denso fica onde est\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exemplo:<\/strong> separar o cascalho do ouro. Muito usado pelos garimpeiros \u00e0 beira do rio.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ventila\u00e7\u00e3o<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A ventila\u00e7\u00e3o tamb\u00e9m \u00e9 usada para <strong>separar s\u00f3lidos que possuem diferentes densidades<\/strong>, mas isso \u00e9 feito utilizando uma <strong>rajada de ar<\/strong>. Quando o vento passa, <strong>leva consigo a subst\u00e2ncia menos densa.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exemplo:<\/strong> soprar para separar a casca do amendoim.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Filtra\u00e7\u00e3o<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A filtra\u00e7\u00e3o \u00e9 o m\u00e9todo que usamos para <strong>separar subst\u00e2ncias s\u00f3lidas de gases ou s\u00f3lidas n\u00e3o dissolvidas em l\u00edquidos<\/strong>. Para isso, um <strong>filtro ret\u00e9m<\/strong> o componente s\u00f3lido de uma mistura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exemplo<\/strong>: coar caf\u00e9 ou usar a \u00e1gua do filtro de casa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Existe uma modalidade chamada <strong>filtra\u00e7\u00e3o \u00e0 v\u00e1cuo<\/strong>, em que a velocidade da filtra\u00e7\u00e3o \u00e9 <strong>acelerada<\/strong>. Isto ocorre porque <strong>o l\u00edquido filtrado n\u00e3o apresenta a resist\u00eancia do ar <\/strong>ao cair dentro do recipiente. <strong>Exemplo<\/strong>: separar areia da \u00e1gua ou uma mistura pastosa.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Decanta\u00e7\u00e3o<\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"300\" src=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/12\/decanta\u00e7ao.jpg\" alt=\"decanta\u00e7ao oleo e agua msitura heterogenea\" class=\"wp-image-19346\" srcset=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/12\/decanta\u00e7ao.jpg 600w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/12\/decanta\u00e7ao-300x150.jpg 300w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/12\/decanta\u00e7ao-320x160.jpg 320w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">A decanta\u00e7\u00e3o \u00e9 um processo que acontece <strong>naturalmente e com o tempo<\/strong>, utilizado a <strong>diferen\u00e7a de densidades. <\/strong>Pode ser observado entre <strong>dois l\u00edquidos n\u00e3o misc\u00edveis<\/strong> ou entre um <strong>s\u00f3lido n\u00e3o dissolvido em l\u00edquido.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Naturalmente <\/strong>o componente <strong>menos denso<\/strong> da mistura \u00e9 posicionado <strong>em cima<\/strong> do componente <strong>mais denso<\/strong>, devido a a\u00e7\u00e3o da <strong>gravidade.<\/strong>\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exemplo<\/strong>: separar \u00e1gua de \u00f3leo ou \u00e1gua de areia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Centrifuga\u00e7\u00e3o<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A centrifuga\u00e7\u00e3o \u00e9 um m\u00e9todo que <strong>acelera<\/strong> o fen\u00f4meno da decanta\u00e7\u00e3o por meio de movimentos circulares. Isso acontece quando a mistura \u00e9 colocada na <strong>centr\u00edfuga<\/strong>, um aparelho que <strong>rotaciona <\/strong>e acelera a <strong>transla\u00e7\u00e3o <\/strong>dos componentes.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exemplos<\/strong>: m\u00e1quina de lavar retira excesso de \u00e1gua da roupa ou no laborat\u00f3rio para separar os elementos do sangue.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Separa\u00e7\u00e3o magn\u00e9tica<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Como o pr\u00f3prio nome aponta, esse m\u00e9todo precisa de um <a href=\"https:\/\/beduka.com\/blog\/materias\/fisica\/o-que-e-magnetismo\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">\u00edm\u00e3<\/a> para <strong>retirar o componente met\u00e1lico ferromagn\u00e9tico<\/strong> que est\u00e1 em meio a uma mistura de s\u00f3lidos.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exemplo<\/strong>: separar a limalha de ferro da areia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Aten\u00e7\u00e3o<\/strong>: nem todos os metais s\u00e3o magn\u00e9ticos (atra\u00eddos por im\u00e3), tome cuidado com as pegadinhas!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Flota\u00e7\u00e3o<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Na flota\u00e7\u00e3o um <strong>l\u00edquido \u00e9 adicionado<\/strong> a uma mistura formada por <strong>dois s\u00f3lidos de diferentes densidades. <\/strong>Assim, quando estiverem em meio l\u00edquido, um ir\u00e1 <strong>flutuar <\/strong>(menos denso) e o outro n\u00e3o (mais denso). Depois, basta fazer uma decanta\u00e7\u00e3o e filtra\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exemplo<\/strong>: adicionar \u00e1gua em uma mistura formada por areia e isopor.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Sifona\u00e7\u00e3o<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A sifona\u00e7\u00e3o \u00e9 um m\u00e9todo no qual <strong>usamos mangueira, pipeta, canudo, seringa<\/strong> ou qualquer objeto do tipo. Isso \u00e9 feito para <strong>retirar o l\u00edquido<\/strong> mais denso ou menos denso de uma mistura formada por apenas l\u00edquidos.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exemplo<\/strong>: Separar os componentes da mistura formada por \u00e1gua e \u00f3leo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Coagula\u00e7\u00e3o e Flocula\u00e7\u00e3o<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A coagula\u00e7\u00e3o \u00e9 um m\u00e9todo no qual uma <strong>subst\u00e2ncia \u00e9 adicionada<\/strong> a uma mistura para que ela <strong>se una aos componentes s\u00f3lidos<\/strong> que estejam <strong>em suspens\u00e3o em um l\u00edquido<\/strong>. Essa subst\u00e2ncia ir\u00e1 \u201catrair\u201d quimicamente os s\u00f3lidos e aglomera-los na superf\u00edcie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exemplo<\/strong>: adicionar sulfato de alum\u00ednio na \u00e1gua em uma esta\u00e7\u00e3o de tratamento de \u00e1gua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A flocula\u00e7\u00e3o \u00e9 um m\u00e9todo que complementa a coagula\u00e7\u00e3o, j\u00e1 que nele a mistura \u00e9 agitada para favorecer a a\u00e7\u00e3o do coagulante.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tamisa\u00e7\u00e3o ou Peneira\u00e7\u00e3o<\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"300\" src=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/12\/peneira\u00e7ao-ou-tamiza\u00e7ao.jpg\" alt=\"peneira\u00e7ao-ou-tamiza\u00e7ao\" class=\"wp-image-19347\" srcset=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/12\/peneira\u00e7ao-ou-tamiza\u00e7ao.jpg 600w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/12\/peneira\u00e7ao-ou-tamiza\u00e7ao-300x150.jpg 300w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/12\/peneira\u00e7ao-ou-tamiza\u00e7ao-320x160.jpg 320w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">A peneira\u00e7\u00e3o \u00e9 o m\u00e9todo em que usamos uma peneira para <strong>separar os s\u00f3lidos de tamanhos diferentes<\/strong>.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exemplo<\/strong>: peneirar uma mistura de farinha e arroz para separar os gr\u00e3os.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Dissolu\u00e7\u00e3o fracionada<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A dissolu\u00e7\u00e3o \u00e9 o m\u00e9todo no qual um <strong>l\u00edquido \u00e9 adicionado<\/strong> a uma mistura formada por <strong>dois s\u00f3lidos<\/strong> com o objetivo de <strong>dissolver apenas um deles.<\/strong> Depois que um dos s\u00f3lidos estiver dilu\u00eddo na parte l\u00edquida, basta aplicar qualquer m\u00e9todo para separar l\u00edquidos de s\u00f3lidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exemplo<\/strong>: adicionar \u00e1gua em uma mistura formada por sal e areia e depois realizar filtra\u00e7\u00e3o ou decanta\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gostou do nosso artigo sobre a separa\u00e7\u00e3o de misturas? Confira <strong>outros artigos <\/strong>do nosso blog e <strong>se prepare para o Enem<\/strong> da melhor maneira! Voc\u00ea tamb\u00e9m pode se organizar com o nosso <a href=\"https:\/\/beduka.com\/blog\/dicas\/enem-dicas\/plano-de-estudos-gratuito\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">plano de estudos<\/a>, o mais completo da internet, e o melhor: <strong>totalmente gratuito!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Queremos te ajudar a encontrar a <strong>FACULDADE IDEAL!<\/strong> Logo abaixo, fa\u00e7a uma pesquisa por curso e cidade que te mostraremos todas as faculdades que podem te atender. Informamos a nota de corte, valor de mensalidade, nota do MEC, avalia\u00e7\u00e3o dos alunos, modalidades de ensino e muito mais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Experimente agora!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A separa\u00e7\u00e3o de misturas \u00e9 o processo de afastar subst\u00e2ncias diferentes que antes estavam juntas em uma mistura. As misturas podem ser heterog\u00eaneas ou homog\u00eaneas e isso influencia na escolha de um m\u00e9todo para realizar a separa\u00e7\u00e3o eficaz. Neste artigo sobre separa\u00e7\u00e3o de misturas, voc\u00ea encontrar\u00e1: O que s\u00e3o misturas homog\u00eaneas e heterog\u00eaneas Import\u00e2ncia da [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19344,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[496],"tags":[],"class_list":["post-19343","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-quimica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Separa\u00e7\u00e3o de misturas (O MELHOR RESUMO)<\/title>\n<meta name=\"description\" content=\"Tudo sobre separa\u00e7\u00e3o de misturas: descubra o que \u00e9 mistura homog\u00eanea e heterog\u00eanea, quais m\u00e9todos usar para separar cada uma delas e qual a sua import\u00e2ncia!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beduka.com\/blog\/materias\/quimica\/separacao-de-misturas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Separa\u00e7\u00e3o de misturas (O MELHOR RESUMO)\" \/>\n<meta property=\"og:description\" content=\"Tudo sobre separa\u00e7\u00e3o de misturas: descubra o que \u00e9 mistura homog\u00eanea e heterog\u00eanea, quais m\u00e9todos usar para separar cada uma delas e qual a sua import\u00e2ncia!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beduka.com\/blog\/materias\/quimica\/separacao-de-misturas\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-24T02:55:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-24T02:55:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/12\/Tudo-sobre-os-m\u00e9todos-de-separa\u00e7\u00e3o-de-mistura.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/quimica\\\/separacao-de-misturas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/quimica\\\/separacao-de-misturas\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/person\\\/325d912d2cb8dd9ede8ab291427d2b8a\"},\"headline\":\"Separa\u00e7\u00e3o de misturas: principais m\u00e9todos e import\u00e2ncia!\",\"datePublished\":\"2020-12-24T02:55:35+00:00\",\"dateModified\":\"2020-12-24T02:55:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/quimica\\\/separacao-de-misturas\\\/\"},\"wordCount\":2334,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/quimica\\\/separacao-de-misturas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Tudo-sobre-os-m\u00e9todos-de-separa\u00e7\u00e3o-de-mistura.jpg\",\"articleSection\":[\"Qu\u00edmica\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/quimica\\\/separacao-de-misturas\\\/\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/quimica\\\/separacao-de-misturas\\\/\",\"name\":\"Separa\u00e7\u00e3o de misturas (O MELHOR RESUMO)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/quimica\\\/separacao-de-misturas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/quimica\\\/separacao-de-misturas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Tudo-sobre-os-m\u00e9todos-de-separa\u00e7\u00e3o-de-mistura.jpg\",\"datePublished\":\"2020-12-24T02:55:35+00:00\",\"dateModified\":\"2020-12-24T02:55:37+00:00\",\"description\":\"Tudo sobre separa\u00e7\u00e3o de misturas: descubra o que \u00e9 mistura homog\u00eanea e heterog\u00eanea, quais m\u00e9todos usar para separar cada uma delas e qual a sua import\u00e2ncia!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/quimica\\\/separacao-de-misturas\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/quimica\\\/separacao-de-misturas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/quimica\\\/separacao-de-misturas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Tudo-sobre-os-m\u00e9todos-de-separa\u00e7\u00e3o-de-mistura.jpg\",\"contentUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Tudo-sobre-os-m\u00e9todos-de-separa\u00e7\u00e3o-de-mistura.jpg\",\"width\":600,\"height\":300,\"caption\":\"Tudo sobre os m\u00e9todos de separa\u00e7\u00e3o de mistura!\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/quimica\\\/separacao-de-misturas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/beduka.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Separa\u00e7\u00e3o de misturas: principais m\u00e9todos e import\u00e2ncia!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/\",\"name\":\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\",\"description\":\"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!\",\"publisher\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beduka.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#organization\",\"name\":\"Beduka\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/marca-beduka.png\",\"contentUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/marca-beduka.png\",\"width\":1077,\"height\":368,\"caption\":\"Beduka\"},\"image\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/beduka.buscadordefaculdades\\\/\",\"https:\\\/\\\/www.instagram.com\\\/beduka_oficial\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/beduka\",\"https:\\\/\\\/br.pinterest.com\\\/bedukaoficial\\\/\",\"https:\\\/\\\/www.youtube.com\\\/beduka\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/person\\\/325d912d2cb8dd9ede8ab291427d2b8a\",\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o Beduka (a)\"},\"description\":\"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/beduka.buscadordefaculdades\",\"https:\\\/\\\/www.instagram.com\\\/beduka_oficial\\\/\",\"https:\\\/\\\/br.pinterest.com\\\/bedukaoficial\\\/\"],\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Separa\u00e7\u00e3o de misturas (O MELHOR RESUMO)","description":"Tudo sobre separa\u00e7\u00e3o de misturas: descubra o que \u00e9 mistura homog\u00eanea e heterog\u00eanea, quais m\u00e9todos usar para separar cada uma delas e qual a sua import\u00e2ncia!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beduka.com\/blog\/materias\/quimica\/separacao-de-misturas\/","og_locale":"pt_BR","og_type":"article","og_title":"Separa\u00e7\u00e3o de misturas (O MELHOR RESUMO)","og_description":"Tudo sobre separa\u00e7\u00e3o de misturas: descubra o que \u00e9 mistura homog\u00eanea e heterog\u00eanea, quais m\u00e9todos usar para separar cada uma delas e qual a sua import\u00e2ncia!","og_url":"https:\/\/beduka.com\/blog\/materias\/quimica\/separacao-de-misturas\/","og_site_name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","article_publisher":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","article_author":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades","article_published_time":"2020-12-24T02:55:35+00:00","article_modified_time":"2020-12-24T02:55:37+00:00","og_image":[{"width":600,"height":300,"url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/12\/Tudo-sobre-os-m\u00e9todos-de-separa\u00e7\u00e3o-de-mistura.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Beduka (a)","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Beduka (a)","Est. tempo de leitura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beduka.com\/blog\/materias\/quimica\/separacao-de-misturas\/#article","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/materias\/quimica\/separacao-de-misturas\/"},"author":{"name":"Reda\u00e7\u00e3o Beduka (a)","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a"},"headline":"Separa\u00e7\u00e3o de misturas: principais m\u00e9todos e import\u00e2ncia!","datePublished":"2020-12-24T02:55:35+00:00","dateModified":"2020-12-24T02:55:37+00:00","mainEntityOfPage":{"@id":"https:\/\/beduka.com\/blog\/materias\/quimica\/separacao-de-misturas\/"},"wordCount":2334,"commentCount":0,"publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"image":{"@id":"https:\/\/beduka.com\/blog\/materias\/quimica\/separacao-de-misturas\/#primaryimage"},"thumbnailUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/12\/Tudo-sobre-os-m\u00e9todos-de-separa\u00e7\u00e3o-de-mistura.jpg","articleSection":["Qu\u00edmica"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/beduka.com\/blog\/materias\/quimica\/separacao-de-misturas\/","url":"https:\/\/beduka.com\/blog\/materias\/quimica\/separacao-de-misturas\/","name":"Separa\u00e7\u00e3o de misturas (O MELHOR RESUMO)","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beduka.com\/blog\/materias\/quimica\/separacao-de-misturas\/#primaryimage"},"image":{"@id":"https:\/\/beduka.com\/blog\/materias\/quimica\/separacao-de-misturas\/#primaryimage"},"thumbnailUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/12\/Tudo-sobre-os-m\u00e9todos-de-separa\u00e7\u00e3o-de-mistura.jpg","datePublished":"2020-12-24T02:55:35+00:00","dateModified":"2020-12-24T02:55:37+00:00","description":"Tudo sobre separa\u00e7\u00e3o de misturas: descubra o que \u00e9 mistura homog\u00eanea e heterog\u00eanea, quais m\u00e9todos usar para separar cada uma delas e qual a sua import\u00e2ncia!","breadcrumb":{"@id":"https:\/\/beduka.com\/blog\/materias\/quimica\/separacao-de-misturas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beduka.com\/blog\/materias\/quimica\/separacao-de-misturas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/materias\/quimica\/separacao-de-misturas\/#primaryimage","url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/12\/Tudo-sobre-os-m\u00e9todos-de-separa\u00e7\u00e3o-de-mistura.jpg","contentUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/12\/Tudo-sobre-os-m\u00e9todos-de-separa\u00e7\u00e3o-de-mistura.jpg","width":600,"height":300,"caption":"Tudo sobre os m\u00e9todos de separa\u00e7\u00e3o de mistura!"},{"@type":"BreadcrumbList","@id":"https:\/\/beduka.com\/blog\/materias\/quimica\/separacao-de-misturas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/beduka.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Separa\u00e7\u00e3o de misturas: principais m\u00e9todos e import\u00e2ncia!"}]},{"@type":"WebSite","@id":"https:\/\/beduka.com\/blog\/#website","url":"https:\/\/beduka.com\/blog\/","name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","description":"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!","publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beduka.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beduka.com\/blog\/#organization","name":"Beduka","url":"https:\/\/beduka.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","contentUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","width":1077,"height":368,"caption":"Beduka"},"image":{"@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/www.linkedin.com\/company\/beduka","https:\/\/br.pinterest.com\/bedukaoficial\/","https:\/\/www.youtube.com\/beduka"]},{"@type":"Person","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a","name":"Reda\u00e7\u00e3o Beduka (a)","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o Beduka (a)"},"description":"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.","sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/br.pinterest.com\/bedukaoficial\/"],"url":"https:\/\/beduka.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/19343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/comments?post=19343"}],"version-history":[{"count":1,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/19343\/revisions"}],"predecessor-version":[{"id":19348,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/19343\/revisions\/19348"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media\/19344"}],"wp:attachment":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media?parent=19343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/categories?post=19343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/tags?post=19343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}