{"id":20088,"date":"2021-02-25T11:32:57","date_gmt":"2021-02-25T14:32:57","guid":{"rendered":"https:\/\/beduka.com\/blog\/?p=20088"},"modified":"2021-02-25T12:15:32","modified_gmt":"2021-02-25T15:15:32","slug":"camada-de-ozonio","status":"publish","type":"post","link":"https:\/\/beduka.com\/blog\/materias\/geografia\/camada-de-ozonio\/","title":{"rendered":"Resumo da Camada de Oz\u00f4nio: fun\u00e7\u00e3o, local, import\u00e2ncia &#8230;"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A Camada de Oz\u00f4nio \u00e9 uma faixa gasosa da atmosfera terrestre. Seu principal componente \u00e9 o g\u00e1s oz\u00f4nio (O3), respons\u00e1vel pela filtra\u00e7\u00e3o de radia\u00e7\u00e3o solar UV. A Ozonosfera fica na Estratosfera (40 km de altitude) e \u00e9 muito importante para a prote\u00e7\u00e3o da vida na Terra. Ela tem sofrido danos pela libera\u00e7\u00e3o de CFCs e medidas preventivas t\u00eam sido tomadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Neste texto sobre a Camada de Oz\u00f4nio, <strong>voc\u00ea encontrar\u00e1:<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>O que \u00e9 a Camada de Oz\u00f4nio?<\/li><li>Onde ela se encontra?<\/li><li>Forma\u00e7\u00e3o e funcionamento do oz\u00f4nio em 3 fases (fot\u00f3lise, forma\u00e7\u00e3o e consumo)<\/li><li>Fun\u00e7\u00e3o e Import\u00e2ncia da Ozonosfera<\/li><li>O que est\u00e1 acontecendo com ela?<\/li><li>Buraco na Camada de oz\u00f4nio e consequ\u00eancias para a sa\u00fade e o meio ambiente<\/li><\/ol>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Estudando para as provas?<\/strong> Conhe\u00e7a <a href=\"https:\/\/beduka.com\/blog\/dicas\/enem-dicas\/simulados-para-enem-online-e-gratuito\/\" target=\"_blank\" rel=\"noreferrer noopener\">O melhor Simulado do Brasil!<\/a> Ele pode ser personalizado com as mat\u00e9rias que voc\u00ea mais precisa!<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">O que \u00e9 a Camada de Oz\u00f4nio? (Defini\u00e7\u00e3o)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A Camada de Oz\u00f4nio, tamb\u00e9m chamada de Ozonosfera, \u00e9 <strong>uma das <\/strong><a href=\"https:\/\/beduka.com\/blog\/materias\/geografia\/camadas-da-atmosfera-terrestre\/\" target=\"_blank\" rel=\"noreferrer noopener\">camadas da atmosfera<\/a> terrestre. Essa camada \u00e9 fina e seu <strong>principal componente \u00e9 o<\/strong> <strong>g\u00e1s oz\u00f4nio (O3)<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea sabia que o dia 16 de setembro \u00e9 considerado o Dia Internacional de Prote\u00e7\u00e3o \u00e0 Camada de Oz\u00f4nio? Pois \u00e9, sua fun\u00e7\u00e3o \u00e9 importante para a vida na terra, embora nas \u00faltimas d\u00e9cadas ela tenha sofrido danos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m existem v\u00e1rias reuni\u00f5es mundiais feitas para preserv\u00e1-la e lembrarmos da sua import\u00e2ncia. Adiante falaremos mais sobre isso. Vamos come\u00e7ar por sua localiza\u00e7\u00e3o:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Onde se encontra a Camada de Oz\u00f4nio?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O que chamamos de Ozonosfera fica<strong> localizado em meio \u00e0 Estratosfera<\/strong>, em uma <strong>altura de 20 a 35 km<\/strong> da superf\u00edcie. Essa \u00e9 <strong>a segunda regi\u00e3o da nossa atmosfera<\/strong>, contando de baixo para cima.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Importante:<\/strong> o g\u00e1s oz\u00f4nio pode ser encontrado em duas regi\u00f5es diferentes da atmosfera terrestre. Em cada uma delas, existe em uma determinada concentra\u00e7\u00e3o, desempenhando pap\u00e9is e efeitos distintos.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Estratosfera:<\/strong> 90% do O3 est\u00e1 aqui e o efeito causado \u00e9 ben\u00e9fico: forma a Camada de Oz\u00f4nio que filtra radia\u00e7\u00f5es.<\/li><li><strong>Troposfera <\/strong>(camada mais baixa): apenas 10% do O3 se encontra aqui e o efeito causado \u00e9 mal\u00e9fico: se os n\u00edveis ultrapassam a normalidade, causa polui\u00e7\u00e3o do ar e <a href=\"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-a-chuva-acida\/\" target=\"_blank\" rel=\"noreferrer noopener\">chuva \u00e1cida<\/a>.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Forma\u00e7\u00e3o e funcionamento do oz\u00f4nio<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">J\u00e1 vimos que o g\u00e1s oz\u00f4nio pode ser encontrado em dois locais diferentes. Da mesma forma, em cada um desses locais sua forma\u00e7\u00e3o acontece de formas distintas. Observe:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Na Troposfera:<\/strong> nas camadas mais baixas e em menores concentra\u00e7\u00f5es, o oz\u00f4nio \u00e9 produzido pela oxida\u00e7\u00e3o do g\u00e1s oxig\u00eanio (O2) causada pelo \u00f3xido nitroso (N2O) e luz solar. Por isso, nesse local, ele pode formar a chuva \u00e1cida.<\/li><li><strong>Na Estratosfera:<\/strong> onde \u00e9 encontrado em maior quantidade, ele \u00e9 produzido pela da radia\u00e7\u00e3o ultravioleta (UV) que atua sob a mol\u00e9cula de oxig\u00eanio (O2).<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">A forma\u00e7\u00e3o do g\u00e1s oz\u00f4nio na Ozonosfera \u00e9 <strong>muito din\u00e2mica<\/strong>, pois ele \u00e9 formado e destru\u00eddo naturalmente a todo momento, pela participa\u00e7\u00e3o do oxig\u00eanio e dos raios ultravioletas. <strong>\u00c9 essa que ocorre na Estratosfera que \u00e9 relevante para n\u00f3s.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vamos entender, em 3 etapas, como essas rea\u00e7\u00f5es acontecem:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">1.Fot\u00f3lise do oxig\u00eanio<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O termo \u201cfot\u00f3lise\u201d significa a quebra de algo usando a luz. Nesse caso, n\u00f3s sabemos que a atmosfera possui muitas mol\u00e9culas de oxig\u00eanio, principalmente na forma de g\u00e1s oxig\u00eanio (O2).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sendo assim, nessa primeira fase a<strong> radia\u00e7\u00e3o solar ultravioleta (UV)<\/strong> <strong>atinge uma mol\u00e9cula de O<\/strong><strong>2<\/strong><strong> <\/strong>e separa seus dois \u00e1tomos. Com isso, <strong>s\u00e3o formados dois \u00e1tomos livres de oxig\u00eanio<\/strong> (O).<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">1 O2(g) \u2192 2 O(g)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vamos supor que j\u00e1 chegamos ao fim dos processos e j\u00e1 temos O3 na atmosfera. Al\u00e9m de causar a fot\u00f3lise do O2, <strong>a radia\u00e7\u00e3o solar tamb\u00e9m consegue separar um dos tr\u00eas \u00e1tomos de oxig\u00eanio do oz\u00f4nio, formando mais g\u00e1s oxig\u00eanio.<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">1 O3(g) \u2192 1 O2(g) + 1 O(g)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2.Forma\u00e7\u00e3o do oz\u00f4nio<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Na segunda etapa, cada <strong>oxig\u00eanio livre (O) produzido na fot\u00f3lise reage com uma mol\u00e9cula de O<\/strong><strong>2<\/strong> <strong>e forma o g\u00e1s oz\u00f4nio (O<\/strong><strong>3<\/strong><strong>).&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">1 O + 1 O2(g) \u2192 1 O3(g)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para entender esse processo \u00e9 importante ressaltar que nem todas as mol\u00e9culas de oz\u00f4nio ou de oxig\u00eanio foram quebradas na primeira etapa. Assim, todas essas <strong>esp\u00e9cies qu\u00edmicas coexistem e as rea\u00e7\u00f5es ocorrem ao mesmo tempo<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Outro fator importante \u00e9 que cada uma acontece em determinada velocidade, ent\u00e3o d\u00e1 tempo de tirar e repor as coisas de forma equilibrada. Por isso, dizemos que as concentra\u00e7\u00f5es dos gases na Ozonosfera s\u00e3o din\u00e2micas!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por fim, \u00e9 importante dizer que a forma\u00e7\u00e3o do O3 acontece com a ajuda de um <strong>catalisador<\/strong>. Os catalisadores podem ser \u00e1tomos ou mol\u00e9culas que participam de uma rea\u00e7\u00e3o s\u00f3 para aceler\u00e1-la. Eles entram e saem dessa rea\u00e7\u00e3o sem serem consumidos ou modificados.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3.Consumo do oz\u00f4nio&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Como <strong>estamos falando de um ciclo<\/strong>, chegamos \u00e0 terceira etapa com o p\u00e9 j\u00e1 na primeira. Nesse momento o O3 produzido passa a compor a atmosfera, mas <strong>uma parte dele \u00e9, novamente, quebrado pela radia\u00e7\u00e3o<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A novidade aqui \u00e9 essa:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">H\u00e1 outra forma do oz\u00f4nio ser degradado (n\u00e3o s\u00f3 pela radia\u00e7\u00e3o). <strong>A mol\u00e9cula de O<\/strong><strong>3<\/strong><strong> \u00e9 altamente reativa <\/strong>e suscet\u00edvel \u00e0s mudan\u00e7as. Ent\u00e3o, <strong>quando h\u00e1 \u00e1tomos de oxig\u00eanio livre (O), ele reage com o O<\/strong><strong>3<\/strong><strong>.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por\u00e9m, <strong>n\u00e3o existe a mol\u00e9cula \u201cO<\/strong><strong>4<\/strong><strong>\u201d<\/strong> na natureza, pois \u00e9 muito inst\u00e1vel. Assim, o que realmente \u00e9 formado s\u00e3o <strong>2 mol\u00e9culas de O<\/strong><strong>2<\/strong><strong>.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E assim o ciclo recome\u00e7a!<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>S\u00e3o mais de 200 resumos gratuitos no <a href=\"https:\/\/www.instagram.com\/beduka_oficial\/?hl=pt\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram do Beduka<\/a>. Aproveite!<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Qual \u00e9 a fun\u00e7\u00e3o da Ozonosfera? (Import\u00e2ncia)<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"300\" src=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2021\/02\/esquema-infografico-da-camada-de-ozonio-filtrando-a-radiacao-solar-uv-e-nao-deixando-chegar-na-superficie-da-terra.jpg\" alt=\"esquema infografico da camada de ozonio filtrando a radia\u00e7ao solar uv e n\u00e3o deixando chegar na superficie da terra\" class=\"wp-image-20091\" srcset=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2021\/02\/esquema-infografico-da-camada-de-ozonio-filtrando-a-radiacao-solar-uv-e-nao-deixando-chegar-na-superficie-da-terra.jpg 600w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2021\/02\/esquema-infografico-da-camada-de-ozonio-filtrando-a-radiacao-solar-uv-e-nao-deixando-chegar-na-superficie-da-terra-300x150.jpg 300w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2021\/02\/esquema-infografico-da-camada-de-ozonio-filtrando-a-radiacao-solar-uv-e-nao-deixando-chegar-na-superficie-da-terra-320x160.jpg 320w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">A Camada de Oz\u00f4nio \u00e9 de extrema import\u00e2ncia, pois o oz\u00f4nio \u00e9 o <strong>\u00fanico g\u00e1s naturalmente capaz de filtrar a radia\u00e7\u00e3o ultravioleta do tipo B<\/strong> (UV-B). Al\u00e9m disso, ela tamb\u00e9m filtra os demais tipos de radia\u00e7\u00e3o solar. Ent\u00e3o ela age como um escudo protetor!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O sol emite ondas de luz muito fortes, chamadas de radia\u00e7\u00e3o. A <a href=\"https:\/\/beduka.com\/blog\/materias\/fisica\/fisica-ondulatoria\/\" target=\"_blank\" rel=\"noreferrer noopener\">frequ\u00eancia<\/a> dessa onda \u00e9 muito alta e est\u00e1 acima das ondas vis\u00edveis (que vemos as cores). Por isso, dizemos que a radia\u00e7\u00e3o solar \u00e9 ultravioleta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os raios ultravioletas abrangem muitos valores, ent\u00e3o ainda podemos subdividi-las em UV-A, UV-B e UV-C. Todos esses tipos causam danos a n\u00f3s, mas s\u00e3o diferentes na intensidade e no que causa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A exist\u00eancia da Camada de Oz\u00f4nio <strong>filtra cerca de 95% de todos os raios UV<\/strong>, impedindo que a maior parte atinja a superf\u00edcie terrestre. Assim, \u00e9 um <strong>filtro que protege a vida na Terra<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essa \u00e9 a sua fun\u00e7\u00e3o e import\u00e2ncia prim\u00e1ria, mas disso saem v\u00e1rios desdobramentos:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Evita o desenvolvimento de enfermidades, preservando a sa\u00fade das pessoas.<\/li><li>Mant\u00e9m o Efeito Estufa em n\u00edveis normais, preservando o planeta do <a href=\"https:\/\/beduka.com\/blog\/materias\/biologia\/definicao-de-aquecimento-global\/\" target=\"_blank\" rel=\"noreferrer noopener\">Aquecimento Global<\/a>.<\/li><li>Mant\u00e9m condi\u00e7\u00f5es favor\u00e1veis para a <a href=\"https:\/\/beduka.com\/blog\/materias\/biologia\/o-que-e-ecologia\/\" target=\"_blank\" rel=\"noreferrer noopener\">biodiversidade nos ecossistemas<\/a>.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Enfim, pensar no funcionamento da Camada de Oz\u00f4nio e sua import\u00e2ncia \u00e9 pensar sobre o <strong>equil\u00edbrio e manuten\u00e7\u00e3o da vida<\/strong> no nosso planeta.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O que est\u00e1 acontecendo com a Camada de Oz\u00f4nio? (destrui\u00e7\u00e3o)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Apesar de toda a sua import\u00e2ncia, a Ozonosfera tem sido destru\u00edda nas \u00faltimas d\u00e9cadas, fazendo com que essa camada se torne cada vez mais fina e filtrando menos radia\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O que tem causado essa degrada\u00e7\u00e3o \u00e9, principalmente, a emiss\u00e3o excessiva de gases <strong>CFCs (clorofluorcarbonetos)<\/strong>, ou seja, gases que t\u00eam os elementos Cloro, Fl\u00faor e Carbono na sua composi\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mesmo sendo os principais vil\u00f5es, eles n\u00e3o s\u00e3o os \u00fanicos. <strong>As subst\u00e2ncias<\/strong> <strong>que prejudicam <\/strong>a camada s\u00e3o:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>\u00d3xido n\u00edtrico<\/strong> (NO): produzido pela queima de combust\u00edveis f\u00f3sseis.<\/li><li><strong>\u00d3xido nitroso<\/strong> (N2O): eliminado pelos ve\u00edculos e ind\u00fastrias.<\/li><li><strong>Di\u00f3xido de carbono<\/strong> (CO2): gerado em rea\u00e7\u00f5es de combust\u00e3o completa.<\/li><li><strong>Clorofluorcarbonos <\/strong>(CFCs): utilizados em aeross\u00f3is (desodorante spray), na produ\u00e7\u00e3o de pl\u00e1sticos e de refrigeradores (geladeiras).<\/li><li><strong>Halon <\/strong>(CBrCtF2):<strong> <\/strong>usados em extintores de inc\u00eandio.<\/li><li><strong>Tetracloreto de carbono <\/strong>(CTC): tamb\u00e9m usado em extintores e refrigeradores.<\/li><li><strong>Brometo de metila <\/strong>(CH3BR): usado na \u00e1rea da sa\u00fade e na agricultura.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Como os CFCs e demais subst\u00e2ncias destroem a Ozonosfera?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">De modo geral, esses componentes prejudicam a Camada de Oz\u00f4nio porque eles s\u00e3o <strong>facilmente quebrados pela radia\u00e7\u00e3o UV.<\/strong> Assim, a grande emiss\u00e3o deles faz com que eles atinjam a Camada de Oz\u00f4nio e l\u00e1 eles s\u00e3o <strong>decompostos em \u00e1tomos livres.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como o oz\u00f4nio \u00e9 muito reativo e eles tamb\u00e9m, <strong>os compostos reagem entre si<\/strong>. O problema \u00e9 que isso <strong>desestabiliza o equil\u00edbrio natural<\/strong> que vimos acima. O O3 se transforma em oxig\u00eanio e agora temos 2x mais produ\u00e7\u00e3o de oxig\u00eanio do que de oz\u00f4nio.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Outro agravante \u00e9 que alguns elementos qu\u00edmicos ficam ativos por 80, 90 e at\u00e9 100 anos. Assim, o ciclo natural perde sua efici\u00eancia, a concentra\u00e7\u00e3o de Oz\u00f4nio diminui e a camada afina. Com tudo isso, <strong>a filtragem dos raios ultravioleta diminui.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>No caso dos CFCs h\u00e1 um agravante<\/strong> que os tornam os principais vil\u00f5es. Eles levam cerca de oito anos para chegar \u00e0 estratosfera e uma \u00fanica mol\u00e9cula de CFC pode destruir 100 mil mol\u00e9culas de oz\u00f4nio!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Existe um buraco na Camada de Oz\u00f4nio?<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"300\" src=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2021\/02\/buraco-na-camada-de-ozonio-evolucao-diminuindo-nos-anos-de-2014-2015-2016-2017-2018-2019.jpg\" alt=\"buraco na camada de ozonio evolu\u00e7ao diminuindo nos anos de 2014 2015 2016 2017 2018 2019\" class=\"wp-image-20090\" srcset=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2021\/02\/buraco-na-camada-de-ozonio-evolucao-diminuindo-nos-anos-de-2014-2015-2016-2017-2018-2019.jpg 600w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2021\/02\/buraco-na-camada-de-ozonio-evolucao-diminuindo-nos-anos-de-2014-2015-2016-2017-2018-2019-300x150.jpg 300w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2021\/02\/buraco-na-camada-de-ozonio-evolucao-diminuindo-nos-anos-de-2014-2015-2016-2017-2018-2019-320x160.jpg 320w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Sim! Em 1977, alguns cientistas observaram a exist\u00eancia de um buraco na Camada de Oz\u00f4nio, que ficava bem acima da Ant\u00e1rtida. Desde ent\u00e3o, ele tem sido monitorado e v\u00e1rias conclus\u00f5es foram elaboradas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esses buracos podem aparecer em v\u00e1rias partes do globo, embora sejam mais comuns nos polos e especialmente no Polo Sul. Esse fen\u00f4meno \u00e9 natural por causa da dinamicidade do ciclo do oz\u00f4nio e acontece mais no Sul por causa das condi\u00e7\u00f5es clim\u00e1ticas de l\u00e1.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m foi constatado que <strong>esses buracos aparecem e somem naturalmente, mas isso passou a n\u00e3o acontecer. <\/strong>O buraco acima da Ant\u00e1rtida apareceu e s\u00f3 tem aumentado de tamanho, cada vez mais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como voc\u00ea deve imaginar, foi o aumento na emiss\u00e3o dos gases CFCs e os demais mencionados acima que contribu\u00edram para isso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Atualmente <strong>o mundo inteiro coopera para reduzir a produ\u00e7\u00e3o e uso desses gases<\/strong>, a fim de estabilizar a Camada de Oz\u00f4nio e impedir o crescimento do buraco. Isso \u00e9 muito importante pois <strong>sua destrui\u00e7\u00e3o causa s\u00e9rios riscos \u00e0 sa\u00fade e ao equil\u00edbrio ambiental<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em 1985, houve uma reuni\u00e3o com v\u00e1rias na\u00e7\u00f5es, chamada de <strong>Conven\u00e7\u00e3o de Viena<\/strong> para a Prote\u00e7\u00e3o da Camada de Oz\u00f4nio. Os 28 pa\u00edses envolvidos estabeleceram promessas de ajudar nas pesquisas, no monitoramento e na redu\u00e7\u00e3o da produ\u00e7\u00e3o de CFCs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O <strong>Protocolo de Montreal <\/strong>foi um conjunto de medidas ratificadas no Brasil em 19 de mar\u00e7o de 1990, uma consequ\u00eancia dessa Conven\u00e7\u00e3o. Nele, o nosso pa\u00eds se dispunha a fazer todas as medidas ditas acima.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Atualmente, observa-se que o tamanho do Buraco sob a Ant\u00e1rtica continua preocupante e acima da m\u00e9dia. Por\u00e9m, em compara\u00e7\u00e3o aos \u00faltimos 10 anos, ele n\u00e3o tem crescido mais e tende \u00e0 diminui\u00e7\u00e3o. Ainda assim, levar\u00e1 muitos anos para normalizar a situa\u00e7\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Quais as consequ\u00eancias da destrui\u00e7\u00e3o da Camada de Oz\u00f4nio?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Depois de ver a fun\u00e7\u00e3o e a import\u00e2ncia da Ozonosfera, voc\u00ea j\u00e1 deve imaginar quais s\u00e3o as consequ\u00eancias da sua destrui\u00e7\u00e3o. Sem a prote\u00e7\u00e3o da Camada de Oz\u00f4nio, podemos citar v\u00e1rios impactos ao meio ambiente e \u00e0 sa\u00fade:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Casos de envelhecimento precoce.<\/li><li>Aumento nos casos de cegueira por catarata e outros problemas de vis\u00e3o.<\/li><li>Alergias e c\u00e2nceres envolvendo a pele.<\/li><li>Aumento de casos com o v\u00edrus herpes em indiv\u00edduos que j\u00e1 tinham contra\u00eddo.<\/li><li>Aumento da temperatura do planeta, j\u00e1 que um maior n\u00famero de raios ultravioletas atingem a superf\u00edcie da Terra, retendo mais calor.<\/li><li>Enfraquecimento do sistema imunol\u00f3gico.<\/li><li>Redu\u00e7\u00e3o das calotas polares e aumento do degelo.<\/li><li>Poss\u00edvel aumento no n\u00edvel do mar<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Gostou do nosso artigo sobre a Camada de Oz\u00f4nio, suas fases e caracter\u00edsticas?<\/strong> Confira outros artigos do nosso blog e se prepare para o Enem da melhor maneira! Voc\u00ea tamb\u00e9m pode se organizar com o nosso <a href=\"https:\/\/beduka.com\/blog\/dicas\/enem-dicas\/plano-de-estudos-gratuito\/\" target=\"_blank\" rel=\"noreferrer noopener\">plano de estudos<\/a>, o mais completo da internet, e o melhor: totalmente gratuito!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Queremos te ajudar a encontrar a FACULDADE IDEAL!<\/strong> Logo abaixo, fa\u00e7a uma pesquisa por curso e cidade que te mostraremos todas as faculdades que podem te atender. Informamos a nota de corte, valor de mensalidade, nota do MEC, avalia\u00e7\u00e3o dos alunos, modalidades de ensino e muito mais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Experimente agora<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Camada de Oz\u00f4nio \u00e9 uma faixa gasosa da atmosfera terrestre. Seu principal componente \u00e9 o g\u00e1s oz\u00f4nio (O3), respons\u00e1vel pela filtra\u00e7\u00e3o de radia\u00e7\u00e3o solar UV. A Ozonosfera fica na Estratosfera (40 km de altitude) e \u00e9 muito importante para a prote\u00e7\u00e3o da vida na Terra. Ela tem sofrido danos pela libera\u00e7\u00e3o de CFCs e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":20089,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[493],"tags":[],"class_list":["post-20088","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geografia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O que \u00e9 a Camada de Oz\u00f4nio? (Resumo Completo)<\/title>\n<meta name=\"description\" content=\"A Camada de Oz\u00f4nio \u00e9 uma faixa de g\u00e1s O3 que faz parte da atmosfera terrestre. Descubra como ela se forma, qual sua import\u00e2ncia e o que tem acontecido nela!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beduka.com\/blog\/materias\/geografia\/camada-de-ozonio\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O que \u00e9 a Camada de Oz\u00f4nio? (Resumo Completo)\" \/>\n<meta property=\"og:description\" content=\"A Camada de Oz\u00f4nio \u00e9 uma faixa de g\u00e1s O3 que faz parte da atmosfera terrestre. Descubra como ela se forma, qual sua import\u00e2ncia e o que tem acontecido nela!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beduka.com\/blog\/materias\/geografia\/camada-de-ozonio\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-25T14:32:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-25T15:15:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2021\/02\/Tudo-o-que-voce-precisa-saber-sobre-a-Camada-de-Ozonio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"609\" \/>\n\t<meta property=\"og:image:height\" content=\"342\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/geografia\\\/camada-de-ozonio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/geografia\\\/camada-de-ozonio\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/person\\\/325d912d2cb8dd9ede8ab291427d2b8a\"},\"headline\":\"Resumo da Camada de Oz\u00f4nio: fun\u00e7\u00e3o, local, import\u00e2ncia &#8230;\",\"datePublished\":\"2021-02-25T14:32:57+00:00\",\"dateModified\":\"2021-02-25T15:15:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/geografia\\\/camada-de-ozonio\\\/\"},\"wordCount\":2177,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/geografia\\\/camada-de-ozonio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Tudo-o-que-voce-precisa-saber-sobre-a-Camada-de-Ozonio.jpg\",\"articleSection\":[\"Geografia\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/geografia\\\/camada-de-ozonio\\\/\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/geografia\\\/camada-de-ozonio\\\/\",\"name\":\"O que \u00e9 a Camada de Oz\u00f4nio? (Resumo Completo)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/geografia\\\/camada-de-ozonio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/geografia\\\/camada-de-ozonio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Tudo-o-que-voce-precisa-saber-sobre-a-Camada-de-Ozonio.jpg\",\"datePublished\":\"2021-02-25T14:32:57+00:00\",\"dateModified\":\"2021-02-25T15:15:32+00:00\",\"description\":\"A Camada de Oz\u00f4nio \u00e9 uma faixa de g\u00e1s O3 que faz parte da atmosfera terrestre. Descubra como ela se forma, qual sua import\u00e2ncia e o que tem acontecido nela!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/geografia\\\/camada-de-ozonio\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/geografia\\\/camada-de-ozonio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/geografia\\\/camada-de-ozonio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Tudo-o-que-voce-precisa-saber-sobre-a-Camada-de-Ozonio.jpg\",\"contentUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Tudo-o-que-voce-precisa-saber-sobre-a-Camada-de-Ozonio.jpg\",\"width\":609,\"height\":342,\"caption\":\"Tudo o que voc\u00ea precisa saber sobre a Camada de Oz\u00f4nio!\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/geografia\\\/camada-de-ozonio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/beduka.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resumo da Camada de Oz\u00f4nio: fun\u00e7\u00e3o, local, import\u00e2ncia &#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/\",\"name\":\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\",\"description\":\"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!\",\"publisher\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beduka.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#organization\",\"name\":\"Beduka\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/marca-beduka.png\",\"contentUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/marca-beduka.png\",\"width\":1077,\"height\":368,\"caption\":\"Beduka\"},\"image\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/beduka.buscadordefaculdades\\\/\",\"https:\\\/\\\/www.instagram.com\\\/beduka_oficial\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/beduka\",\"https:\\\/\\\/br.pinterest.com\\\/bedukaoficial\\\/\",\"https:\\\/\\\/www.youtube.com\\\/beduka\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/person\\\/325d912d2cb8dd9ede8ab291427d2b8a\",\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o Beduka (a)\"},\"description\":\"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/beduka.buscadordefaculdades\",\"https:\\\/\\\/www.instagram.com\\\/beduka_oficial\\\/\",\"https:\\\/\\\/br.pinterest.com\\\/bedukaoficial\\\/\"],\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O que \u00e9 a Camada de Oz\u00f4nio? (Resumo Completo)","description":"A Camada de Oz\u00f4nio \u00e9 uma faixa de g\u00e1s O3 que faz parte da atmosfera terrestre. Descubra como ela se forma, qual sua import\u00e2ncia e o que tem acontecido nela!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beduka.com\/blog\/materias\/geografia\/camada-de-ozonio\/","og_locale":"pt_BR","og_type":"article","og_title":"O que \u00e9 a Camada de Oz\u00f4nio? (Resumo Completo)","og_description":"A Camada de Oz\u00f4nio \u00e9 uma faixa de g\u00e1s O3 que faz parte da atmosfera terrestre. Descubra como ela se forma, qual sua import\u00e2ncia e o que tem acontecido nela!","og_url":"https:\/\/beduka.com\/blog\/materias\/geografia\/camada-de-ozonio\/","og_site_name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","article_publisher":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","article_author":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades","article_published_time":"2021-02-25T14:32:57+00:00","article_modified_time":"2021-02-25T15:15:32+00:00","og_image":[{"width":609,"height":342,"url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2021\/02\/Tudo-o-que-voce-precisa-saber-sobre-a-Camada-de-Ozonio.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Beduka (a)","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Beduka (a)","Est. tempo de leitura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beduka.com\/blog\/materias\/geografia\/camada-de-ozonio\/#article","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/materias\/geografia\/camada-de-ozonio\/"},"author":{"name":"Reda\u00e7\u00e3o Beduka (a)","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a"},"headline":"Resumo da Camada de Oz\u00f4nio: fun\u00e7\u00e3o, local, import\u00e2ncia &#8230;","datePublished":"2021-02-25T14:32:57+00:00","dateModified":"2021-02-25T15:15:32+00:00","mainEntityOfPage":{"@id":"https:\/\/beduka.com\/blog\/materias\/geografia\/camada-de-ozonio\/"},"wordCount":2177,"commentCount":0,"publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"image":{"@id":"https:\/\/beduka.com\/blog\/materias\/geografia\/camada-de-ozonio\/#primaryimage"},"thumbnailUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2021\/02\/Tudo-o-que-voce-precisa-saber-sobre-a-Camada-de-Ozonio.jpg","articleSection":["Geografia"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/beduka.com\/blog\/materias\/geografia\/camada-de-ozonio\/","url":"https:\/\/beduka.com\/blog\/materias\/geografia\/camada-de-ozonio\/","name":"O que \u00e9 a Camada de Oz\u00f4nio? (Resumo Completo)","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beduka.com\/blog\/materias\/geografia\/camada-de-ozonio\/#primaryimage"},"image":{"@id":"https:\/\/beduka.com\/blog\/materias\/geografia\/camada-de-ozonio\/#primaryimage"},"thumbnailUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2021\/02\/Tudo-o-que-voce-precisa-saber-sobre-a-Camada-de-Ozonio.jpg","datePublished":"2021-02-25T14:32:57+00:00","dateModified":"2021-02-25T15:15:32+00:00","description":"A Camada de Oz\u00f4nio \u00e9 uma faixa de g\u00e1s O3 que faz parte da atmosfera terrestre. Descubra como ela se forma, qual sua import\u00e2ncia e o que tem acontecido nela!","breadcrumb":{"@id":"https:\/\/beduka.com\/blog\/materias\/geografia\/camada-de-ozonio\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beduka.com\/blog\/materias\/geografia\/camada-de-ozonio\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/materias\/geografia\/camada-de-ozonio\/#primaryimage","url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2021\/02\/Tudo-o-que-voce-precisa-saber-sobre-a-Camada-de-Ozonio.jpg","contentUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2021\/02\/Tudo-o-que-voce-precisa-saber-sobre-a-Camada-de-Ozonio.jpg","width":609,"height":342,"caption":"Tudo o que voc\u00ea precisa saber sobre a Camada de Oz\u00f4nio!"},{"@type":"BreadcrumbList","@id":"https:\/\/beduka.com\/blog\/materias\/geografia\/camada-de-ozonio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/beduka.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Resumo da Camada de Oz\u00f4nio: fun\u00e7\u00e3o, local, import\u00e2ncia &#8230;"}]},{"@type":"WebSite","@id":"https:\/\/beduka.com\/blog\/#website","url":"https:\/\/beduka.com\/blog\/","name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","description":"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!","publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beduka.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beduka.com\/blog\/#organization","name":"Beduka","url":"https:\/\/beduka.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","contentUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","width":1077,"height":368,"caption":"Beduka"},"image":{"@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/www.linkedin.com\/company\/beduka","https:\/\/br.pinterest.com\/bedukaoficial\/","https:\/\/www.youtube.com\/beduka"]},{"@type":"Person","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a","name":"Reda\u00e7\u00e3o Beduka (a)","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o Beduka (a)"},"description":"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.","sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/br.pinterest.com\/bedukaoficial\/"],"url":"https:\/\/beduka.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/20088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/comments?post=20088"}],"version-history":[{"count":3,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/20088\/revisions"}],"predecessor-version":[{"id":20097,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/20088\/revisions\/20097"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media\/20089"}],"wp:attachment":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media?parent=20088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/categories?post=20088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/tags?post=20088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}