{"id":25084,"date":"2022-03-21T15:57:59","date_gmt":"2022-03-21T18:57:59","guid":{"rendered":"https:\/\/beduka.com\/blog\/?p=25084"},"modified":"2026-08-26T15:49:24","modified_gmt":"2026-08-26T18:49:24","slug":"quem-foi-maria-firmina-dos-reis","status":"publish","type":"post","link":"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-maria-firmina-dos-reis\/","title":{"rendered":"Quem foi Maria Firmina dos Reis? Biografia, obras, caracter\u00edsticas e muito mais."},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong><em>Maria Firmina dos Reis foi uma importante escritora maranhense do s\u00e9culo XIX. Autora do primeiro romance afrodescente do Brasil, permaneceu esquecida por cerca de um s\u00e9culo. Nesse artigo, voc\u00ea vai descobrir quem foi Maria Firmina dos Reis, ter\u00e1 acesso a sua biografia, principais obras e muito mais!<\/em><\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Neste texto, voc\u00ea ter\u00e1 acesso a tudo sobre quem foi Maria Firmina dos Reis. Tem bastante conte\u00fado pela frente, ent\u00e3o<strong> clique em um dos t\u00f3picos para ir diretamente ao que deseja saber:<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><a href=\"#uem-foi-\" data-type=\"internal\" data-id=\"#uem-foi-\">Quem foi Maria Firmina dos Reis?<\/a><\/li>\n\n\n\n<li><a href=\"#autora\" data-type=\"internal\" data-id=\"#autora\">\u00darsula: primeira e principal publica\u00e7\u00e3o da autora<\/a><\/li>\n\n\n\n<li><a href=\"#eis-viveu?\" data-type=\"internal\" data-id=\"#eis-viveu?\">Qual o contexto hist\u00f3rico em que Maria Firmina dos Reis viveu?<\/a><\/li>\n\n\n\n<li><a href=\"#caracter\u00edsticas\" data-type=\"internal\" data-id=\"#caracter\u00edsticas\">Quais as caracter\u00edsticas da escritora Maria Firmina dos Reis?<\/a><\/li>\n\n\n\n<li><a href=\"#publica\u00e7\u00f5es\" data-type=\"internal\" data-id=\"#publica\u00e7\u00f5es\">Lista de todas as publica\u00e7\u00f5es da autora Maria Firmina dos Reis<\/a><\/li>\n\n\n\n<li><a href=\"#perfeita\" data-type=\"internal\" data-id=\"#perfeita\">Quer entrar na faculdade? Conhe\u00e7a a chance perfeita<\/a><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea est\u00e1 se preparando para o Enem? <strong>Se a resposta for sim, saiba que acabamos de lan\u00e7ar\u00a0 o <\/strong><a href=\"https:\/\/beduka.com\/blog\/dicas\/enem-dicas\/plano-de-estudos-gratuito\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Plano de Estudo Beduka<\/strong>.<\/a> Ele est\u00e1 maravilhoso e vai te ajudar demais nessa jornada!\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"uem-foi-\">Quem foi Maria Firmina dos Reis?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Maria Firmina dos Reis foi uma escritora maranhense que permaneceu por cerca de 100 anos no anonimato.&nbsp; <\/strong>Seu nascimento foi na ilha de S\u00e3o Lu\u00eds, em 11 de outubro de 1822. No ano da <a href=\"https:\/\/beduka.com\/blog\/materias\/historia\/como-aconteceu-a-independencia-do-brasil\/\" target=\"_blank\" rel=\"noreferrer noopener\">independ\u00eancia do Brasil.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O compromisso com a independ\u00eancia, tanto na esfera pessoal quanto na social e profissional, fez parte de todos os anos da sua exist\u00eancia.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A autora participou ativamente do cen\u00e1rio educacional, iniciando sua carreira como<strong>&nbsp; professora concursada do Maranh\u00e3o. <\/strong>Atuou por muitos anos em uma escola de educa\u00e7\u00e3o prim\u00e1ria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Em 1880, misturou meninos e meninas em sala de aula pela primeira vez no pa\u00eds. <\/strong>Na \u00e9poca, isso era algo totalmente subversivo (desafiava o contexto do per\u00edodo). Logo, n\u00e3o demorou para que a escola fundada pela autora tivesse que fechar as portas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea j\u00e1 deve ter percebido que naquele tempo nada era muito favor\u00e1vel a quem foi Maria Firmina dos Reis. <strong>Uma mulher, professora e escritora com um olhar cr\u00edtico e inovador.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essas mesmas caracter\u00edsticas que a fizeram permanecer por muito tempo longe dos holofotes liter\u00e1rios, a fariam ter seu nome e obras consolidadas a partir da d\u00e9cada de 60. Como dissemos anteriormente, cerca de 100 anos depois!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Vou te contar como aconteceu\u2026<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Reconhecimento e primeira publica\u00e7\u00e3o<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Em 1962, um historiador chamado Hor\u00e1cio de Almeida resolveu fazer mais uma de suas peregrina\u00e7\u00f5es pelos sebos da cidade.<strong> Foi quando se deparou com a primeira publica\u00e7\u00e3o da autora,<\/strong> <strong>o romance \u201c\u00darsula\u201d.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por sinal, devido a essa produ\u00e7\u00e3o, Maria Firmina \u00e9 considerada<strong> autora do primeiro romance afro-brasileiro.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voltando ao in\u00edcio de sua ascens\u00e3o p\u00f3stuma, Hor\u00e1cio comprou a publica\u00e7\u00e3o e atestou a qualidade de seus escritos. Isso fez com que Maria Firmina come\u00e7asse a ser<strong> redescoberta pelos cr\u00edticos e cen\u00e1rio da literatura em geral.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Assim, importantes editoras reeditaram e publicaram \u201c\u00darsula\u201d.<\/strong> Infelizmente , ela n\u00e3o conseguiu o devido reconhecimento em vida, muito menos um retorno financeiro. Viveu e faleceu em condi\u00e7\u00f5es financeiras e de sa\u00fade desfavor\u00e1veis.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00e3o tem como se aprofundar sobre quem foi Maria Firmina dos Reis sem conhecer melhor a sua principal publica\u00e7\u00e3o. Veja no pr\u00f3ximo t\u00f3pico.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"autora\">\u00darsula: primeira e principal publica\u00e7\u00e3o da autora<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Publicado pela primeira vez em 1959,<\/strong> \u201c<strong>\u00darsula\u201d foi o livro de estreia da autora Maria Firmina dos Reis.<\/strong> Apesar de n\u00e3o ter representado um reconhecimento liter\u00e1rio em vida, \u00e9 a obra que a consagrou como escritora quase um s\u00e9culo depois.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Trata-se de um romance abolicionista. <\/strong>Hoje, muitos estudiosos consideram a obra o primeiro romance publicado por uma mulher afrodescendente no Brasil. Al\u00e9m disso, o livro \u00e9 pioneiro em abordar sem ressalvas o abolicionismo, antes mesmo dos escritos de Castro Alves.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O autor teve publicada sua primeira produ\u00e7\u00e3o liter\u00e1ria sobre a escravid\u00e3o, um poema, apenas em 1963.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em \u00darsula, al\u00e9m da cr\u00edtica principal (ao racismo e \u00e0 escravid\u00e3o), <strong>tamb\u00e9m \u00e9 poss\u00edvel identificar cr\u00edticas nada sutis ao patriarcado e ao machismo presente na sociedade brasileira desse per\u00edodo.<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O cen\u00e1rio liter\u00e1rio n\u00e3o escapou da indigna\u00e7\u00e3o de Maria Firmino. Afinal, parte dele, possu\u00eda as mesmas caracter\u00edsticas inaceit\u00e1veis presentes no resto da sociedade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Abaixo, \u00e9 poss\u00edvel constatar isso em um dos trechos do livro:&nbsp;<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>\u201cMesquinho e humilde livro \u00e9 este que vos apresento, leitor. (\u2026) Sei que pouco vale este romance, porque escrito por uma mulher, e mulher brasileira, de educa\u00e7\u00e3o acanhada e sem o trato e a conversa\u00e7\u00e3o dos homens ilustrados (\u2026)\u201d<\/em><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Em 1988, uma editora carioca respons\u00e1vel por publicar grandes cl\u00e1ssicos da literatura brasileira, lan\u00e7ou \u00darsula. <strong>Com essa publica\u00e7\u00e3o da Montecristo Editora, o nome de Maria Firmina chegou ao sudeste e sul do Brasil.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Foi assim, que o livro passou a ser classificado como<strong> pertencente ao <\/strong><a href=\"https:\/\/beduka.com\/blog\/materias\/literatura\/o-que-foi-o-romantismo\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Romantismo Brasileiro. <\/strong><\/a>Ele \u00e9 fundamental para compreender quem foi Maria Firmina dos Reis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Quer conhecer o enredo da obra?<\/strong> Ent\u00e3o, essa \u00e9 a hora!<strong> <\/strong>Temos<strong> <\/strong><a href=\"https:\/\/beduka.com\/blog\/materias\/literatura\/resumo-de-ursula-de-maria-firmina\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>um resumo completo de \u00darsula, mais an\u00e1lise!&nbsp;<\/strong><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"eis-viveu?\">Qual o contexto hist\u00f3rico em que Maria Firmina dos Reis viveu?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Quando tratamos da quest\u00e3o sobre quem foi Maria Firmina dos Reis, nos deparamos logo com um fato hist\u00f3rico presente no ano de seu nascimento.<strong> Estou falando de 1822, quando finalmente o pa\u00eds deixou de ser col\u00f4nia de Portugal, ou seja,&nbsp; da <\/strong><a href=\"https:\/\/beduka.com\/blog\/exercicios\/historia-exercicios\/exercicios-sobre-a-independencia-do-brasil\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Independ\u00eancia do Brasil<\/strong>.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Infelizmente, ap\u00f3s isso, nem tudo foi flores. A escravid\u00e3o que teve inic\u00edo por volta de 1530 perdurou at\u00e9 maio de 1988, o ano da aboli\u00e7\u00e3o. Sendo assim, a escritora passou d\u00e9cadas de sua vida convivendo em meio a esse contexto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Por sinal,\u00e9 importante enfatizar que \u201c\u00darsula\u201d&nbsp; foi publicado antes da Lei \u00c1urea. <\/strong>&nbsp;Al\u00e9m disso, Maria Firmina tamb\u00e9m precisou enfrentar o patriarcado presente na \u00e9poca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Para aprender mais sobre escravid\u00e3o que assolou o Brasil, leia os artigos abaixo:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/beduka.com\/blog\/materias\/historia\/resumo-da-escravidao-no-brasil\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Como foi a escravid\u00e3o no Brasil?<\/strong><\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/beduka.com\/blog\/exercicios\/exercicios-sobre-escravidao-no-brasil\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Exerc\u00edcios sobre a escravid\u00e3o no Brasil<\/strong><\/a><strong>&nbsp;<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">De uma forma simples, o patriarcado consiste na presen\u00e7a e dom\u00ednio do homem nas mais diversas esferas sociais. Isso n\u00e3o se resume \u00e0 fam\u00edlia, muito pelo contr\u00e1rio. Por exemplo, <strong>ele estava fortemente presente no cen\u00e1rio liter\u00e1rio.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na \u00e9poca, a ascens\u00e3o social de uma mulher era muito mais dif\u00edcil. <strong>Havia a predomin\u00e2ncia de escritores homens, al\u00e9m de maioria branca.<\/strong> O fato \u00e9 que, para quem foi Maria Firmina dos Reis, essas eram circunst\u00e2ncias muito dif\u00edceis de lidar.&nbsp;&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"caracter\u00edsticas\">Quais as caracter\u00edsticas da escritora Maria Firmina dos Reis?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Primeiro, para entendermos melhor quem foi Maria Firmina dos Reis e suas caracter\u00edsticas, <strong>\u00e9 preciso saber que o per\u00edodo de sua produ\u00e7\u00e3o corresponde a terceira fase do Romantismo. <\/strong>Sendo assim, a autora e suas obras tamb\u00e9m possuem tra\u00e7os desse per\u00edodo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Esses tra\u00e7os podem ser observados em \u00darsula, sua principal produ\u00e7\u00e3o. <\/strong>Na obra, temos um casal branco (Tancredo e \u00darsula) que vive um amor cheio de obst\u00e1culos para se concretizar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Entre esse contexto rom\u00e2ntico, a autora \u201cimprimiu\u201d seu perfil inovador, considerado \u00fanico para a \u00e9poca. <\/strong>Como ela fez isso?&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inserindo na produ\u00e7\u00e3o cr\u00edticas \u00e0 escravid\u00e3o e ao patriarcado, apoio ao abolicinismo e <strong>dando voz a personagens negros por meio da narra\u00e7\u00e3o.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esses personagens n\u00e3o eram meros coadjuvantes do livro, muito pelo contr\u00e1rio, receberam um importante e envolvente protagonismo. <strong>Por meio da narrativa, eles t\u00eam participa\u00e7\u00e3o ativa nas cr\u00edticas que permeiam o enredo.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>O indianismo tamb\u00e9m fala muito sobre quem foi Maria Firmina dos Reis.<\/strong> Em uma de suas obras, a autora segue essa vertente bastante comum na escola liter\u00e1ria de sua \u00e9poca. Estamos nos referindo ao livro Gupeva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Maria Firmina tamb\u00e9m escreveu poemas.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"publica\u00e7\u00f5es\">Lista de todas as publica\u00e7\u00f5es da autora Maria Firmina dos Reis<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Agora que voc\u00ea j\u00e1 sabe quem foi Maria Firmina dos Reis, fica bem mais f\u00e1cil entender suas obras.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Todas essas produ\u00e7\u00f5es apresentam uma inquieta\u00e7\u00e3o a respeito das injusti\u00e7as presentes na sociedade da \u00e9poca.<\/strong> Veja a lista completa:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00darsula \u2014 romance (1859)<\/li>\n\n\n\n<li>Gupeva \u2014 romance (1861)<\/li>\n\n\n\n<li>Parnaso maranhense \u2014 colet\u00e2nea de poemas junto com outros autores (1861)<\/li>\n\n\n\n<li>A escrava \u2014 conto (1887)<\/li>\n\n\n\n<li>Cantos \u00e0 beira-mar \u2014 poesias (1871)<\/li>\n\n\n\n<li>Hino da liberta\u00e7\u00e3o dos escravos (1888)<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"perfeita\">Quer entrar na faculdade? Conhe\u00e7a a chance perfeita<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Eu quero te perguntar! J\u00e1 pensou em fazer uma faculdade?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se esse \u00e9 seu sonho, voc\u00ea est\u00e1 no lugar certo. Agora, se n\u00e3o for, <strong>vou te dar tr\u00eas motivos para se tornar:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mais chances no mercado de trabalho<\/li>\n\n\n\n<li>Aumento da rede de contatos<\/li>\n\n\n\n<li>Melhoria de sal\u00e1rio<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Tudo isso sem precisar fazer prova e totalmente desvinculado do Enem.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estou falando do <a href=\"https:\/\/beduka.com\/blog\/dicas\/faculdades\/beduka-bolsas\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Beduka Bolsas<\/strong><\/a><strong>! Nessa plataforma, voc\u00ea tem chance de ganhar bolsas de 65% para v\u00e1rios cursos, cidades e modalidades.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Basta escolher a bolsa para o curso dos seus sonhos e gerar a sua Carta Matr\u00edcula. Pronto! J\u00e1 pode estudar. E voc\u00ea pode fazer isso em qualquer \u00e9poca do ano. <strong>Estudar nunca foi t\u00e3o f\u00e1cil!&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Independente de qualquer coisa, <\/strong>&nbsp;saber quem foi Maria Firmina dos Reis \u00e9 muito importante para entender diversas caracter\u00edsticas hist\u00f3ricas e sociais do pa\u00eds.<strong> E, esse \u00e9 nosso papel, preparar conte\u00fados sobre assuntos important\u00edssimos e de uma forma super f\u00e1cil de compreender.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>No mais, ainda queremos te ajudar a encontrar a FACULDADE IDEAL!<\/strong> Logo abaixo, fa\u00e7a uma pesquisa por curso e cidade que te mostraremos todas as faculdades que podem te atender. Informamos a nota de corte, valor de mensalidade, nota do MEC, avalia\u00e7\u00e3o dos alunos, modalidades de ensino e muito mais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p> Leia esse artigo para descobrir tudo sobre quem foi Maria Firmina dos Reis, mas j\u00e1 adianto, ela \u00e9 considerada a autora do primeiro romance afrodescendente produzido no Brasil e suas obras caem nos vestibulares. <\/p>\n","protected":false},"author":20,"featured_media":25085,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[489],"tags":[],"class_list":["post-25084","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-literatura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quem foi Maria Firmina dos Reis? Biografia, principais obras e muito mais.<\/title>\n<meta name=\"description\" content=\"Leia esse artigo para descobrir tudo sobre quem foi Maria Firmina dos Reis, mas j\u00e1 adianto, ela \u00e9 considerada a autora do primeiro romance afrodescendente produzido no Brasil e suas obras caem nos vestibulares.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-maria-firmina-dos-reis\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quem foi Maria Firmina dos Reis? Biografia, principais obras e muito mais.\" \/>\n<meta property=\"og:description\" content=\"Leia esse artigo para descobrir tudo sobre quem foi Maria Firmina dos Reis, mas j\u00e1 adianto, ela \u00e9 considerada a autora do primeiro romance afrodescendente produzido no Brasil e suas obras caem nos vestibulares.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-maria-firmina-dos-reis\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-21T18:57:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-26T18:49:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2022\/03\/Quem-foi-Maria-Firmina-dos-Reis.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"609\" \/>\n\t<meta property=\"og:image:height\" content=\"342\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Beduka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Beduka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/literatura\\\/quem-foi-maria-firmina-dos-reis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/literatura\\\/quem-foi-maria-firmina-dos-reis\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Beduka\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/person\\\/6663b033dafd59fc30595515af1715a6\"},\"headline\":\"Quem foi Maria Firmina dos Reis? Biografia, obras, caracter\u00edsticas e muito mais.\",\"datePublished\":\"2022-03-21T18:57:59+00:00\",\"dateModified\":\"2026-08-26T18:49:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/literatura\\\/quem-foi-maria-firmina-dos-reis\\\/\"},\"wordCount\":1646,\"publisher\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/literatura\\\/quem-foi-maria-firmina-dos-reis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Quem-foi-Maria-Firmina-dos-Reis.jpg\",\"articleSection\":[\"Literatura\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/literatura\\\/quem-foi-maria-firmina-dos-reis\\\/\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/literatura\\\/quem-foi-maria-firmina-dos-reis\\\/\",\"name\":\"Quem foi Maria Firmina dos Reis? Biografia, principais obras e muito mais.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/literatura\\\/quem-foi-maria-firmina-dos-reis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/literatura\\\/quem-foi-maria-firmina-dos-reis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Quem-foi-Maria-Firmina-dos-Reis.jpg\",\"datePublished\":\"2022-03-21T18:57:59+00:00\",\"dateModified\":\"2026-08-26T18:49:24+00:00\",\"description\":\"Leia esse artigo para descobrir tudo sobre quem foi Maria Firmina dos Reis, mas j\u00e1 adianto, ela \u00e9 considerada a autora do primeiro romance afrodescendente produzido no Brasil e suas obras caem nos vestibulares.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/literatura\\\/quem-foi-maria-firmina-dos-reis\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/literatura\\\/quem-foi-maria-firmina-dos-reis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/literatura\\\/quem-foi-maria-firmina-dos-reis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Quem-foi-Maria-Firmina-dos-Reis.jpg\",\"contentUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Quem-foi-Maria-Firmina-dos-Reis.jpg\",\"width\":609,\"height\":342,\"caption\":\"Quem foi Maria Firmina dos Reis\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/literatura\\\/quem-foi-maria-firmina-dos-reis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/beduka.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quem foi Maria Firmina dos Reis? Biografia, obras, caracter\u00edsticas e muito mais.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/\",\"name\":\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\",\"description\":\"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!\",\"publisher\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beduka.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#organization\",\"name\":\"Beduka\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/marca-beduka.png\",\"contentUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/marca-beduka.png\",\"width\":1077,\"height\":368,\"caption\":\"Beduka\"},\"image\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/beduka.buscadordefaculdades\\\/\",\"https:\\\/\\\/www.instagram.com\\\/beduka_oficial\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/beduka\",\"https:\\\/\\\/br.pinterest.com\\\/bedukaoficial\\\/\",\"https:\\\/\\\/www.youtube.com\\\/beduka\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/person\\\/6663b033dafd59fc30595515af1715a6\",\"name\":\"Reda\u00e7\u00e3o Beduka\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4cca68ccf0f47cf979ec86ec34932b09942727b58e560ae94fb56228883358bc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4cca68ccf0f47cf979ec86ec34932b09942727b58e560ae94fb56228883358bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4cca68ccf0f47cf979ec86ec34932b09942727b58e560ae94fb56228883358bc?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o Beduka\"},\"description\":\"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/beduka.buscadordefaculdades\",\"https:\\\/\\\/www.instagram.com\\\/beduka_oficial\\\/\",\"https:\\\/\\\/br.pinterest.com\\\/bedukaoficial\\\/\"],\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/author\\\/alessandra\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quem foi Maria Firmina dos Reis? Biografia, principais obras e muito mais.","description":"Leia esse artigo para descobrir tudo sobre quem foi Maria Firmina dos Reis, mas j\u00e1 adianto, ela \u00e9 considerada a autora do primeiro romance afrodescendente produzido no Brasil e suas obras caem nos vestibulares.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-maria-firmina-dos-reis\/","og_locale":"pt_BR","og_type":"article","og_title":"Quem foi Maria Firmina dos Reis? Biografia, principais obras e muito mais.","og_description":"Leia esse artigo para descobrir tudo sobre quem foi Maria Firmina dos Reis, mas j\u00e1 adianto, ela \u00e9 considerada a autora do primeiro romance afrodescendente produzido no Brasil e suas obras caem nos vestibulares.","og_url":"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-maria-firmina-dos-reis\/","og_site_name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","article_publisher":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","article_author":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades","article_published_time":"2022-03-21T18:57:59+00:00","article_modified_time":"2026-08-26T18:49:24+00:00","og_image":[{"width":609,"height":342,"url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2022\/03\/Quem-foi-Maria-Firmina-dos-Reis.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Beduka","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Beduka","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-maria-firmina-dos-reis\/#article","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-maria-firmina-dos-reis\/"},"author":{"name":"Reda\u00e7\u00e3o Beduka","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/6663b033dafd59fc30595515af1715a6"},"headline":"Quem foi Maria Firmina dos Reis? Biografia, obras, caracter\u00edsticas e muito mais.","datePublished":"2022-03-21T18:57:59+00:00","dateModified":"2026-08-26T18:49:24+00:00","mainEntityOfPage":{"@id":"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-maria-firmina-dos-reis\/"},"wordCount":1646,"publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"image":{"@id":"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-maria-firmina-dos-reis\/#primaryimage"},"thumbnailUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2022\/03\/Quem-foi-Maria-Firmina-dos-Reis.jpg","articleSection":["Literatura"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-maria-firmina-dos-reis\/","url":"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-maria-firmina-dos-reis\/","name":"Quem foi Maria Firmina dos Reis? Biografia, principais obras e muito mais.","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-maria-firmina-dos-reis\/#primaryimage"},"image":{"@id":"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-maria-firmina-dos-reis\/#primaryimage"},"thumbnailUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2022\/03\/Quem-foi-Maria-Firmina-dos-Reis.jpg","datePublished":"2022-03-21T18:57:59+00:00","dateModified":"2026-08-26T18:49:24+00:00","description":"Leia esse artigo para descobrir tudo sobre quem foi Maria Firmina dos Reis, mas j\u00e1 adianto, ela \u00e9 considerada a autora do primeiro romance afrodescendente produzido no Brasil e suas obras caem nos vestibulares.","breadcrumb":{"@id":"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-maria-firmina-dos-reis\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-maria-firmina-dos-reis\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-maria-firmina-dos-reis\/#primaryimage","url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2022\/03\/Quem-foi-Maria-Firmina-dos-Reis.jpg","contentUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2022\/03\/Quem-foi-Maria-Firmina-dos-Reis.jpg","width":609,"height":342,"caption":"Quem foi Maria Firmina dos Reis"},{"@type":"BreadcrumbList","@id":"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-maria-firmina-dos-reis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/beduka.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Quem foi Maria Firmina dos Reis? Biografia, obras, caracter\u00edsticas e muito mais."}]},{"@type":"WebSite","@id":"https:\/\/beduka.com\/blog\/#website","url":"https:\/\/beduka.com\/blog\/","name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","description":"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!","publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beduka.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beduka.com\/blog\/#organization","name":"Beduka","url":"https:\/\/beduka.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","contentUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","width":1077,"height":368,"caption":"Beduka"},"image":{"@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/www.linkedin.com\/company\/beduka","https:\/\/br.pinterest.com\/bedukaoficial\/","https:\/\/www.youtube.com\/beduka"]},{"@type":"Person","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/6663b033dafd59fc30595515af1715a6","name":"Reda\u00e7\u00e3o Beduka","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/4cca68ccf0f47cf979ec86ec34932b09942727b58e560ae94fb56228883358bc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4cca68ccf0f47cf979ec86ec34932b09942727b58e560ae94fb56228883358bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4cca68ccf0f47cf979ec86ec34932b09942727b58e560ae94fb56228883358bc?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o Beduka"},"description":"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.","sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/br.pinterest.com\/bedukaoficial\/"],"url":"https:\/\/beduka.com\/blog\/author\/alessandra\/"}]}},"_links":{"self":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/25084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/comments?post=25084"}],"version-history":[{"count":2,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/25084\/revisions"}],"predecessor-version":[{"id":30616,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/25084\/revisions\/30616"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media\/25085"}],"wp:attachment":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media?parent=25084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/categories?post=25084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/tags?post=25084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}