{"id":25130,"date":"2022-03-24T14:02:17","date_gmt":"2022-03-24T17:02:17","guid":{"rendered":"https:\/\/beduka.com\/blog\/?p=25130"},"modified":"2026-08-26T15:49:19","modified_gmt":"2026-08-26T18:49:19","slug":"quem-foi-william-shakespeare","status":"publish","type":"post","link":"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-william-shakespeare\/","title":{"rendered":"Quem foi William Shakespeare? Descubra tudo sobre sua carreira!"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong><em>O que Romeu e Julieta, Hamlet e Macbeth t\u00eam em comum? Essas pe\u00e7as foram escritas por William Shakespeare, escritor conhecido como o maior dramaturgo de todos os tempos! Neste artigo, al\u00e9m de descobrir quem foi William Shakespeare, voc\u00ea tamb\u00e9m ter\u00e1 acesso a curiosidades intrigantes sobre ele e suas obras.\u00a0<\/em><\/strong><\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea quiser ir diretamente para alguma parte do texto,<strong> clique em um dos t\u00f3picos abaixo:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"#quem-foi-william-shakespeare\" data-type=\"internal\" data-id=\"#quem-foi-william-shakespeare\">Quem foi William Shakespeare?<\/a><\/li><li><a href=\"#5-curiosidades-para-entender-quem-foi-william-shakespeare\" data-type=\"internal\" data-id=\"#5-curiosidades-para-entender-quem-foi-william-shakespeare\">5 Curiosidades para entender quem foi William Shakespeare<\/a><\/li><li><a href=\"#obras-de-william-shakespeare\" data-type=\"internal\" data-id=\"#obras-de-william-shakespeare\">Obras de William Shakespeare<\/a><\/li><li><a href=\"#frases-famosas-de-william-shakespeare\" data-type=\"internal\" data-id=\"#frases-famosas-de-william-shakespeare\">Frases famosas de William Shakespeare<\/a><\/li><li><a href=\"#entre-na-faculdade-com-o-beduka\" data-type=\"internal\" data-id=\"#entre-na-faculdade-com-o-beduka\">Entre na faculdade com o Beduka!<\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Quer testar seus conhecimentos sobre Literatura e outras mat\u00e9rias que caem no vestibular? <a href=\"https:\/\/beduka.com\/simulado-enem\/#\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Fa\u00e7a o Simulado Enem do Beduka!<\/strong><\/a> Ele \u00e9 <strong>gratuito<\/strong> e usa o <strong>mesmo m\u00e9todo de corre\u00e7\u00e3o do Enem.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"quem-foi-william-shakespeare\">Quem foi William Shakespeare?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">William Shakespeare nasceu em 23 de abril de 1564, na pequena cidade de Stratford-upon-Avon, no interior da Inglaterra. Shakespeare era filho de John Shakespeare (1531-1601) e Mary Arden (1535-1608).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O ingl\u00eas foi o terceiro e mais velho filho a sobreviver de uma prole de oito, tinha tr\u00eas irm\u00e3os e duas irm\u00e3s. Seu pai era um conhecido fabricante de luvas da regi\u00e3o e que chegou a ser prefeito de Stratford.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Existem poucos registros sobre a juventude de Shakespeare. De acordo com historiadores, <strong>William estudou em uma excelente grammar school<\/strong> da \u00e9poca. Entretanto, aos 15 anos, o jovem teve que deixar a escola para ajudar sua fam\u00edlia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aos 18 anos, William Shakespeare casa-se com Anne Hathaway (1556-1623), que j\u00e1 estava gr\u00e1vida. Shakespeare e a esposa tiveram tr\u00eas filhos: Susanna e os g\u00eameos Hamnet e Judith.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mudou-se para Londres onde come\u00e7ou a trabalhar no <strong>ramo cultural.<\/strong> Ap\u00f3s anos de uma <strong>carreira consolidada<\/strong> no meio, atuando como <strong>escritor<\/strong>, <strong>dramaturgo<\/strong> e <strong>ator<\/strong>, Shakespeare tornou-se <strong>rico e influente.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em Londres, Shakespeare tornou-se um dos propriet\u00e1rios da companhia de teatro<strong> Lord Chamberlain\u2019s Men<\/strong>, que fazia parte do <strong>teatro elisabetano.<\/strong> Depois da morte da <strong>rainha Elizabeth I <\/strong>em 1603, a companhia mudou seu nome para <strong>King\u2019s Men<\/strong>, em homenagem ao novo, <strong>rei James I.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No ano de 1599, William Shakespeare tornou-se s\u00f3cio do <strong>Globe Theatre<\/strong>, um dos <strong>primeiros teatros constru\u00eddos na Inglaterra<\/strong>. Neste lugar, o dramaturgo encenou algumas de suas pe\u00e7as mais importantes como<strong> Hamlet<\/strong> e <strong>Rei Lear.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em 1613, o Globe Theatre foi <strong>destru\u00eddo por um inc\u00eandio<\/strong> durante a apresenta\u00e7\u00e3o da pe\u00e7a <strong>Henrique VIII.<\/strong> Depois do acontecimento, Shakespeare retorna para sua cidade natal para viver com sua fam\u00edlia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O escritor faleceu no dia de seu anivers\u00e1rio, em 23 de abril de 1616, aos 52 anos de idade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agora que voc\u00ea sabe <strong>quem foi William Shakespeare<\/strong>, confira 5 fatos curiosos sobre a vida do escritor ingl\u00eas!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"5-curiosidades-para-entender-quem-foi-william-shakespeare\">5 Curiosidades para entender quem foi William Shakespeare<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea chegou neste artigo para saber <strong>quem foi William Shakespeare<\/strong>, n\u00e3o \u00e9? Ent\u00e3o voc\u00ea n\u00e3o pode deixar de saber essas 5 curiosidades sobre o maior dramaturgo de todos os tempos! Leia a seguir.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">1. Os pais e os filhos de Shakespeare eram analfabetos.&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com historiadores, \u00e9 prov\u00e1vel que a fam\u00edlia de Shakespeare <strong>nunca tenha aprendido a ler ou escrever.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este fato era bastante comum para as pessoas de sua classe social, durante a <strong>era elisabetana. <\/strong>Apenas o pai de Shakespeare e a filha mais velha do escritor sabiam assinar o nome.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2. Pouco se sabe sobre a vida de Shakespeare entre os anos de 1585 e 1592.&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Isso acontece pois <strong>os registros hist\u00f3ricos dessa \u00e9poca s\u00e3o escassos. <\/strong>Esses anos costumam ser chamados de<strong> \u201cAnos Perdidos de Shakespeare\u201d.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo alguns bi\u00f3grafos, o \u00faltimo documento antes desse \u201capag\u00e3o\u201d \u00e9 o registro de batismo dos g\u00eameos em 1585 e o pr\u00f3ximo \u00e9 datado somente 7 anos mais tarde com um panfleto a respeito dos teatros londrinos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Especula-se que durante este per\u00edodo, Shakespeare trabalhou como professor, estudou direito e viajou pela Europa Continental ou se juntou a uma trupe de atores que estava passando por Stratford.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mas s\u00e3o apenas teorias sobre quem foi William Shakespeare.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3. Shakespeare foi o escritor que mais influenciou a l\u00edngua inglesa.&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Com suas pe\u00e7as, houve a <strong>populariza\u00e7\u00e3o de termos coloquiais e frases <\/strong>que eram utilizadas no dia a dia, de forma escrita.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/beduka.com\/blog\/materias\/portugues\/coloquialismo\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Entenda a diferen\u00e7a entre o Coloquialismo e a Linguagem Coloquial<\/strong><\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Conhe\u00e7a algumas palavras e express\u00f5es criadas por William Shakespeare:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u201cBreak the ice\u201d &#8211; Quebrar o gelo (A Megera Domada)<\/li><li>\u201cKnock knock! Who&#8217;s there?\u201d &#8211; Toc toc! Quem bate? (Macbeth)<\/li><li>\u201cGossip\u201d &#8211; Fofoca (A Com\u00e9dia dos Erros)<\/li><li>&#8220;What&#8217;s done is done\u201d &#8211; O que est\u00e1 feito, est\u00e1 feito (Macbeth)&nbsp;<\/li><li>\u201cCold-blooded\u201d &#8211; Sangue frio (Rei Jo\u00e3o)<\/li><li>\u201cCome what, come may\u201d &#8211; Aconte\u00e7a o que acontecer (Macbeth)<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, William Shakespeare tamb\u00e9m teria inventado alguns nomes pr\u00f3prios como Jessica, Olivia e Miranda!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">4. O t\u00famulo de Shakespeare foi protegido contra ladr\u00f5es com uma maldi\u00e7\u00e3o.&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O t\u00famulo de Shakespeare fica em uma igreja em Stratford e cont\u00e9m o seguinte epit\u00e1fio, que teria sido escrito pelo autor antes de morrer:&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cQuerido amigo, pelo amor de Jesus reprima-se de cavar a poeira aqui encerrada. Aben\u00e7oado seja o homem que poupar estas pedras. E amaldi\u00e7oado seja aquele que mexer meus ossos\u201d.\u00a0<\/em><\/p><\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\">5. Algumas pessoas acreditam que William Shakespeare n\u00e3o existiu.&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Sim, se voc\u00ea perguntasse \u201cquem foi William Shakespeare\u201d, alguns te\u00f3ricos do meio diriam que ele n\u00e3o foi ningu\u00e9m. Isso em fun\u00e7\u00e3o de ser um<strong> homem provincial comum e que nunca fez faculdade<\/strong>, por isso duvidam do talento do escritor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As obras de Shakespeare possuem <strong>profundidade filos\u00f3fica<\/strong>, se passam em <strong>outras regi\u00f5es da Europa<\/strong> e tem <strong>contextos hist\u00f3ricos<\/strong> bem estabelecidos. Como Shakespeare teve acesso a tudo isso na \u00e9poca?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algumas pessoas acreditam que a figura de Shakespeare poderia ter sido um disfarce ou at\u00e9 mesmo que o escritor teria sido ajudado por outras pessoas!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gostou das curiosidades? Veja a seguir as principais obras do escritor para conhecer <strong>quem foi William Shakespeare<\/strong> por completo!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"obras-de-william-shakespeare\">Obras de William Shakespeare<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">J\u00e1 no s\u00e9culo XVI as pe\u00e7as de William Shakespeare faziam tremendo sucesso, (inclusive com a rainha Elizabeth I) e ainda hoje possuem <strong>relev\u00e2ncia cultural<\/strong>, por vezes sendo <strong>adaptadas para o cinema <\/strong>ou <strong>servindo como refer\u00eancia para as mais diversas produ\u00e7\u00f5es.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os te\u00f3ricos costumam dividir suas produ\u00e7\u00f5es em tr\u00eas e, \u00e0s vezes, quatro per\u00edodos. Esses per\u00edodos s\u00e3o divididos por seus <a href=\"https:\/\/beduka.com\/blog\/materias\/literatura\/quais-sao-os-generos-literarios\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>g\u00eaneros liter\u00e1rios.<\/strong><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 interessante observar essa diverg\u00eancia entre os estudiosos quanto a classifica\u00e7\u00e3o das pe\u00e7as em per\u00edodos, pois o pr\u00f3prio autor n\u00e3o classificava suas obras.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/beduka.com\/blog\/materias\/literatura\/resumo-de-hamlet\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Leia o nosso resumo sobre a pe\u00e7a Hamlet<\/strong><\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Ali\u00e1s, <strong>voc\u00ea sabia que as obras de Shakespeare quase foram perdidas? <\/strong>Isso porque naquela \u00e9poca, quando os dramaturgos escreviam uma pe\u00e7a, eles entregavam o <em>\u201crole\u201d <\/em>(do ingl\u00eas: papel\/fun\u00e7\u00e3o) diretamente aos atores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ou seja, <strong>cada ator recebia seu papel individualmente<\/strong> e os dramaturgos n\u00e3o tinham a obra completa em m\u00e3os.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quando Shakespeare morreu, seus amigos e tamb\u00e9m atores, John Hemings e Henry Cordell, organizaram suas pe\u00e7as e publicaram seis anos depois o \u201c<em>First Folio\u201d ou <\/em><strong><em>\u201c<\/em><\/strong><strong><em>Mr. William Shakespeare&#8217;s Comedies, Histories, &amp; Tragedies\u201d<\/em><\/strong>, que cont\u00e9m as principais pe\u00e7as do dramaturgo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Confira a seguir a <strong>lista completa de suas obras<\/strong> com seus g\u00eaneros e anos de publica\u00e7\u00e3o e nunca se esque\u00e7a quem foi William Shakespeare:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Com\u00e9dias<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>Trabalhos de Amores Perdidos \u2013 1590<\/li><li>A Com\u00e9dia dos Erros \u2013 1591<\/li><li>Os Dois Cavalheiros de Verona \u2013 1591<\/li><li>Sonho de uma Noite de Ver\u00e3o \u2013 1594<\/li><li>O Mercador de Veneza \u2013 1594<\/li><li>A Megera Domada \u2013 1594<\/li><li>Noite de Reis \u2013 1599<\/li><li>As Alegres Comadres de Windsor \u2013 1599<\/li><li>Muito Barulho por Nada \u2013 1600<\/li><li>Medida por Medida \u2013 1604<\/li><li>P\u00e9ricles, Pr\u00edncipe de Tiro \u2013 1604<\/li><li>Conto do Inverno \u2013 1610<\/li><li>Cimbelino \u2013 1611<\/li><li>A Tempestade \u2013 1611<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Trag\u00e9dias<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>Tito Andr\u00f4nico \u2013 1592<\/li><li>Romeu e Julieta \u2013 1592<\/li><li>J\u00falio C\u00e9sar \u2013 1599<\/li><li><a href=\"https:\/\/beduka.com\/blog\/materias\/literatura\/resumo-de-hamlet\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Hamlet <\/strong><\/a>\u2013 1599\u00a0<\/li><li>Tr\u00f3ilo e Cr\u00e9ssida \u2013 1602<\/li><li>Otelo, o Mouro de Veneza \u2013 1604<\/li><li>Rei Lear \u2013 1605<\/li><li>Macbeth \u2013 1606<\/li><li>Ant\u00f4nio e Cle\u00f3patra \u2013 1607<\/li><li>Coriolano \u2013 1608<\/li><li>A Tempestade \u2013 1611<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Pe\u00e7as hist\u00f3ricas<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>Rei Jo\u00e3o \u2013 1590<\/li><li>Ricardo II \u2013 1595<\/li><li>Ricardo III \u2013 1595<\/li><li>Henrique IV, Parte 1 \u2013 1597<\/li><li>Henrique IV, Parte 2 \u2013 1599<\/li><li>Henrique V \u2013 1599<\/li><li>Henrique VI, Parte 1 &#8211; 1590<\/li><li>Henrique VI, Parte 2 &#8211; 1591<\/li><li>Henrique VI, Parte 3 &#8211; 1591<\/li><li>Henrique VIII &#8211; 1599<\/li><li>Eduardo III &#8211; 1596<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Quantas das pe\u00e7as acima voc\u00ea j\u00e1 ouviu falar? Me conte nos coment\u00e1rios! Continue lendo o artigo para saber as <strong>frases mais famosas que revelam muito sobre quem foi William Shakespeare!<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"frases-famosas-de-william-shakespeare\">Frases famosas de William Shakespeare<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A seguir, selecionamos algumas das frases mais memor\u00e1veis do dramaturgo e que nos d\u00e3o dimens\u00e3o de <strong>quem foi William Shakespeare<\/strong> e a import\u00e2ncia de suas obras.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cSer ou n\u00e3o ser, eis a quest\u00e3o.\u201d<\/em><\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Hamlet, Ato 3, cena 1.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cH\u00e1 mais coisas no c\u00e9u e na terra, Hor\u00e1cio, do que sonha a tua filosofia.\u201d<\/em><\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Hamlet, Ato 1, Cena 5.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cN\u00e3o tenham medo da grandeza. Alguns nascem grandes, alguns conseguem a grandeza, e outros t\u00eam a grandeza imposta a eles.\u201d<\/em><\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Noite de Reis, Ato 2, Cena 5.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cSomos feitos da mat\u00e9ria dos sonhos; nossa vida pequenina \u00e9 cercada pelo sono\u201d.<\/em><\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">A Tempestade, Ato 4, Cena 1.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cA culpa, meu caro Brutus, n\u00e3o est\u00e1 nas estrelas mas em n\u00f3s mesmos.\u201d<\/em><\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">J\u00falio C\u00e9sar, Ato 1, Cena 2.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tenho certeza que voc\u00ea j\u00e1 ouviu ou viu alguma <strong>refer\u00eancia <\/strong>a essas frases. Afinal, William Shakespeare \u00e9 considerado o <strong>maior escritor da l\u00edngua inglesa de todos os tempos!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esperamos que este artigo sobre <strong>quem foi William Shakespeare<\/strong> tenha despertado em voc\u00ea a vontade de ler e estudar as pe\u00e7as do escritor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Logo abaixo temos uma <strong>oportunidade incr\u00edvel <\/strong>para voc\u00ea, n\u00e3o deixe de conferir!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"entre-na-faculdade-com-o-beduka\">Entre na faculdade com o Beduka!<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Seu sonho \u00e9<strong> entrar na faculdade?<\/strong> O que voc\u00ea est\u00e1 fazendo para <strong>alcan\u00e7ar esse objetivo?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tenho <strong>duas coisas<\/strong> para te contar! A<strong> primeira <\/strong>delas \u00e9 que s\u00f3 de voc\u00ea estar aqui lendo este artigo, boa parte do caminho at\u00e9 a faculdade est\u00e1 tra\u00e7ado. E a <strong>segunda<\/strong> \u00e9 que o Beduka tem a<strong> oportunidade perfeita para voc\u00ea!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essa oportunidade se chama<strong> <\/strong><a href=\"https:\/\/beduka.com\/bolsas\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Beduka Bolsas!\u00a0<\/strong><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O <strong>Beduka Bolsas<\/strong> \u00e9 uma plataforma criada pelo Beduka, onde voc\u00ea pode encontrar <strong>bolsas de estudos de at\u00e9 65% de desconto na mensalidade!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 isso mesmo! S\u00e3o mais de <strong>90 op\u00e7\u00f5es de cursos <\/strong>para voc\u00ea escolher em 8 universidades parceiras. Temos <strong>Direito, Engenharia, Odontologia e muito mais!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Realize agora seu sonho e garanta uma vaga na faculdade. <a href=\"https:\/\/beduka.com\/bolsas\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Acesse o Beduka Bolsas!<\/strong><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Siga o Beduka nas redes sociais! No <a href=\"https:\/\/www.instagram.com\/beduka_oficial\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Instagram<\/strong><\/a> postamos <strong>tudo que pode cair no Enem<\/strong> e no <a href=\"https:\/\/br.pinterest.com\/bedukaoficial\/_created\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Pinterest<\/strong><\/a> voc\u00ea encontra os <strong>melhores resumos<\/strong> sobre todas as mat\u00e9rias. Estamos te esperando!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Obrigada por ler at\u00e9 aqui!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quem foi William Shakespeare? Neste artigo voc\u00ea vai descobrir tudo sobre a vida pessoal, principais obras e curiosidades do escritor ingl\u00eas mais famoso da hist\u00f3ria!<\/p>\n","protected":false},"author":1,"featured_media":25131,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[489],"tags":[],"class_list":["post-25130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-literatura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quem foi William Shakespeare? Descubra TUDO sobre sua vida e obra<\/title>\n<meta name=\"description\" content=\"Quem foi William Shakespeare? Neste artigo voc\u00ea vai descobrir tudo sobre a vida pessoal, principais obras e curiosidades intrigantes sobre o escritor ingl\u00eas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-william-shakespeare\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quem foi William Shakespeare? Descubra TUDO sobre sua vida e obra\" \/>\n<meta property=\"og:description\" content=\"Quem foi William Shakespeare? Neste artigo voc\u00ea vai descobrir tudo sobre a vida pessoal, principais obras e curiosidades intrigantes sobre o escritor ingl\u00eas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-william-shakespeare\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-24T17:02:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-26T18:49:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2022\/03\/Quem-foi-William-Shakespeare.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"609\" \/>\n\t<meta property=\"og:image:height\" content=\"342\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/literatura\\\/quem-foi-william-shakespeare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/literatura\\\/quem-foi-william-shakespeare\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/person\\\/325d912d2cb8dd9ede8ab291427d2b8a\"},\"headline\":\"Quem foi William Shakespeare? Descubra tudo sobre sua carreira!\",\"datePublished\":\"2022-03-24T17:02:17+00:00\",\"dateModified\":\"2026-08-26T18:49:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/literatura\\\/quem-foi-william-shakespeare\\\/\"},\"wordCount\":1785,\"publisher\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/literatura\\\/quem-foi-william-shakespeare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Quem-foi-William-Shakespeare.jpg\",\"articleSection\":[\"Literatura\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/literatura\\\/quem-foi-william-shakespeare\\\/\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/literatura\\\/quem-foi-william-shakespeare\\\/\",\"name\":\"Quem foi William Shakespeare? Descubra TUDO sobre sua vida e obra\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/literatura\\\/quem-foi-william-shakespeare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/literatura\\\/quem-foi-william-shakespeare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Quem-foi-William-Shakespeare.jpg\",\"datePublished\":\"2022-03-24T17:02:17+00:00\",\"dateModified\":\"2026-08-26T18:49:19+00:00\",\"description\":\"Quem foi William Shakespeare? Neste artigo voc\u00ea vai descobrir tudo sobre a vida pessoal, principais obras e curiosidades intrigantes sobre o escritor ingl\u00eas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/literatura\\\/quem-foi-william-shakespeare\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/literatura\\\/quem-foi-william-shakespeare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/literatura\\\/quem-foi-william-shakespeare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Quem-foi-William-Shakespeare.jpg\",\"contentUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Quem-foi-William-Shakespeare.jpg\",\"width\":609,\"height\":342,\"caption\":\"Quem foi William Shakespeare?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/literatura\\\/quem-foi-william-shakespeare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/beduka.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quem foi William Shakespeare? Descubra tudo sobre sua carreira!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/\",\"name\":\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\",\"description\":\"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!\",\"publisher\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beduka.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#organization\",\"name\":\"Beduka\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/marca-beduka.png\",\"contentUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/marca-beduka.png\",\"width\":1077,\"height\":368,\"caption\":\"Beduka\"},\"image\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/beduka.buscadordefaculdades\\\/\",\"https:\\\/\\\/www.instagram.com\\\/beduka_oficial\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/beduka\",\"https:\\\/\\\/br.pinterest.com\\\/bedukaoficial\\\/\",\"https:\\\/\\\/www.youtube.com\\\/beduka\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/person\\\/325d912d2cb8dd9ede8ab291427d2b8a\",\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o Beduka (a)\"},\"description\":\"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/beduka.buscadordefaculdades\",\"https:\\\/\\\/www.instagram.com\\\/beduka_oficial\\\/\",\"https:\\\/\\\/br.pinterest.com\\\/bedukaoficial\\\/\"],\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quem foi William Shakespeare? Descubra TUDO sobre sua vida e obra","description":"Quem foi William Shakespeare? Neste artigo voc\u00ea vai descobrir tudo sobre a vida pessoal, principais obras e curiosidades intrigantes sobre o escritor ingl\u00eas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-william-shakespeare\/","og_locale":"pt_BR","og_type":"article","og_title":"Quem foi William Shakespeare? Descubra TUDO sobre sua vida e obra","og_description":"Quem foi William Shakespeare? Neste artigo voc\u00ea vai descobrir tudo sobre a vida pessoal, principais obras e curiosidades intrigantes sobre o escritor ingl\u00eas","og_url":"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-william-shakespeare\/","og_site_name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","article_publisher":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","article_author":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades","article_published_time":"2022-03-24T17:02:17+00:00","article_modified_time":"2026-08-26T18:49:19+00:00","og_image":[{"width":609,"height":342,"url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2022\/03\/Quem-foi-William-Shakespeare.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Beduka (a)","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Beduka (a)","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-william-shakespeare\/#article","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-william-shakespeare\/"},"author":{"name":"Reda\u00e7\u00e3o Beduka (a)","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a"},"headline":"Quem foi William Shakespeare? Descubra tudo sobre sua carreira!","datePublished":"2022-03-24T17:02:17+00:00","dateModified":"2026-08-26T18:49:19+00:00","mainEntityOfPage":{"@id":"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-william-shakespeare\/"},"wordCount":1785,"publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"image":{"@id":"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-william-shakespeare\/#primaryimage"},"thumbnailUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2022\/03\/Quem-foi-William-Shakespeare.jpg","articleSection":["Literatura"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-william-shakespeare\/","url":"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-william-shakespeare\/","name":"Quem foi William Shakespeare? Descubra TUDO sobre sua vida e obra","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-william-shakespeare\/#primaryimage"},"image":{"@id":"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-william-shakespeare\/#primaryimage"},"thumbnailUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2022\/03\/Quem-foi-William-Shakespeare.jpg","datePublished":"2022-03-24T17:02:17+00:00","dateModified":"2026-08-26T18:49:19+00:00","description":"Quem foi William Shakespeare? Neste artigo voc\u00ea vai descobrir tudo sobre a vida pessoal, principais obras e curiosidades intrigantes sobre o escritor ingl\u00eas","breadcrumb":{"@id":"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-william-shakespeare\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-william-shakespeare\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-william-shakespeare\/#primaryimage","url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2022\/03\/Quem-foi-William-Shakespeare.jpg","contentUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2022\/03\/Quem-foi-William-Shakespeare.jpg","width":609,"height":342,"caption":"Quem foi William Shakespeare?"},{"@type":"BreadcrumbList","@id":"https:\/\/beduka.com\/blog\/materias\/literatura\/quem-foi-william-shakespeare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/beduka.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Quem foi William Shakespeare? Descubra tudo sobre sua carreira!"}]},{"@type":"WebSite","@id":"https:\/\/beduka.com\/blog\/#website","url":"https:\/\/beduka.com\/blog\/","name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","description":"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!","publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beduka.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beduka.com\/blog\/#organization","name":"Beduka","url":"https:\/\/beduka.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","contentUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","width":1077,"height":368,"caption":"Beduka"},"image":{"@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/www.linkedin.com\/company\/beduka","https:\/\/br.pinterest.com\/bedukaoficial\/","https:\/\/www.youtube.com\/beduka"]},{"@type":"Person","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a","name":"Reda\u00e7\u00e3o Beduka (a)","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o Beduka (a)"},"description":"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.","sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/br.pinterest.com\/bedukaoficial\/"],"url":"https:\/\/beduka.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/25130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/comments?post=25130"}],"version-history":[{"count":2,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/25130\/revisions"}],"predecessor-version":[{"id":25133,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/25130\/revisions\/25133"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media\/25131"}],"wp:attachment":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media?parent=25130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/categories?post=25130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/tags?post=25130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}