{"id":2671,"date":"2019-01-13T19:23:14","date_gmt":"2019-01-13T22:23:14","guid":{"rendered":"https:\/\/beduka.com\/blog\/?p=2671"},"modified":"2022-02-15T10:52:27","modified_gmt":"2022-02-15T13:52:27","slug":"principais-ideias-de-thomas-hobbes","status":"publish","type":"post","link":"https:\/\/beduka.com\/blog\/materias\/filosofia\/principais-ideias-de-thomas-hobbes\/","title":{"rendered":"Principais Ideias de Thomas Hobbes (Resumo, Biografia e Filosofia)"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><b><i>Thomas Hobbes foi um fil\u00f3sofo ingl\u00eas do s\u00e9culo XVII. Ele \u00e9 considerado um dos fundadores da filosofia pol\u00edtica e ci\u00eancia pol\u00edtica modernas.<\/i><\/b><b><i> Ele acreditava que a natureza humana era mau, ou seja, sem os freios civilizacionais, imperava a barb\u00e1rie.<\/i><\/b><b><i>. Leia o nosso resumo completo, conhe\u00e7a quem foi Thomas Hobbes e suas principais ideias.<\/i><\/b><\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sabe aquela pessoa que procura um sentido por tr\u00e1s de qualquer a\u00e7\u00e3o? <\/strong>Ela n\u00e3o consegue aceitar algo sem realmente compreender sua motiva\u00e7\u00e3o, e nem comece a falar de signos do Zod\u00edaco perto dela\u2026&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esse tamb\u00e9m era um dos principais tra\u00e7os de personalidade de Thomas Hobbes, importante fil\u00f3sofo e cientista.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Voc\u00ea sabe quem foi Thomas Hobbes?<\/strong> \u00c9 o que vamos te contar nesse artigo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Neste artigo sobre Thomas Hobbes, voc\u00ea encontrar\u00e1:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>A Biografia do Thomas Hobbes<\/li><li>A Filosofia Hobbesiana.<\/li><li>Uma an\u00e1lise sobre a vida de Thomas Hobbes<\/li><li>As Principais Ideias Sobre Thomas Hobbes.<\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Selecionamos tamb\u00e9m <a href=\"https:\/\/beduka.com\/blog\/exercicios\/questoes-sobre-thomas-hobbes\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">As Melhores Quest\u00f5es sobre Thomas Hobbes!&nbsp;<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Faz o seguinte:<\/strong> clica no link que ele ir\u00e1 abrir as quest\u00f5es em uma nova aba para voc\u00ea fazer assim que terminar de ler o resumo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">A origem do jovem Thomas (Biografia)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>O fil\u00f3sofo Thomas Hobbes nasceu em 5 de abril de 1588<\/strong>, na aldeia de Westport, na Inglaterra. Filho de um vig\u00e1rio anglicano, for\u00e7ado a deixar o local que vivia depois de participar de uma briga, abandonou os tr\u00eas filhos aos cuidados de seu irm\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Thomas, desde os 4 anos, come\u00e7ou a ser educado na igreja de Westport, passando por duas escolas alguns anos depois e seguindo, aos 15 anos, para para a cidade Oxford, onde mais tarde chegou a frequentar a universidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Depois, em 1608, formado em arte, <strong>Hobbes passou a trabalhar para a poderosa fam\u00edlia Cavendish<\/strong>, de um importante lorde ingl\u00eas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Isso mais para frente lhe ajudaria a fazer viagens e aprimorar seu lado cultural.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Thomas Hobbes chegou a visitar a Fran\u00e7a e a It\u00e1lia em 1610 e estudou literatura e filosofia.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre 1621 e 1626, ele trabalhou como secret\u00e1rio de<a href=\"https:\/\/pt.wikipedia.org\/wiki\/Francis_Bacon\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\"> Francis Bacon<\/a>, para quem traduziu algumas obras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ao mesmo tempo em que descobre quem foi Thomas Hobbes<\/strong>, veja tamb\u00e9m:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/beduka.com\/blog\/filosofia\/quem-foi-john-locke\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">Quem foi John Locke?<\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/portugues\/quem-foi-machado-de-assis\/\" target=\"_blank\">Quem foi Machado de Assis?<\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/educacao\/as-principais-ideias-de-santo-agostinho\/\" target=\"_blank\">Quem foi Santo Agostinho?<\/a><\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Quem foi Thomas Hobbes? (A Filosofia Hobbesiana)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Al\u00e9m de sua genialidade e duras cr\u00edticas expostas em seu trabalho, Hobbes fez parte de uma luta contra o absolutismo da dinastia Stuart<\/strong>, j\u00e1 que o mesmo era um fervoroso defensor da Monarquia, escrevendo at\u00e9 mesmo seu primeiro tratado sobre o regime, Elementos da Lei Natural, em 1640. Ele foi obrigado a se refugiar em Paris logo depois.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"412\" height=\"300\" src=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/11\/Thomas-Hobbesescrevendo.jpg\" alt=\"Thomas Hobbes escrevendo\" class=\"wp-image-18862\" srcset=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/11\/Thomas-Hobbesescrevendo.jpg 412w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/11\/Thomas-Hobbesescrevendo-300x218.jpg 300w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/11\/Thomas-Hobbesescrevendo-320x233.jpg 320w\" sizes=\"auto, (max-width: 412px) 100vw, 412px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Alguns anos ap\u00f3s o tratado, chegou a retornar \u00e0 Inglaterra, mas voltou a se refugiar na Fran\u00e7a por causa de suas ideais absolutistas expostos em Leviat\u00e3, sua mais importante obra, em 1651.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apenas um ano depois voltou \u00e0 Inglaterra, ent\u00e3o governada por <a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/pt.wikipedia.org\/wiki\/Oliver_Cromwell\" target=\"_blank\">Oliver Cromwell<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Thomas era um pouco\u2026 peculiar. Para se ter uma ideia, <strong>o fil\u00f3sofo acreditava que o medo era como um irm\u00e3o para ele<\/strong>, em suas palavras:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>(colocar como cita\u00e7\u00e3o)<\/strong> &#8220;Minha m\u00e3e pariu g\u00eameos, o medo e eu&#8221; (Thomas Hobbes)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ele disse isso pelo fato de sua m\u00e3e ter dado \u00e0 luz de forma prematura pelo terror que infundia a Armada Invenc\u00edvel Espanhola, localizada pr\u00f3xima \u00e0 costa brit\u00e2nica. <strong>#tenso<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Saiba melhor <a href=\"https:\/\/beduka.com\/blog\/dicas\/principais-ideias-platao\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">quais eram as principais ideias de Plat\u00e3o<\/a> e<a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/dicas\/principais-ideias-emile-durkheim\/\" target=\"_blank\"> \u00c9mile Durkheim<\/a>.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Thomas Hobbes e sua genialidade<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Apesar de sua extensa capacidade em dizer e transpor em palavras todos os seus medos e observa\u00e7\u00f5es, <strong>Thomas foi considerado algu\u00e9m obscuro de tal maneira que seus livros foram queimados publicamente e o autor foi considerado ateu<\/strong>, assim como suas obras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Detalhe:<\/strong> a maioria desses casos aconteceram enquanto Thomas ainda estava vivo\u2026 que barra!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hobbes teve dois grandes inimigos contra os quais manteve fortes tens\u00f5es:<\/strong> a igreja da Inglaterra e a Universidade de Oxford. Ambos se sentiam atacados pelas duras cr\u00edticas do fil\u00f3sofo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A obra de Hobbes, contudo, foi considerada como a linha de quebra com a Idade M\u00e9dia, especialmente por suas impressionantes descri\u00e7\u00f5es da realidade da \u00e9poca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Thomas Hobbes <\/strong>morreu em 4 de dezembro de 1679.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Estudando para as provas? <\/strong>Conhe\u00e7a nosso <a href=\"https:\/\/beduka.com\/blog\/dicas\/enem-dicas\/simulados-para-enem-online-e-gratuito\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">Simulado gratuito<\/a>, que pode ser personalizado com as mat\u00e9rias que voc\u00ea mais precisa!<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Quais s\u00e3o as Principais Ideias de Thomas Hobbes?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A obra de Thomas Hobbes tem dois pontos centrais:<\/strong> um da Filosofia teor\u00e9tica e outro da pr\u00e1tica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na perspectiva teor\u00e9tica, Hobbes era um empirista, ou seja, defendia que n\u00e3o h\u00e1 nenhuma ideia anterior \u00e0 experi\u00eancia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A grande produ\u00e7\u00e3o filos\u00f3fica dele est\u00e1 ligada \u00e0 pr\u00e1tica, ou seja, \u00e0 Filosofia pol\u00edtica. No cen\u00e1rio pol\u00edtico ele defendia:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>O estado de natureza humano como momento de inaptid\u00e3o natural para a vida social;<\/li><li>A sociedade como uma composi\u00e7\u00e3o complexa de \u201c\u00e1tomos\u201d, que s\u00e3o os indiv\u00edduos;<\/li><li>O Contrato social como forma\u00e7\u00e3o da comunidade humana que retira o homem de seu Estado de Natureza;<\/li><li>A necessidade da monarquia para estabelecer a ordem entre as pessoas.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">O que \u00e9 o Contrato Social?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 uma teoria que defende que em algum momento determinados agrupamentos humanos formaram uma esp\u00e9cie de contrato estabelecendo uma ordem social e um Estado. <strong>Esse contrato social transformou esse grupo em uma sociedade civilizada e o tirou do Estado de Natureza.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hobbes entendia que houve um momento onde os seres humanos viviam em um Estado de Natureza, ou seja, sem civiliza\u00e7\u00e3o ou freios para seus impulsos naturais. <strong>Al\u00e9m do mais, ele acreditava que a natureza humana era m\u00e1, ou seja, sem os freios civilizacionais, imperava a barb\u00e1rie.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>\u201cO lobo \u00e9 o lobo do homem\u201d<\/em><\/strong>, essa frase criada por Plauto e popularizada por Thomas Hobbes, demonstra como o ser humano \u00e9 quem causa mal a ele pr\u00f3prio.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Qual foi a Obra mais Conhecida de Thomas Hobbes? (LEVIAT\u00c3)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>O livro \u201cLeviat\u00e3 ou Mat\u00e9ria, Palavra e Poder de um Governo Eclesi\u00e1stico e Civil\u201d, escrito em 1651<\/strong> por Thomas Hobbes foi a maior obra do Fil\u00f3sofo. Comumente chamado apenas de <em>Leviat\u00e3<\/em>,<strong> <\/strong>o livro<strong> diz respeito da estrutura da sociedade e do governo.<\/strong> Ele \u00e9 considerado uma das mais antigas e influentes teorias do Contrato Social.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"300\" src=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/11\/leviata.jpg\" alt=\"Livro Leviat\u00e3 Thomas Hobbes\" class=\"wp-image-18863\" srcset=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/11\/leviata.jpg 600w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/11\/leviata-300x150.jpg 300w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/11\/leviata-320x160.jpg 320w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">No livro, Hobbes defende o Contrato Social e um Governo de um soberano absoluto.<strong> Hobbes defendia que a eterna luta de todos contra todos, ou seja, o caos e a guerra civil, s\u00f3 podem ser evitados por um governo central forte.<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/beduka.com\/blog\/materias\/historia\/o-que-era-absolutismo\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">O que era o Absolutismo?<\/a><strong> <\/strong>Resumo completo escrito para voc\u00ea entender tudo sobre essa regime pol\u00edtico.<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Thomas Hobbes foi um fil\u00f3sofo ingl\u00eas do s\u00e9culo XVII. Ele \u00e9 considerado um dos fundadores da filosofia pol\u00edtica e ci\u00eancia pol\u00edtica modernas. Ele acreditava que a natureza humana era mau, ou seja, sem os freios civilizacionais, imperava a barb\u00e1rie.. Leia o nosso resumo completo, conhe\u00e7a quem foi Thomas Hobbes e suas principais ideias. Sabe aquela [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18860,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[492],"tags":[],"class_list":["post-2671","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-filosofia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Principais Ideias de Thomas Hobbes (Resumo, Biografia e Filosofia)<\/title>\n<meta name=\"description\" content=\"Conhe\u00e7a as principais ideias de um dos maiores fil\u00f3sofos da modernidade, Thomas Hobbes. Saiba quem ele foi, sua filosofia e sua trajet\u00f3ria de vida.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beduka.com\/blog\/materias\/filosofia\/principais-ideias-de-thomas-hobbes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Principais Ideias de Thomas Hobbes (Resumo, Biografia e Filosofia)\" \/>\n<meta property=\"og:description\" content=\"Conhe\u00e7a as principais ideias de um dos maiores fil\u00f3sofos da modernidade, Thomas Hobbes. Saiba quem ele foi, sua filosofia e sua trajet\u00f3ria de vida.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beduka.com\/blog\/materias\/filosofia\/principais-ideias-de-thomas-hobbes\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-13T22:23:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-15T13:52:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/01\/Thomas-Hobbes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/filosofia\\\/principais-ideias-de-thomas-hobbes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/filosofia\\\/principais-ideias-de-thomas-hobbes\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/person\\\/325d912d2cb8dd9ede8ab291427d2b8a\"},\"headline\":\"Principais Ideias de Thomas Hobbes (Resumo, Biografia e Filosofia)\",\"datePublished\":\"2019-01-13T22:23:14+00:00\",\"dateModified\":\"2022-02-15T13:52:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/filosofia\\\/principais-ideias-de-thomas-hobbes\\\/\"},\"wordCount\":1117,\"commentCount\":6,\"publisher\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/filosofia\\\/principais-ideias-de-thomas-hobbes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/Thomas-Hobbes.jpg\",\"articleSection\":[\"Filosofia\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/filosofia\\\/principais-ideias-de-thomas-hobbes\\\/\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/filosofia\\\/principais-ideias-de-thomas-hobbes\\\/\",\"name\":\"Principais Ideias de Thomas Hobbes (Resumo, Biografia e Filosofia)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/filosofia\\\/principais-ideias-de-thomas-hobbes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/filosofia\\\/principais-ideias-de-thomas-hobbes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/Thomas-Hobbes.jpg\",\"datePublished\":\"2019-01-13T22:23:14+00:00\",\"dateModified\":\"2022-02-15T13:52:27+00:00\",\"description\":\"Conhe\u00e7a as principais ideias de um dos maiores fil\u00f3sofos da modernidade, Thomas Hobbes. Saiba quem ele foi, sua filosofia e sua trajet\u00f3ria de vida.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/filosofia\\\/principais-ideias-de-thomas-hobbes\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/filosofia\\\/principais-ideias-de-thomas-hobbes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/filosofia\\\/principais-ideias-de-thomas-hobbes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/Thomas-Hobbes.jpg\",\"contentUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/Thomas-Hobbes.jpg\",\"width\":600,\"height\":300,\"caption\":\"As Principais Ideias de Thomas Hobbes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/filosofia\\\/principais-ideias-de-thomas-hobbes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/beduka.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Principais Ideias de Thomas Hobbes (Resumo, Biografia e Filosofia)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/\",\"name\":\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\",\"description\":\"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!\",\"publisher\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beduka.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#organization\",\"name\":\"Beduka\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/marca-beduka.png\",\"contentUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/marca-beduka.png\",\"width\":1077,\"height\":368,\"caption\":\"Beduka\"},\"image\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/beduka.buscadordefaculdades\\\/\",\"https:\\\/\\\/www.instagram.com\\\/beduka_oficial\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/beduka\",\"https:\\\/\\\/br.pinterest.com\\\/bedukaoficial\\\/\",\"https:\\\/\\\/www.youtube.com\\\/beduka\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/person\\\/325d912d2cb8dd9ede8ab291427d2b8a\",\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o Beduka (a)\"},\"description\":\"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/beduka.buscadordefaculdades\",\"https:\\\/\\\/www.instagram.com\\\/beduka_oficial\\\/\",\"https:\\\/\\\/br.pinterest.com\\\/bedukaoficial\\\/\"],\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Principais Ideias de Thomas Hobbes (Resumo, Biografia e Filosofia)","description":"Conhe\u00e7a as principais ideias de um dos maiores fil\u00f3sofos da modernidade, Thomas Hobbes. Saiba quem ele foi, sua filosofia e sua trajet\u00f3ria de vida.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beduka.com\/blog\/materias\/filosofia\/principais-ideias-de-thomas-hobbes\/","og_locale":"pt_BR","og_type":"article","og_title":"Principais Ideias de Thomas Hobbes (Resumo, Biografia e Filosofia)","og_description":"Conhe\u00e7a as principais ideias de um dos maiores fil\u00f3sofos da modernidade, Thomas Hobbes. Saiba quem ele foi, sua filosofia e sua trajet\u00f3ria de vida.","og_url":"https:\/\/beduka.com\/blog\/materias\/filosofia\/principais-ideias-de-thomas-hobbes\/","og_site_name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","article_publisher":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","article_author":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades","article_published_time":"2019-01-13T22:23:14+00:00","article_modified_time":"2022-02-15T13:52:27+00:00","og_image":[{"width":600,"height":300,"url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/01\/Thomas-Hobbes.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Beduka (a)","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Beduka (a)","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beduka.com\/blog\/materias\/filosofia\/principais-ideias-de-thomas-hobbes\/#article","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/materias\/filosofia\/principais-ideias-de-thomas-hobbes\/"},"author":{"name":"Reda\u00e7\u00e3o Beduka (a)","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a"},"headline":"Principais Ideias de Thomas Hobbes (Resumo, Biografia e Filosofia)","datePublished":"2019-01-13T22:23:14+00:00","dateModified":"2022-02-15T13:52:27+00:00","mainEntityOfPage":{"@id":"https:\/\/beduka.com\/blog\/materias\/filosofia\/principais-ideias-de-thomas-hobbes\/"},"wordCount":1117,"commentCount":6,"publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"image":{"@id":"https:\/\/beduka.com\/blog\/materias\/filosofia\/principais-ideias-de-thomas-hobbes\/#primaryimage"},"thumbnailUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/01\/Thomas-Hobbes.jpg","articleSection":["Filosofia"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/beduka.com\/blog\/materias\/filosofia\/principais-ideias-de-thomas-hobbes\/","url":"https:\/\/beduka.com\/blog\/materias\/filosofia\/principais-ideias-de-thomas-hobbes\/","name":"Principais Ideias de Thomas Hobbes (Resumo, Biografia e Filosofia)","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beduka.com\/blog\/materias\/filosofia\/principais-ideias-de-thomas-hobbes\/#primaryimage"},"image":{"@id":"https:\/\/beduka.com\/blog\/materias\/filosofia\/principais-ideias-de-thomas-hobbes\/#primaryimage"},"thumbnailUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/01\/Thomas-Hobbes.jpg","datePublished":"2019-01-13T22:23:14+00:00","dateModified":"2022-02-15T13:52:27+00:00","description":"Conhe\u00e7a as principais ideias de um dos maiores fil\u00f3sofos da modernidade, Thomas Hobbes. Saiba quem ele foi, sua filosofia e sua trajet\u00f3ria de vida.","breadcrumb":{"@id":"https:\/\/beduka.com\/blog\/materias\/filosofia\/principais-ideias-de-thomas-hobbes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beduka.com\/blog\/materias\/filosofia\/principais-ideias-de-thomas-hobbes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/materias\/filosofia\/principais-ideias-de-thomas-hobbes\/#primaryimage","url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/01\/Thomas-Hobbes.jpg","contentUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/01\/Thomas-Hobbes.jpg","width":600,"height":300,"caption":"As Principais Ideias de Thomas Hobbes"},{"@type":"BreadcrumbList","@id":"https:\/\/beduka.com\/blog\/materias\/filosofia\/principais-ideias-de-thomas-hobbes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/beduka.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Principais Ideias de Thomas Hobbes (Resumo, Biografia e Filosofia)"}]},{"@type":"WebSite","@id":"https:\/\/beduka.com\/blog\/#website","url":"https:\/\/beduka.com\/blog\/","name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","description":"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!","publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beduka.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beduka.com\/blog\/#organization","name":"Beduka","url":"https:\/\/beduka.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","contentUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","width":1077,"height":368,"caption":"Beduka"},"image":{"@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/www.linkedin.com\/company\/beduka","https:\/\/br.pinterest.com\/bedukaoficial\/","https:\/\/www.youtube.com\/beduka"]},{"@type":"Person","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a","name":"Reda\u00e7\u00e3o Beduka (a)","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o Beduka (a)"},"description":"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.","sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/br.pinterest.com\/bedukaoficial\/"],"url":"https:\/\/beduka.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/2671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/comments?post=2671"}],"version-history":[{"count":12,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/2671\/revisions"}],"predecessor-version":[{"id":24681,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/2671\/revisions\/24681"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media\/18860"}],"wp:attachment":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media?parent=2671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/categories?post=2671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/tags?post=2671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}