{"id":30214,"date":"2023-07-21T15:51:05","date_gmt":"2023-07-21T18:51:05","guid":{"rendered":"https:\/\/beduka.com\/blog\/?p=30214"},"modified":"2026-08-26T15:42:43","modified_gmt":"2026-08-26T18:42:43","slug":"quem-foi-marechal-floriano-peixoto","status":"publish","type":"post","link":"https:\/\/beduka.com\/blog\/materias\/historia\/quem-foi-marechal-floriano-peixoto\/","title":{"rendered":"Quem foi o marechal Floriano Peixoto? Saiba a hist\u00f3ria do presidente que tinha todo o Brasil contra ele"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Em 1889 o Brasil passou por uma transi\u00e7\u00e3o de regime, <a href=\"https:\/\/beduka.com\/blog\/exercicios\/historia-exercicios\/exercicios-sobre-a-queda-da-monarquia-no-brasil\/\" target=\"_blank\" rel=\"noreferrer noopener\">da monarquia para a rep\u00fablica<\/a>. Isso n\u00e3o foi feito de maneira pac\u00edfica, pelo contr\u00e1rio. <strong>Houve bastante turbul\u00eancia e instabilidade, que ficaram a cargo de um homem resolver<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ele foi o marechal Floriano Peixoto, importante militar brasileiro que ficou conhecido como o marechal de ferro devido ao modo como agiu durante os anos em que foi presidente da rep\u00fablica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Neste artigo, <strong>vamos desvendar os principais eventos da biografia dele para voc\u00ea entender de uma vez quem foi o marechal Floriano Peixoto<\/strong> e como ele exerceu o poder no Brasil. Continue lendo e descubra!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quem foi o marechal Floriano Peixoto?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Floriano Vieira Peixoto foi um importante militar e pol\u00edtico da hist\u00f3ria brasileira<\/strong>, que desenvolveu sua carreira ao longo do <strong>Imp\u00e9rio brasileiro e da <\/strong><a href=\"https:\/\/beduka.com\/blog\/materias\/historia\/o-que-foi-a-republica-velha\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Primeira Rep\u00fablica<\/strong>.<\/a> Chegou ao posto de marechal de campo, o mais alto cargo do ex\u00e9rcito, e foi <strong>o primeiro vice-presidente da rep\u00fablica e o seu segundo presidente<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Floriano nasceu em Macei\u00f3, em 1839. Seus pais, por serem muito pobres, o entregaram para ser criado pelo tio e padrinho Jos\u00e9 Vieira de Ara\u00fajo Peixoto. Ele mantinha um engenho de a\u00e7\u00facar e era um influente pol\u00edtico na regi\u00e3o, al\u00e9m de ter a patente de coronel do ex\u00e9rcito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A cria\u00e7\u00e3o na casa do tio garantiu a Floriano mais recursos e possibilidades de ascens\u00e3o social. Iniciou seus estudos com um padre amigo do seu tio e depois ingressou em um internato. Em 1855 rumou para o Rio de Janeiro, ent\u00e3o capital do imp\u00e9rio, onde fez o curso secund\u00e1rio. Dois anos depois, iniciou sua carreira militar.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Carreira militar do Marechal Floriano Peixoto<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Floriano <strong>iniciou sua carreira no ex\u00e9rcito em 1857<\/strong>, como soldado volunt\u00e1rio no 1\u00ba Batalh\u00e3o de Artilharia a P\u00e9. No ano seguinte ingressou na Escola Militar do Rio de Janeiro, na qual se formavam os oficiais. Concluiu o curso em 1861, obtendo a patente de segundo-tenente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em 1863 foi promovido a primeiro-tenente. Dois anos depois, <strong>dirigiu-se ao Rio Grande do Sul, para repelir as tropas de Solano L\u00f3pez, durante a Guerra do Paraguai<\/strong>. Em 1866 subiu ao posto de capit\u00e3o, ainda em meio aos conflitos, e assumiu o comando de uma bateria do 1\u00ba Batalh\u00e3o de Artilharia a P\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/beduka.com\/blog\/exercicios\/historia-exercicios\/exercicios-resumo-guerra-do-paraguai\/\" target=\"_blank\" rel=\"noreferrer noopener\">Entenda melhor quem foi o marechal Floriano Peixoto com nosso resumo sobre a Guerra do Paraguai<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Floriano <strong>participou de in\u00fameras batalhas<\/strong>, entre elas, epis\u00f3dios important\u00edssimos para o curso da guerra e a vit\u00f3ria do Brasil. Entre as balas de fuzis e os estudos para engenharia a que foi designado, ele estreou sua <strong>amizade com o oficial Benjamin Constant Botelho de Magalh\u00e3es, grande nome do republicanismo brasileiro<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em 1870, chegou ao cargo de tenente-coronel por servi\u00e7os relevantes. No mesmo ano, foi nomeado inspetor de fortifica\u00e7\u00f5es e obras militares. Atuou na engenharia militar at\u00e9 1874, quando foi promovido a coronel e passou a comandar um regimento de cavalaria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em 1883, recebeu outra promo\u00e7\u00e3o, para brigadeiro, e foi integrado ao corpo do Estado-Maior General. Tamb\u00e9m tornou-se s\u00f3cio do Clube Abolicionista Cear\u00e1 Livre. Recebeu sua \u00faltima promo\u00e7\u00e3o pelo imp\u00e9rio em 1889, como <strong>marechal de campo e ajudante-general do ex\u00e9rcito<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com isso, <strong>tornou-se comandante da Guarni\u00e7\u00e3o da Corte e Prov\u00edncia do Rio de Janeiro<\/strong>. Todos os demais comandantes de armas estavam subordinados a ele. <strong>Sua posi\u00e7\u00e3o foi fundamental para a queda da monarquia e o estabelecimento da rep\u00fablica<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lembre-se que \u00e9 muito importante estudar praticando exerc\u00edcios. Por isso, n\u00e3o deixe de usar o <a href=\"https:\/\/beduka.com\/simulado-enem\/\" target=\"_blank\" rel=\"noreferrer noopener\">Simulado Enem Gratuito e Online<\/a> que o Beduka preparou para voc\u00ea!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Carreira Pol\u00edtica de Floriano Peixoto<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A experi\u00eancia pol\u00edtica explica quem foi o marechal Floriano Peixoto. E, <strong>apesar de curta durante o imp\u00e9rio, j\u00e1 adiantava o que seria seu mandato na rep\u00fablica<\/strong>. Ele assumiu o cargo de comandante de armas e <strong>presidente da prov\u00edncia do Mato Grosso em 1884<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante o ano em que ocupou o cargo, <strong>apoiou a extra\u00e7\u00e3o de erva-mate e reprimiu fortemente os \u00edndios que amea\u00e7avam Cuiab\u00e1<\/strong>, capital da prov\u00edncia. Ap\u00f3s ser substitu\u00eddo em outubro de 1885, voltou a Alagoas para cuidar do engenho da fam\u00edlia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Depois disso, <strong>s\u00f3 viria a assumir cargos pol\u00edticos ap\u00f3s a proclama\u00e7\u00e3o da rep\u00fablica<\/strong>, em novembro de 1889. Foi <strong>vice-presidente de Deodoro da Fonseca<\/strong> entre 1891 e 1892.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s a ren\u00fancia de Deodoro,<strong> assumiu a chefia do governo<\/strong> em um momento de crise, guerra civil e instabilidade. Por isso, ficou a seu cargo consolidar o novo regime.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Est\u00e1 curtindo saber quem foi o marechal Floriano Peixoto? <\/strong>Agora vamos entrar em uma parte da vida dele que o tornou uma das figuras mais relevantes da nossa hist\u00f3ria.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Qual foi o papel de Floriano Peixoto na Proclama\u00e7\u00e3o da Rep\u00fablica?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A rep\u00fablica brasileira foi proclamada em 15 de novembro de 1889<\/strong>, ap\u00f3s um golpe dado pelo Marechal Deodoro da Fonseca, articulado com membros de setores civis, do ex\u00e9rcito e da marinha. <strong>Sem Floriano, isso jamais teria acontecido<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estando \u00e0 frente de todo o ex\u00e9rcito nacional, <strong>Floriano era o chefe de todo o corpo militar do imp\u00e9rio<\/strong>. As tropas lhe deviam submiss\u00e3o e obedi\u00eancia. Caso ele se mostrasse contr\u00e1rio ao movimento de Deodoro, o golpe n\u00e3o seria dado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Contudo, <strong>ele se recusou a comandar a resist\u00eancia e aderiu ao movimento<\/strong>. O Visconde de Ouro Preto, que era o chefe do minist\u00e9rio, ainda ordenou o assalto aos rebeldes, lembrando que no Paraguai os brasileiros tinham lutado em situa\u00e7\u00e3o mais adversa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Floriano retrucou: \u201cSim, mas l\u00e1 t\u00ednhamos pela frente inimigos e aqui somos todos brasileiros\u201d. Com isso, <strong>as for\u00e7as rebeldes tomaram os pr\u00e9dios p\u00fablicos e prenderam os membros do governo<\/strong>, dando fim \u00e0 monarquia no pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entender quem foi o marechal Floriano Peixoto te deixa a par de um dos temas de Hist\u00f3ria que mais caem no Enem: a primeira rep\u00fablica. <a href=\"https:\/\/beduka.com\/blog\/enem\/temas-que-podem-cair\/o-que-mais-cai-em-historia-no-enem\/\" target=\"_blank\" rel=\"noreferrer noopener\">Saiba quais s\u00e3o os outros<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como foi o governo do marechal Floriano Peixoto?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O governo de Floriano Peixoto foi o segundo da Primeira Rep\u00fablica. <strong>Ele ficou marcado por instabilidade, crises recorrentes e autoritarismo<\/strong>. Mas tamb\u00e9m pela busca de <strong>atenuar pre\u00e7os e consolidar a rep\u00fablica rec\u00e9m-proclamada<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s a proclama\u00e7\u00e3o, Floriano continuou no seu cargo de ajudante-general do ex\u00e9rcito e reprimiu movimentos de restaura\u00e7\u00e3o da monarquia. Em seguida, <strong>foi eleito pelo congresso como vice-presidente de Deodoro da Fonseca,<\/strong> em 1891.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tornou-se assim o primeiro vice-presidente do Brasil. Deodoro assumiu o cargo em um momento complicado. A maior parte do congresso era composta de bachar\u00e9is que n\u00e3o o viam com bons olhos e faziam oposi\u00e7\u00e3o a seu governo, impedindo que ele deslanchasse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como \u00faltima tentativa de fazer valer sua chefia, <strong>fechou o congresso nacional e nomeou interventores dos estados<\/strong>. Isso aumentou ainda mais a insatisfa\u00e7\u00e3o contra ele, que se viu <strong>for\u00e7ado a renunciar ao cargo<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por lei, novas elei\u00e7\u00f5es deveriam ser realizadas caso o presidente n\u00e3o conclu\u00edsse dois anos de mandato. Por\u00e9m, <strong>Floriano assumiu a presid\u00eancia e a exerceu at\u00e9 o limite estabelecido, 1895<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Isso s\u00f3 agravou os problemas anteriores e, devido \u00e0 amea\u00e7a ao regime, <strong>o congresso entrou em recesso e entregou plenos poderes a Floriano para abafar as revoltas e consolidar a rep\u00fablica<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ele prendeu opositores, exilou outros no Amazonas, aposentou compulsoriamente generais que pediam novas elei\u00e7\u00f5es e amea\u00e7ou ju\u00edzes<\/strong> para impedir que seus atos fossem revogados.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por\u00e9m, <strong>conquistou certo prest\u00edgio entre as camadas m\u00e9dias e populares<\/strong>, gra\u00e7as \u00e0s suas pol\u00edticas de diminui\u00e7\u00e3o de pre\u00e7os e conten\u00e7\u00e3o de danos econ\u00f4micos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Teste seus conhecimentos sobre quem foi o Marechal Floriano Peixoto com os <a href=\"https:\/\/beduka.com\/blog\/exercicios\/exercicios-sobre-republica-das-espadas\/\" target=\"_blank\" rel=\"noreferrer noopener\">29 melhores exerc\u00edcios sobre a Rep\u00fablica da Espada<\/a> da qual ele fez parte.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Por que ele ficou conhecido como Marechal de Ferro?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O que podemos falar sobre o ferro? Que ele \u00e9 r\u00edgido, dificilmente se dobra, e \u00e9 capaz de machucar caso seja usado como arma.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O apelido Marechal de Ferro dado a Floriano Peixoto tem a ver com isso e revela bastante quem ele foi e como ele governou o pa\u00eds. Mas <strong>ele ganhou a alcunha s\u00f3 depois de reprimir as duas principais revoltas<\/strong>: a Revolta da Armada e a Revolta Federalista.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Revolta da Armada<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A Revolta da Armada ocorreu entre 1893 e 1894 e envolveu um confronto armado entre a Marinha brasileira e o governo federal<\/strong>. Ela foi liderada por setores insatisfeitos com o governo ilegal do marechal Floriano Peixoto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O clima j\u00e1 era de conflito, pois <strong>a lealdade a Deodoro e as mudan\u00e7as implantadas por Floriano dividiram a popula\u00e7\u00e3o e a elite<\/strong>. Diversos apoiadores do primeiro presidente foram depostos de seus cargos, para dar lugar a aliados de Floriano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em 1893, <strong>as diverg\u00eancias e oposi\u00e7\u00f5es se tornaram uma guerra civil<\/strong> quando o almirante Cust\u00f3dio Jos\u00e9 de Melo foi demitido do cargo de ministro da Marinha.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Isso gerou uma crise, que aumentou quando Eduardo Wandenkolk foi eleito presidente do Clube Naval. Ele tinha sido preso por Floriano em 1892.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Os marinheiros ficaram amotinados nos navios, bloquearam o mar e amea\u00e7aram bombardear a capital federal, caso n\u00e3o tivessem suas reivindica\u00e7\u00f5es atendidas<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Contudo, o governo recebeu ajuda da marinha americana e conseguiu furar o bloqueio. Tamb\u00e9m impossibilitou a chegada dos marinheiros brasileiros \u00e0 praia para conseguir suprimentos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Isso enfraqueceu a revolta. Os participantes pediram ajuda a navios portugueses, que passavam pela regi\u00e3o e <strong>fugiram para Buenos Aires e o sul do Brasil, onde iriam se juntar \u00e0s tropas opositoras a Floriano que lutavam na Revolta Federalista<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Revolta Federalista<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A Revolta Federalista ocorreu entre 1893 e 1895. Foi uma<strong> disputa armada<\/strong> entre os <strong>federalistas<\/strong>, que defendiam maior <strong>autonomia<\/strong> pol\u00edtica para os estados, e os <strong>republicanos<\/strong>, que apoiavam a <strong>centraliza\u00e7\u00e3o <\/strong>do poder nas m\u00e3os do governo central.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os federalistas eram liderados por <strong>Gaspar Silveira Martins<\/strong>, enquanto os republicanos eram liderados por J<strong>\u00falio de Castilhos<\/strong>. A Revolta Federalista resultou em intensos combates, especialmente no estado do Rio Grande do Sul.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Antes mesmo dela acontecer, diversos governos haviam se sucedido desde a proclama\u00e7\u00e3o da rep\u00fablica. Todos buscando estabelecer a ordem, mas nenhum com vida muito longa.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nesse intrevalo, foram fundados o Partido Federalista por Silveira Martins, e o Partido Republicano Rio-grandense, de Castilhos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Castilhos usou da influ\u00eancia de Floriano Peixoto para tomar o poder no estado e promover persegui\u00e7\u00f5es pol\u00edticas<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os <strong>federalistas responderam<\/strong> com a morte de um dos aliados de Castilhos, dando <strong>in\u00edcio a uma guerra civil<\/strong> extremamente violenta onde cabe\u00e7as rolaram literalmente. Uma das principais formas de execu\u00e7\u00e3o de prisioneiros de guerra, era a degola.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os federalistas come\u00e7aram vencendo as batalhas e tomando territ\u00f3rios, como Santa Catarina e o Paran\u00e1. A capital do estado federalista foi a cidade de Nossa Senhora do Desterro em Santa Catarina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>O sentimento antiflorianista era um dos motivos para a revolta<\/strong>. Com isso, Floriano mobilizou tropas para sufocar as tropas federalistas. Isso foi um fator decisivo para o enfraquecimento dos soldados de Silveira Martins e sua derrota.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como forma de demonstrar o poder do governo federal, Herc\u00edlio Luz, o governador de Santa Catarina empossado por Floriano mudou o nome da capital. De Nossa Senhora do Desterro, ela passou a se chamar Florian\u00f3polis, a cidade de Floriano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Foi desta forma que Floriano consolidou a rep\u00fablica. Em 1894, ele entregou o poder a Prudente de Morais, o primeiro presidente civil do pa\u00eds. Assim, fechou o ciclo da <a href=\"https:\/\/beduka.com\/blog\/materias\/historia\/republica-da-espada\/\" target=\"_blank\" rel=\"noreferrer noopener\">Rep\u00fablica da Espada<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Saber quem foi o marechal Floriano Peixoto e como foi seu governo \u00e9 muito importante para o Enem. Mas existem outros temas t\u00e3o importantes quanto e que fizemos quest\u00e3o de colocar no nosso Plano de Estudos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com ele voc\u00ea descobre o que mais cai e quando estudar cada mat\u00e9ria. Adquira j\u00e1 o seu:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/beduka.com\/blog\/dicas\/enem-dicas\/plano-de-estudos\/\">Desejo meu plano<\/a><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Esperamos que tenha entendido bem quem foi o Marechal Floriano Peixoto. Bons estudos!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A transi\u00e7\u00e3o da monarquia para a rep\u00fablica brasileira teve um problema, resolvido por este homem. Mas para isso, ele usou de meios muito violentos\u2026<\/p>\n","protected":false},"author":18,"featured_media":30215,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[491],"tags":[],"class_list":["post-30214","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marechal de Ferro: entenda quem foi Floriano Peixoto<\/title>\n<meta name=\"description\" content=\"A transi\u00e7\u00e3o da monarquia para a rep\u00fablica brasileira teve um problema, resolvido por este homem. Mas para isso, ele usou de meios muito violentos\u2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beduka.com\/blog\/materias\/historia\/quem-foi-marechal-floriano-peixoto\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marechal de Ferro: entenda quem foi Floriano Peixoto\" \/>\n<meta property=\"og:description\" content=\"A transi\u00e7\u00e3o da monarquia para a rep\u00fablica brasileira teve um problema, resolvido por este homem. Mas para isso, ele usou de meios muito violentos\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beduka.com\/blog\/materias\/historia\/quem-foi-marechal-floriano-peixoto\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-21T18:51:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-26T18:42:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2023\/07\/quem-foi-marechal-floriano-peixoto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Beduka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Beduka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/historia\\\/quem-foi-marechal-floriano-peixoto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/historia\\\/quem-foi-marechal-floriano-peixoto\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Beduka\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/person\\\/a642c9aad29bdea97a352689b053f80f\"},\"headline\":\"Quem foi o marechal Floriano Peixoto? Saiba a hist\u00f3ria do presidente que tinha todo o Brasil contra ele\",\"datePublished\":\"2023-07-21T18:51:05+00:00\",\"dateModified\":\"2026-08-26T18:42:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/historia\\\/quem-foi-marechal-floriano-peixoto\\\/\"},\"wordCount\":2037,\"publisher\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/historia\\\/quem-foi-marechal-floriano-peixoto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/quem-foi-marechal-floriano-peixoto.jpg\",\"articleSection\":[\"Hist\u00f3ria\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/historia\\\/quem-foi-marechal-floriano-peixoto\\\/\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/historia\\\/quem-foi-marechal-floriano-peixoto\\\/\",\"name\":\"Marechal de Ferro: entenda quem foi Floriano Peixoto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/historia\\\/quem-foi-marechal-floriano-peixoto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/historia\\\/quem-foi-marechal-floriano-peixoto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/quem-foi-marechal-floriano-peixoto.jpg\",\"datePublished\":\"2023-07-21T18:51:05+00:00\",\"dateModified\":\"2026-08-26T18:42:43+00:00\",\"description\":\"A transi\u00e7\u00e3o da monarquia para a rep\u00fablica brasileira teve um problema, resolvido por este homem. Mas para isso, ele usou de meios muito violentos\u2026\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/historia\\\/quem-foi-marechal-floriano-peixoto\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/historia\\\/quem-foi-marechal-floriano-peixoto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/historia\\\/quem-foi-marechal-floriano-peixoto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/quem-foi-marechal-floriano-peixoto.jpg\",\"contentUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/quem-foi-marechal-floriano-peixoto.jpg\",\"width\":600,\"height\":300,\"caption\":\"Quem foi marechal Floriano Peixoto?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/historia\\\/quem-foi-marechal-floriano-peixoto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/beduka.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quem foi o marechal Floriano Peixoto? Saiba a hist\u00f3ria do presidente que tinha todo o Brasil contra ele\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/\",\"name\":\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\",\"description\":\"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!\",\"publisher\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beduka.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#organization\",\"name\":\"Beduka\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/marca-beduka.png\",\"contentUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/marca-beduka.png\",\"width\":1077,\"height\":368,\"caption\":\"Beduka\"},\"image\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/beduka.buscadordefaculdades\\\/\",\"https:\\\/\\\/www.instagram.com\\\/beduka_oficial\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/beduka\",\"https:\\\/\\\/br.pinterest.com\\\/bedukaoficial\\\/\",\"https:\\\/\\\/www.youtube.com\\\/beduka\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/person\\\/a642c9aad29bdea97a352689b053f80f\",\"name\":\"Reda\u00e7\u00e3o Beduka\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3395f9cda33faa4c8c705d46a95a8971e6ab91f6e4e2870a05c6398b68531e4d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3395f9cda33faa4c8c705d46a95a8971e6ab91f6e4e2870a05c6398b68531e4d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3395f9cda33faa4c8c705d46a95a8971e6ab91f6e4e2870a05c6398b68531e4d?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o Beduka\"},\"description\":\"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/beduka.buscadordefaculdades\",\"https:\\\/\\\/www.instagram.com\\\/beduka_oficial\\\/\",\"https:\\\/\\\/br.pinterest.com\\\/bedukaoficial\\\/\"],\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/author\\\/dioney\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marechal de Ferro: entenda quem foi Floriano Peixoto","description":"A transi\u00e7\u00e3o da monarquia para a rep\u00fablica brasileira teve um problema, resolvido por este homem. Mas para isso, ele usou de meios muito violentos\u2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beduka.com\/blog\/materias\/historia\/quem-foi-marechal-floriano-peixoto\/","og_locale":"pt_BR","og_type":"article","og_title":"Marechal de Ferro: entenda quem foi Floriano Peixoto","og_description":"A transi\u00e7\u00e3o da monarquia para a rep\u00fablica brasileira teve um problema, resolvido por este homem. Mas para isso, ele usou de meios muito violentos\u2026","og_url":"https:\/\/beduka.com\/blog\/materias\/historia\/quem-foi-marechal-floriano-peixoto\/","og_site_name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","article_publisher":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","article_author":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades","article_published_time":"2023-07-21T18:51:05+00:00","article_modified_time":"2026-08-26T18:42:43+00:00","og_image":[{"width":600,"height":300,"url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2023\/07\/quem-foi-marechal-floriano-peixoto.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Beduka","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Beduka","Est. tempo de leitura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beduka.com\/blog\/materias\/historia\/quem-foi-marechal-floriano-peixoto\/#article","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/materias\/historia\/quem-foi-marechal-floriano-peixoto\/"},"author":{"name":"Reda\u00e7\u00e3o Beduka","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/a642c9aad29bdea97a352689b053f80f"},"headline":"Quem foi o marechal Floriano Peixoto? Saiba a hist\u00f3ria do presidente que tinha todo o Brasil contra ele","datePublished":"2023-07-21T18:51:05+00:00","dateModified":"2026-08-26T18:42:43+00:00","mainEntityOfPage":{"@id":"https:\/\/beduka.com\/blog\/materias\/historia\/quem-foi-marechal-floriano-peixoto\/"},"wordCount":2037,"publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"image":{"@id":"https:\/\/beduka.com\/blog\/materias\/historia\/quem-foi-marechal-floriano-peixoto\/#primaryimage"},"thumbnailUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2023\/07\/quem-foi-marechal-floriano-peixoto.jpg","articleSection":["Hist\u00f3ria"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/beduka.com\/blog\/materias\/historia\/quem-foi-marechal-floriano-peixoto\/","url":"https:\/\/beduka.com\/blog\/materias\/historia\/quem-foi-marechal-floriano-peixoto\/","name":"Marechal de Ferro: entenda quem foi Floriano Peixoto","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beduka.com\/blog\/materias\/historia\/quem-foi-marechal-floriano-peixoto\/#primaryimage"},"image":{"@id":"https:\/\/beduka.com\/blog\/materias\/historia\/quem-foi-marechal-floriano-peixoto\/#primaryimage"},"thumbnailUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2023\/07\/quem-foi-marechal-floriano-peixoto.jpg","datePublished":"2023-07-21T18:51:05+00:00","dateModified":"2026-08-26T18:42:43+00:00","description":"A transi\u00e7\u00e3o da monarquia para a rep\u00fablica brasileira teve um problema, resolvido por este homem. Mas para isso, ele usou de meios muito violentos\u2026","breadcrumb":{"@id":"https:\/\/beduka.com\/blog\/materias\/historia\/quem-foi-marechal-floriano-peixoto\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beduka.com\/blog\/materias\/historia\/quem-foi-marechal-floriano-peixoto\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/materias\/historia\/quem-foi-marechal-floriano-peixoto\/#primaryimage","url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2023\/07\/quem-foi-marechal-floriano-peixoto.jpg","contentUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2023\/07\/quem-foi-marechal-floriano-peixoto.jpg","width":600,"height":300,"caption":"Quem foi marechal Floriano Peixoto?"},{"@type":"BreadcrumbList","@id":"https:\/\/beduka.com\/blog\/materias\/historia\/quem-foi-marechal-floriano-peixoto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/beduka.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Quem foi o marechal Floriano Peixoto? Saiba a hist\u00f3ria do presidente que tinha todo o Brasil contra ele"}]},{"@type":"WebSite","@id":"https:\/\/beduka.com\/blog\/#website","url":"https:\/\/beduka.com\/blog\/","name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","description":"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!","publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beduka.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beduka.com\/blog\/#organization","name":"Beduka","url":"https:\/\/beduka.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","contentUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","width":1077,"height":368,"caption":"Beduka"},"image":{"@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/www.linkedin.com\/company\/beduka","https:\/\/br.pinterest.com\/bedukaoficial\/","https:\/\/www.youtube.com\/beduka"]},{"@type":"Person","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/a642c9aad29bdea97a352689b053f80f","name":"Reda\u00e7\u00e3o Beduka","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3395f9cda33faa4c8c705d46a95a8971e6ab91f6e4e2870a05c6398b68531e4d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3395f9cda33faa4c8c705d46a95a8971e6ab91f6e4e2870a05c6398b68531e4d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3395f9cda33faa4c8c705d46a95a8971e6ab91f6e4e2870a05c6398b68531e4d?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o Beduka"},"description":"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.","sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/br.pinterest.com\/bedukaoficial\/"],"url":"https:\/\/beduka.com\/blog\/author\/dioney\/"}]}},"_links":{"self":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/30214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/comments?post=30214"}],"version-history":[{"count":1,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/30214\/revisions"}],"predecessor-version":[{"id":30216,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/30214\/revisions\/30216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media\/30215"}],"wp:attachment":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media?parent=30214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/categories?post=30214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/tags?post=30214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}