{"id":3475,"date":"2019-02-18T17:36:06","date_gmt":"2019-02-18T20:36:06","guid":{"rendered":"https:\/\/beduka.com\/blog\/?p=3475"},"modified":"2022-09-27T15:44:06","modified_gmt":"2022-09-27T18:44:06","slug":"o-que-e-estrutura-atomica","status":"publish","type":"post","link":"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-estrutura-atomica\/","title":{"rendered":"O que \u00e9 estrutura at\u00f4mica? Resumo dos 4 modelos: Dalton, Thomson, Rutherford e Bohr"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote\"><p><strong><em>O que \u00e9 estrutura at\u00f4mica? A estrutura at\u00f4mica \u00e9 composta por tr\u00eas part\u00edculas fundamentais: pr\u00f3tons, n\u00eautrons e el\u00e9trons. Saiba mais sobre cada part\u00edcula e sobre os modelos at\u00f4micos nesse artigo! <\/em><\/strong><\/p><p><\/p><\/blockquote>\n\n\n\n<p>Nesse artigo iremos explicar <b>o que \u00e9 estrutura at\u00f4mica<\/b>, al\u00e9m de explicar sobre os modelos at\u00f4micos e tirar as principais d\u00favidas sobre o assunto. <strong>Clique no t\u00f3pico de seu interesse: <\/strong><\/p>\n\n\n\n<ul><li><a href=\"#\u00e1tomos\" data-type=\"internal\" data-id=\"#\u00e1tomos\">O que s\u00e3o os \u00e1tomos?<\/a><\/li><li><a href=\"#modelos-at\u00f4micos\" data-type=\"internal\" data-id=\"#modelos-at\u00f4micos\">Quais s\u00e3o os principais modelos at\u00f4micos?<\/a><\/li><li><a href=\"#estrutura-at\u00f4mica\" data-type=\"internal\" data-id=\"#estrutura-at\u00f4mica\">O que \u00e9 estrutura at\u00f4mica?<\/a><\/li><li><a href=\"#n\u00f3s-conectamos-voc\u00ea-\u00e0-faculdade\" data-type=\"internal\" data-id=\"#n\u00f3s-conectamos-voc\u00ea-\u00e0-faculdade\">N\u00f3s conectamos voc\u00ea \u00e0 faculdade!<\/a><\/li><\/ul>\n\n\n\n<p>Depois de ler este resumo sobre o que \u00e9 estrutura at\u00f4mica, teste seus conhecimentos com o\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/beduka.com\/simulado-enem\" target=\"_blank\"><strong>Simulado Enem do Beduka<\/strong><\/a>. Ele \u00e9\u00a0<strong>100% gratuito<\/strong>\u00a0e utiliza o m\u00e9todo\u00a0<strong>TRI de corre\u00e7\u00e3o!<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"\u00e1tomos\">O que s\u00e3o os \u00e1tomos?<\/h2>\n\n\n\n<p>Se voc\u00ea est\u00e1 se preparando para o vestibular e j\u00e1 come\u00e7ou a estudar qu\u00edmica ent\u00e3o voc\u00ea j\u00e1 deve saber que os <strong>\u00e1tomos s\u00e3o a base dessa mat\u00e9ria.<\/strong><\/p>\n\n\n\n<p>Na verdade, eles s\u00e3o a base de tudo no universo j\u00e1 que ele \u00e9 o que constitui a mat\u00e9ria (tudo aquilo que ocupa espa\u00e7o e possui massa). <\/p>\n\n\n\n<p><strong>Os \u00e1tomos s\u00e3o part\u00edculas infinitamente pequenas que constituem toda a mat\u00e9ria do universo.<\/strong> O estudo do \u00e1tomo iniciou na Gr\u00e9cia Antiga com o fil\u00f3sofo Leucipo e seu disc\u00edpulo Dem\u00f3crito. Para eles o \u00e1tomo era o menor componente de toda mat\u00e9ria existente. Ent\u00e3o, era imposs\u00edvel que ela fosse dividido em partes menores.<\/p>\n\n\n\n<ul><li><strong>Aproveite e fa\u00e7a os<a href=\"https:\/\/beduka.com\/blog\/exercicios\/quimica-exercicios\/exercicios-sobre-atomos\/\"> exerc\u00edcios sobre \u00e1tomos<\/a>!<\/strong><\/li><\/ul>\n\n\n\n<p>Ao desenrolar da hist\u00f3ria, diversos cientistas e estudiosos tentaram definir o \u00e1tomo quanto a sua forma, dando origem a diversas teorias sobre sua constitui\u00e7\u00e3o f\u00edsica. Surgiram, ent\u00e3o, os modelos at\u00f4micos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"modelos-at\u00f4micos\"><span style=\"color: #1c609a;\">Quais s\u00e3o os principais modelos at\u00f4micos?<\/span><\/h2>\n\n\n\n<p>Confira abaixo o resumo dos 4 principais modelos at\u00f4micos estudados.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"color: #1c609a;\">Modelo At\u00f4mico de Dalton<\/span><\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" loading=\"lazy\" width=\"803\" height=\"746\" src=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/02\/modelo-atomico.png\" alt=\"modelo at\u00f4mico de Dalton no resumo de estrutura at\u00f4mica\" class=\"wp-image-3480\" srcset=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/02\/modelo-atomico.png 803w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/02\/modelo-atomico-300x279.png 300w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/02\/modelo-atomico-768x713.png 768w\" sizes=\"(max-width: 803px) 100vw, 803px\" \/><\/figure><\/div>\n\n\n<p>Para Dalton, a teoria de Leucipo e Dem\u00f3crito era muito coerente. De acordo com esse modelo,<strong> os \u00e1tomos eram as menores part\u00edculas poss\u00edveis<\/strong>, <strong>assumiam formas esf\u00e9ricas e possu\u00edam massa semelhante<\/strong> caso fossem correspondente ao mesmo elemento qu\u00edmico.<\/p>\n\n\n\n<p>Esse modelo \u00e9 conhecido como <strong>bola de bilhar<\/strong> e possui os seguintes princ\u00edpios:<\/p>\n\n\n\n<ul><li>Todas as subst\u00e2ncias s\u00e3o formadas de pequenas part\u00edculas chamadas \u00e1tomos;<\/li><li>Os \u00e1tomos de diferentes elementos possuem diferentes propriedades, mas <strong>quando os \u00e1tomos s\u00e3o do mesmo elemento eles s\u00e3o exatamente iguais;<\/strong><\/li><li>Os \u00e1tomos n\u00e3o se alteram quando formam componentes qu\u00edmicos;<\/li><li><strong>Os \u00e1tomos s\u00e3o permanentes e indivis\u00edveis<\/strong> e n\u00e3o podem ser criados ou destru\u00eddos;<\/li><li>As rea\u00e7\u00f5es qu\u00edmicas correspondem a uma reorganiza\u00e7\u00e3o de \u00e1tomos.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"color: #1c609a;\">Modelo At\u00f4mico de Thomson<\/span><\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" loading=\"lazy\" width=\"984\" height=\"1024\" src=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/02\/modelo-atomico-2-984x1024.png\" alt=\"representa\u00e7\u00e3o do modelo at\u00f4mico de Thomson no resumo de estrutura at\u00f4mica\" class=\"wp-image-3478\" srcset=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/02\/modelo-atomico-2-984x1024.png 984w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/02\/modelo-atomico-2-288x300.png 288w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/02\/modelo-atomico-2-768x799.png 768w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/02\/modelo-atomico-2.png 1690w\" sizes=\"(max-width: 984px) 100vw, 984px\" \/><\/figure><\/div>\n\n\n<p>Atrav\u00e9s da descoberta do el\u00e9tron (part\u00edcula que constitui o \u00e1tomo e que possui carga el\u00e9trica negativa), o modelo at\u00f4mico de Dalton se tornou defasado. E com os estudos de Thomson um novo modelo foi idealizado.<\/p>\n\n\n\n<p>O modelo at\u00f4mico de Thomson foi o <strong>primeiro a realizar a divisibilidade do \u00e1tomo.<\/strong> Ao pesquisar sobre raios cat\u00f3dicos, o f\u00edsico ingl\u00eas prop\u00f4s esse modelo que ficou conhecido como o<strong> modelo pudim de ameixa.<\/strong><\/p>\n\n\n\n<p>De acordo com esse modelo, o \u00e1tomo era uma esfera de carga el\u00e9trica positiva incrustada com el\u00e9trons, de carga negativa, tornando-se assim eletricamente neutro.<\/p>\n\n\n\n<p>Ele descobriu essa m\u00ednima part\u00edcula e assim estabeleceu a <strong>teoria da natureza el\u00e9trica da mat\u00e9ria.<\/strong> Concluiu que os el\u00e9trons eram constituintes de todos os tipos de mat\u00e9ria, pois observou que a rela\u00e7\u00e3o carga\/massa do el\u00e9tron era a mesma para qualquer g\u00e1s empregado em suas experi\u00eancias.<\/p>\n\n\n\n<p>Devido aos seus estudos em rela\u00e7\u00e3o \u00e0 essa part\u00edcula, Thomson se tornou <strong>\u201cpai do el\u00e9tron\u201d.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"color: #1c609a;\">Modelo At\u00f4mico de Rutherford<\/span><\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" loading=\"lazy\" width=\"981\" height=\"913\" src=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/02\/modelo-atomico-3.png\" alt=\"modelo at\u00f4mico de Rutherford no resumo de estrutura at\u00f4mica\" class=\"wp-image-3479\" srcset=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/02\/modelo-atomico-3.png 981w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/02\/modelo-atomico-3-300x279.png 300w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/02\/modelo-atomico-3-768x715.png 768w\" sizes=\"(max-width: 981px) 100vw, 981px\" \/><\/figure><\/div>\n\n\n<p>Em 1911, o f\u00edsico Rutherford colocou uma folha de ouro muito fina dentro de uma c\u00e2mara met\u00e1lica. Seu objetivo era analisar a trajet\u00f3ria das part\u00edculas alfa a partir do obst\u00e1culo criado pela folha de ouro.<\/p>\n\n\n\n<p>Nesse experimento, Rutherford observou que algumas part\u00edculas ficavam totalmente bloqueadas. Outras part\u00edculas n\u00e3o eram afetadas, mas a maioria ultrapassava a folha sofrendo desvios.<\/p>\n\n\n\n<p>Segundo o f\u00edsico, esse comportamento podia ser explicados gra\u00e7as \u00e0s <strong>for\u00e7as de repuls\u00e3o el\u00e9trica<\/strong> entre essas part\u00edculas.<\/p>\n\n\n\n<p>Devido \u00e0s suas observa\u00e7\u00f5es, <strong>ele afirmou que o \u00e1tomo era nucleado e sua parte positiva se concentrava num volume extremamente pequeno, que seria o pr\u00f3prio n\u00facleo.<\/strong><\/p>\n\n\n\n<p>O modelo at\u00f4mico de Rutherford \u00e9 tamb\u00e9m conhecido como <strong>modelo planet\u00e1rio<\/strong>, pois corresponde a uma modelo planet\u00e1rio em miniatura. Nesse modelo, os el\u00e9trons se movem em \u00f3rbitas circulares ao redor do n\u00facleo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"color: #1c609a;\">Modelo At\u00f4mico de Bohr<\/span><\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" loading=\"lazy\" width=\"750\" height=\"818\" src=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/02\/modelo-atomico-1.png\" alt=\"modelo at\u00f4mico de Bohr no resumo de estrutura at\u00f4mica\" class=\"wp-image-3477\" srcset=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/02\/modelo-atomico-1.png 750w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/02\/modelo-atomico-1-275x300.png 275w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure><\/div>\n\n\n<p>O modelo apresentado por Rutherford foi aperfei\u00e7oado por Bohr. A teoria do f\u00edsico Niels Bohr estabeleceu as seguintes concep\u00e7\u00f5es at\u00f4micas:<\/p>\n\n\n\n<ul><li>Os <strong>el\u00e9trons que giram ao redor do n\u00facleo<\/strong> n\u00e3o giram ao acaso, e sim fazer rotas determinadas;<\/li><li>O \u00e1tomo \u00e9 extremamente pequeno, mesmo assim <strong>a maior parte do \u00e1tomo \u00e9 vazia.<\/strong> O di\u00e2metro do n\u00facleo at\u00f4mico \u00e9 cerca de cem mil vezes menor que o \u00e1tomo todo. <strong>Os el\u00e9trons giram t\u00e3o depressa que parecem tomar todo o espa\u00e7o.<\/strong><\/li><li><strong>Quando os el\u00e9trons saltam de uma \u00f3rbita para a outra resulta luz.<\/strong> Bohr conseguiu prever os comprimentos de onda a partir da constitui\u00e7\u00e3o do \u00e1tomo e do salto dos el\u00e9trons de uma \u00f3rbita para a outra.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"estrutura-at\u00f4mica\"><span style=\"color: #1c609a;\">O que \u00e9 estrutura at\u00f4mica?<\/span><\/h2>\n\n\n\n<p><strong>\u00c9 estrutura at\u00f4mica \u00e9 a composi\u00e7\u00e3o de um \u00e1tomo<\/strong>, part\u00edculas   infinitamente pequenas que constituem toda a mat\u00e9ria do universo. <strong>S\u00e3o tr\u00eas part\u00edculas fundamentais: <\/strong>pr\u00f3tons (positivos), el\u00e9trons (negativos) e n\u00eautrons (neutros).<\/p>\n\n\n\n<ol><li>Pr\u00f3tons (+)<\/li><li>N\u00eautrons (-)<\/li><li>El\u00e9trons (0)<\/li><\/ol>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"color: #1c609a;\">Pr\u00f3tons<\/span><\/h3>\n\n\n\n<p>O pr\u00f3ton \u00e9 uma part\u00edcula fundamental na estrutura at\u00f4mica. Ele <strong>possui carga positiva<\/strong> e, juntamente com os n\u00eautrons,<strong> forma todos os n\u00facleos at\u00f4micos.<\/strong> Exceto o n\u00facleo at\u00f4mico do hidrog\u00eanio que \u00e9 formado por um \u00fanico pr\u00f3ton.<\/p>\n\n\n\n<p>O que caracteriza um elemento \u00e9 n\u00famero de pr\u00f3tons do \u00e1tomo, tamb\u00e9m conhecido como n\u00famero at\u00f4mico do elemento.<\/p>\n\n\n\n<p><strong>A massa de um \u00e1tomo \u00e9 a soma dos pr\u00f3tons e n\u00eautrons.<\/strong> Como a massa do el\u00e9tron \u00e9 muito pequena, ela n\u00e3o \u00e9 considerada. A massa do \u00e1tomo \u00e9 representada pela letra (A), o n\u00famero de pr\u00f3tons pela letra (Z) e o n\u00famero de n\u00eautrons pela letra (N). Ou seja: <b>A = Z + N<\/b>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"color: #1c609a;\">N\u00eautrons<\/span><\/h3>\n\n\n\n<p>Os n\u00eautrons s\u00e3o <strong>part\u00edculas neutras<\/strong> que fazem parte da estrutura at\u00f4mica. <strong>Ele possui massa, mas n\u00e3o possui carga.<\/strong><\/p>\n\n\n\n<p>O n\u00eautron se localiza na por\u00e7\u00e3o central do \u00e1tomo, ou seja, no<strong> n\u00facleo.<\/strong> E para se calcular a quantidade exata de n\u00eautrons em um \u00e1tomo \u00e9 s\u00f3 fazer a subtra\u00e7\u00e3o entre o n\u00famero de massa (A) e o n\u00famero at\u00f4mico (Z).<b> Ou seja: N = A &#8211; Z<\/b>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"color: #1c609a;\">El\u00e9trons<\/span><\/h3>\n\n\n\n<p>O el\u00e9tron \u00e9 uma <strong>part\u00edcula subat\u00f4mica<\/strong> que circunda o n\u00facleo at\u00f4mico, sendo respons\u00e1vel pela cria\u00e7\u00e3o de campos magn\u00e9ticos eletr\u00f4nicos.<\/p>\n\n\n\n<p>Um pr\u00f3ton na presen\u00e7a de outro pr\u00f3ton se repele, o mesmo ocorre com os el\u00e9trons, mas<strong> entre um pr\u00f3ton e um el\u00e9tron existe uma for\u00e7a de atra\u00e7\u00e3o.<\/strong> Dessa maneira atribui-se ao pr\u00f3ton e ao el\u00e9tron uma propriedade f\u00edsica denominada carga el\u00e9trica. Enquanto a carga do pr\u00f3ton \u00e9 positiva, a do el\u00e9tron \u00e9 negativa.<\/p>\n\n\n\n<p>Os el\u00e9trons dos \u00e1tomos giram em \u00f3rbitas espec\u00edficas e de n\u00edveis energ\u00e9ticos bem definidos. Sempre que um el\u00e9tron muda de \u00f3rbita, um pacote de energia seria emitido ou absorvido.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color: #1c609a;\">Semelhan\u00e7a entre os \u00e1tomos<\/span><\/h2>\n\n\n\n<p><strong>Os is\u00f3topos, is\u00f3baros e is\u00f3tonos s\u00e3o classifica\u00e7\u00f5es dos \u00e1tomos dos elementos qu\u00edmicos presentes na tabela peri\u00f3dica<\/strong>, de acordo com a quantidade de pr\u00f3tons, el\u00e9trons e n\u00eautrons presentes em cada um deles.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"color: #1c609a;\">\u00c1tomos Is\u00f3topos<\/span><\/h3>\n\n\n\n<p>S\u00e3o \u00e1tomos que possuem <strong>mesmo n\u00famero at\u00f4mico<\/strong> (Z), mas n\u00fameros de massa (A) diferentes. Ou seja, <strong>o n\u00famero de pr\u00f3tons \u00e9 igual<\/strong>, mas o n\u00famero de n\u00eautrons \u00e9 diferente. Podemos observar que como possuem o mesmo n\u00famero at\u00f4mico s\u00e3o \u00e1tomos de um mesmo elemento qu\u00edmico.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"color: #1c609a;\">\u00c1tomos Is\u00f3baros<\/span><\/h3>\n\n\n\n<p>S\u00e3o \u00e1tomos que possuem <strong>o mesmo n\u00famero de massa<\/strong> (A) e diferentes n\u00fameros at\u00f4micos (Z).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"color: #1c609a;\">\u00c1tomos Is\u00f3tonos<\/span><\/h3>\n\n\n\n<p>S\u00e3o \u00e1tomos que possuem <strong>o mesmo n\u00famero de n\u00eautrons<\/strong> (N) e diferentes n\u00fameros at\u00f4micos (Z) e de massa (A).<\/p>\n\n\n\n<p>Esperamos ter ajudado voc\u00ea a entender o que \u00e9 estrutura at\u00f4mica.\u00a0No mais, n\u00e3o deixe de conferir a\u00a0<strong>oportunidade incr\u00edvel que espera por voc\u00ea a seguir!<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"n\u00f3s-conectamos-voc\u00ea-\u00e0-faculdade\">N\u00f3s conectamos voc\u00ea \u00e0 faculdade!<\/h2>\n\n\n\n<p>J\u00e1 pensou fazer faculdade em uma das&nbsp;<strong>melhores universidades do Brasil&nbsp;<\/strong>e ainda&nbsp;<strong>economizar o seu dinheiro?<\/strong><\/p>\n\n\n\n<p>N\u00f3s conectamos voc\u00ea \u00e0 faculdade com o<a href=\"https:\/\/beduka.com\/bolsas\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>&nbsp;Beduka Bolsas!<\/strong><\/a><\/p>\n\n\n\n<p>Nesse programa, voc\u00ea pode adquirir uma&nbsp;<strong>bolsa de estudos de at\u00e9 65% de desconto na mensalidade<\/strong>, a qualquer momento, sem precisar de Enem ou vestibular.&nbsp;<\/p>\n\n\n\n<p>\u00c9 isso mesmo!<strong>\u00a0<\/strong>Essa \u00e9 a sua chance de fazer o curso dos seus sonhos pagando pouco.\u00a0 S\u00e3o mais de\u00a0<strong>90 op\u00e7\u00f5es de cursos<\/strong>\u00a0para voc\u00ea escolher, em\u00a0<strong>8 universidades<\/strong>\u00a0parceiras de excelent\u00edssimo n\u00edvel!<\/p>\n\n\n\n<ul><li><a href=\"https:\/\/beduka.com\/bolsas\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Garanta j\u00e1 sua bolsa de estudos!<\/strong><\/a><\/li><\/ul>\n\n\n\n<p>Siga o Beduka no&nbsp;<a href=\"https:\/\/www.instagram.com\/beduka_oficial\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Instagram<\/strong><\/a>&nbsp;e no&nbsp;<a href=\"https:\/\/www.tiktok.com\/@beduka.oficial\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Tiktok<\/strong><\/a>&nbsp;e receba conte\u00fados gratuitos sobre o Enem e outros vestibulares diariamente.<\/p>\n\n\n\n<p>Obrigada por ler at\u00e9 o final!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entenda de uma vez por todas o que \u00e9 estrutura at\u00f4mica, com pr\u00f3tons, el\u00e9trons e n\u00eautrons. Veja o resumo dos 4 modelos: Dalton, Thomson, Rutherford e Bohr.<\/p>\n","protected":false},"author":1,"featured_media":27078,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[496],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>O que \u00e9 estrutura at\u00f4mica? RESUMO COMPLETO dos 4 modelos!<\/title>\n<meta name=\"description\" content=\"Entenda de uma vez por todas o que \u00e9 estrutura at\u00f4mica, com pr\u00f3tons, el\u00e9trons e n\u00eautrons. Veja o resumo dos 4 modelos: Dalton, Thomson, Rutherford e Bohr.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-estrutura-atomica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O que \u00e9 estrutura at\u00f4mica? RESUMO COMPLETO dos 4 modelos!\" \/>\n<meta property=\"og:description\" content=\"Entenda de uma vez por todas o que \u00e9 estrutura at\u00f4mica, com pr\u00f3tons, el\u00e9trons e n\u00eautrons. Veja o resumo dos 4 modelos: Dalton, Thomson, Rutherford e Bohr.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-estrutura-atomica\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-18T20:36:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-27T18:44:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/02\/O-que-e-Estrutura-Atomica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"609\" \/>\n\t<meta property=\"og:image:height\" content=\"342\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-estrutura-atomica\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-estrutura-atomica\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a\"},\"headline\":\"O que \u00e9 estrutura at\u00f4mica? Resumo dos 4 modelos: Dalton, Thomson, Rutherford e Bohr\",\"datePublished\":\"2019-02-18T20:36:06+00:00\",\"dateModified\":\"2022-09-27T18:44:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-estrutura-atomica\/\"},\"wordCount\":1634,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/beduka.com\/blog\/#organization\"},\"articleSection\":[\"Qu\u00edmica\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-estrutura-atomica\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-estrutura-atomica\/\",\"url\":\"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-estrutura-atomica\/\",\"name\":\"O que \u00e9 estrutura at\u00f4mica? RESUMO COMPLETO dos 4 modelos!\",\"isPartOf\":{\"@id\":\"https:\/\/beduka.com\/blog\/#website\"},\"datePublished\":\"2019-02-18T20:36:06+00:00\",\"dateModified\":\"2022-09-27T18:44:06+00:00\",\"description\":\"Entenda de uma vez por todas o que \u00e9 estrutura at\u00f4mica, com pr\u00f3tons, el\u00e9trons e n\u00eautrons. Veja o resumo dos 4 modelos: Dalton, Thomson, Rutherford e Bohr.\",\"breadcrumb\":{\"@id\":\"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-estrutura-atomica\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-estrutura-atomica\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-estrutura-atomica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/beduka.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O que \u00e9 estrutura at\u00f4mica? Resumo dos 4 modelos: Dalton, Thomson, Rutherford e Bohr\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/beduka.com\/blog\/#website\",\"url\":\"https:\/\/beduka.com\/blog\/\",\"name\":\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\",\"description\":\"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!\",\"publisher\":{\"@id\":\"https:\/\/beduka.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/beduka.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/beduka.com\/blog\/#organization\",\"name\":\"Beduka\",\"url\":\"https:\/\/beduka.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png\",\"contentUrl\":\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png\",\"width\":1077,\"height\":368,\"caption\":\"Beduka\"},\"image\":{\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/\",\"https:\/\/www.instagram.com\/beduka_oficial\/\",\"https:\/\/www.linkedin.com\/company\/beduka\",\"https:\/\/br.pinterest.com\/bedukaoficial\/\",\"https:\/\/www.youtube.com\/beduka\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a\",\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o Beduka (a)\"},\"description\":\"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.\",\"sameAs\":[\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\",\"https:\/\/www.instagram.com\/beduka_oficial\/\",\"https:\/\/br.pinterest.com\/bedukaoficial\/\"],\"url\":\"https:\/\/beduka.com\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O que \u00e9 estrutura at\u00f4mica? RESUMO COMPLETO dos 4 modelos!","description":"Entenda de uma vez por todas o que \u00e9 estrutura at\u00f4mica, com pr\u00f3tons, el\u00e9trons e n\u00eautrons. Veja o resumo dos 4 modelos: Dalton, Thomson, Rutherford e Bohr.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-estrutura-atomica\/","og_locale":"pt_BR","og_type":"article","og_title":"O que \u00e9 estrutura at\u00f4mica? RESUMO COMPLETO dos 4 modelos!","og_description":"Entenda de uma vez por todas o que \u00e9 estrutura at\u00f4mica, com pr\u00f3tons, el\u00e9trons e n\u00eautrons. Veja o resumo dos 4 modelos: Dalton, Thomson, Rutherford e Bohr.","og_url":"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-estrutura-atomica\/","og_site_name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","article_publisher":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","article_author":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades","article_published_time":"2019-02-18T20:36:06+00:00","article_modified_time":"2022-09-27T18:44:06+00:00","og_image":[{"width":609,"height":342,"url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/02\/O-que-e-Estrutura-Atomica.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Beduka (a)","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Beduka (a)","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-estrutura-atomica\/#article","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-estrutura-atomica\/"},"author":{"name":"Reda\u00e7\u00e3o Beduka (a)","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a"},"headline":"O que \u00e9 estrutura at\u00f4mica? Resumo dos 4 modelos: Dalton, Thomson, Rutherford e Bohr","datePublished":"2019-02-18T20:36:06+00:00","dateModified":"2022-09-27T18:44:06+00:00","mainEntityOfPage":{"@id":"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-estrutura-atomica\/"},"wordCount":1634,"commentCount":0,"publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"articleSection":["Qu\u00edmica"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-estrutura-atomica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-estrutura-atomica\/","url":"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-estrutura-atomica\/","name":"O que \u00e9 estrutura at\u00f4mica? RESUMO COMPLETO dos 4 modelos!","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/#website"},"datePublished":"2019-02-18T20:36:06+00:00","dateModified":"2022-09-27T18:44:06+00:00","description":"Entenda de uma vez por todas o que \u00e9 estrutura at\u00f4mica, com pr\u00f3tons, el\u00e9trons e n\u00eautrons. Veja o resumo dos 4 modelos: Dalton, Thomson, Rutherford e Bohr.","breadcrumb":{"@id":"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-estrutura-atomica\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-estrutura-atomica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-estrutura-atomica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/beduka.com\/blog\/"},{"@type":"ListItem","position":2,"name":"O que \u00e9 estrutura at\u00f4mica? Resumo dos 4 modelos: Dalton, Thomson, Rutherford e Bohr"}]},{"@type":"WebSite","@id":"https:\/\/beduka.com\/blog\/#website","url":"https:\/\/beduka.com\/blog\/","name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","description":"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!","publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beduka.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beduka.com\/blog\/#organization","name":"Beduka","url":"https:\/\/beduka.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","contentUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","width":1077,"height":368,"caption":"Beduka"},"image":{"@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/www.linkedin.com\/company\/beduka","https:\/\/br.pinterest.com\/bedukaoficial\/","https:\/\/www.youtube.com\/beduka"]},{"@type":"Person","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a","name":"Reda\u00e7\u00e3o Beduka (a)","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o Beduka (a)"},"description":"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.","sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/br.pinterest.com\/bedukaoficial\/"],"url":"https:\/\/beduka.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/3475"}],"collection":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/comments?post=3475"}],"version-history":[{"count":10,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/3475\/revisions"}],"predecessor-version":[{"id":27079,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/3475\/revisions\/27079"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media\/27078"}],"wp:attachment":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media?parent=3475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/categories?post=3475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/tags?post=3475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}