{"id":7087,"date":"2019-05-02T12:09:56","date_gmt":"2019-05-02T15:09:56","guid":{"rendered":"https:\/\/beduka.com\/blog\/?p=7087"},"modified":"2019-09-16T13:17:45","modified_gmt":"2019-09-16T16:17:45","slug":"o-que-e-hidrostatica","status":"publish","type":"post","link":"https:\/\/beduka.com\/blog\/materias\/fisica\/o-que-e-hidrostatica\/","title":{"rendered":"O que \u00e9 Hidrost\u00e1tica?"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong><em>A Hidrost\u00e1tica \u00e9 o ramo da F\u00edsica que estuda os fluidos (que podem ser tanto l\u00edquidos como gasosos) que est\u00e3o em repouso, isto \u00e9, que n\u00e3o est\u00e3o em movimento. A Hidrost\u00e1tica tamb\u00e9m estuda as for\u00e7as que os fluidos exercem sobre corpos neles imersos, estejam eles parcialmente ou totalmente submersos.<\/em><\/strong><\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Aprenda um pouco mais de f\u00edsica com esse artigo sobre <strong>o que \u00e9 Hidrost\u00e1tica<\/strong> que o Beduka preparou para te ajudar a se preparar para o ENEM e outros vestibulares. Voc\u00ea tamb\u00e9m pode testar os seus conhecimentos sobre diversas mat\u00e9rias no nosso <a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/simulado\/#\/\" target=\"_blank\">Simulado ENEM.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00e3o deixe de conferir nossos <a href=\"https:\/\/beduka.com\/blog\/exercicios\/fisica-exercicios\/exercicios-de-hidrostatica\/\">exerc\u00edcios sobre Hidrost\u00e1tica<\/a>!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nesse artigo vamos falar sobre:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>O que \u00e9 Hidrost\u00e1tica;<\/li><li>Principais for\u00e7as estudadas;<\/li><li>Princ\u00edpios fundamentais.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">O que \u00e9 Hidrost\u00e1tica?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hidrost\u00e1tica<\/strong> \u00e9 a parte da F\u00edsica que estuda os fluidos (l\u00edquidos e gases) em repouso, ou seja, que n\u00e3o estejam em escoamento. A Hidrost\u00e1tica tem por objetivo analisar tamb\u00e9m todas as<strong> for\u00e7as f\u00edsicas<\/strong> que envolvem esses fluidos e os corpos que neles est\u00e3o submergidos, parcial ou totalmente. Dentro da Hidrost\u00e1tica existem conceitos e princ\u00edpios que s\u00e3o essenciais para entendermos como esses fluidos em repouso se comportam.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O que \u00e9 Densidade?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A <strong>densidade <\/strong>de um objeto consiste no quanto de mat\u00e9ria est\u00e1 presente em determinado volume. Atrav\u00e9s dela que pode-se, por exemplo, dizer que a \u00e1gua \u00e9 mais densa que o gelo, e por isso ele flutua. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A f\u00f3rmula utilizada para <strong>determinar a densidade<\/strong> \u00e9:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:center\"><strong>d = m\/v<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:center\"><strong>d<\/strong> = densidade, medida quilogramas por metro c\u00fabico (Kg\/m\u00b3);<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:center\"><strong>m<\/strong> = massa, medida em quilogramas (Kg);<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:center\"><strong>v <\/strong>= volume, medido em metros c\u00fabicos (m\u00b3).<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Confira o artigo completo sobre <a href=\"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-densidade\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Densidade (abre numa nova aba)\">Densidade<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O que \u00e9 Press\u00e3o hidrost\u00e1tica?<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Lei de Stevin<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m conhecido como <strong>Lei Fundamental da Hidrost\u00e1tica<\/strong>, o Teorema de Stevin determina que \u201cA diferen\u00e7a da press\u00e3o entre dois pontos A e B de um l\u00edquido, situados em n\u00edveis diferentes, se deve \u00e0 press\u00e3o exercida pela coluna l\u00edquida compreendida entre os n\u00edveis determinados por A e B\u201d. <br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tomando como exemplo uma garrafa que est\u00e1 cheia de \u00e1gua que tenha o ponto A em sua superf\u00edcie e o ponto B em seu fundo. A press\u00e3o no ponto B ser\u00e1 maior do que no ponto A, isso acontece porque, segundo Stevin, a coluna de \u00e1gua acima do ponto B \u00e9 muito maior do que a que est\u00e1 acima do ponto A.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ou seja, quanto<strong> maior for a profundidade de um fluido, mais press\u00e3o ele exercer\u00e1<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/h1.jpg\" alt=\"lei de stevin\" class=\"wp-image-7107\" width=\"550\" height=\"275\" srcset=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/h1.jpg 600w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/h1-300x150.jpg 300w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/h1-320x160.jpg 320w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/lh5.googleusercontent.com\/28UQqbfxrOTdgNTkOAZ-0Z5G3Jt2KZcawfQw0HPIvj98kQdOv9ovyR8QUpk4IcVrDb6SdCrjz3sjAs1752rxcVLHaDlr7UUH8hmOKthWr5KYFNxBIwcyHUUoKxMhP_x2I4pknbh9\" alt=\"Princ\u00edpio fundamental da Hidrodin\u00e2mica \u2013 f\u00f3rmula\"\/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:center\"><strong>\u0394P<\/strong> \u2013 diferen\u00e7a de press\u00e3o (Pa)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:center\"><strong>d<\/strong> \u2013 densidade do fluido (kg\/m\u00b3)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:center\"><strong>\u0394h<\/strong> \u2013 diferen\u00e7a de altura entre pontos do fluido (m)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:center\"><strong>g <\/strong>\u2013 acelera\u00e7\u00e3o da gravidade (m\/s\u00b2)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Atrav\u00e9s do princ\u00edpio apresentado, pode-se concluir:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Dois pontos que se est\u00e3o \u00e0 <strong>mesma altura<\/strong> em um fluido possuir\u00e3o a mesma press\u00e3o;<\/li><li>A press\u00e3o em um fluido aumenta de acordo com sua <strong>profundidade.<\/strong><\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Princ\u00edpio de Pascal<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O <strong>Princ\u00edpio de Pascal<\/strong> afirma que: \u201cUm acr\u00e9scimo de press\u00e3o exercido em qualquer ponto de um flu\u00eddo \u00e9 transmitido para todo o flu\u00eddo\u201d. Isso significa que a press\u00e3o exercida em uma \u00e1rea de um fluido em equil\u00edbrio \u00e9 transmitida a todas as demais \u00e1reas desse fluido, bem como \u00e0s suas paredes internas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sendo assim, temos a <strong>f\u00f3rmula do Teorema de Pascal<\/strong>:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"300\" src=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/pascal.jpg\" alt=\"teorema de pascal\" class=\"wp-image-7108\" srcset=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/pascal.jpg 600w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/pascal-300x150.jpg 300w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/pascal-320x160.jpg 320w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:center\"><strong>F1\/A1 = F2\/A2<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:center\"><strong>F1<\/strong> \u00e9 a for\u00e7a exercida no ponto A (N);<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:center\"><strong>A1 <\/strong>\u00e9 a \u00e1rea em que a F1 foi aplicada (m\u00b2);<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:center\"><strong>F2<\/strong> \u00e9 a for\u00e7a exercida no ponto B (N);<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:center\"><strong>A2<\/strong> \u00e9 a \u00e1rea em que a F2 foi aplicada (m\u00b2).<br><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O que \u00e9 Empuxo?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Empuxo<\/strong> \u00e9 a for\u00e7a resultante vertical exercida por um fluido e que atua sobre um corpo. Ao entrar em uma piscina, temos a sensa\u00e7\u00e3o de que ficamos mais leves. Essa sensa\u00e7\u00e3o \u00e9 a for\u00e7a empuxo que sentimos atuando sobre n\u00f3s. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Princ\u00edpio de Arquimedes<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Arquimedes<\/strong> foi um fil\u00f3sofo, matem\u00e1tico, inventor, engenheiro e f\u00edsico que descobriu o empuxo. Ao colocar um objeto em um recipiente que estava cheio de \u00e1gua, Arquimedes observou que parte da \u00e1gua transbordava do recipiente, apontando que parte do volume havia sido deslocado. O peso do volume \u00e9 exatamente igual ao empuxo, por isso temos: <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"300\" src=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/arquimedes.jpg\" alt=\"princ\u00edpio de arquimedes\" class=\"wp-image-7109\" srcset=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/arquimedes.jpg 600w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/arquimedes-300x150.jpg 300w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/arquimedes-320x160.jpg 320w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:center\"><strong>E = d . V . g<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:center\"><strong>E<\/strong> \u00e9 o empuxo, medido em Newton (N);<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:center\"><strong>d<\/strong> \u00e9 a densidade do l\u00edquido (Kg\/m\u00b3);<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:center\"><strong>V<\/strong> \u00e9 o volume do l\u00edquido deslocado (m\u00b3);<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:center\"><strong>g<\/strong> \u00e9 a acelera\u00e7\u00e3o da gravidade (m\/s\u00b2)<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O Beduka te ajuda a passar no vestibular<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Acabamos de explicar o que \u00e9 Hidrost\u00e1tica, aproveite e confira outros assuntos que caem nos vestibulares. Saiba o que \u00e9<a href=\"https:\/\/beduka.com\/blog\/materias\/fisica\/fisica-ondulatoria\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\"> f\u00edsica ondulat\u00f3ria<\/a>, aprenda <a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/materias\/fisica\/o-que-e-magnetismo\/\" target=\"_blank\">o que \u00e9 magnetismo <\/a>e descubra <a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/materias\/fisica\/quais-as-tres-leis-de-newton\/\" target=\"_blank\">quais as tr\u00eas leis de Newton<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea estiver se preparando para o ENEM, pode ainda testar os seus conhecimentos respondendo algumas quest\u00f5es que ca\u00edram em edi\u00e7\u00f5es antigas do Exame em nosso <a href=\"https:\/\/beduka.com\/simulado\/#\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">simulado gratuito<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Beduka \u00e9 um buscador de universidades e cursos superiores reconhecidos pelo Minist\u00e9rio da Educa\u00e7\u00e3o (MEC) que surgiu em 2017. Aqui em nosso site o estudante pode conferir diversas informa\u00e7\u00f5es para encontrar a melhor faculdade para a gradua\u00e7\u00e3o que deseja fazer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Experimente agora!<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Hidrost\u00e1tica \u00e9 o ramo da F\u00edsica que estuda os fluidos (que podem ser tanto l\u00edquidos como gasosos) que est\u00e3o em repouso, isto \u00e9, que n\u00e3o est\u00e3o em movimento. A Hidrost\u00e1tica tamb\u00e9m estuda as for\u00e7as que os fluidos exercem sobre corpos neles imersos, estejam eles parcialmente ou totalmente submersos. Aprenda um pouco mais de f\u00edsica [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7106,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[494],"tags":[678,677],"class_list":["post-7087","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fisica","tag-hidrostatica","tag-o-que-e-hidrostatica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u25b7 O que \u00e9 HIDROST\u00c1TICA? - Densidade, Empuxo, Press\u00e3o e mais!<\/title>\n<meta name=\"description\" content=\"Descubra o que \u00e9 Hidrost\u00e1tica, quais as suas defini\u00e7\u00f5es, for\u00e7as estudadas e princ\u00edpios fundamentais. Se prepare com o Beduka para o ENEM e outros vestibulares.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beduka.com\/blog\/materias\/fisica\/o-que-e-hidrostatica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u25b7 O que \u00e9 HIDROST\u00c1TICA? - Densidade, Empuxo, Press\u00e3o e mais!\" \/>\n<meta property=\"og:description\" content=\"Descubra o que \u00e9 Hidrost\u00e1tica, quais as suas defini\u00e7\u00f5es, for\u00e7as estudadas e princ\u00edpios fundamentais. Se prepare com o Beduka para o ENEM e outros vestibulares.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beduka.com\/blog\/materias\/fisica\/o-que-e-hidrostatica\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-02T15:09:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-16T16:17:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/o-que-\u00e9-hidrost\u00e1tica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/fisica\\\/o-que-e-hidrostatica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/fisica\\\/o-que-e-hidrostatica\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/person\\\/325d912d2cb8dd9ede8ab291427d2b8a\"},\"headline\":\"O que \u00e9 Hidrost\u00e1tica?\",\"datePublished\":\"2019-05-02T15:09:56+00:00\",\"dateModified\":\"2019-09-16T16:17:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/fisica\\\/o-que-e-hidrostatica\\\/\"},\"wordCount\":879,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/fisica\\\/o-que-e-hidrostatica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/o-que-\u00e9-hidrost\u00e1tica.jpg\",\"keywords\":[\"hidrostatica\",\"O que \u00e9 hidrost\u00e1tica\"],\"articleSection\":[\"F\u00edsica\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/fisica\\\/o-que-e-hidrostatica\\\/\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/fisica\\\/o-que-e-hidrostatica\\\/\",\"name\":\"\u25b7 O que \u00e9 HIDROST\u00c1TICA? - Densidade, Empuxo, Press\u00e3o e mais!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/fisica\\\/o-que-e-hidrostatica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/fisica\\\/o-que-e-hidrostatica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/o-que-\u00e9-hidrost\u00e1tica.jpg\",\"datePublished\":\"2019-05-02T15:09:56+00:00\",\"dateModified\":\"2019-09-16T16:17:45+00:00\",\"description\":\"Descubra o que \u00e9 Hidrost\u00e1tica, quais as suas defini\u00e7\u00f5es, for\u00e7as estudadas e princ\u00edpios fundamentais. Se prepare com o Beduka para o ENEM e outros vestibulares.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/fisica\\\/o-que-e-hidrostatica\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/fisica\\\/o-que-e-hidrostatica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/fisica\\\/o-que-e-hidrostatica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/o-que-\u00e9-hidrost\u00e1tica.jpg\",\"contentUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/o-que-\u00e9-hidrost\u00e1tica.jpg\",\"width\":600,\"height\":300,\"caption\":\"O Que \u00e9 Hidrost\u00e1tica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/fisica\\\/o-que-e-hidrostatica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/beduka.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O que \u00e9 Hidrost\u00e1tica?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/\",\"name\":\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\",\"description\":\"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!\",\"publisher\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beduka.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#organization\",\"name\":\"Beduka\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/marca-beduka.png\",\"contentUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/marca-beduka.png\",\"width\":1077,\"height\":368,\"caption\":\"Beduka\"},\"image\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/beduka.buscadordefaculdades\\\/\",\"https:\\\/\\\/www.instagram.com\\\/beduka_oficial\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/beduka\",\"https:\\\/\\\/br.pinterest.com\\\/bedukaoficial\\\/\",\"https:\\\/\\\/www.youtube.com\\\/beduka\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/person\\\/325d912d2cb8dd9ede8ab291427d2b8a\",\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o Beduka (a)\"},\"description\":\"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/beduka.buscadordefaculdades\",\"https:\\\/\\\/www.instagram.com\\\/beduka_oficial\\\/\",\"https:\\\/\\\/br.pinterest.com\\\/bedukaoficial\\\/\"],\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u25b7 O que \u00e9 HIDROST\u00c1TICA? - Densidade, Empuxo, Press\u00e3o e mais!","description":"Descubra o que \u00e9 Hidrost\u00e1tica, quais as suas defini\u00e7\u00f5es, for\u00e7as estudadas e princ\u00edpios fundamentais. Se prepare com o Beduka para o ENEM e outros vestibulares.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beduka.com\/blog\/materias\/fisica\/o-que-e-hidrostatica\/","og_locale":"pt_BR","og_type":"article","og_title":"\u25b7 O que \u00e9 HIDROST\u00c1TICA? - Densidade, Empuxo, Press\u00e3o e mais!","og_description":"Descubra o que \u00e9 Hidrost\u00e1tica, quais as suas defini\u00e7\u00f5es, for\u00e7as estudadas e princ\u00edpios fundamentais. Se prepare com o Beduka para o ENEM e outros vestibulares.","og_url":"https:\/\/beduka.com\/blog\/materias\/fisica\/o-que-e-hidrostatica\/","og_site_name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","article_publisher":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","article_author":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades","article_published_time":"2019-05-02T15:09:56+00:00","article_modified_time":"2019-09-16T16:17:45+00:00","og_image":[{"width":600,"height":300,"url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/o-que-\u00e9-hidrost\u00e1tica.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Beduka (a)","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Beduka (a)","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beduka.com\/blog\/materias\/fisica\/o-que-e-hidrostatica\/#article","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/materias\/fisica\/o-que-e-hidrostatica\/"},"author":{"name":"Reda\u00e7\u00e3o Beduka (a)","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a"},"headline":"O que \u00e9 Hidrost\u00e1tica?","datePublished":"2019-05-02T15:09:56+00:00","dateModified":"2019-09-16T16:17:45+00:00","mainEntityOfPage":{"@id":"https:\/\/beduka.com\/blog\/materias\/fisica\/o-que-e-hidrostatica\/"},"wordCount":879,"commentCount":0,"publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"image":{"@id":"https:\/\/beduka.com\/blog\/materias\/fisica\/o-que-e-hidrostatica\/#primaryimage"},"thumbnailUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/o-que-\u00e9-hidrost\u00e1tica.jpg","keywords":["hidrostatica","O que \u00e9 hidrost\u00e1tica"],"articleSection":["F\u00edsica"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/beduka.com\/blog\/materias\/fisica\/o-que-e-hidrostatica\/","url":"https:\/\/beduka.com\/blog\/materias\/fisica\/o-que-e-hidrostatica\/","name":"\u25b7 O que \u00e9 HIDROST\u00c1TICA? - Densidade, Empuxo, Press\u00e3o e mais!","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beduka.com\/blog\/materias\/fisica\/o-que-e-hidrostatica\/#primaryimage"},"image":{"@id":"https:\/\/beduka.com\/blog\/materias\/fisica\/o-que-e-hidrostatica\/#primaryimage"},"thumbnailUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/o-que-\u00e9-hidrost\u00e1tica.jpg","datePublished":"2019-05-02T15:09:56+00:00","dateModified":"2019-09-16T16:17:45+00:00","description":"Descubra o que \u00e9 Hidrost\u00e1tica, quais as suas defini\u00e7\u00f5es, for\u00e7as estudadas e princ\u00edpios fundamentais. Se prepare com o Beduka para o ENEM e outros vestibulares.","breadcrumb":{"@id":"https:\/\/beduka.com\/blog\/materias\/fisica\/o-que-e-hidrostatica\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beduka.com\/blog\/materias\/fisica\/o-que-e-hidrostatica\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/materias\/fisica\/o-que-e-hidrostatica\/#primaryimage","url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/o-que-\u00e9-hidrost\u00e1tica.jpg","contentUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/o-que-\u00e9-hidrost\u00e1tica.jpg","width":600,"height":300,"caption":"O Que \u00e9 Hidrost\u00e1tica"},{"@type":"BreadcrumbList","@id":"https:\/\/beduka.com\/blog\/materias\/fisica\/o-que-e-hidrostatica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/beduka.com\/blog\/"},{"@type":"ListItem","position":2,"name":"O que \u00e9 Hidrost\u00e1tica?"}]},{"@type":"WebSite","@id":"https:\/\/beduka.com\/blog\/#website","url":"https:\/\/beduka.com\/blog\/","name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","description":"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!","publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beduka.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beduka.com\/blog\/#organization","name":"Beduka","url":"https:\/\/beduka.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","contentUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","width":1077,"height":368,"caption":"Beduka"},"image":{"@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/www.linkedin.com\/company\/beduka","https:\/\/br.pinterest.com\/bedukaoficial\/","https:\/\/www.youtube.com\/beduka"]},{"@type":"Person","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a","name":"Reda\u00e7\u00e3o Beduka (a)","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o Beduka (a)"},"description":"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.","sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/br.pinterest.com\/bedukaoficial\/"],"url":"https:\/\/beduka.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/7087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/comments?post=7087"}],"version-history":[{"count":6,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/7087\/revisions"}],"predecessor-version":[{"id":11496,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/7087\/revisions\/11496"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media\/7106"}],"wp:attachment":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media?parent=7087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/categories?post=7087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/tags?post=7087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}