{"id":7313,"date":"2019-05-10T17:35:08","date_gmt":"2019-05-10T20:35:08","guid":{"rendered":"https:\/\/beduka.com\/blog\/?p=7313"},"modified":"2022-10-27T11:37:17","modified_gmt":"2022-10-27T14:37:17","slug":"resumo-da-revolucao-francesa","status":"publish","type":"post","link":"https:\/\/beduka.com\/blog\/materias\/historia\/resumo-da-revolucao-francesa\/","title":{"rendered":"Resumo da Revolu\u00e7\u00e3o Francesa! Causas, principais acontecimentos e consequ\u00eancias"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong><em>Resumo da Revolu\u00e7\u00e3o Francesa: movimento revolucion\u00e1rio entre 1789 e 1799 que marcou o fim do Antigo Regime. Come\u00e7ou na Fran\u00e7a e espalhou para a Europa, acabando com o absolutismo. Inspirados pelo Iluminismo, o contexto era de crise no final do s\u00e9culo XVIII. Foi liderada por burgueses e apoiada por camponeses, opondo-se ao clero e \u00e0 nobreza.<\/em><\/strong><\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Neste artigo com o resumo da Revolu\u00e7\u00e3o Francesa, voc\u00ea encontrar\u00e1 todos os t\u00f3picos abaixo, com explica\u00e7\u00f5es e exemplos detalhados.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Se quiser, clique em um tema para ir diretamente ao conte\u00fado:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"#1\">Resumo: o que foi a Revolu\u00e7\u00e3o Francesa?<\/a><\/li><li><a href=\"#2\">Quais foram as principais causas.<\/a><\/li><li><a href=\"#3\">Resumo do Contexto hist\u00f3rico da Revolu\u00e7\u00e3o Francesa.<\/a><\/li><li><a href=\"#4\">Populariza\u00e7\u00e3o do Iluminismo.<\/a><\/li><li><a href=\"#5\">Resumo das causas da Revolu\u00e7\u00e3o Francesa.<\/a><\/li><li><a href=\"#6\">Desigualdade social.<\/a><\/li><li><a href=\"#7\">Crise econ\u00f4mica.<\/a><\/li><li><a href=\"#8\">Revolu\u00e7\u00e3o Americana.<\/a><\/li><li><a href=\"#9\">Resumo do In\u00edcio da Revolu\u00e7\u00e3o Francesa.<\/a><\/li><li><a href=\"#10\">A queda da Bastilha.<\/a><\/li><li><a href=\"#11\">Resumo das tr\u00eas grandes fases da Revolu\u00e7\u00e3o Francesa.<\/a><\/li><li><a href=\"#12\">A Assembleia Nacional Constituinte.<\/a><\/li><li><a href=\"#13\">Monarquia Constitucional.<\/a><\/li><li><a href=\"#14\">Girondinos e Jacobinos.<\/a><\/li><li><a href=\"#15\">A Conven\u00e7\u00e3o Nacional.<\/a><\/li><li><a href=\"#16\">Terror Jacobino.<\/a><\/li><li><a href=\"#17\">O Diret\u00f3rio.<\/a><\/li><li><a href=\"#18\">Como terminou a revolu\u00e7\u00e3o?<\/a><\/li><li><a href=\"#19\">Resumo das Consequ\u00eancias da Revolu\u00e7\u00e3o Francesa.<\/a><\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Treinando para as provas?<\/strong> Conhe\u00e7a <a href=\"https:\/\/beduka.com\/blog\/dicas\/enem-dicas\/simulados-para-enem-online-e-gratuito\/\" target=\"_blank\" rel=\"noreferrer noopener\">O melhor Simulado do Brasil!<\/a> Ele pode ser personalizado com as mat\u00e9rias que voc\u00ea mais precisa!<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">O movimento revolucion\u00e1rio franc\u00eas \u00e9 um tema bastante recorrente no<a href=\"https:\/\/enem.inep.gov.br\" target=\"_blank\" rel=\"noreferrer noopener\"> ENEM<\/a> e em outros <a href=\"https:\/\/beduka.com\/blog\/dicas\/vestibulares\/como-e-uma-prova-de-vestibular\/\" target=\"_blank\" rel=\"noreferrer noopener\">vestibulares<\/a>. Para te ajudar a compreender mais sobre o tema e se preparar para a prova, preparamos um Resumo da Revolu\u00e7\u00e3o Francesa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"1\">Resumo: O que foi a Revolu\u00e7\u00e3o Francesa?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A Revolu\u00e7\u00e3o Francesa foi um processo revolucion\u00e1rio que ocorreu entre 1789 e 1799 na Fran\u00e7a. Alguns autores indicam que foi a burguesia quem a liderou e, por isso, ela \u00e9 uma das <a rel=\"noreferrer noopener\" href=\"https:\/\/beduka.com\/blog\/materias\/historia\/revolucoes-burguesas\/\" target=\"_blank\">Revolu\u00e7\u00f5es Burguesas<\/a>.\u00a0\u00a0Mas isso \u00e9 controverso, uma vez que parte da nobreza, como o duque de Orleans, apoiou as modifica\u00e7\u00f5es que ela trouxe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, <strong>a caracter\u00edstica de revolu\u00e7\u00e3o burguesa da Revolu\u00e7\u00e3o Francesa \u00e9 mais pelo seu resultado final, que colocou a burguesia como classe dominante<\/strong> ap\u00f3s o longo processo em que ela aconteceu. A burguesia n\u00e3o existia como classe, ou seja, n\u00e3o tinha uma organiza\u00e7\u00e3o e um pensamento comum e s\u00f3 ganhou algo assim durante o processo revolucion\u00e1rio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Revolu\u00e7\u00e3o Francesa espalhou pelo mundo os ideais de <strong>\u201cigualdade, fraternidade e liberdade\u201d<\/strong>. Este era o seu lema, representado por uma imagem da Marianne, uma mulher erguendo a bandeira da Fran\u00e7a, personificando as ideias revolucion\u00e1rias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esse lema est\u00e1 presente at\u00e9 os dias de hoje, e <strong>inspirou acontecimentos marcantes<\/strong> da hist\u00f3ria da humanidade durante a Idade Moderna.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mas isto \u00e9 um grande paradoxo, pois os revolucion\u00e1rios n\u00e3o aplicam esses tr\u00eas valores \u00e0queles que discordam de seus m\u00e9todos. Foram aproximadamente <strong>18.000 assassinatos em 10 anos.<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Grande parte das mortes aconteceram na segunda das <strong>tr\u00eas fases da revolu\u00e7\u00e3o<\/strong>, mas a forte oposi\u00e7\u00e3o aos que discordam sempre foi uma marca desse movimento.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>H\u00e1 outras causas e caracter\u00edsticas importantes que veremos adiante<\/strong>, detalhando essas fases e seus acontecimentos! Tamb\u00e9m entenderemos melhor o contexto em que tudo isso surgiu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Aten\u00e7\u00e3o:<\/strong> o termo \u201crevolu\u00e7\u00e3o\u201d \u00e9 usado para se referir \u00e0s mudan\u00e7as dr\u00e1sticas, movimentos violentos que alteraram a base e a estrutura de uma sociedade. J\u00e1 \u201crevolta\u201d s\u00e3o mudan\u00e7as superficiais, que n\u00e3o \u00e9 este caso.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"2\">Quais foram as principais caracter\u00edsticas da Revolu\u00e7\u00e3o Francesa?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">As principais caracter\u00edsticas da Revolu\u00e7\u00e3o Francesa, que a difere das outras Revolu\u00e7\u00f5es burguesas, foram: participa\u00e7\u00e3o de camadas populares no processo revolucion\u00e1rio, defesa dos ideais iluministas, separa\u00e7\u00e3o da Igreja e do Estado e exalta\u00e7\u00e3o da Raz\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao final do artigo, teste seu conhecimento com nossos<a href=\"https:\/\/beduka.com\/blog\/exercicios\/historia-exercicios\/exercicios-sobre-revolucao-francesa\/\" target=\"_blank\" rel=\"noreferrer noopener\"> exerc\u00edcios sobre a Revolu\u00e7\u00e3o Francesa<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"3\">Contexto Hist\u00f3rico da Fran\u00e7a pr\u00e9 &#8211; revolu\u00e7\u00e3o<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">No final do s\u00e9culo XVIII, a Fran\u00e7a vivia em um regime <a rel=\"noreferrer noopener\" href=\"https:\/\/beduka.com\/blog\/materias\/historia\/o-que-era-absolutismo\/\" target=\"_blank\">mon\u00e1rquico absolutista<\/a>, em que o rei era <strong>Lu\u00eds XVI.<\/strong> O poder de Lu\u00eds XVI era absoluto, pois reformas acontecidas desde o s\u00e9culo XIII levaram \u00e0 concentra\u00e7\u00e3o do poder na m\u00e3o do monarca. Entre elas, a ideia do <strong>direito divino dos reis<\/strong>, que defendia a origem divina do poder real.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nesse contexto, a sociedade francesa era estratificada em <strong>grupos sociais muito bem definidos.<\/strong> A composi\u00e7\u00e3o social da Fran\u00e7a era a seguinte:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Primeiro Estado:<\/strong> clero;<\/li><li><strong>Segundo Estado:<\/strong> nobreza;<\/li><li><strong>Terceiro Estado:<\/strong> restante da popula\u00e7\u00e3o (burgueses, camponeses, artes\u00e3os e escravos).<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00e3o mais de 200 resumos gratuitos no <a href=\"https:\/\/www.instagram.com\/beduka_oficial\/?hl=pt\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram do Beduka<\/a>. Aproveite!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"4\">Populariza\u00e7\u00e3o do Iluminismo<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00f3s estamos falando de um contexto que foi <strong>antecedido pelo fim da<\/strong> <a href=\"https:\/\/beduka.com\/blog\/materias\/historia\/o-que-foi-a-idade-media\/\" target=\"_blank\" rel=\"noreferrer noopener\">Idade M\u00e9dia<\/a> e se <strong>sucedeu ao <\/strong><a href=\"https:\/\/beduka.com\/blog\/materias\/historia\/o-que-foi-o-renascimento\/\" target=\"_blank\" rel=\"noreferrer noopener\">Renascimento<\/a>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na \u00e9poca feudal, a ci\u00eancia havia come\u00e7ado a ser desenvolvida dentro dos mosteiros, trazendo grandes revela\u00e7\u00f5es \u00e0 humanidade. Essas pesquisas eram feitas com muito cuidado, pois o intuito n\u00e3o era buscar um progresso a todo custo, mas entender a cria\u00e7\u00e3o de Deus. Al\u00e9m disso, as ferramentas ainda estavam sendo desenvolvidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por\u00e9m, certos religiosos desobedeciam a Igreja e davam maus exemplos. Isso gerou uma resist\u00eancia \u00e0 religi\u00e3o como um todo. Em um ato generalizado, a sociedade tendeu a se desvincular da religi\u00e3o e valorizar somente a ci\u00eancia e a raz\u00e3o puras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, houve uma populariza\u00e7\u00e3o da racionalidade voltada para combater a religi\u00e3o, retomando (renascendo) os valores pag\u00e3os da Gr\u00e9cia e Roma Antiga.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nesse contexto, surge ainda o <a href=\"https:\/\/beduka.com\/blog\/materias\/historia\/o-que-foi-iluminismo\/\" target=\"_blank\" rel=\"noreferrer noopener\">Iluminismo<\/a>, uma ideologia que retirava os aspectos m\u00edsticos do renascimento e defendia <strong>somente a autoridade da raz\u00e3o<\/strong>. Ela era vista como <strong>a maior de todas as formas de se obter conhecimento, inspirados pelo m\u00e9todo cient\u00edfico.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Exaltava-se a liberdade (a todo custo), o constitucionalismo (todos os princ\u00edpios devem estar na lei para valer) e a defesa da separa\u00e7\u00e3o da Igreja e do Estado (proibi\u00e7\u00e3o de mencionar assuntos de credo na esfera p\u00fablica).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"5\">Resumo das causas da Revolu\u00e7\u00e3o Francesa<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Veja os motivos que levaram \u00e0 revolu\u00e7\u00e3o. Eles envolvem principalmente a desigualdade, a pobreza, a crise econ\u00f4mica que gerou fome e mortes e a influ\u00eancia da Revolu\u00e7\u00e3o Americana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As <strong>principais causas<\/strong> (com explica\u00e7\u00e3o) da Revolu\u00e7\u00e3o Francesa foram:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"6\">Desigualdade Social<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A <strong>divis\u00e3o social<\/strong>,<strong> <\/strong>naquela \u00e9poca, trouxe uma desigualdade social muito aparente por causa do modo como o rei conduzia as coisas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ele desvalorizava o Terceiro estamento, enquanto aos Primeiro e Segundo foram dados privil\u00e9gios. Estes dois estavam <strong>isentos de pagar impostos<\/strong>, diferentemente do restante da popula\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Terceiro Estado era constitu\u00eddo por diferentes grupos, como a burguesia e os camponeses. Os camponeses ficavam cada vez mais pobres \u00e0 medida que a <strong>aristocracia (nobreza) francesa<\/strong> vivia com muito luxo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A nobreza n\u00e3o gerava riqueza econ\u00f4mica significativa, apenas consumiam os recursos. Para a burguesia, os privil\u00e9gios da aristocracia do pa\u00eds eram um obst\u00e1culo para a evolu\u00e7\u00e3o de seus neg\u00f3cios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A burguesia acabara de ganhar destaque, pois estamos em um contexto com menos princ\u00edpios para limitar o com\u00e9rcio. Por exemplo, n\u00e3o h\u00e1 mais uma moral religiosa que fale sobre os excessos de lucro ou sobre o tipo de mercadoria que seja \u00e9tico vender.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, no in\u00edcio os burgueses eram apoiados pelo rei, pois eram vistos como um aliado para enriquecimento. Por\u00e9m, logo a burguesia viu que <strong>o rei iria controlar tudo<\/strong>, ent\u00e3o se revoltou contra ele tamb\u00e9m.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"7\">Crise Econ\u00f4mica<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A <strong>desigualdade social <\/strong>se intensificou ainda mais com a crise que existia na Fran\u00e7a. A crise econ\u00f4mica francesa era resultado dos <strong>elevados gastos do pa\u00eds<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esses gastos foram agravados pelo <strong>envolvimento da Fran\u00e7a em conflitos no exterior<\/strong>. A exist\u00eancia de <strong>privil\u00e9gios para os Primeiro e Segundo Estados<\/strong> no pa\u00eds tamb\u00e9m contribu\u00eda para a crise.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A <strong>crise econ\u00f4mica <\/strong>na Fran\u00e7a fez com que o custo de vida aumentasse, a demanda de empregos fosse reduzida, e os impostos cobrados pela nobreza aumentassem.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essa crise j\u00e1 era o suficiente para levar os <strong>camponeses \u00e0 fome<\/strong>. Al\u00e9m disso, entre 1788 e 1789, a Fran\u00e7a passou por um <strong>inverno rigoroso<\/strong>, que prejudicou as colheitas e fez com que a alimenta\u00e7\u00e3o tivesse um custo ainda maior para todos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In\u00fameras tentativas de <strong>reformula\u00e7\u00e3o<\/strong> tinham sido sugeridas, mas n\u00e3o avan\u00e7aram porque o Primeiro e Segundo Estados haviam se mostrado resistentes \u00e0s chances de reformas que pudessem acabar com alguns de seus privil\u00e9gios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim sendo, em 1789, a Fran\u00e7a se encontrava uma condu\u00e7\u00e3o cr\u00edtica. A crise econ\u00f4mica era grave e a pobreza e a fome levaram a popula\u00e7\u00e3o a um estado de quase <strong>rebeli\u00e3o<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"8\">Revolu\u00e7\u00e3o Americana<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Por fim, temos tamb\u00e9m um contexto em que havia acontecido <strong>a primeira grande revolu\u00e7\u00e3o pol\u00edtica<\/strong> da Idade Moderna. No dia 4 de julho de 1776, a Revolu\u00e7\u00e3o Americana ou <strong>Independ\u00eancia dos Estados Unidos <\/strong>foi declarada.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nesse processo, vemos uma ex-col\u00f4nia que <strong>ganhou autonomia e relev\u00e2ncia diante de todo o mundo<\/strong>, aderindo aos valores burgueses e <strong>rompendo com o regime mon\u00e1rquico.<\/strong> N\u00e3o por coincid\u00eancia, ele tamb\u00e9m foi inspirada pelos <strong>valores Iluministas.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 pela soma desses fatores que a <a href=\"https:\/\/beduka.com\/blog\/materias\/historia\/diferenca-entre-monarquia-e-republica\/\" target=\"_blank\" rel=\"noreferrer noopener\">Rep\u00fablica<\/a> ganhou destaque e se tornou um ideal de perfei\u00e7\u00e3o para muitas na\u00e7\u00f5es.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"9\">Resumo do in\u00edcio da Revolu\u00e7\u00e3o Francesa<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A solu\u00e7\u00e3o encontrada pela nobreza francesa, diante de todo esse caos, foi convocar os <strong>Estados<\/strong> <strong>Gerais<\/strong>. Essa era uma reuni\u00e3o criada na Fran\u00e7a feudal para situa\u00e7\u00f5es de emerg\u00eancia, em que todos os setores se uniam para discutir o problema e achar solu\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta<strong> pareceu a melhor estrat\u00e9gia para a aristocracia<\/strong> manter seus privil\u00e9gios e tentar combater a crise ao mesmo tempo. Isso porque era comum nos tempos antigos o Primeiro e Segundo Estados se unirem e ter mais for\u00e7a de voto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>No entanto,<\/strong> <strong>o Terceiro Estado prop\u00f4s uma altera\u00e7\u00e3o <\/strong>no funcionamento dos Estados Gerais. A proposta era de que <strong>o voto n\u00e3o fosse mais por Estado<\/strong>, mas sim individual. Dessa forma, todos os membros de todos os Estados teriam direito ao voto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m esta era uma proposta que parecia a melhor chance dos burgueses, porque eles sabiam que, convencendo os camponeses e artes\u00e3os, eles somariam mais votos e venceriam.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O rei da Fran\u00e7a <strong>n\u00e3o aceitou<\/strong> a proposta. Diante desse cen\u00e1rio, <strong>o Terceiro Estado rompeu<\/strong> com os Estados Gerais <strong>e fundou a<\/strong> <strong>Assembleia<\/strong> <strong>Nacional<\/strong> <strong>Constituinte<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ela tinha o objetivo de elaborar uma <strong>Constitui\u00e7\u00e3o <\/strong>que traria mudan\u00e7as para a Fran\u00e7a, fazendo com que ela se tornasse uma <strong>monarquia constitucional<\/strong>. Quando Lu\u00eds XVI tentou fechar a Constituinte \u00e0 for\u00e7a, a popula\u00e7\u00e3o parisiense <strong>se rebelou<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os burgueses j\u00e1 tinham mais for\u00e7a econ\u00f4mica que o pr\u00f3prio Estado. Al\u00e9m disso, a burguesia havia convencido o restante da popula\u00e7\u00e3o, que estava \u00e1vida por qualquer solu\u00e7\u00e3o contra aquele que havia desvalorizado seu setor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ent\u00e3o, no dia <strong>12 de julho de 1789<\/strong>, a popula\u00e7\u00e3o francesa tomou as ruas de Paris. <strong>No dia 13<\/strong>, uma <strong>Comuna <\/strong>foi criada por oper\u00e1rios para governar Paris. Tamb\u00e9m foi formada uma <strong>Guarda<\/strong> <strong>Nacional<\/strong>, um tipo de mil\u00edcia popular.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"10\">O marco mais importante do in\u00edcio da Revolu\u00e7\u00e3o: A Queda da Bastilha<\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/resumo-da-revolucao-francesa-a-queda-da-bastilha.jpg\" alt=\"resumo da revolu\u00e7ao francesa a queda da bastilha\" class=\"wp-image-20619\" srcset=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/resumo-da-revolucao-francesa-a-queda-da-bastilha.jpg 1024w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/resumo-da-revolucao-francesa-a-queda-da-bastilha-300x150.jpg 300w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/resumo-da-revolucao-francesa-a-queda-da-bastilha-768x384.jpg 768w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/resumo-da-revolucao-francesa-a-queda-da-bastilha-320x160.jpg 320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>No dia 14 de julho<\/strong>, a popula\u00e7\u00e3o saiu para tomar armas e p\u00f3lvora do governo, atacando a <strong>Bastilha<\/strong>. Esta era uma antiga fortaleza que foi transformada em <strong>pris\u00e3o <\/strong>para os que se opunham aos reis da Fran\u00e7a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, os revoltosos invadiram e tomaram o controle da pris\u00e3o. Claramente, esse lugar <strong>simbolizava a<\/strong> <strong>opress\u00e3o absolutista<\/strong>, ent\u00e3o sua destrui\u00e7\u00e3o era vista como forma de resist\u00eancia.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Muito al\u00e9m disso, era um local de <strong>dep\u00f3sito de armas<\/strong>, ent\u00e3o tamb\u00e9m serviu de mat\u00e9ria-prima para que os revolucion\u00e1rios iniciassem a <strong>guerra civil<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Depois desse dia, a revolu\u00e7\u00e3o espalhou-se por toda a Fran\u00e7a, alcan\u00e7ando novas cidades e chegando ao campo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"11\">Etapas da Revolu\u00e7\u00e3o Francesa<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s a queda da Bastilha, a revolu\u00e7\u00e3o se espalhou por toda a Fran\u00e7a e se estendeu pelos pr\u00f3ximos dez anos. S\u00f3 chegou ao fim quando Napole\u00e3o Bonaparte assumiu o poder do pa\u00eds por meio do Golpe de 18 de Brum\u00e1rio. At\u00e9 acontecer isso, muita \u201c\u00e1gua rolou\u201d.<strong>&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O resumo da Revolu\u00e7\u00e3o Francesa pode ser <strong>dividido em per\u00edodos que correspondem \u00e0s institui\u00e7\u00f5es<\/strong> pol\u00edticas que atuaram no pa\u00eds:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Assembleia Nacional Constituinte e Assembleia Legislativa (1789-1792);<\/li><li>Conven\u00e7\u00e3o Nacional (1792-1795);<\/li><li>Diret\u00f3rio (1795-1799).<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"12\">Assembleia Nacional Constituinte e Assembleia Legislativa (1789-1792)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Esse per\u00edodo corresponde aos anos em que <strong>foi redigida uma Constitui\u00e7\u00e3o para a Fran\u00e7a<\/strong> e ao per\u00edodo da <strong>Assembleia Legislativa.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A queda da Bastilha fez com que a revolu\u00e7\u00e3o se espalhasse por toda a Fran\u00e7a, e <strong>os camponeses foram ao ataque<\/strong>, com medo de que a nobreza francesa tomasse alguma atitude e os deixasse sem alimento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conhecida como <strong>Grande Medo<\/strong>, essa investida aconteceu entre julho e agosto de 1789 e ficou marcada por <strong>saqueamentos e ataques contra propriedades da nobreza<\/strong>, seguidos<strong> <\/strong>de, em muitos casos, <strong>assassinato<\/strong> do propriet\u00e1rio do local.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O fim de alguns impostos e o maior acesso aos alimentos eram os principais motivos da luta dos camponeses. \u00c0 medida que a popula\u00e7\u00e3o se tornava radical, muitas mudan\u00e7as ocorreram na Fran\u00e7a. <strong>Todos os privil\u00e9gios feudais foram banidos.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Logo a <strong>Declara\u00e7\u00e3o dos Direitos do Homem e do Cidad\u00e3o<\/strong> foi anunciada. Este documento determinava (em teoria) que todos eram iguais perante a lei. Mas os fatos apontam que isso s\u00f3 era praticado para aqueles que concordassem com o m\u00e9todo revolucion\u00e1rio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta declara\u00e7\u00e3o pode ser considerada <strong>a mais importante de toda a Revolu\u00e7\u00e3o Francesa<\/strong> e inspirou as cartilhas internacionais que temos at\u00e9 hoje. Com base no constitucionalismo, os direitos que j\u00e1 existiam como valores, passam a ser legislativos e fiscalizados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por fim, <strong>a radicaliza\u00e7\u00e3o do povo fez com que a burguesia e a classe m\u00e9dia tomassem um posicionamento <\/strong><a href=\"https:\/\/beduka.com\/blog\/materias\/sociologia\/conservadorismo\/\" target=\"_blank\" rel=\"noreferrer noopener\">conservador<\/a>, com o objetivo de reter o \u00edmpeto da popula\u00e7\u00e3o.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"13\">A Fran\u00e7a se torna Monarquia Constitucional<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Os Primeiro e Segundo Estados come\u00e7aram a fugir da Fran\u00e7a, indo para pa\u00edses como a \u00c1ustria e Pr\u00fassia. O rei Lu\u00eds XVI tamb\u00e9m tentou fugir do pa\u00eds, mas foi reconhecido e trazido de volta ao Pal\u00e1cio de Tulherias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante esse per\u00edodo, os revolucion\u00e1rios atacaram tamb\u00e9m os privil\u00e9gios do clero atrav\u00e9s da <strong>Constitui\u00e7\u00e3o Civil do Clero<\/strong>, em 1790. O objetivo era <strong>submeter a Igreja \u00e0 autoridade do Estado<\/strong>, sendo controlada por ele.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Isso contribuiu para que o clero aderisse \u00e0 Contrarrevolu\u00e7\u00e3o, pois viu que n\u00e3o lhe restaria nenhuma autonomia. Os revolucion\u00e1rios tinham \u00f3dio \u00e0 f\u00e9 Crist\u00e3 e queriam mud\u00e1-la por dentro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em 1791 a nova Constitui\u00e7\u00e3o Francesa foi promulgada, tentando interromper a radicaliza\u00e7\u00e3o. A Fran\u00e7a foi transformada em uma Monarquia Constitucional, <strong>contrariando o desejo de muitos<\/strong> em fazer do pa\u00eds uma Rep\u00fablica democr\u00e1tica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em resposta a isso, <strong>a Assembleia Nacional Constituinte se transformou em Assembleia Legislativa.<\/strong><\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"14\">Girondinos e jacobinos<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Os dois grandes grupos pol\u00edticos que marcaram a Revolu\u00e7\u00e3o Francesa se consolidaram: <strong>Girondinos <\/strong>(sentavam \u00e0 <strong>direita <\/strong>no sagu\u00e3o de reuni\u00e3o) e <strong>jacobinos <\/strong>(sentavam \u00e0 <strong>esquerda<\/strong>).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Note que ambos eram revolucion\u00e1rios. Os que queriam manter a ordem e fazer apenas modifica\u00e7\u00f5es pontuais se sentavam ao centro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os Girondinos entendiam que as mudan\u00e7as deveriam ser <strong>contidas<\/strong>, j\u00e1 os Jacobinos achavam que as mudan\u00e7as deveriam ser mais<strong> radicalizadas<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, nesse per\u00edodo a Assembleia Legislativa declarou <strong>guerra com muitas outras na\u00e7\u00f5es da Europa<\/strong>. A Revolu\u00e7\u00e3o Francesa era uma amea\u00e7a a todos os pa\u00edses absolutistas e muitos deles conspiraram para invadir a Fran\u00e7a.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, a Assembleia Legislativa se antecipou e declarou guerra contra a \u00c1ustria e a Pr\u00fassia. Essa declara\u00e7\u00e3o fez com que a <strong>Revolu\u00e7\u00e3o Francesa se radicalizasse ainda mais<\/strong>, dando in\u00edcio ao per\u00edodo chamado TERROR.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O clima de guerra empurrou <strong>a sociedade francesa para o lado dos jacobinos e dos sans-culottes <\/strong>(\u201csem culotes\u201d, ou seja, os pobres que n\u00e3o tinham culote nas cal\u00e7as, como era a dos nobres).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como resultado disso, os sans-culottes organizaram-se, <strong>derrubaram a Monarquia Francesa e instauraram a Rep\u00fablica.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"15\">Conven\u00e7\u00e3o Nacional (1792-1795)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s a institui\u00e7\u00e3o da Rep\u00fablica na Fran\u00e7a, em 1792 a <strong>Assembleia Legislativa deu lugar \u00e0 Conven\u00e7\u00e3o<\/strong>. Os membros da Conven\u00e7\u00e3o foram escolhidos atrav\u00e9s do sufr\u00e1gio universal masculino (voto para todos).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enquanto os girondinos exigiam que Lu\u00eds XVI fosse exilado, os jacobinos exigiam sua execu\u00e7\u00e3o. Quando descobriram que Lu\u00eds XVI estava se associando \u00e0 Contrarrevolu\u00e7\u00e3o, <strong>o rei foi executado em janeiro de 1793.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s a execu\u00e7\u00e3o, os jacobinos <strong>radicalizaram ainda mais a revolu\u00e7\u00e3o<\/strong> para tentar implantar uma <strong>agenda reformista na Fran\u00e7a.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Liderados por <strong>Maximilien Robespierre<\/strong>, os jacobinos <strong>impuseram seus ideais <\/strong>a todos, por meio do <strong>Comit\u00ea de Salva\u00e7\u00e3o P\u00fablica<\/strong>. Fizeram com que sua organiza\u00e7\u00e3o fosse valer at\u00e9 mesmo acima da Conven\u00e7\u00e3o, a institui\u00e7\u00e3o mais importante do pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Veja s\u00f3 a que ponto os revolucion\u00e1rios chegaram: <strong>16 religiosas carmelitas foram condenadas \u00e0 guilhotina<\/strong> (m\u00e1quina de cortar cabe\u00e7as) porque se recusaram a assinar o manifesto revolucion\u00e1rio. Elas continuaram no convento rezando e foram mortas por isso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Isso aconteceu no dia 17 de julho de 1794 e h\u00e1 um filme chamado \u201cO di\u00e1logo das Carmelitas\u201d que documenta esse fato. Mas isso n\u00e3o foi s\u00f3 com elas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todos os que eram padres, camponeses, membros da corte, da nobreza e qualquer um que discordasse da causa (at\u00e9 mesmo entre os revolucion\u00e1rios), era <strong>morto s\u00f3 por ter uma posi\u00e7\u00e3o diferente.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A partir da\u00ed, <strong>a morte por guilhotina se generalizou <\/strong>e come\u00e7ou a pior das fases da Revolu\u00e7\u00e3o Francesa:<strong> O terror jacobino.<\/strong><\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"16\">O Terror Jacobino<\/h4>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/resumo-da-revoluacao-francesa-e-do-terror-jacobino-com-as-mortes-por-guilhotina.jpg\" alt=\"resumo da revolua\u00e7ao francesa e do terror jacobino com as mortes por guilhotina\" class=\"wp-image-20622\" srcset=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/resumo-da-revoluacao-francesa-e-do-terror-jacobino-com-as-mortes-por-guilhotina.jpg 1024w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/resumo-da-revoluacao-francesa-e-do-terror-jacobino-com-as-mortes-por-guilhotina-300x150.jpg 300w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/resumo-da-revoluacao-francesa-e-do-terror-jacobino-com-as-mortes-por-guilhotina-768x384.jpg 768w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/resumo-da-revoluacao-francesa-e-do-terror-jacobino-com-as-mortes-por-guilhotina-320x160.jpg 320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">A Rep\u00fablica governada pelos jacobinos conseguiu estabilizar a situa\u00e7\u00e3o do pa\u00eds e controlar a guerra e a popula\u00e7\u00e3o. No entanto, isso foi feito a custo de mortes dos que discordavam. Al\u00e9m disso, a guerra se agravou depois da execu\u00e7\u00e3o de Lu\u00eds XVI.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ent\u00e3o a <strong>Lei dos Suspeitos <\/strong>foi imposta pelos jacobinos, dando <strong>permiss\u00e3o para perseguir todos os que fossem considerados inimigos da revolu\u00e7\u00e3o<\/strong>. Os suspeitos eram julgados, condenados e guilhotinados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">At\u00e9 ent\u00e3o, j\u00e1 havia mortes para a implanta\u00e7\u00e3o da rep\u00fablica jacobina. Mas agora eram <strong>cada vez mais mortes<\/strong> para que ela permanecesse vigorando conforme suas leis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A postura dos jacobinos gerou um desconforto por parte dos grupos mais conservadores, que decidiram reagir com o <strong>apoio da alta burguesia<\/strong> francesa. Eles articularam um golpe chamado <strong>Rea\u00e7\u00e3o Termidoriana<\/strong>, que aconteceu em 1794.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A partir dessa data, os <strong>girondinos tomaram uma s\u00e9rie de medidas que reverteram as decis\u00f5es jacobinas<\/strong>. Em 1795, a <strong>Conven\u00e7\u00e3o foi substitu\u00edda pelo Diret\u00f3rio<\/strong>. Com a Rea\u00e7\u00e3o Termidoriana v\u00e1rios jacobinos, incluindo Robespierre, foram tamb\u00e9m guilhotinados.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"17\">Diret\u00f3rio (1795-1799)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Com a derrota dos jacobinos, a alta burguesia e os girondinos redigiram uma <strong>Nova Constitui\u00e7\u00e3o para o pa\u00eds<\/strong>, restaurando algumas medidas. Foi um <strong>per\u00edodo autorit\u00e1rio<\/strong> em que o ex\u00e9rcito foi utilizado para reprimir o povo v\u00e1rias vezes.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A alta burguesia defendeu o autoritarismo devido \u00e0 instabilidade que o pa\u00eds vivia, pois a popula\u00e7\u00e3o estava insatisfeita, a economia estava em colapso e as amea\u00e7as de guerra eram iminentes.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ent\u00e3o, a implanta\u00e7\u00e3o de uma ditadura autorit\u00e1ria come\u00e7ou a ser defendida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m do mais, houve tentativas de golpe por parte de jacobinos para retomar o poder e at\u00e9 de monarquistas para voltar tudo ao in\u00edcio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"18\">Como terminou a Revolu\u00e7\u00e3o Francesa?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Em meio ao contexto do Diret\u00f3rio, surge o <strong>apoio da popula\u00e7\u00e3o a Napole\u00e3o Bonaparte<\/strong>, general que liderava os ex\u00e9rcitos franceses.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ele era visto como uma figura que agradava um pouco a cada grupo, porque <strong>combinava aspectos dos girondinos<\/strong> (que eram revolucion\u00e1rios burgueses moderados) e a <strong>n\u00e3o propaga\u00e7\u00e3o do \u00f3dio \u00e0 nobreza e ao clero<\/strong>, embora n\u00e3o os favorecesse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, Napole\u00e3o organizou um golpe para tomar o poder da Fran\u00e7a em 1799, em um evento conhecido como <strong>Golpe do 18 de Brum\u00e1rio<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Iniciou-se, ent\u00e3o, o <strong>Per\u00edodo Napole\u00f4nico<\/strong>, que ocorreu de 1799 a 1815. Esse governo foi dividido em tr\u00eas fases (Consulado (1799-1804), Imp\u00e9rio Napole\u00f4nico (1804-1815) e Governo dos Cem Dias (20\/03\/1815 a 08\/07\/1815).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em cada momento Napole\u00e3o tendia a uma forma de governo, aparentando uma figura controversa. Por\u00e9m, conseguiu manter certa estabilidade social, como n\u00e3o se via desde antes da revolu\u00e7\u00e3o, e isso foi o suficiente para se manter no poder.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No fim das contas, ele <strong>s\u00f3 foi tirado do governo com a derrota na Batalha de Waterloo. <\/strong>Isso porque ele havia expandido sua influ\u00eancia militar, pol\u00edtica e autorit\u00e1ria por toda a Europa, ditando como os pa\u00edses deveriam reger sua economia e criando guerras.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"19\">Resumo das Consequ\u00eancias da Revolu\u00e7\u00e3o Francesa<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">As principais consequ\u00eancias da Revolu\u00e7\u00e3o Francesa foram:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Aproximadamente 18.000 pessoas assassinadas na guilhotina (cerca de 4 por dia);<\/li><li>Desestabilizou a Fran\u00e7a de forma que nunca mais prosperou como antes da Revolu\u00e7\u00e3o;<\/li><li>Imp\u00e9rio do Estado sobre a liberdade religiosa e persegui\u00e7\u00e3o dos crist\u00e3os;<\/li><li>Desuni\u00e3o do povo franc\u00eas;<\/li><li>Fim do feudalismo e in\u00edcio da consolida\u00e7\u00e3o do capitalismo;<\/li><li>Queda do absolutismo em toda a Europa;<\/li><li>Inspirou os movimentos de independ\u00eancia na Am\u00e9rica, sobretudo das na\u00e7\u00f5es colonizadas pela Espanha;<\/li><li>Popularizou a rep\u00fablica como forma de governo;<\/li><li>Popularizou a ideia de separa\u00e7\u00e3o dos poderes;<\/li><li>Garantiu a aplica\u00e7\u00e3o dos ideais liberais de liberdade individual do lema \u201ctodos os homens s\u00e3o iguais perante a lei\u201d;<\/li><li>Consolidou o nacionalismo enquanto ideologia de reconhecimento do dever patri\u00f3tico;<\/li><li>Influenciou futuras ideologias a adotar o m\u00e9todo revolucion\u00e1rio e o apelo aos pobres para conquistar seus objetivos pol\u00edticos;<\/li><li>Foi a primeira tentativa de uma Declara\u00e7\u00e3o Universal de Direitos Humanos.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Se gostou do nosso artigo<\/strong> com o resumo da Revolu\u00e7\u00e3o Francesa, confira outros artigos do nosso blog e se prepare para o Enem da melhor maneira! Voc\u00ea tamb\u00e9m pode se organizar com o nosso<a href=\"https:\/\/beduka.com\/blog\/dicas\/enem-dicas\/plano-de-estudos-gratuito\/\" target=\"_blank\" rel=\"noreferrer noopener\"> plano de estudos<\/a>, o mais completo da internet, e o melhor: totalmente gratuito!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Queremos te ajudar a encontrar a FACULDADE IDEAL!<\/strong> Logo abaixo, fa\u00e7a uma pesquisa por curso e cidade que te mostraremos todas as faculdades que podem te atender. Informamos a nota de corte, valor de mensalidade, nota do MEC, avalia\u00e7\u00e3o dos alunos, modalidades de ensino e muito mais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Experimente agora!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resumo da Revolu\u00e7\u00e3o Francesa: movimento revolucion\u00e1rio entre 1789 e 1799 que marcou o fim do Antigo Regime. Come\u00e7ou na Fran\u00e7a e espalhou para a Europa, acabando com o absolutismo. Inspirados pelo Iluminismo, o contexto era de crise no final do s\u00e9culo XVIII. Foi liderada por burgueses e apoiada por camponeses, opondo-se ao clero e \u00e0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":20621,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[491],"tags":[641,708],"class_list":["post-7313","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historia","tag-resumo","tag-revolucao-francesa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Resumo da Revolu\u00e7\u00e3o Francesa: Causas, Etapas e Consequ\u00eancias!<\/title>\n<meta name=\"description\" content=\"A Revolu\u00e7\u00e3o Francesa foi uma revolta burguesa que marcou o mundo. Veja o Resumo da Revolu\u00e7\u00e3o Francesa com Contexto Hist\u00f3rico, Etapas e Consequ\u00eancias!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beduka.com\/blog\/materias\/historia\/resumo-da-revolucao-francesa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resumo da Revolu\u00e7\u00e3o Francesa: Causas, Etapas e Consequ\u00eancias!\" \/>\n<meta property=\"og:description\" content=\"A Revolu\u00e7\u00e3o Francesa foi uma revolta burguesa que marcou o mundo. Veja o Resumo da Revolu\u00e7\u00e3o Francesa com Contexto Hist\u00f3rico, Etapas e Consequ\u00eancias!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beduka.com\/blog\/materias\/historia\/resumo-da-revolucao-francesa\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-10T20:35:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-27T14:37:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/Procurando-um-Resumo-da-Revolucao-Francesa-Vem-ver-esse-artigo-completo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"609\" \/>\n\t<meta property=\"og:image:height\" content=\"342\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"19 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/historia\\\/resumo-da-revolucao-francesa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/historia\\\/resumo-da-revolucao-francesa\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/person\\\/325d912d2cb8dd9ede8ab291427d2b8a\"},\"headline\":\"Resumo da Revolu\u00e7\u00e3o Francesa! Causas, principais acontecimentos e consequ\u00eancias\",\"datePublished\":\"2019-05-10T20:35:08+00:00\",\"dateModified\":\"2022-10-27T14:37:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/historia\\\/resumo-da-revolucao-francesa\\\/\"},\"wordCount\":3835,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/historia\\\/resumo-da-revolucao-francesa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Procurando-um-Resumo-da-Revolucao-Francesa-Vem-ver-esse-artigo-completo.jpg\",\"keywords\":[\"resumo\",\"revolu\u00e7\u00e3o francesa\"],\"articleSection\":[\"Hist\u00f3ria\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/historia\\\/resumo-da-revolucao-francesa\\\/\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/historia\\\/resumo-da-revolucao-francesa\\\/\",\"name\":\"Resumo da Revolu\u00e7\u00e3o Francesa: Causas, Etapas e Consequ\u00eancias!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/historia\\\/resumo-da-revolucao-francesa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/historia\\\/resumo-da-revolucao-francesa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Procurando-um-Resumo-da-Revolucao-Francesa-Vem-ver-esse-artigo-completo.jpg\",\"datePublished\":\"2019-05-10T20:35:08+00:00\",\"dateModified\":\"2022-10-27T14:37:17+00:00\",\"description\":\"A Revolu\u00e7\u00e3o Francesa foi uma revolta burguesa que marcou o mundo. Veja o Resumo da Revolu\u00e7\u00e3o Francesa com Contexto Hist\u00f3rico, Etapas e Consequ\u00eancias!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/historia\\\/resumo-da-revolucao-francesa\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/historia\\\/resumo-da-revolucao-francesa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/historia\\\/resumo-da-revolucao-francesa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Procurando-um-Resumo-da-Revolucao-Francesa-Vem-ver-esse-artigo-completo.jpg\",\"contentUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Procurando-um-Resumo-da-Revolucao-Francesa-Vem-ver-esse-artigo-completo.jpg\",\"width\":609,\"height\":342,\"caption\":\"Procurando um Resumo da Revolu\u00e7\u00e3o Francesa ?Vem ver esse artigo completo!\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/materias\\\/historia\\\/resumo-da-revolucao-francesa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/beduka.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resumo da Revolu\u00e7\u00e3o Francesa! Causas, principais acontecimentos e consequ\u00eancias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/\",\"name\":\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\",\"description\":\"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!\",\"publisher\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beduka.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#organization\",\"name\":\"Beduka\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/marca-beduka.png\",\"contentUrl\":\"https:\\\/\\\/beduka.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/marca-beduka.png\",\"width\":1077,\"height\":368,\"caption\":\"Beduka\"},\"image\":{\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/beduka.buscadordefaculdades\\\/\",\"https:\\\/\\\/www.instagram.com\\\/beduka_oficial\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/beduka\",\"https:\\\/\\\/br.pinterest.com\\\/bedukaoficial\\\/\",\"https:\\\/\\\/www.youtube.com\\\/beduka\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/beduka.com\\\/blog\\\/#\\\/schema\\\/person\\\/325d912d2cb8dd9ede8ab291427d2b8a\",\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o Beduka (a)\"},\"description\":\"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/beduka.buscadordefaculdades\",\"https:\\\/\\\/www.instagram.com\\\/beduka_oficial\\\/\",\"https:\\\/\\\/br.pinterest.com\\\/bedukaoficial\\\/\"],\"url\":\"https:\\\/\\\/beduka.com\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Resumo da Revolu\u00e7\u00e3o Francesa: Causas, Etapas e Consequ\u00eancias!","description":"A Revolu\u00e7\u00e3o Francesa foi uma revolta burguesa que marcou o mundo. Veja o Resumo da Revolu\u00e7\u00e3o Francesa com Contexto Hist\u00f3rico, Etapas e Consequ\u00eancias!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beduka.com\/blog\/materias\/historia\/resumo-da-revolucao-francesa\/","og_locale":"pt_BR","og_type":"article","og_title":"Resumo da Revolu\u00e7\u00e3o Francesa: Causas, Etapas e Consequ\u00eancias!","og_description":"A Revolu\u00e7\u00e3o Francesa foi uma revolta burguesa que marcou o mundo. Veja o Resumo da Revolu\u00e7\u00e3o Francesa com Contexto Hist\u00f3rico, Etapas e Consequ\u00eancias!","og_url":"https:\/\/beduka.com\/blog\/materias\/historia\/resumo-da-revolucao-francesa\/","og_site_name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","article_publisher":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","article_author":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades","article_published_time":"2019-05-10T20:35:08+00:00","article_modified_time":"2022-10-27T14:37:17+00:00","og_image":[{"width":609,"height":342,"url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/Procurando-um-Resumo-da-Revolucao-Francesa-Vem-ver-esse-artigo-completo.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Beduka (a)","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Beduka (a)","Est. tempo de leitura":"19 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beduka.com\/blog\/materias\/historia\/resumo-da-revolucao-francesa\/#article","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/materias\/historia\/resumo-da-revolucao-francesa\/"},"author":{"name":"Reda\u00e7\u00e3o Beduka (a)","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a"},"headline":"Resumo da Revolu\u00e7\u00e3o Francesa! Causas, principais acontecimentos e consequ\u00eancias","datePublished":"2019-05-10T20:35:08+00:00","dateModified":"2022-10-27T14:37:17+00:00","mainEntityOfPage":{"@id":"https:\/\/beduka.com\/blog\/materias\/historia\/resumo-da-revolucao-francesa\/"},"wordCount":3835,"commentCount":2,"publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"image":{"@id":"https:\/\/beduka.com\/blog\/materias\/historia\/resumo-da-revolucao-francesa\/#primaryimage"},"thumbnailUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/Procurando-um-Resumo-da-Revolucao-Francesa-Vem-ver-esse-artigo-completo.jpg","keywords":["resumo","revolu\u00e7\u00e3o francesa"],"articleSection":["Hist\u00f3ria"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/beduka.com\/blog\/materias\/historia\/resumo-da-revolucao-francesa\/","url":"https:\/\/beduka.com\/blog\/materias\/historia\/resumo-da-revolucao-francesa\/","name":"Resumo da Revolu\u00e7\u00e3o Francesa: Causas, Etapas e Consequ\u00eancias!","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beduka.com\/blog\/materias\/historia\/resumo-da-revolucao-francesa\/#primaryimage"},"image":{"@id":"https:\/\/beduka.com\/blog\/materias\/historia\/resumo-da-revolucao-francesa\/#primaryimage"},"thumbnailUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/Procurando-um-Resumo-da-Revolucao-Francesa-Vem-ver-esse-artigo-completo.jpg","datePublished":"2019-05-10T20:35:08+00:00","dateModified":"2022-10-27T14:37:17+00:00","description":"A Revolu\u00e7\u00e3o Francesa foi uma revolta burguesa que marcou o mundo. Veja o Resumo da Revolu\u00e7\u00e3o Francesa com Contexto Hist\u00f3rico, Etapas e Consequ\u00eancias!","breadcrumb":{"@id":"https:\/\/beduka.com\/blog\/materias\/historia\/resumo-da-revolucao-francesa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beduka.com\/blog\/materias\/historia\/resumo-da-revolucao-francesa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/materias\/historia\/resumo-da-revolucao-francesa\/#primaryimage","url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/Procurando-um-Resumo-da-Revolucao-Francesa-Vem-ver-esse-artigo-completo.jpg","contentUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/05\/Procurando-um-Resumo-da-Revolucao-Francesa-Vem-ver-esse-artigo-completo.jpg","width":609,"height":342,"caption":"Procurando um Resumo da Revolu\u00e7\u00e3o Francesa ?Vem ver esse artigo completo!"},{"@type":"BreadcrumbList","@id":"https:\/\/beduka.com\/blog\/materias\/historia\/resumo-da-revolucao-francesa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/beduka.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Resumo da Revolu\u00e7\u00e3o Francesa! Causas, principais acontecimentos e consequ\u00eancias"}]},{"@type":"WebSite","@id":"https:\/\/beduka.com\/blog\/#website","url":"https:\/\/beduka.com\/blog\/","name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","description":"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!","publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beduka.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beduka.com\/blog\/#organization","name":"Beduka","url":"https:\/\/beduka.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","contentUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","width":1077,"height":368,"caption":"Beduka"},"image":{"@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/www.linkedin.com\/company\/beduka","https:\/\/br.pinterest.com\/bedukaoficial\/","https:\/\/www.youtube.com\/beduka"]},{"@type":"Person","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a","name":"Reda\u00e7\u00e3o Beduka (a)","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a85c0aa7c22e79b1781a1231135ed5ec0433cd68bfee5d95d429cac9f7816a6d?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o Beduka (a)"},"description":"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.","sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/br.pinterest.com\/bedukaoficial\/"],"url":"https:\/\/beduka.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/7313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/comments?post=7313"}],"version-history":[{"count":12,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/7313\/revisions"}],"predecessor-version":[{"id":27356,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/7313\/revisions\/27356"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media\/20621"}],"wp:attachment":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media?parent=7313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/categories?post=7313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/tags?post=7313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}