{"id":7938,"date":"2019-06-05T17:52:28","date_gmt":"2019-06-05T20:52:28","guid":{"rendered":"https:\/\/beduka.com\/blog\/?p=7938"},"modified":"2019-09-05T17:11:00","modified_gmt":"2019-09-05T20:11:00","slug":"o-que-e-sintaxe","status":"publish","type":"post","link":"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-sintaxe\/","title":{"rendered":"Aprenda tudo sobre o que \u00e9 sintaxe"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote\"><p><strong><em>Sintaxe \u00e9 a parte da gram\u00e1tica que estuda a estrutura, fun\u00e7\u00e3o e disposi\u00e7\u00e3o das palavras nas frases, ora\u00e7\u00f5es e per\u00edodos, e tamb\u00e9m todas as rela\u00e7\u00f5es que elas criam entre si para construir o significado da senten\u00e7a. <\/em><\/strong><br><\/p><\/blockquote>\n\n\n\n<p>O Beduka preparou esse artigo para tirar suas d\u00favidas sobre o que \u00e9 sintaxe e te ajudar a se preparar para o ENEM e outros vestibulares.<br><\/p>\n\n\n\n<p>N\u00e3o deixe de conferir nossos <a rel=\"noreferrer noopener\" aria-label=\"exerc\u00edcios sobre Sintaxe (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/exercicios\/portugues-exercicios\/exercicios-de-sintaxe\/\" target=\"_blank\">exerc\u00edcios sobre Sintaxe<\/a>!<\/p>\n\n\n\n<p>Nesse artigo vamos falar sobre:<\/p>\n\n\n\n<ul><li>O que \u00e9 Sintaxe;<\/li><li>Frase, Ora\u00e7\u00e3o e Per\u00edodo;<\/li><li>Rela\u00e7\u00f5es e Fun\u00e7\u00f5es Sint\u00e1ticas.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">O que \u00e9 Sintaxe?<\/h2>\n\n\n\n<p>A <strong>Sintaxe <\/strong>\u00e9 a parte da gram\u00e1tica respons\u00e1vel por estudar a <strong>disposi\u00e7\u00e3o das palavras<\/strong> dentro de <strong>frases <\/strong>e <strong>ora\u00e7\u00f5es<\/strong>, bem como as <strong>rela\u00e7\u00f5es que elas criam entre si <\/strong>para compor o significado. Ela tamb\u00e9m \u00e9 a respons\u00e1vel pelo estudo da <strong>rela\u00e7\u00e3o das ora\u00e7\u00f5es dentro do per\u00edodo. <\/strong><br><\/p>\n\n\n\n<p>A Sintaxe \u00e9 utilizada para formar uma <strong>senten\u00e7a compreens\u00edvel<\/strong>, dessa forma, quando h\u00e1 <strong>altera\u00e7\u00e3o nas rela\u00e7\u00f5es<\/strong> que as palavras estabelecem entre si, o <strong>sentido <\/strong>de toda a senten\u00e7a tamb\u00e9m <strong>muda<\/strong>, ainda que sejam as mesmas palavras. <br><\/p>\n\n\n\n<p>Mesmo n\u00e3o havendo somente uma maneira de <strong>organiza\u00e7\u00e3o das senten\u00e7as<\/strong> lingu\u00edsticas, o fato de as l\u00ednguas terem sua sintaxe pr\u00f3pria impede a realiza\u00e7\u00e3o de <strong>combina\u00e7\u00f5es aleat\u00f3rias <\/strong>das palavras. <br><\/p>\n\n\n\n<p>Para entender o que \u00e9 sintaxe, precisamos aprender alguns conceitos principais que dizem respeito a essa mat\u00e9ria, tais como:<br><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Frase<\/h2>\n\n\n\n<p>A <strong>frase <\/strong>tem como objetivo transmitir uma mensagem objetiva, podendo ser constitu\u00edda por apenas uma palavra ou pode ter maior complexidade. Pode-se observar o in\u00edcio e o fim de uma frase ao verificar o come\u00e7o com letra mai\u00fascula e o final marcado por um ponto. <br><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Tipos de Frase<\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>1. Frases declarativas<\/strong><\/h4>\n\n\n\n<p>Frases que <strong>declaram ou informam<\/strong> algo. Podem ser tanto no sentido positivo quanto no negativo.<br><\/p>\n\n\n\n<p><strong>Exemplos<\/strong>: <\/p>\n\n\n\n<ul><li>Frase declarativa afirmativa: \u201cIsto vai cair\u201d; <\/li><li>Frase declarativa negativa: \u201cIsto n\u00e3o vai cair\u201d.<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>2. Frases interrogativas <\/strong><\/h4>\n\n\n\n<p>Frases atrav\u00e9s das quais se procura ter uma <strong>informa\u00e7\u00e3o<\/strong> ou realiza-se um <strong>questionamento<\/strong>. Podem ser diretas ou indiretas.<br><\/p>\n\n\n\n<p><strong>Exemplos<\/strong>: <\/p>\n\n\n\n<ul><li>Frase interrogativa direta: \u201cEle vai sair?\u201d; <\/li><li>Frase interrogativa indireta: \u201cQueria saber se ele vai sair\u201d.<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>3. Frases imperativas<\/strong><\/h4>\n\n\n\n<p>Normalmente empregadas em <strong>pedidos, ordens e conselhos<\/strong>. S\u00e3o frases que t\u00eam o objetivo de <strong>influenciar as a\u00e7\u00f5es do receptor<\/strong> da mensagem. Tamb\u00e9m podem ser afirmativas e negativas.<br><\/p>\n\n\n\n<p><strong>Exemplos<\/strong>: <\/p>\n\n\n\n<ul><li>Frase imperativa afirmativa: \u201cV\u00e1 para a sala\u201d; <\/li><li>Frase imperativa negativa: \u201cN\u00e3o v\u00e1 para a sala.<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>4. Frases exclamativas<\/strong><\/h4>\n\n\n\n<p>Frases usadas para <strong>expressar uma emo\u00e7\u00e3o<\/strong> ou estado emotivo.<br><strong>Exemplo<\/strong>: \u201cIsto vai cair em mim!\u201d.<br><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>5. Frases optativas<\/strong><\/h4>\n\n\n\n<p>Frases usadas para desejar algo.<br><strong>Exemplo<\/strong>: \u201cQue Deus te aben\u00e7oe!\u201d.<br><\/p>\n\n\n\n<p>Aprenda tamb\u00e9m o <a href=\"https:\/\/beduka.com\/blog\/materias\/portugues\/quais-sao-as-classes-gramaticais\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">quais s\u00e3o as classes gramaticais<\/a>.<br><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ora\u00e7\u00e3o<\/h2>\n\n\n\n<p>A <strong>ora\u00e7\u00e3o <\/strong>\u00e9 uma senten\u00e7a lingu\u00edstica cuja estrutura se caracteriza, obrigatoriamente, pela <strong>presen\u00e7a de um verbo<\/strong> e por ter seu <strong>sentido completo<\/strong>. A ora\u00e7\u00e3o se caracteriza pela presen\u00e7a de um<strong> predicado<\/strong>, o qual \u00e9 introduzido pela presen\u00e7a de um verbo. Normalmente, a ora\u00e7\u00e3o apresenta um sujeito, verbo, termos essenciais, integrantes ou acess\u00f3rios.<br><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Termos Essenciais da Ora\u00e7\u00e3o<\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Sujeito<\/strong><\/h4>\n\n\n\n<p>O <strong>sujeito <\/strong>\u00e9 sobre quem diz o resto da ora\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Exemplo:<\/strong> <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" loading=\"lazy\" width=\"600\" height=\"300\" src=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/06\/sintaxe_exemplo.jpg\" alt=\"exemplo sintaxe\" class=\"wp-image-7939\" srcset=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/06\/sintaxe_exemplo.jpg 600w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/06\/sintaxe_exemplo-300x150.jpg 300w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/06\/sintaxe_exemplo-320x160.jpg 320w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n\n\n\n<p>O sujeito \u00e9 \u201cBruno\u201d, pois \u201cesqueceu a carteira em casa\u201d (restante da ora\u00e7\u00e3o) se refere a ele.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Predicado<\/strong><\/h4>\n\n\n\n<p>O <strong>predicado <\/strong>\u00e9 o restante da ora\u00e7\u00e3o, ou seja, a parte que <strong>informa algo sobre o sujeito<\/strong>.<\/p>\n\n\n\n<p>\u00c9 a parte onde o verbo est\u00e1 presente. No exemplo, o predicado \u00e9 \u201cesqueceu a carteira em casa.\u201d<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Termos Integrantes da Ora\u00e7\u00e3o<\/strong><\/h3>\n\n\n\n<ul><li><a rel=\"noreferrer noopener\" aria-label=\"Complemento Verbal (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-complemento-verbal\/\" target=\"_blank\">Complemento Verbal<\/a>;<\/li><li><a rel=\"noreferrer noopener\" aria-label=\"Complemento Nominal (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-complemento-nominal\/\" target=\"_blank\">Complemento Nominal<\/a>;<\/li><li><a rel=\"noreferrer noopener\" aria-label=\"Agente da Passiva (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-sao-verbos\/\" target=\"_blank\">Agente da Passiva<\/a>.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"mce_13\"><strong>Termos Assess\u00f3rios da Ora\u00e7\u00e3o<\/strong><\/h3>\n\n\n\n<ul><li><a rel=\"noreferrer noopener\" aria-label=\"Adjuntos Adverbiais (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-adjunto-adverbial\/\" target=\"_blank\">Adjuntos Adverbiais<\/a>;<\/li><li><a href=\"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-adjunto-adnominal\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Adjuntos Adnominais (abre numa nova aba)\">Adjuntos Adnominais<\/a>;<\/li><li>Aposto.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Tipos de Ora\u00e7\u00e3o<\/strong><\/h3>\n\n\n\n<ul><li><strong><a href=\"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-sao-oracoes-coordenadas\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Ora\u00e7\u00f5es Coordenadas (abre numa nova aba)\">Ora\u00e7\u00f5es Coordenadas<\/a>:<\/strong>&nbsp;Ora\u00e7\u00f5es que s\u00e3o sintaticamente independentes uma da outra (n\u00e3o precisam da outra para terem sentido completo);<\/li><li><strong><a rel=\"noreferrer noopener\" aria-label=\"Ora\u00e7\u00f5es Subordinadas (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-oracao-subordinada\/\" target=\"_blank\">Ora\u00e7\u00f5es Subordinadas<\/a>:<\/strong>&nbsp;S\u00e3o ora\u00e7\u00f5es que desempenham uma fun\u00e7\u00e3o sint\u00e1tica em rela\u00e7\u00e3o \u00e0 ora\u00e7\u00e3o principal, complementando o seu significado e sendo dependente dela.<\/li><\/ul>\n\n\n\n<p>Confira o artigo completo sobre <a href=\"https:\/\/beduka.com\/blog\/materias\/portugues\/oracoes-coordenadas-e-subordinadas\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Ora\u00e7\u00f5es Coordenadas e Subordinadas (abre numa nova aba)\">Ora\u00e7\u00f5es Coordenadas e Subordinadas<\/a>.<br><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Per\u00edodo<\/h2>\n\n\n\n<p>O <strong>per\u00edodo <\/strong>\u00e9 um enunciado formado por uma ou mais ora\u00e7\u00f5es e possui sentido completo. Na <strong>linguagem falada<\/strong>, o in\u00edcio e o final do per\u00edodo s\u00e3o marcados pela <strong>entona\u00e7\u00e3o,<\/strong> j\u00e1<strong> <\/strong>na escrita, s\u00e3o marcados pela<strong> letra mai\u00fascula inicial<\/strong> e a <strong>pontua\u00e7\u00e3o<\/strong> que delimita sua extens\u00e3o. Os per\u00edodos podem ser simples ou compostos.<br><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Per\u00edodo simples<\/strong><\/h3>\n\n\n\n<p>Os <strong>per\u00edodos simples<\/strong> s\u00e3o os constitu\u00eddos por <strong>uma ora\u00e7\u00e3o<\/strong>, ou seja, um enunciado com apenas um verbo e sentido completo. <\/p>\n\n\n\n<p><strong>Exemplo:<\/strong> Os dias de ver\u00e3o s\u00e3o muito longos! (verbo ser)<br><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Per\u00edodo composto<\/strong><\/h3>\n\n\n\n<p>Os <strong>per\u00edodos compostos<\/strong> s\u00e3o aqueles constitu\u00eddos por mais de uma ora\u00e7\u00e3o, ou seja, dois ou mais verbos. <\/p>\n\n\n\n<p><strong>Exemplo<\/strong>: Rafael me ligou para dizer que n\u00e3o ir\u00e1 ao restaurante mais tarde. (Per\u00edodo composto por tr\u00eas ora\u00e7\u00f5es: verbos ligar, dizer e ir).<br><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Rela\u00e7\u00f5es e fun\u00e7\u00f5es sint\u00e1ticas <\/h2>\n\n\n\n<p>Os enunciados das l\u00ednguas refletem uma <strong>organiza\u00e7\u00e3o espec\u00edfica<\/strong>, e essa associa\u00e7\u00e3o de palavras \u00e9 <strong>ordenada pela sintaxe<\/strong>, que estabelece as <strong>sequ\u00eancias poss\u00edveis no interior dessas estruturas. <\/strong><br><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Rela\u00e7\u00f5es sint\u00e1ticas<\/strong><\/h3>\n\n\n\n<p>S\u00e3o as <strong>rela\u00e7\u00f5es estabelecidas<\/strong> entre as palavras que definem as estruturas poss\u00edveis na sintaxe das l\u00ednguas. <br><\/p>\n\n\n\n<p><strong>Exemplo:<\/strong><br><\/p>\n\n\n\n<p>Rafael comprou um celular novo m\u00eas passado.<\/p>\n\n\n\n<ul><li>Rafael: agente da a\u00e7\u00e3o expressa pelo verbo &#8216;comprar&#8217;;<\/li><li>M\u00eas passado: quando a a\u00e7\u00e3o foi realizada.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Fun\u00e7\u00f5es sint\u00e1ticas<\/strong><\/h3>\n\n\n\n<p>Diz respeito \u00e0<strong> fun\u00e7\u00e3o de cada elemento<\/strong> na senten\u00e7a ao se relacionar com os demais elementos que comp\u00f5em o enunciado. Quando \u00e9 poss\u00edvel estabelecer uma rela\u00e7\u00e3o sint\u00e1tica entre os elementos de um enunciado, esses elementos <strong>exercem uma fun\u00e7\u00e3o sint\u00e1tica <\/strong>espec\u00edfica. <br><\/p>\n\n\n\n<p><strong>Exemplo:<\/strong><\/p>\n\n\n\n<p>Rafael comprou um celular novo m\u00eas passado.<\/p>\n\n\n\n<ul><li>Rafael: sujeito do verbo &#8216;comprar&#8217;.<\/li><li>Um: adjunto adnominal.<\/li><li>Um celular novo: objeto direto de comprar.<\/li><\/ul>\n\n\n\n<p>Al\u00e9m de aprender o que \u00e9 sintaxe, voc\u00ea pode testar seus conhecimentos de Portugu\u00eas e de outras mat\u00e9rias respondendo algumas quest\u00f5es que ca\u00edram em edi\u00e7\u00f5es antigas do Exame em nosso <a href=\"https:\/\/beduka.com\/simulado\/#\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">simulado gratuito.<\/a><br><\/p>\n\n\n\n<p>Gostou de aprender o que \u00e9 sintaxe? Queremos te ajudar tamb\u00e9m a encontrar a FACULDADE IDEAL! Logo abaixo, fa\u00e7a uma pesquisa por curso e cidade que te mostraremos todas as faculdades que podem te atender. Informamos a nota de corte, valor de mensalidade, nota do MEC, avalia\u00e7\u00e3o dos alunos, modalidades de ensino e muito mais.<br><\/p>\n\n\n\n<p>Experimente agora!<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sintaxe \u00e9 a parte da gram\u00e1tica que estuda a estrutura, fun\u00e7\u00e3o e disposi\u00e7\u00e3o das palavras nas frases, ora\u00e7\u00f5es e per\u00edodos, e tamb\u00e9m todas as rela\u00e7\u00f5es que elas criam entre si para construir o significado da senten\u00e7a. O Beduka preparou esse artigo para tirar suas d\u00favidas sobre o que \u00e9 sintaxe e te ajudar a se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7942,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[488],"tags":[800,801],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u25b7 O que \u00e9 SINTAXE? - Defini\u00e7\u00e3o, Principais Conceitos e Exemplos<\/title>\n<meta name=\"description\" content=\"Aprenda o que \u00e9 Sintaxe! Veja os principais conceitos da sintaxe e aprenda tudo sobre rela\u00e7\u00f5es e fun\u00e7\u00f5es sint\u00e1ticas. Se prepare com o Beduka para o ENEM e outros vestibulares.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-sintaxe\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u25b7 O que \u00e9 SINTAXE? - Defini\u00e7\u00e3o, Principais Conceitos e Exemplos\" \/>\n<meta property=\"og:description\" content=\"Aprenda o que \u00e9 Sintaxe! Veja os principais conceitos da sintaxe e aprenda tudo sobre rela\u00e7\u00f5es e fun\u00e7\u00f5es sint\u00e1ticas. Se prepare com o Beduka para o ENEM e outros vestibulares.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-sintaxe\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-05T20:52:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-05T20:11:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/06\/sintaxe_capa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-sintaxe\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-sintaxe\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a\"},\"headline\":\"Aprenda tudo sobre o que \u00e9 sintaxe\",\"datePublished\":\"2019-06-05T20:52:28+00:00\",\"dateModified\":\"2019-09-05T20:11:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-sintaxe\/\"},\"wordCount\":1106,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/beduka.com\/blog\/#organization\"},\"keywords\":[\"o que \u00e9 sintaxe\",\"sintaxe\"],\"articleSection\":[\"Portugu\u00eas\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-sintaxe\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-sintaxe\/\",\"url\":\"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-sintaxe\/\",\"name\":\"\u25b7 O que \u00e9 SINTAXE? - Defini\u00e7\u00e3o, Principais Conceitos e Exemplos\",\"isPartOf\":{\"@id\":\"https:\/\/beduka.com\/blog\/#website\"},\"datePublished\":\"2019-06-05T20:52:28+00:00\",\"dateModified\":\"2019-09-05T20:11:00+00:00\",\"description\":\"Aprenda o que \u00e9 Sintaxe! Veja os principais conceitos da sintaxe e aprenda tudo sobre rela\u00e7\u00f5es e fun\u00e7\u00f5es sint\u00e1ticas. Se prepare com o Beduka para o ENEM e outros vestibulares.\",\"breadcrumb\":{\"@id\":\"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-sintaxe\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-sintaxe\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-sintaxe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/beduka.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aprenda tudo sobre o que \u00e9 sintaxe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/beduka.com\/blog\/#website\",\"url\":\"https:\/\/beduka.com\/blog\/\",\"name\":\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\",\"description\":\"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!\",\"publisher\":{\"@id\":\"https:\/\/beduka.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/beduka.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/beduka.com\/blog\/#organization\",\"name\":\"Beduka\",\"url\":\"https:\/\/beduka.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png\",\"contentUrl\":\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png\",\"width\":1077,\"height\":368,\"caption\":\"Beduka\"},\"image\":{\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/\",\"https:\/\/www.instagram.com\/beduka_oficial\/\",\"https:\/\/www.linkedin.com\/company\/beduka\",\"https:\/\/br.pinterest.com\/bedukaoficial\/\",\"https:\/\/www.youtube.com\/beduka\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a\",\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o Beduka (a)\"},\"description\":\"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.\",\"sameAs\":[\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\",\"https:\/\/www.instagram.com\/beduka_oficial\/\",\"https:\/\/br.pinterest.com\/bedukaoficial\/\"],\"url\":\"https:\/\/beduka.com\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u25b7 O que \u00e9 SINTAXE? - Defini\u00e7\u00e3o, Principais Conceitos e Exemplos","description":"Aprenda o que \u00e9 Sintaxe! Veja os principais conceitos da sintaxe e aprenda tudo sobre rela\u00e7\u00f5es e fun\u00e7\u00f5es sint\u00e1ticas. Se prepare com o Beduka para o ENEM e outros vestibulares.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-sintaxe\/","og_locale":"pt_BR","og_type":"article","og_title":"\u25b7 O que \u00e9 SINTAXE? - Defini\u00e7\u00e3o, Principais Conceitos e Exemplos","og_description":"Aprenda o que \u00e9 Sintaxe! Veja os principais conceitos da sintaxe e aprenda tudo sobre rela\u00e7\u00f5es e fun\u00e7\u00f5es sint\u00e1ticas. Se prepare com o Beduka para o ENEM e outros vestibulares.","og_url":"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-sintaxe\/","og_site_name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","article_publisher":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","article_author":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades","article_published_time":"2019-06-05T20:52:28+00:00","article_modified_time":"2019-09-05T20:11:00+00:00","og_image":[{"width":600,"height":300,"url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/06\/sintaxe_capa.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Beduka (a)","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Beduka (a)","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-sintaxe\/#article","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-sintaxe\/"},"author":{"name":"Reda\u00e7\u00e3o Beduka (a)","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a"},"headline":"Aprenda tudo sobre o que \u00e9 sintaxe","datePublished":"2019-06-05T20:52:28+00:00","dateModified":"2019-09-05T20:11:00+00:00","mainEntityOfPage":{"@id":"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-sintaxe\/"},"wordCount":1106,"commentCount":0,"publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"keywords":["o que \u00e9 sintaxe","sintaxe"],"articleSection":["Portugu\u00eas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-sintaxe\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-sintaxe\/","url":"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-sintaxe\/","name":"\u25b7 O que \u00e9 SINTAXE? - Defini\u00e7\u00e3o, Principais Conceitos e Exemplos","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/#website"},"datePublished":"2019-06-05T20:52:28+00:00","dateModified":"2019-09-05T20:11:00+00:00","description":"Aprenda o que \u00e9 Sintaxe! Veja os principais conceitos da sintaxe e aprenda tudo sobre rela\u00e7\u00f5es e fun\u00e7\u00f5es sint\u00e1ticas. Se prepare com o Beduka para o ENEM e outros vestibulares.","breadcrumb":{"@id":"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-sintaxe\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-sintaxe\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/beduka.com\/blog\/materias\/portugues\/o-que-e-sintaxe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/beduka.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Aprenda tudo sobre o que \u00e9 sintaxe"}]},{"@type":"WebSite","@id":"https:\/\/beduka.com\/blog\/#website","url":"https:\/\/beduka.com\/blog\/","name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","description":"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!","publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beduka.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beduka.com\/blog\/#organization","name":"Beduka","url":"https:\/\/beduka.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","contentUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","width":1077,"height":368,"caption":"Beduka"},"image":{"@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/www.linkedin.com\/company\/beduka","https:\/\/br.pinterest.com\/bedukaoficial\/","https:\/\/www.youtube.com\/beduka"]},{"@type":"Person","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a","name":"Reda\u00e7\u00e3o Beduka (a)","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o Beduka (a)"},"description":"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.","sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/br.pinterest.com\/bedukaoficial\/"],"url":"https:\/\/beduka.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/7938"}],"collection":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/comments?post=7938"}],"version-history":[{"count":6,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/7938\/revisions"}],"predecessor-version":[{"id":10888,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/7938\/revisions\/10888"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media\/7942"}],"wp:attachment":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media?parent=7938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/categories?post=7938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/tags?post=7938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}