{"id":8162,"date":"2019-06-14T15:50:03","date_gmt":"2019-06-14T18:50:03","guid":{"rendered":"https:\/\/beduka.com\/blog\/?p=8162"},"modified":"2022-03-22T16:11:28","modified_gmt":"2022-03-22T19:11:28","slug":"nota-de-corte-para-pedagogia","status":"publish","type":"post","link":"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-para-pedagogia\/","title":{"rendered":"Nota de Corte para Pedagogia: Sisu 2022 \/ Prouni 2022"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote\"><p><strong><em>Veja as maiores e menores notas de corte para o curso de Pedagogia e tenha uma ideia mais clara de qual nota voc\u00ea precisa tirar na prova do ENEM se quiser fazer este curso. Vamos te mostrar a nota tirada do ranking geral, ele envolve tanto as institui\u00e7\u00f5es p\u00fablicas (federais ou estaduais) quanto as privadas.<\/em><\/strong><\/p><\/blockquote>\n\n\n\n<p>Neste artigo que o Beduka preparou, voc\u00ea vai descobrir quais s\u00e3o as notas de corte para Pedagogia nas principais institui\u00e7\u00f5es p\u00fablicas e privadas.<\/p>\n\n\n\n<p><strong>Clique em algum dos t\u00f3picos abaixo<\/strong> e v\u00e1 diretamente para a nota do seu interesse!<\/p>\n\n\n\n<ol><li><a href=\"#1\">Afinal, o que \u00e9 a nota de corte?<\/a><\/li><li><a href=\"#2\">Menor nota de corte no SISU 2022.<\/a><\/li><li><a href=\"#3\">Maior nota de corte no SISU 2022.<\/a><\/li><li><a href=\"#4\">Menor nota de corte no PROUNI 2022.<\/a><\/li><li><a href=\"#5\">Maior nota de corte no PROUNI 2022.<\/a><\/li><li><a href=\"#6\">Nota de corte para o FIES.<\/a><\/li><\/ol>\n\n\n\n<p>Nosso objetivo \u00e9 fazer com que voc\u00ea saiba quanto voc\u00ea precisa tirar no ENEM caso deseje fazer este curso.<\/p>\n\n\n\n<p>Aqui no site, n\u00f3s tamb\u00e9m te ajudamos a<strong> saber como realizar a inscri\u00e7\u00e3o do<\/strong><a href=\"https:\/\/beduka.com\/blog\/sisu\/como-se-inscrever-no-sisu\/\" target=\"_blank\" rel=\"noreferrer noopener\"> Sisu<\/a> <strong>e do<\/strong><a href=\"https:\/\/beduka.com\/blog\/inscricao-prouni\/\" target=\"_blank\" rel=\"noreferrer noopener\"> Prouni<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"1\">Afinal, o que \u00e9 a nota de corte?<\/h2>\n\n\n\n<p>A nota de corte do Sisu <strong>\u00e9 a menor pontua\u00e7\u00e3o poss\u00edvel para um candidato conseguir a vaga<\/strong> que ele est\u00e1 disputando.<\/p>\n\n\n\n<p>Ao final de cada dia do prazo de inscri\u00e7\u00e3o, o sistema calcula uma m\u00e9dia e libera a <strong>nota de corte parcial.<\/strong> Ou seja, qual \u00e9 o valor m\u00ednimo, at\u00e9 o momento, para se classificar.<\/p>\n\n\n\n<p>Essa informa\u00e7\u00e3o ajuda o candidato a avaliar se tem chances de ser selecionado. Caso tenha uma pontua\u00e7\u00e3o menor do que a nota de corte, \u00e9 poss\u00edvel modificar as op\u00e7\u00f5es escolhidas (antes do encerramento dos 3 dias) e aumentar a probabilidade de conseguir uma vaga.<\/p>\n\n\n\n<p>Ap\u00f3s o encerramento do processo seletivo, o Sisu divulga as <strong>notas de corte finais<\/strong>. Elas correspondem \u00e0 pontua\u00e7\u00e3o do Enem apresentada pelo \u00faltimo candidato classificado <strong>em determinado curso, universidade, unidade, turno e modalidade de concorr\u00eancia.<\/strong><\/p>\n\n\n\n<p>Se o candidato conseguir alcan\u00e7ar ou superar a nota de corte at\u00e9 o fim do per\u00edodo de inscri\u00e7\u00f5es, ele conseguir\u00e1 passar e bastar\u00e1 esperar a divulga\u00e7\u00e3o dos resultados pelo MEC.<\/p>\n\n\n\n<p>Por outro lado, <strong>se voc\u00ea n\u00e3o conseguir alcan\u00e7ar a nota de corte, n\u00e3o desespere!<\/strong> Isso n\u00e3o significa que voc\u00ea est\u00e1 automaticamente eliminado da disputa.<\/p>\n\n\n\n<p>H\u00e1 chances de que algum candidato aprovado na primeira chamada desista ou se matricule em outro curso. A\u00ed haver\u00e1 vagas \u201csobrando\u201d e os melhores colocados abaixo da nota de corte ser\u00e3o chamados. Para que isso aconte\u00e7a, voc\u00ea precisa participar da<a href=\"https:\/\/beduka.com\/blog\/sisu\/lista-de-espera-sisu\/\" target=\"_blank\" rel=\"noreferrer noopener\"> lista de espera.<\/a><\/p>\n\n\n\n<ul><li>Se quiser, entenda mais sobre a<a href=\"https:\/\/beduka.com\/blog\/sisu\/nota-de-corte-sisu\/#:~:text=A%20nota%20de%20corte%20sisu,no%20Sistema%20de%20Sele%C3%A7%C3%A3o%20Unificada!\" target=\"_blank\" rel=\"noreferrer noopener\"> nota de corte do Sisu<\/a>!<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"2\">Qual foi a MENOR nota de corte para Pedagogia no SISU 2022?<\/h2>\n\n\n\n<p>Em uma <strong>federal<\/strong>, a menor nota foi de <strong>392,29<\/strong>, na UFG (Universidade Federal de Goi\u00e1s), na modalidade Ampla Concorr\u00eancia.<\/p>\n\n\n\n<p>A menor nota de corte para o curso de Pedagogia em uma <strong>estadual<\/strong> foi na UEMG (Universidade do Estado de Minas Gerais). A nota foi de <strong>394,48<\/strong> na modalidade Ampla Concorr\u00eancia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"3\">Qual foi a MAIOR nota de corte para Pedagogia no SISU 2022?<\/h2>\n\n\n\n<p>A maior nota de corte para Pedagogia em uma <strong>federal<\/strong> foi de <strong>718,7<\/strong>! Essa nota foi registrada na UFRJ (Universidade Federal do Rio de Janeiro) na modalidade Ampla Concorr\u00eancia.<\/p>\n\n\n\n<p>Para uma universidade <strong>estadual<\/strong>, a UESB (Universidade Estadual do Sudoeste da Bahia) teve a maior nota de corte de <strong>620,07<\/strong> na modalidade Ampla Concorr\u00eancia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"4\">Qual foi a MENOR nota de corte para Pedagogia no PROUNI 2022?<\/h2>\n\n\n\n<p>Em Canoas &#8211; RS, na <strong>Universidade La Salle<\/strong>, a nota de corte para o curso de Pedagogia foi <strong>450.02<\/strong>. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"5\">Qual foi a MAIOR nota de corte para Pedagogia no PROUNI 2022?<\/h2>\n\n\n\n<p>foi na <strong><a rel=\"noreferrer noopener\" href=\"https:\/\/portal.uniasselvi.com.br\/\" data-type=\"URL\" data-id=\"https:\/\/portal.uniasselvi.com.br\/\" target=\"_blank\">UNIASSELVI<\/a> (Centro Universit\u00e1rio Leonardo da Vinci)<\/strong>, que tivemos a maior nota de corte do Prouni foi <strong>702.88<\/strong>. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Nota de corte Enem para Pedagogia<\/h2>\n\n\n\n<p>Na realidade, <strong>n\u00e3o h\u00e1 uma nota de corte do Enem<\/strong>, mas dos vestibulares. O que acontece \u00e9 que a nota do Enem \u00e9 usada para se cadastrar e concorrer nos vestibulares das faculdades p\u00fablicas e provadas que participam do <a href=\"https:\/\/beduka.com\/blog\/sisu\/guia-completo-sisu\/tudo-sobre-o-sisu\/\" target=\"_blank\" rel=\"noreferrer noopener\">Sisu<\/a>, <a href=\"https:\/\/beduka.com\/blog\/prouni\/guia-completo-prouni\/tudo-sobre-o-prouni\/\" target=\"_blank\" rel=\"noreferrer noopener\">Prouni<\/a> e <a href=\"https:\/\/beduka.com\/blog\/fies\/guia-completo-fies\/tudo-sobre-o-fies\/\" target=\"_blank\" rel=\"noreferrer noopener\">Fies<\/a>.<\/p>\n\n\n\n<p>Assim, todos os programas ter\u00e3o as suas respectivas notas de corte que ser\u00e3o dadas pela nota Enem do \u00faltimo candidato a ser selecionado no determinado programa.<\/p>\n\n\n\n<ul><li><a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/dicas\/cursos\/como-e-curso-pedagogia\/\" target=\"_blank\">Como \u00e9 o curso de Pedagogia?<\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/b\/pedagogia\/brasil?tipo=%5B%221;2%22%5D&amp;valor=10000&amp;pagina=1&amp;ordenar=pscls\" target=\"_blank\">Todas as notas de corte Sisu para Pedagogia<\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/b\/pedagogia\/brasil?tipo=%5B%224;5%22%5D&amp;valor=10000&amp;pagina=1&amp;ordenar=pscls\" target=\"_blank\">Todas as notas de corte Prouni para Pedagogia <\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/dicas\/faculdades\/melhores-faculdades-de-pedagogia\/\" target=\"_blank\">Melhores faculdades de Pedagogia do Brasil.<\/a><\/li><\/ul>\n\n\n\n<p>Quer saber mais sobre outros cursos e outras universidades? Consulte no<a href=\"https:\/\/beduka.com\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\"> Beduka<\/a>!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"6\">Nota de Corte para Pedagogia no Fies<\/h2>\n\n\n\n<p>A exig\u00eancia do Fies \u00e9 que o candidato, <strong>no m\u00ednimo, obtenha 450 pontos<\/strong> como nota no Enem e que <strong>n\u00e3o zere a reda\u00e7\u00e3o<\/strong>.<\/p>\n\n\n\n<p>Atendido isso, o candidato disputa normalmente depois de ser avaliado nas condi\u00e7\u00f5es socioecon\u00f4micas. As maiores notas preencher\u00e3o as vagas disponibilizadas para financiamento.<\/p>\n\n\n\n<ul><li><a href=\"https:\/\/beduka.com\/blog\/como-funciona-o-fies\/\" target=\"_blank\" rel=\"noreferrer noopener\">Aprenda tamb\u00e9m como funciona o Fies<\/a>.<\/li><\/ul>\n\n\n\n<p>Gostou de conferir as notas de corte para Pedagogia? Se prepare para a prova do ENEM ou de outros vestibulares com o<a href=\"https:\/\/beduka.com\/simulado\/#\/\" target=\"_blank\" rel=\"noreferrer noopener\"> Simulado do Beduka<\/a>. \u00c9 gratuito e voc\u00ea pode fazer a hora que quiser!<\/p>\n\n\n\n<p>Queremos te ajudar a encontrar a <strong>FACULDADE IDEAL<\/strong>! Logo abaixo, fa\u00e7a uma pesquisa por curso e cidade que te mostraremos todas as faculdades que podem te atender. <strong>Informamos a nota de corte, valor de mensalidade, nota do MEC, avalia\u00e7\u00e3o dos alunos, modalidades de ensino e muito mais.<\/strong><\/p>\n\n\n\n<p>Experimente agora!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Veja as maiores e menores notas de corte para o curso de Pedagogia e tenha uma ideia mais clara de qual nota voc\u00ea precisa tirar na prova do ENEM se quiser fazer este curso. Vamos te mostrar a nota tirada do ranking geral, ele envolve tanto as institui\u00e7\u00f5es p\u00fablicas (federais ou estaduais) quanto as privadas. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8163,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[535],"tags":[779,599],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nota de Corte para Pedagogia: Sisu 2021 \/ Prouni 2020 \/ Fies!<\/title>\n<meta name=\"description\" content=\"Descubra a nota de corte para Pedagogia (maiores e menores), seja no Sisu 2021, Prouni 2020 ou Fies. \u00c9 a nota que voc\u00ea precisa tirar no ENEM!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-para-pedagogia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nota de Corte para Pedagogia: Sisu 2021 \/ Prouni 2020 \/ Fies!\" \/>\n<meta property=\"og:description\" content=\"Descubra a nota de corte para Pedagogia (maiores e menores), seja no Sisu 2021, Prouni 2020 ou Fies. \u00c9 a nota que voc\u00ea precisa tirar no ENEM!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-para-pedagogia\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-14T18:50:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-22T19:11:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/06\/Nota-de-corte-para-Pedagogia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-para-pedagogia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-para-pedagogia\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a\"},\"headline\":\"Nota de Corte para Pedagogia: Sisu 2022 \/ Prouni 2022\",\"datePublished\":\"2019-06-14T18:50:03+00:00\",\"dateModified\":\"2022-03-22T19:11:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-para-pedagogia\/\"},\"wordCount\":898,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/beduka.com\/blog\/#organization\"},\"keywords\":[\"nota de corte\",\"pedagogia\"],\"articleSection\":[\"Cursos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-para-pedagogia\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-para-pedagogia\/\",\"url\":\"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-para-pedagogia\/\",\"name\":\"Nota de Corte para Pedagogia: Sisu 2021 \/ Prouni 2020 \/ Fies!\",\"isPartOf\":{\"@id\":\"https:\/\/beduka.com\/blog\/#website\"},\"datePublished\":\"2019-06-14T18:50:03+00:00\",\"dateModified\":\"2022-03-22T19:11:28+00:00\",\"description\":\"Descubra a nota de corte para Pedagogia (maiores e menores), seja no Sisu 2021, Prouni 2020 ou Fies. \u00c9 a nota que voc\u00ea precisa tirar no ENEM!\",\"breadcrumb\":{\"@id\":\"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-para-pedagogia\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-para-pedagogia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-para-pedagogia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/beduka.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nota de Corte para Pedagogia: Sisu 2022 \/ Prouni 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/beduka.com\/blog\/#website\",\"url\":\"https:\/\/beduka.com\/blog\/\",\"name\":\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\",\"description\":\"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!\",\"publisher\":{\"@id\":\"https:\/\/beduka.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/beduka.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/beduka.com\/blog\/#organization\",\"name\":\"Beduka\",\"url\":\"https:\/\/beduka.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png\",\"contentUrl\":\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png\",\"width\":1077,\"height\":368,\"caption\":\"Beduka\"},\"image\":{\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/\",\"https:\/\/www.instagram.com\/beduka_oficial\/\",\"https:\/\/www.linkedin.com\/company\/beduka\",\"https:\/\/br.pinterest.com\/bedukaoficial\/\",\"https:\/\/www.youtube.com\/beduka\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a\",\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o Beduka (a)\"},\"description\":\"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.\",\"sameAs\":[\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\",\"https:\/\/www.instagram.com\/beduka_oficial\/\",\"https:\/\/br.pinterest.com\/bedukaoficial\/\"],\"url\":\"https:\/\/beduka.com\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nota de Corte para Pedagogia: Sisu 2021 \/ Prouni 2020 \/ Fies!","description":"Descubra a nota de corte para Pedagogia (maiores e menores), seja no Sisu 2021, Prouni 2020 ou Fies. \u00c9 a nota que voc\u00ea precisa tirar no ENEM!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-para-pedagogia\/","og_locale":"pt_BR","og_type":"article","og_title":"Nota de Corte para Pedagogia: Sisu 2021 \/ Prouni 2020 \/ Fies!","og_description":"Descubra a nota de corte para Pedagogia (maiores e menores), seja no Sisu 2021, Prouni 2020 ou Fies. \u00c9 a nota que voc\u00ea precisa tirar no ENEM!","og_url":"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-para-pedagogia\/","og_site_name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","article_publisher":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","article_author":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades","article_published_time":"2019-06-14T18:50:03+00:00","article_modified_time":"2022-03-22T19:11:28+00:00","og_image":[{"width":600,"height":300,"url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/06\/Nota-de-corte-para-Pedagogia.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Beduka (a)","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Beduka (a)","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-para-pedagogia\/#article","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-para-pedagogia\/"},"author":{"name":"Reda\u00e7\u00e3o Beduka (a)","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a"},"headline":"Nota de Corte para Pedagogia: Sisu 2022 \/ Prouni 2022","datePublished":"2019-06-14T18:50:03+00:00","dateModified":"2022-03-22T19:11:28+00:00","mainEntityOfPage":{"@id":"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-para-pedagogia\/"},"wordCount":898,"commentCount":0,"publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"keywords":["nota de corte","pedagogia"],"articleSection":["Cursos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-para-pedagogia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-para-pedagogia\/","url":"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-para-pedagogia\/","name":"Nota de Corte para Pedagogia: Sisu 2021 \/ Prouni 2020 \/ Fies!","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/#website"},"datePublished":"2019-06-14T18:50:03+00:00","dateModified":"2022-03-22T19:11:28+00:00","description":"Descubra a nota de corte para Pedagogia (maiores e menores), seja no Sisu 2021, Prouni 2020 ou Fies. \u00c9 a nota que voc\u00ea precisa tirar no ENEM!","breadcrumb":{"@id":"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-para-pedagogia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-para-pedagogia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/beduka.com\/blog\/dicas\/cursos\/nota-de-corte-para-pedagogia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/beduka.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Nota de Corte para Pedagogia: Sisu 2022 \/ Prouni 2022"}]},{"@type":"WebSite","@id":"https:\/\/beduka.com\/blog\/#website","url":"https:\/\/beduka.com\/blog\/","name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","description":"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!","publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beduka.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beduka.com\/blog\/#organization","name":"Beduka","url":"https:\/\/beduka.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","contentUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","width":1077,"height":368,"caption":"Beduka"},"image":{"@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/www.linkedin.com\/company\/beduka","https:\/\/br.pinterest.com\/bedukaoficial\/","https:\/\/www.youtube.com\/beduka"]},{"@type":"Person","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a","name":"Reda\u00e7\u00e3o Beduka (a)","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o Beduka (a)"},"description":"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.","sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/br.pinterest.com\/bedukaoficial\/"],"url":"https:\/\/beduka.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/8162"}],"collection":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/comments?post=8162"}],"version-history":[{"count":3,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/8162\/revisions"}],"predecessor-version":[{"id":25110,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/8162\/revisions\/25110"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media\/8163"}],"wp:attachment":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media?parent=8162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/categories?post=8162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/tags?post=8162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}