{"id":9191,"date":"2019-07-10T12:08:04","date_gmt":"2019-07-10T15:08:04","guid":{"rendered":"https:\/\/beduka.com\/blog\/?p=9191"},"modified":"2019-09-24T17:50:19","modified_gmt":"2019-09-24T20:50:19","slug":"o-que-e-entalpia","status":"publish","type":"post","link":"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-entalpia\/","title":{"rendered":"Descubra o que \u00e9 Entalpia"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote\"><p><strong><em>Entalpia \u00e9 a quantidade de energia que uma subst\u00e2ncia que sofre rea\u00e7\u00e3o possui. Ela calcula o calor de um sistema e \u00e9 a maneira mais usada para descobrir se a rea\u00e7\u00e3o qu\u00edmica \u00e9 exot\u00e9rmica ou endot\u00e9rmica.<\/em><\/strong><br><\/p><\/blockquote>\n\n\n\n<p>No caderno de Ci\u00eancias da Natureza e suas tecnologias do ENEM, as quest\u00f5es de Qu\u00edmica sempre s\u00e3o motivo de preocupa\u00e7\u00e3o dos estudantes. Dentro dessa mat\u00e9ria, entender o que \u00e9 Entalpia \u00e9 essencial para responder quest\u00f5es que surgem sobre o tema.<br><\/p>\n\n\n\n<p>N\u00e3o deixe de conferir os <a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/beduka.com\/blog\/exercicios\/quimica-exercicios\/exercicios-sobre-entalpia\/\" target=\"_blank\">exerc\u00edcios sobre Entalpia<\/a>!<br><\/p>\n\n\n\n<p>Nesse artigo vamos falar sobre:<br><\/p>\n\n\n\n<ul><li>O que \u00e9 Entalpia;<\/li><li>Varia\u00e7\u00e3o de Entalpia;<\/li><li>Tipos de Entalpia.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">O que \u00e9 Entalpia?<\/h2>\n\n\n\n<p><strong>Entalpia <\/strong>\u00e9 a grandeza f\u00edsica que <strong>mede a quantidade de energia dentro das subst\u00e2ncias <\/strong>que sofrem uma rea\u00e7\u00e3o qu\u00edmica. Ou seja, pode-se dizer que a entalpia calcula <strong>a quantidade de calor absorvido ou liberado<\/strong> em uma rea\u00e7\u00e3o qu\u00edmica.&nbsp;<br><\/p>\n\n\n\n<p>O c\u00e1lculo da entalpia \u00e9 o respons\u00e1vel por definir se uma rea\u00e7\u00e3o qu\u00edmica \u00e9 <strong>endot\u00e9rmica <\/strong>ou<strong> exot\u00e9rmica<\/strong>:<br><\/p>\n\n\n\n<ul><li><strong>Rea\u00e7\u00e3o Endot\u00e9rmica:<\/strong> S\u00e3o rea\u00e7\u00f5es ou mudan\u00e7as de estado f\u00edsico em que os reagentes absorvem calor;<\/li><\/ul>\n\n\n\n<ul><li><strong>Rea\u00e7\u00e3o Exot\u00e9rmica: <\/strong>S\u00e3o rea\u00e7\u00f5es ou mudan\u00e7as de estado f\u00edsico em que h\u00e1 a libera\u00e7\u00e3o de calor.&nbsp;<\/li><\/ul>\n\n\n\n<p>Essa energia estava <strong>contida nos reagentes da rea\u00e7\u00e3o qu\u00edmica<\/strong>, sendo proveniente da <strong>movimenta\u00e7\u00e3o das mol\u00e9culas<\/strong>, e, quando eles se transformaram em produtos, essa energia foi liberada em <strong>forma de calor<\/strong>. Essa quantidade espec\u00edfica de energia interna que cada subst\u00e2ncia tem \u00e9 chamada de <strong>entalpia<\/strong>, e pode ser simbolizada pela letra H.<br><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Varia\u00e7\u00e3o de Entalpia<\/h2>\n\n\n\n<p>A <strong>varia\u00e7\u00e3o da entalpia<\/strong> acontece quando h\u00e1 <strong>diferen\u00e7a entre a entalpia dos produtos e a dos reagentes<\/strong>, ou seja, o calor de uma rea\u00e7\u00e3o \u00e9 equivalente ao calor liberado ou absorvido nessa rea\u00e7\u00e3o, e \u00e9 simbolizado por \u2206 H. <br><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Lei de Hess<\/strong><\/h3>\n\n\n\n<p>Desenvolvida pelo su\u00ed\u00e7o Germain Henri Hess, a <strong>Lei de Hess<\/strong> afirma que a <strong>varia\u00e7\u00e3o da entalpia deve ser calculada pela somat\u00f3ria das suas mudan\u00e7as <\/strong>em etapas individuais.<\/p>\n\n\n\n<p>Isso significa que h\u00e1 um<strong> c\u00e1lculo espec\u00edfico<\/strong> que pode avaliar a quantidade de energia nas subst\u00e2ncias de um sistema depois de sofrerem suas pr\u00f3prias rea\u00e7\u00f5es qu\u00edmicas. Portanto, a varia\u00e7\u00e3o de entalpia <strong>n\u00e3o depende da quantidade de rea\u00e7\u00f5es <\/strong>por que ela passou, precisa somente dos valores iniciais e finais de cada rea\u00e7\u00e3o.<br><\/p>\n\n\n\n<p>Em resumo, uma rea\u00e7\u00e3o a varia\u00e7\u00e3o de entalpia \u00e9 a mesma, independente de qual seja a etapa em que a rea\u00e7\u00e3o ocorre, sendo assim a varia\u00e7\u00e3o da entalpia \u00e9 a <strong>entalpia final (ap\u00f3s a rea\u00e7\u00e3o) menos a entalpia inicial (anterior a rea\u00e7\u00e3o)<\/strong>.<br><\/p>\n\n\n\n<p>A varia\u00e7\u00e3o da entalpia pode ser calculada atrav\u00e9s da seguinte f\u00f3rmula:<br><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" loading=\"lazy\" width=\"600\" height=\"300\" src=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/07\/formula-2.jpg\" alt=\"varia\u00e7\u00e3o da entalpia\" class=\"wp-image-9193\" srcset=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/07\/formula-2.jpg 600w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/07\/formula-2-300x150.jpg 300w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/07\/formula-2-320x160.jpg 320w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n\n\n\n<p>A f\u00f3rmula da varia\u00e7\u00e3o da entalpia depende de alguns fatores, tais como:<br><\/p>\n\n\n\n<ul><li>Temperatura;<\/li><li>Press\u00e3o;<\/li><li>Estado f\u00edsico;<\/li><li>N\u00famero de mol;<\/li><li>Variedade alotr\u00f3pica das subst\u00e2ncias.<\/li><\/ul>\n\n\n\n<p>Se o resultado for <strong>negativo<\/strong>, isso significa que a rea\u00e7\u00e3o \u00e9 <strong>exot\u00e9rmica<\/strong>, pois o <strong>calor foi liberado<\/strong> e o valor da entalpia dos produtos \u00e9 inferior \u00e0 entalpia dos reagentes. Entretanto, se o resultado for <strong>positivo<\/strong>, isso significa que a rea\u00e7\u00e3o \u00e9 <strong>endot\u00e9rmica<\/strong>, pois ao <strong>absorver energia <\/strong>a entalpia dos produtos \u00e9 maior do que a dos reagentes. Sendo assim:<br><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" loading=\"lazy\" width=\"600\" height=\"300\" src=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/07\/formula-1-1.jpg\" alt=\"entalpia\" class=\"wp-image-9195\" srcset=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/07\/formula-1-1.jpg 600w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/07\/formula-1-1-300x150.jpg 300w, https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/07\/formula-1-1-320x160.jpg 320w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Tipos de Entalpia<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Entalpia de mudan\u00e7a de estado f\u00edsico<\/strong><\/h3>\n\n\n\n<p>Diz respeito \u00e0 <strong>quantidade de energia que \u00e9 necess\u00e1ria <\/strong>para que um mol de subst\u00e2ncia, a press\u00e3o e a temperatura constante <strong>mude de estado f\u00edsico<\/strong>. <\/p>\n\n\n\n<p>Vale lembrar que <strong>mol <\/strong>\u00e9 uma unidade de medida utilizada para <strong>expressar a quantidade de mat\u00e9ria<\/strong> microsc\u00f3pica, como \u00e1tomos e mol\u00e9culas. \u00c9 estabelecido que 1 mol \u00e9 igual a 6.02.1023 mol\u00e9culas. Dentro deste tipo de entalpia se encontram v\u00e1rios subtipos:<br><\/p>\n\n\n\n<p><strong>Entalpia de vaporiza\u00e7\u00e3o:<\/strong> \u00e9 a energia necess\u00e1ria para <strong>vaporizar <\/strong>um mol de subst\u00e2ncia, ou seja, passar do estado f\u00edsico l\u00edquido para o estado gasoso. A energia <strong>absorvida <\/strong>est\u00e1 em forma de calor, ou seja, esse processo \u00e9 <strong>endot\u00e9rmico <\/strong>e o valor da entalpia sempre ser\u00e1 <strong>positivo<\/strong>.<br><\/p>\n\n\n\n<p><strong>Entalpia de fus\u00e3o:<\/strong> \u00e9 energia que precisa ser consumida para que um mol de subst\u00e2ncia sofra a fus\u00e3o, ou seja, passe do estado f\u00edsico s\u00f3lido para o estado l\u00edquido. Esse processo tamb\u00e9m \u00e9 endot\u00e9rmico, onde a energia absorvida est\u00e1 em forma de calor, por esse motivo, a entalpia tamb\u00e9m sempre ser\u00e1 positiva.<br><\/p>\n\n\n\n<p><strong>Entalpia de combust\u00e3o:<\/strong> \u00e9 a energia liberada durante a <strong>combust\u00e3o <\/strong>completa de um mol de subst\u00e2ncia \u00e0 press\u00e3o e de temperatura constante. Essa rea\u00e7\u00e3o que <strong>libera energia <\/strong>em forma de calor, ou seja, essa rea\u00e7\u00e3o \u00e9 <strong>exot\u00e9rmica <\/strong>e a varia\u00e7\u00e3o da entalpia \u00e9 <strong>negativa<\/strong>.<br><\/p>\n\n\n\n<p><strong>Entalpia de solidifica\u00e7\u00e3o:<\/strong> \u00e9 quantidade de energia que necessita de ser liberada para que um mol de subst\u00e2ncia, a temperatura e a press\u00e3o constante, <strong>passe do estado f\u00edsico l\u00edquido para o estado s\u00f3lido<\/strong>. Esse processo tamb\u00e9m \u00e9 <strong>exot\u00e9rmico <\/strong>e o valor da entalpia \u00e9 <strong>negativo<\/strong>.<br><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Entalpia de forma\u00e7\u00e3o<\/strong><strong>&nbsp;<\/strong><\/h3>\n\n\n\n<p>\u00c9 a energia em forma de calor <strong>liberada ou absorvida<\/strong> na <strong>forma\u00e7\u00e3o de um mol de subst\u00e2ncia <\/strong>a partir dos seus elementos correspondentes dos quais s\u00e3o subst\u00e2ncias simples. Nesse caso, a press\u00e3o e a temperatura tamb\u00e9m permanecem constantes e a <strong>entalpia \u00e9 igual a zero<\/strong>.<br><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Entalpia de liga\u00e7\u00e3o<\/strong><\/h3>\n\n\n\n<p>\u00c9 energia que precisa ser <strong>absorvida<\/strong> para <strong>quebrar<\/strong> 1 mol de de liga\u00e7\u00f5es no estado gasoso, em condi\u00e7\u00f5es de press\u00e3o e temperatura constantes. Nesse caso, o valor da energia de liga\u00e7\u00e3o ser\u00e1 o valor da <strong>varia\u00e7\u00e3o de entalpia da rea\u00e7\u00e3o<\/strong>. Como h\u00e1 a <strong>absor\u00e7\u00e3o <\/strong>de energia, trata-se de um processo <strong>endot\u00e9rmico<\/strong>.<br><\/p>\n\n\n\n<p>Al\u00e9m de aprender o que \u00e9 Entalpia, voc\u00ea pode testar seus conhecimentos de outras mat\u00e9rias respondendo algumas quest\u00f5es que ca\u00edram em edi\u00e7\u00f5es antigas do Exame em nosso <a rel=\"noreferrer noopener\" aria-label=\"simulado (abre numa nova aba)\" href=\"https:\/\/beduka.com\/simulado\/#\/\" target=\"_blank\">simulado<\/a> gratuito.<br><\/p>\n\n\n\n<p>Gostou de aprender sobre o que \u00e9 Entalpia? Queremos te ajudar tamb\u00e9m a encontrar a FACULDADE IDEAL! Logo abaixo, fa\u00e7a uma pesquisa por curso e cidade que te mostraremos todas as faculdades que podem te atender. Informamos a nota de corte, valor de mensalidade, nota do MEC, avalia\u00e7\u00e3o dos alunos, modalidades de ensino e muito mais.<br><\/p>\n\n\n\n<p>Experimente agora!<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entalpia \u00e9 a quantidade de energia que uma subst\u00e2ncia que sofre rea\u00e7\u00e3o possui. Ela calcula o calor de um sistema e \u00e9 a maneira mais usada para descobrir se a rea\u00e7\u00e3o qu\u00edmica \u00e9 exot\u00e9rmica ou endot\u00e9rmica. No caderno de Ci\u00eancias da Natureza e suas tecnologias do ENEM, as quest\u00f5es de Qu\u00edmica sempre s\u00e3o motivo de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9196,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[496],"tags":[940,941],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u25b7 O que \u00e9 ENTALPIA? - Defini\u00e7\u00e3o, Tipos, F\u00f3rmulas e Varia\u00e7\u00e3o de Entalpia!<\/title>\n<meta name=\"description\" content=\"Descubra o que \u00e9 Entalpia! Aprenda o que \u00e9, quais s\u00e3o os Tipos de entalpia, o que \u00e9 Varia\u00e7\u00e3o de Entalpia, f\u00f3rmulas e muito mais! Se prepare com o Beduka para o ENEM.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-entalpia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u25b7 O que \u00e9 ENTALPIA? - Defini\u00e7\u00e3o, Tipos, F\u00f3rmulas e Varia\u00e7\u00e3o de Entalpia!\" \/>\n<meta property=\"og:description\" content=\"Descubra o que \u00e9 Entalpia! Aprenda o que \u00e9, quais s\u00e3o os Tipos de entalpia, o que \u00e9 Varia\u00e7\u00e3o de Entalpia, f\u00f3rmulas e muito mais! Se prepare com o Beduka para o ENEM.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-entalpia\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-10T15:08:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-24T20:50:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/07\/entalpia_capa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Beduka (a)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-entalpia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-entalpia\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a\"},\"headline\":\"Descubra o que \u00e9 Entalpia\",\"datePublished\":\"2019-07-10T15:08:04+00:00\",\"dateModified\":\"2019-09-24T20:50:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-entalpia\/\"},\"wordCount\":1064,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/beduka.com\/blog\/#organization\"},\"keywords\":[\"O que \u00e9 Entalpia\",\"varia\u00e7\u00e3o de entalpia\"],\"articleSection\":[\"Qu\u00edmica\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-entalpia\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-entalpia\/\",\"url\":\"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-entalpia\/\",\"name\":\"\u25b7 O que \u00e9 ENTALPIA? - Defini\u00e7\u00e3o, Tipos, F\u00f3rmulas e Varia\u00e7\u00e3o de Entalpia!\",\"isPartOf\":{\"@id\":\"https:\/\/beduka.com\/blog\/#website\"},\"datePublished\":\"2019-07-10T15:08:04+00:00\",\"dateModified\":\"2019-09-24T20:50:19+00:00\",\"description\":\"Descubra o que \u00e9 Entalpia! Aprenda o que \u00e9, quais s\u00e3o os Tipos de entalpia, o que \u00e9 Varia\u00e7\u00e3o de Entalpia, f\u00f3rmulas e muito mais! Se prepare com o Beduka para o ENEM.\",\"breadcrumb\":{\"@id\":\"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-entalpia\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-entalpia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-entalpia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/beduka.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Descubra o que \u00e9 Entalpia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/beduka.com\/blog\/#website\",\"url\":\"https:\/\/beduka.com\/blog\/\",\"name\":\"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem\",\"description\":\"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!\",\"publisher\":{\"@id\":\"https:\/\/beduka.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/beduka.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/beduka.com\/blog\/#organization\",\"name\":\"Beduka\",\"url\":\"https:\/\/beduka.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png\",\"contentUrl\":\"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png\",\"width\":1077,\"height\":368,\"caption\":\"Beduka\"},\"image\":{\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/\",\"https:\/\/www.instagram.com\/beduka_oficial\/\",\"https:\/\/www.linkedin.com\/company\/beduka\",\"https:\/\/br.pinterest.com\/bedukaoficial\/\",\"https:\/\/www.youtube.com\/beduka\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a\",\"name\":\"Reda\u00e7\u00e3o Beduka (a)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/beduka.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o Beduka (a)\"},\"description\":\"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.\",\"sameAs\":[\"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\",\"https:\/\/www.instagram.com\/beduka_oficial\/\",\"https:\/\/br.pinterest.com\/bedukaoficial\/\"],\"url\":\"https:\/\/beduka.com\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u25b7 O que \u00e9 ENTALPIA? - Defini\u00e7\u00e3o, Tipos, F\u00f3rmulas e Varia\u00e7\u00e3o de Entalpia!","description":"Descubra o que \u00e9 Entalpia! Aprenda o que \u00e9, quais s\u00e3o os Tipos de entalpia, o que \u00e9 Varia\u00e7\u00e3o de Entalpia, f\u00f3rmulas e muito mais! Se prepare com o Beduka para o ENEM.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-entalpia\/","og_locale":"pt_BR","og_type":"article","og_title":"\u25b7 O que \u00e9 ENTALPIA? - Defini\u00e7\u00e3o, Tipos, F\u00f3rmulas e Varia\u00e7\u00e3o de Entalpia!","og_description":"Descubra o que \u00e9 Entalpia! Aprenda o que \u00e9, quais s\u00e3o os Tipos de entalpia, o que \u00e9 Varia\u00e7\u00e3o de Entalpia, f\u00f3rmulas e muito mais! Se prepare com o Beduka para o ENEM.","og_url":"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-entalpia\/","og_site_name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","article_publisher":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","article_author":"https:\/\/www.facebook.com\/beduka.buscadordefaculdades","article_published_time":"2019-07-10T15:08:04+00:00","article_modified_time":"2019-09-24T20:50:19+00:00","og_image":[{"width":600,"height":300,"url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2019\/07\/entalpia_capa.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Beduka (a)","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Beduka (a)","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-entalpia\/#article","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-entalpia\/"},"author":{"name":"Reda\u00e7\u00e3o Beduka (a)","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a"},"headline":"Descubra o que \u00e9 Entalpia","datePublished":"2019-07-10T15:08:04+00:00","dateModified":"2019-09-24T20:50:19+00:00","mainEntityOfPage":{"@id":"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-entalpia\/"},"wordCount":1064,"commentCount":0,"publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"keywords":["O que \u00e9 Entalpia","varia\u00e7\u00e3o de entalpia"],"articleSection":["Qu\u00edmica"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-entalpia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-entalpia\/","url":"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-entalpia\/","name":"\u25b7 O que \u00e9 ENTALPIA? - Defini\u00e7\u00e3o, Tipos, F\u00f3rmulas e Varia\u00e7\u00e3o de Entalpia!","isPartOf":{"@id":"https:\/\/beduka.com\/blog\/#website"},"datePublished":"2019-07-10T15:08:04+00:00","dateModified":"2019-09-24T20:50:19+00:00","description":"Descubra o que \u00e9 Entalpia! Aprenda o que \u00e9, quais s\u00e3o os Tipos de entalpia, o que \u00e9 Varia\u00e7\u00e3o de Entalpia, f\u00f3rmulas e muito mais! Se prepare com o Beduka para o ENEM.","breadcrumb":{"@id":"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-entalpia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-entalpia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/beduka.com\/blog\/materias\/quimica\/o-que-e-entalpia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/beduka.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Descubra o que \u00e9 Entalpia"}]},{"@type":"WebSite","@id":"https:\/\/beduka.com\/blog\/#website","url":"https:\/\/beduka.com\/blog\/","name":"Blog do Beduka | Mat\u00e9rias resumidas, Dicas e Exerc\u00edcios Enem","description":"O Blog do Beduka tem os conte\u00fados que mais caem no Enem, exerc\u00edcios de vestibular com gabarito, resumos, dicas e informa\u00e7\u00f5es Sisu, Prouni e Fies.Encontre dicas para o ENEM, resumos, exerc\u00edcios e informa\u00e7\u00f5es sobre os vestibulares. Acesse agora!","publisher":{"@id":"https:\/\/beduka.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beduka.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/beduka.com\/blog\/#organization","name":"Beduka","url":"https:\/\/beduka.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","contentUrl":"https:\/\/beduka.com\/blog\/wp-content\/uploads\/2020\/06\/marca-beduka.png","width":1077,"height":368,"caption":"Beduka"},"image":{"@id":"https:\/\/beduka.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades\/","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/www.linkedin.com\/company\/beduka","https:\/\/br.pinterest.com\/bedukaoficial\/","https:\/\/www.youtube.com\/beduka"]},{"@type":"Person","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/325d912d2cb8dd9ede8ab291427d2b8a","name":"Reda\u00e7\u00e3o Beduka (a)","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/beduka.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6f58a181ef24e0dc0bb73f096aa0f8b5?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o Beduka (a)"},"description":"Este conte\u00fado foi criado e validado por uma equipe multidisciplinar, formada por especialistas em cada \u00e1rea do conhecimento. O Beduka est\u00e1 presente no Instagram, YouTube, LinkedIn e em diversos outros ambientes digitais. O site foi criado em 2017 e, desde a sua funda\u00e7\u00e3o, atua para fornecer materiais de qualidade para facilitar a vida de estudantes de todo o Brasil, ajudando-os a se preparar para os principais vestibulares e o Enem.","sameAs":["https:\/\/www.facebook.com\/beduka.buscadordefaculdades","https:\/\/www.instagram.com\/beduka_oficial\/","https:\/\/br.pinterest.com\/bedukaoficial\/"],"url":"https:\/\/beduka.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/9191"}],"collection":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/comments?post=9191"}],"version-history":[{"count":6,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/9191\/revisions"}],"predecessor-version":[{"id":11922,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/posts\/9191\/revisions\/11922"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media\/9196"}],"wp:attachment":[{"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/media?parent=9191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/categories?post=9191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beduka.com\/blog\/wp-json\/wp\/v2\/tags?post=9191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}